{"id":70972,"date":"2024-10-17T18:57:55","date_gmt":"2024-10-17T16:57:55","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/"},"modified":"2024-10-17T18:57:55","modified_gmt":"2024-10-17T16:57:55","slug":"pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/","title":{"rendered":"Pj\u00f6ngjang: S\u00fcdkorea offiziell als &quot;feindlicher Staat&quot; definiert"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/671111f3b480cc2a7e0ed737.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die Lage auf der koreanischen Halbinsel spitzt sich weiter zu. Pj\u00f6ngjang hat in der \u00fcberarbeiteten Verfassung S\u00fcdkorea als &#8220;feindlichen Staat&#8221; bezeichtet. Nordkorea hat s\u00e4mtliche Stra\u00dfen- und Eisenbahnverbindungen zum S\u00fcden gekappt und plant eine weitere Abgrenzung des Territoriums.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Nordkorea hat seine Haltung zum Konzept\u00a0der friedlichen Wiedervereinigung mit dem S\u00fcden grundlegend ge\u00e4ndert.\u00a0S\u00fcdkorea wird nun offiziell als &#8220;Hauptfeind&#8221; in der nordkoreanischen \u00fcberarbeiteten Verfassung bezeichnet, wie die staatliche Nachrichtenagentur <em>KCNA<\/em> am Donnerstag <a rel=\"nofollow noopener\" target=\"_blank\" href=\"http:\/\/kcna.kp\/en\/article\/q\/64e900f5bd0353837ca02d7babcce3ad8b04704642132a6cb3c6fd8ca38550c6a71110c246820e75b27f0800d3bfeaf6.kcmsf\">mitteilt<\/a>.\u00a0<\/p>\n<p>Vergangene Woche hatte Nordkorea eine Sitzung seiner Obersten Volksversammlung abgehalten. Es wurde erwartet, dass das Parlament den Punkt \u00fcber die Wiedervereinigung der beiden Nachbarl\u00e4nder aus der Verfassung streichen w\u00fcrde.\u00a0Erst heute hat die Agentur <em>KCNA<\/em> in ihrem Bericht erw\u00e4hnt, dass die Definition &#8220;Hauptfeind&#8221; in Bezug auf Seoul in der Verfassung verankert worden sei.<\/p>\n<p>Am Dienstag hat das nordkoreanische Milit\u00e4r Teile der innerkoreanischen Stra\u00dfenverbindungen n\u00f6rdlich der milit\u00e4rischen Demarkationslinie gesprengt. Nunmehr sind die Stra\u00dfen- und Bahnverbindungen nach S\u00fcdkorea komplett gekappt.\u00a0&#8220;Dies ist eine unvermeidliche und legitime Ma\u00dfnahme in \u00dcbereinstimmung mit der Verfassung der DVRK, die die Republik Korea klar als feindlichen Staat definiert&#8221;, erkl\u00e4rte <em>KCNA<\/em>.<\/p>\n<p>Wie es hei\u00dft, seien 60 Meter lange Stra\u00dfen- und Eisenbahnabschnitte auf nordkoreanischer Seite, die als Grenz\u00fcberg\u00e4nge dienten, nun vollst\u00e4ndig blockiert. Diese Ma\u00dfnahme sei Teil einer schrittweisen vollst\u00e4ndigen Abgrenzung des nordkoreanischen Territoriums vom S\u00fcden.<\/p>\n<p>Pj\u00f6ngjang werde weiterhin Ma\u00dfnahmen ergreifen, um die &#8220;geschlossene S\u00fcdgrenze dauerhaft zu befestigen&#8221;, berichtet die <em>KCNA<\/em>\u00a0unter Bezugnahme auf das nordkoreanische Verteidigungsministerium.\u00a0<\/p>\n<p><strong>Mehr zum Thema \u2013<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/222668-nordkorea-14-millionen-menschen-wollen\/\">Nordkorea: 1,4 Millionen Menschen wollen in Armee, um S\u00fcdkorea zu bestrafen<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v5gmub9\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/asien\/222801-pjoengjang-suedkorea-offiziell-feindlicher-staat\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Lage auf der koreanischen Halbinsel spitzt sich weiter zu. Pj\u00f6ngjang hat in der \u00fcberarbeiteten Verfassung S\u00fcdkorea als &#8220;feindlichen Staat&#8221; bezeichtet. Nordkorea hat s\u00e4mtliche Stra\u00dfen- und Eisenbahnverbindungen zum S\u00fcden gekappt und plant eine weitere Abgrenzung des Territoriums. Nordkorea hat seine Haltung zum Konzept\u00a0der friedlichen Wiedervereinigung mit dem S\u00fcden grundlegend ge\u00e4ndert.\u00a0S\u00fcdkorea wird nun offiziell als &#8220;Hauptfeind&#8221; [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":70973,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1729185184"],"wp_automatic_camp":["217"],"d30ec086d41ef96e5b6b737f2e19986a":["Pj\u00f6ngjang: S\u00fcdkorea offiziell als &quot;feindlicher Staat&quot; definiert"],"original_link":["https:\/\/de.rt.com\/asien\/222801-pjoengjang-suedkorea-offiziell-feindlicher-staat\/"],"_thumbnail_id":["70973"],"jnews_social_counter_last_update":["1784049090"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-10-17 19:14:27\";}"]},"categories":[19,23],"tags":[273,28281,2390,34850,58199,21832,18576],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pj\u00f6ngjang: S\u00fcdkorea offiziell als &quot;feindlicher Staat&quot; definiert - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pj\u00f6ngjang: S\u00fcdkorea offiziell als &quot;feindlicher Staat&quot; definiert\" \/>\n<meta property=\"og:description\" content=\"Die Lage auf der koreanischen Halbinsel spitzt sich weiter zu. Pj\u00f6ngjang hat in der \u00fcberarbeiteten Verfassung S\u00fcdkorea als &#8220;feindlichen Staat&#8221; bezeichtet. Nordkorea hat s\u00e4mtliche Stra\u00dfen- und Eisenbahnverbindungen zum S\u00fcden gekappt und plant eine weitere Abgrenzung des Territoriums. Nordkorea hat seine Haltung zum Konzept\u00a0der friedlichen Wiedervereinigung mit dem S\u00fcden grundlegend ge\u00e4ndert.\u00a0S\u00fcdkorea wird nun offiziell als &#8220;Hauptfeind&#8221; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-17T16:57:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/671111f3b480cc2a7e0ed737.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Pj\u00f6ngjang: S\u00fcdkorea offiziell als &quot;feindlicher Staat&quot; definiert\",\"datePublished\":\"2024-10-17T16:57:55+00:00\",\"dateModified\":\"2024-10-17T16:57:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/\"},\"wordCount\":285,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/Pjoengjang-Suedkorea-offiziell-als-quotfeindlicher-Staatquot-definiert.jpg\",\"keywords\":[\"als\",\"definiert\",\"Offiziell\",\"Pj\u00f6ngjang\",\"quotfeindlicher\",\"Staatquot\",\"S\u00fcdkorea\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/\",\"name\":\"Pj\u00f6ngjang: S\u00fcdkorea offiziell als &quot;feindlicher Staat&quot; definiert - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/Pjoengjang-Suedkorea-offiziell-als-quotfeindlicher-Staatquot-definiert.jpg\",\"datePublished\":\"2024-10-17T16:57:55+00:00\",\"dateModified\":\"2024-10-17T16:57:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/Pjoengjang-Suedkorea-offiziell-als-quotfeindlicher-Staatquot-definiert.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/Pjoengjang-Suedkorea-offiziell-als-quotfeindlicher-Staatquot-definiert.jpg\",\"width\":460,\"height\":259,\"caption\":\"Pj\u00f6ngjang: S\u00fcdkorea offiziell als &quot;feindlicher Staat&quot; definiert\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pj\u00f6ngjang: S\u00fcdkorea offiziell als &quot;feindlicher Staat&quot; definiert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pj\u00f6ngjang: S\u00fcdkorea offiziell als &quot;feindlicher Staat&quot; definiert - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/","og_locale":"de_DE","og_type":"article","og_title":"Pj\u00f6ngjang: S\u00fcdkorea offiziell als &quot;feindlicher Staat&quot; definiert","og_description":"Die Lage auf der koreanischen Halbinsel spitzt sich weiter zu. Pj\u00f6ngjang hat in der \u00fcberarbeiteten Verfassung S\u00fcdkorea als &#8220;feindlichen Staat&#8221; bezeichtet. Nordkorea hat s\u00e4mtliche Stra\u00dfen- und Eisenbahnverbindungen zum S\u00fcden gekappt und plant eine weitere Abgrenzung des Territoriums. Nordkorea hat seine Haltung zum Konzept\u00a0der friedlichen Wiedervereinigung mit dem S\u00fcden grundlegend ge\u00e4ndert.\u00a0S\u00fcdkorea wird nun offiziell als &#8220;Hauptfeind&#8221; [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-10-17T16:57:55+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/671111f3b480cc2a7e0ed737.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Pj\u00f6ngjang: S\u00fcdkorea offiziell als &quot;feindlicher Staat&quot; definiert","datePublished":"2024-10-17T16:57:55+00:00","dateModified":"2024-10-17T16:57:55+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/"},"wordCount":285,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/Pjoengjang-Suedkorea-offiziell-als-quotfeindlicher-Staatquot-definiert.jpg","keywords":["als","definiert","Offiziell","Pj\u00f6ngjang","quotfeindlicher","Staatquot","S\u00fcdkorea"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/","url":"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/","name":"Pj\u00f6ngjang: S\u00fcdkorea offiziell als &quot;feindlicher Staat&quot; definiert - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/Pjoengjang-Suedkorea-offiziell-als-quotfeindlicher-Staatquot-definiert.jpg","datePublished":"2024-10-17T16:57:55+00:00","dateModified":"2024-10-17T16:57:55+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/Pjoengjang-Suedkorea-offiziell-als-quotfeindlicher-Staatquot-definiert.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/Pjoengjang-Suedkorea-offiziell-als-quotfeindlicher-Staatquot-definiert.jpg","width":460,"height":259,"caption":"Pj\u00f6ngjang: S\u00fcdkorea offiziell als &quot;feindlicher Staat&quot; definiert"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/pjoengjang-suedkorea-offiziell-als-feindlicher-staat-definiert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Pj\u00f6ngjang: S\u00fcdkorea offiziell als &quot;feindlicher Staat&quot; definiert"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/70972"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=70972"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/70972\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/70973"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=70972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=70972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=70972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}