{"id":70952,"date":"2024-10-17T14:29:33","date_gmt":"2024-10-17T12:29:33","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/"},"modified":"2024-10-17T14:29:33","modified_gmt":"2024-10-17T12:29:33","slug":"ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/","title":{"rendered":"EZB senkt abermals die Zinsen \u2013 Leitzins jetzt bei 3,25 Prozent"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/breaking3.jpg\" \/><\/p>\n<div class=\"ArticleView-bottomShares\">\n<div class=\"ShareBlock-isReact\" data-rtcomponent=\"ShareBlock\" onload=\"return {\n        socials: JSON.parse('\\u005B\\u0022facebook\\u0022,\\u0022fbmessage\\u0022,\\u0022xtwitter\\u0022,\\u0022whatsapp\\u0022,\\u0022telegram\\u0022,\\u0022mailto\\u0022,\\u0022pocket\\u0022,\\u0022copylink\\u0022,\\u0022pdflink\\u0022\\u005D'),\n        direction: JSON.parse('\\u0022row\\u0022'),\n        type: JSON.parse('\\u0022hasFull\\u0022'),\n        params: JSON.parse('\\u007B\\u0022counters\\u0022\\u003Atrue,\\u0022href\\u0022\\u003A\\u0022https\\u003A\\\\\\\/\\\\\\\/de.rt.com\\\\\\\/europa\\\\\\\/222783\\u002Dezb\\u002Dsenkt\\u002Dabermals\\u002Dzinsen\\u002Dleitzins\\\\\\\/\\u0022,\\u0022shortUrl\\u0022\\u003A\\u0022https\\u003A\\\\\\\/\\\\\\\/kurz.rt.com\\\\\\\/4rwf\\u0022\\u007D'),\n    };\"><\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/222783-ezb-senkt-abermals-zinsen-leitzins\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Source link<\/p>\n","protected":false},"author":3,"featured_media":58637,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1729168859"],"wp_automatic_camp":["217"],"e49592a368bceb36d4197dbce428b36d":["EZB senkt abermals die Zinsen \u2013 Leitzins jetzt bei 3,25 Prozent"],"original_link":["https:\/\/de.rt.com\/europa\/222783-ezb-senkt-abermals-zinsen-leitzins\/"],"_thumbnail_id":["58637"],"jnews_social_counter_last_update":["1778480355"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-10-17 14:42:01\";}"]},"categories":[19,23],"tags":[58177,363,45,1082,2731,21886,1429,12210,8442],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EZB senkt abermals die Zinsen \u2013 Leitzins jetzt bei 3,25 Prozent - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EZB senkt abermals die Zinsen \u2013 Leitzins jetzt bei 3,25 Prozent\" \/>\n<meta property=\"og:description\" content=\"Source link\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-17T12:29:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/breaking3.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"EZB senkt abermals die Zinsen \u2013 Leitzins jetzt bei 3,25 Prozent\",\"datePublished\":\"2024-10-17T12:29:33+00:00\",\"dateModified\":\"2024-10-17T12:29:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/\"},\"wordCount\":12,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg\",\"keywords\":[\"abermals\",\"bei\",\"die\",\"EZB\",\"Jetzt\",\"Leitzins\",\"Prozent\",\"senkt\",\"zinsen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/\",\"name\":\"EZB senkt abermals die Zinsen \u2013 Leitzins jetzt bei 3,25 Prozent - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg\",\"datePublished\":\"2024-10-17T12:29:33+00:00\",\"dateModified\":\"2024-10-17T12:29:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg\",\"width\":460,\"height\":259,\"caption\":\"China beginnt mit Umzingelungs\u00fcbungen rund um Taiwan\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EZB senkt abermals die Zinsen \u2013 Leitzins jetzt bei 3,25 Prozent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"EZB senkt abermals die Zinsen \u2013 Leitzins jetzt bei 3,25 Prozent - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/","og_locale":"de_DE","og_type":"article","og_title":"EZB senkt abermals die Zinsen \u2013 Leitzins jetzt bei 3,25 Prozent","og_description":"Source link","og_url":"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-10-17T12:29:33+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/breaking3.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"EZB senkt abermals die Zinsen \u2013 Leitzins jetzt bei 3,25 Prozent","datePublished":"2024-10-17T12:29:33+00:00","dateModified":"2024-10-17T12:29:33+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/"},"wordCount":12,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg","keywords":["abermals","bei","die","EZB","Jetzt","Leitzins","Prozent","senkt","zinsen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/","url":"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/","name":"EZB senkt abermals die Zinsen \u2013 Leitzins jetzt bei 3,25 Prozent - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg","datePublished":"2024-10-17T12:29:33+00:00","dateModified":"2024-10-17T12:29:33+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg","width":460,"height":259,"caption":"China beginnt mit Umzingelungs\u00fcbungen rund um Taiwan"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/ezb-senkt-abermals-die-zinsen-leitzins-jetzt-bei-325-prozent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"EZB senkt abermals die Zinsen \u2013 Leitzins jetzt bei 3,25 Prozent"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/70952"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=70952"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/70952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/58637"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=70952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=70952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=70952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}