{"id":69729,"date":"2024-09-26T07:08:41","date_gmt":"2024-09-26T05:08:41","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/"},"modified":"2024-09-26T07:08:41","modified_gmt":"2024-09-26T05:08:41","slug":"gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/","title":{"rendered":"Gr\u00fcnen-Krise geht weiter: Jugend-Vorstand tritt geschlossen aus Partei aus"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/66f4ede6b480cc660379f458.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Nach der R\u00fccktrittsank\u00fcndigung der beiden Bundesvorsitzenden Ricarda Lang und Omid Nouripour erkl\u00e4rt nun auch der zehnk\u00f6pfige Vorstand der Gr\u00fcnen Jugend, nicht mehr kandidieren zu wollen. Man wolle zudem geschlossen aus der Partei austreten.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die Vorsitzenden der Gr\u00fcnen Jugend Svenja Appuhn und Katharina Stolla haben ihren R\u00fccktritt von ihren \u00c4mtern und ihren Austritt aus der Partei erkl\u00e4rt. Gemeinsam mit dem Rest des insgesamt 10-k\u00f6pfigen Vorstands wollen sie zudem aus der Partei austreten, wie der <em>Spiegel<\/em> und <em>Table Media<\/em> berichtet. Dem <em>Spiegel <\/em>wurde dies aus der gr\u00fcnen Bundestagsfraktion best\u00e4tigt. In einem Brief an die scheidenden Parteivorsitzenden Lang und Nouripour sowie die Vorsitzenden der Bundestagsfraktion Katharina Dr\u00f6ge und Britta Ha\u00dfelmann schreibt der Vorstand der Gr\u00fcnen Jugend:<\/p>\n<p><em>&#8220;Wie ihr vielleicht schon geh\u00f6rt habt, haben wir \u2013 der gesamte Bundesvorstand der Gr\u00fcnen Jugend \u2013 uns dazu entschieden, nicht erneut zu kandidieren und morgen aus der Partei auszutreten.Wir wissen, dass viele von Euch sehr \u00fcberrascht, sicherlich auch w\u00fctend oder entt\u00e4uscht von dieser Entscheidung sind.&#8221;<\/em><\/p>\n<p>Die Entscheidung, die Partei zu verlassen, sei demnach bereits vor dem R\u00fccktritt der gr\u00fcnen Bundesvorsitzenden, &#8220;in den letzten Wochen&#8221; getroffen worden. Die Vorstandsmitglieder zollen den scheidenden Vorsitzenden Lang und Nouripour Respekt f\u00fcr ihre Entscheidung, das \u00e4ndere jedoch nichts an ihrer Entscheidung, schreiben sie.<\/p>\n<p><em>&#8220;Wir gehen nicht davon aus, dass eine personelle Neuaufstellung zu einer inhaltlichen und strategischen Neuausrichtung der Partei in unserem Sinne f\u00fchren wird. Es ist besser, wenn sich unsere Wege jetzt trennen und ihr gut neu starten k\u00f6nnt.&#8221;<\/em><\/p>\n<p>Es sei dauerhaft nicht m\u00f6glich, gleichzeitig Teil einer Partei zu sein und f\u00fcr eine grunds\u00e4tzlich andere Politik zu werben, als die eigene Partei umsetzt, hei\u00dft es weiter. In den letzten Jahren h\u00e4tten sich die Konflikte zwischen der Partei und der Gr\u00fcnen Jugend immer weiter zugespitzt. Als Beispiele wurden das Sonderverm\u00f6gen f\u00fcr die Bundeswehr, Streitigkeiten um die R\u00e4umung von L\u00fctzerath sowie Versch\u00e4rfungen des Asylrechts angef\u00fchrt.<\/p>\n<p>Es brauche wieder eine &#8220;linke Kraft in Deutschland, die gerade diejenigen anspricht, die in Armut und Abstiegsangst lebten, schon lange nicht mehr w\u00e4hlen gingen oder sich den Rechten zugewandt h\u00e4tten&#8221;.<\/p>\n<blockquote>\n<p><em>&#8220;Diese Kraft wird die gr\u00fcne Partei unserer Einsch\u00e4tzung nach nicht mehr werden.&#8221;<\/em><\/p>\n<\/blockquote>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/220221-95-prozent-gruene-jetzt-einstellig\/\">9,5 Prozent: Gr\u00fcne jetzt laut Umfrage einstellig \u2013 Ampel zusammen nur noch 28,5 Prozent<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v5e2dp9\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/220487-gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach der R\u00fccktrittsank\u00fcndigung der beiden Bundesvorsitzenden Ricarda Lang und Omid Nouripour erkl\u00e4rt nun auch der zehnk\u00f6pfige Vorstand der Gr\u00fcnen Jugend, nicht mehr kandidieren zu wollen. Man wolle zudem geschlossen aus der Partei austreten. Die Vorsitzenden der Gr\u00fcnen Jugend Svenja Appuhn und Katharina Stolla haben ihren R\u00fccktritt von ihren \u00c4mtern und ihren Austritt aus der Partei [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":69730,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1727327854"],"wp_automatic_camp":["217"],"7ba107790062329d56881c73c331d04b":["Gr\u00fcnen-Krise geht weiter: Jugend-Vorstand tritt geschlossen aus Partei aus"],"original_link":["https:\/\/de.rt.com\/inland\/220487-gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/"],"_thumbnail_id":["69730"],"jnews_social_counter_last_update":["1788310562"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-09-26 07:18:38\";}"]},"categories":[19,23],"tags":[679,1673,24341,58917,58918,2504,3470,601],"class_list":["post-69729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-aus","tag-geht","tag-geschlossen","tag-gruenenkrise","tag-jugendvorstand","tag-partei","tag-tritt","tag-weiter"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gr\u00fcnen-Krise geht weiter: Jugend-Vorstand tritt geschlossen aus Partei aus - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gr\u00fcnen-Krise geht weiter: Jugend-Vorstand tritt geschlossen aus Partei aus\" \/>\n<meta property=\"og:description\" content=\"Nach der R\u00fccktrittsank\u00fcndigung der beiden Bundesvorsitzenden Ricarda Lang und Omid Nouripour erkl\u00e4rt nun auch der zehnk\u00f6pfige Vorstand der Gr\u00fcnen Jugend, nicht mehr kandidieren zu wollen. Man wolle zudem geschlossen aus der Partei austreten. Die Vorsitzenden der Gr\u00fcnen Jugend Svenja Appuhn und Katharina Stolla haben ihren R\u00fccktritt von ihren \u00c4mtern und ihren Austritt aus der Partei [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-26T05:08:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/66f4ede6b480cc660379f458.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Gr\u00fcnen-Krise geht weiter: Jugend-Vorstand tritt geschlossen aus Partei aus\",\"datePublished\":\"2024-09-26T05:08:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\\\/\"},\"wordCount\":411,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/09\\\/Gruenen-Krise-geht-weiter-Jugend-Vorstand-tritt-geschlossen-aus-Partei-aus.jpg\",\"keywords\":[\"aus\",\"Geht\",\"geschlossen\",\"Gr\u00fcnenKrise\",\"JugendVorstand\",\"Partei\",\"tritt\",\"weiter\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\\\/\",\"name\":\"Gr\u00fcnen-Krise geht weiter: Jugend-Vorstand tritt geschlossen aus Partei aus - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/09\\\/Gruenen-Krise-geht-weiter-Jugend-Vorstand-tritt-geschlossen-aus-Partei-aus.jpg\",\"datePublished\":\"2024-09-26T05:08:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/09\\\/Gruenen-Krise-geht-weiter-Jugend-Vorstand-tritt-geschlossen-aus-Partei-aus.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/09\\\/Gruenen-Krise-geht-weiter-Jugend-Vorstand-tritt-geschlossen-aus-Partei-aus.jpg\",\"width\":460,\"height\":259,\"caption\":\"Gr\u00fcnen-Krise geht weiter: Jugend-Vorstand tritt geschlossen aus Partei aus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gr\u00fcnen-Krise geht weiter: Jugend-Vorstand tritt geschlossen aus Partei aus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gr\u00fcnen-Krise geht weiter: Jugend-Vorstand tritt geschlossen aus Partei aus - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/","og_locale":"de_DE","og_type":"article","og_title":"Gr\u00fcnen-Krise geht weiter: Jugend-Vorstand tritt geschlossen aus Partei aus","og_description":"Nach der R\u00fccktrittsank\u00fcndigung der beiden Bundesvorsitzenden Ricarda Lang und Omid Nouripour erkl\u00e4rt nun auch der zehnk\u00f6pfige Vorstand der Gr\u00fcnen Jugend, nicht mehr kandidieren zu wollen. Man wolle zudem geschlossen aus der Partei austreten. Die Vorsitzenden der Gr\u00fcnen Jugend Svenja Appuhn und Katharina Stolla haben ihren R\u00fccktritt von ihren \u00c4mtern und ihren Austritt aus der Partei [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-09-26T05:08:41+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/66f4ede6b480cc660379f458.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Gr\u00fcnen-Krise geht weiter: Jugend-Vorstand tritt geschlossen aus Partei aus","datePublished":"2024-09-26T05:08:41+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/"},"wordCount":411,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Gruenen-Krise-geht-weiter-Jugend-Vorstand-tritt-geschlossen-aus-Partei-aus.jpg","keywords":["aus","Geht","geschlossen","Gr\u00fcnenKrise","JugendVorstand","Partei","tritt","weiter"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/","url":"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/","name":"Gr\u00fcnen-Krise geht weiter: Jugend-Vorstand tritt geschlossen aus Partei aus - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Gruenen-Krise-geht-weiter-Jugend-Vorstand-tritt-geschlossen-aus-Partei-aus.jpg","datePublished":"2024-09-26T05:08:41+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Gruenen-Krise-geht-weiter-Jugend-Vorstand-tritt-geschlossen-aus-Partei-aus.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Gruenen-Krise-geht-weiter-Jugend-Vorstand-tritt-geschlossen-aus-Partei-aus.jpg","width":460,"height":259,"caption":"Gr\u00fcnen-Krise geht weiter: Jugend-Vorstand tritt geschlossen aus Partei aus"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/gruenen-krise-geht-weiter-jugend-vorstand-tritt-geschlossen-aus-partei-aus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Gr\u00fcnen-Krise geht weiter: Jugend-Vorstand tritt geschlossen aus Partei aus"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/69729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=69729"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/69729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/69730"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=69729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=69729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=69729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}