{"id":69350,"date":"2024-09-20T14:24:46","date_gmt":"2024-09-20T12:24:46","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/"},"modified":"2024-09-20T14:24:46","modified_gmt":"2024-09-20T12:24:46","slug":"hisbollah-startet-massiven-raketenangriff-auf-israel","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/","title":{"rendered":"Hisbollah startet massiven Raketenangriff auf Israel"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/breaking3.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Aus Libanon wurden zahlreiche Raketen auf den Norden Israels abgefeuert. Israels Armee hatte am Donnerstag nach eigenen Angaben in mehreren Angriffswellen Stellungen der Hisbollah im Nachbarland bombardiert.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die Hisbollah hat am Freitag 140 Raketen auf den Norden Israels abgefeuert, einen Tag nachdem der Hisbollah-Chef, Hassan Nasrallah, geschworen hatte, sich an Israel f\u00fcr\u00a0Pager-Anschlag in Libanaon zu r\u00e4chen. Nach Angaben des israelischen Milit\u00e4rs wurden die Raketen am Freitagnachmittag in drei Wellen auf Orte entlang der Grenze zum Libanon abgefeuert.<\/p>\n<p>Israelischen Medien zufolge brachen durch den Beschuss Br\u00e4nde aus. Berichte \u00fcber Verletzte gab es zun\u00e4chst nicht. Anwohner in zahlreichen Orten im Norden Israels sind dazu aufgerufen, in der N\u00e4he von Schutzr\u00e4umen zu bleiben.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">Israel&#8217;s Channel 14:&#8221;Between 150 and 200 rockets were launched from Lebanon during the last hour. Hezbollah wanted to prove that after the Israeli raids yesterday, it is capable of launching rockets as much as it wants, and this is clear.&#8221; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/gr63VWUaDK\">pic.twitter.com\/gr63VWUaDK<\/a><\/p>\n<p>\u2014 The Cradle (@TheCradleMedia) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/TheCradleMedia\/status\/1837099557487780198?ref_src=twsrc%5Etfw\">September 20, 2024<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">Hebrew media reports that over 50 rockets launched by Hezbollah hit the city of Safad and its surroundings. Rockets also fell in a stadium, and a fire broke out in the area.Another fell in Kibbutz Ortal in the occupied Syrian Golan Heights. <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/9CMki7wSVj\">pic.twitter.com\/9CMki7wSVj<\/a><\/p>\n<p>\u2014 The Cradle (@TheCradleMedia) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/TheCradleMedia\/status\/1837079277004615819?ref_src=twsrc%5Etfw\">September 20, 2024<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Die libanesische Hisbollah reklamierte mehrere Angriffe f\u00fcr sich. Die proiranische Gruppe sprach in einigen F\u00e4llen von &#8220;Salven an Katjuscha-Raketen&#8221;, die sie Richtung Israel abgeschossen habe.\u00a0Die Hisbollah erkl\u00e4rte, die Raketen seien eine Vergeltung f\u00fcr israelische Angriffe auf D\u00f6rfer und H\u00e4user im S\u00fcdlibanon.<\/p>\n<p>Israels Armee hatte am Donnerstag in mehreren Angriffswellen rund 100 Raketenabschussrampen der\u00a0Hisbollah nach Eigenen Angaben\u00a0im Nachbarland bombardiert.<\/p>\n<p>Zwei Tage lang wurden Tausende von Pagern und Funkger\u00e4ten der Hisbollah in Libanon im Zuge\u00a0einer Sabotageaktion des Mossads explodiert.\u00a0Tausende Zivilsten fielen dem Anschlag zum Opfer.\u00a0Der Vorfall hat die Bef\u00fcrchtung verst\u00e4rkt, dass der seit fast einem Jahr andauernde Schusswechsel zwischen der Hisbollah und Israel zu einem totalen Krieg eskalieren k\u00f6nnte. Israel hat eine Beteiligung an den Angriffen weder best\u00e4tigt noch dementiert.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/der-nahe-osten\/219805-nach-pager-anschlag-und-nasrallah\/\">Nach Pager-Anschlag und Nasrallah-Rede: Kommt es zum hei\u00dfen Krieg?<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v5da33x\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/der-nahe-osten\/219854-hisbollah-startet-massiven-raketenangriff-auf\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aus Libanon wurden zahlreiche Raketen auf den Norden Israels abgefeuert. Israels Armee hatte am Donnerstag nach eigenen Angaben in mehreren Angriffswellen Stellungen der Hisbollah im Nachbarland bombardiert. Die Hisbollah hat am Freitag 140 Raketen auf den Norden Israels abgefeuert, einen Tag nachdem der Hisbollah-Chef, Hassan Nasrallah, geschworen hatte, sich an Israel f\u00fcr\u00a0Pager-Anschlag in Libanaon zu [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":58637,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1726835947"],"wp_automatic_camp":["217"],"b4c82d82a862d1f8b6eb45943cb0e731":["Hisbollah startet massiven Raketenangriff auf Israel"],"original_link":["https:\/\/de.rt.com\/der-nahe-osten\/219854-hisbollah-startet-massiven-raketenangriff-auf\/"],"_thumbnail_id":["58637"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-09-20 14:40:24\";}"],"jnews_social_counter_last_update":["1788338642"]},"categories":[19,23],"tags":[133,20546,432,20782,11435,1338],"class_list":["post-69350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-auf","tag-hisbollah","tag-israel","tag-massiven","tag-raketenangriff","tag-startet"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hisbollah startet massiven Raketenangriff auf Israel - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hisbollah startet massiven Raketenangriff auf Israel\" \/>\n<meta property=\"og:description\" content=\"Aus Libanon wurden zahlreiche Raketen auf den Norden Israels abgefeuert. Israels Armee hatte am Donnerstag nach eigenen Angaben in mehreren Angriffswellen Stellungen der Hisbollah im Nachbarland bombardiert. Die Hisbollah hat am Freitag 140 Raketen auf den Norden Israels abgefeuert, einen Tag nachdem der Hisbollah-Chef, Hassan Nasrallah, geschworen hatte, sich an Israel f\u00fcr\u00a0Pager-Anschlag in Libanaon zu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-20T12:24:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/breaking3.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hisbollah-startet-massiven-raketenangriff-auf-israel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hisbollah-startet-massiven-raketenangriff-auf-israel\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Hisbollah startet massiven Raketenangriff auf Israel\",\"datePublished\":\"2024-09-20T12:24:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hisbollah-startet-massiven-raketenangriff-auf-israel\\\/\"},\"wordCount\":374,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hisbollah-startet-massiven-raketenangriff-auf-israel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg\",\"keywords\":[\"AUF\",\"Hisbollah\",\"Israel\",\"massiven\",\"Raketenangriff\",\"startet\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hisbollah-startet-massiven-raketenangriff-auf-israel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hisbollah-startet-massiven-raketenangriff-auf-israel\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hisbollah-startet-massiven-raketenangriff-auf-israel\\\/\",\"name\":\"Hisbollah startet massiven Raketenangriff auf Israel - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hisbollah-startet-massiven-raketenangriff-auf-israel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hisbollah-startet-massiven-raketenangriff-auf-israel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg\",\"datePublished\":\"2024-09-20T12:24:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hisbollah-startet-massiven-raketenangriff-auf-israel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hisbollah-startet-massiven-raketenangriff-auf-israel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hisbollah-startet-massiven-raketenangriff-auf-israel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg\",\"width\":460,\"height\":259,\"caption\":\"China beginnt mit Umzingelungs\u00fcbungen rund um Taiwan\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hisbollah-startet-massiven-raketenangriff-auf-israel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hisbollah startet massiven Raketenangriff auf Israel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hisbollah startet massiven Raketenangriff auf Israel - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/","og_locale":"de_DE","og_type":"article","og_title":"Hisbollah startet massiven Raketenangriff auf Israel","og_description":"Aus Libanon wurden zahlreiche Raketen auf den Norden Israels abgefeuert. Israels Armee hatte am Donnerstag nach eigenen Angaben in mehreren Angriffswellen Stellungen der Hisbollah im Nachbarland bombardiert. Die Hisbollah hat am Freitag 140 Raketen auf den Norden Israels abgefeuert, einen Tag nachdem der Hisbollah-Chef, Hassan Nasrallah, geschworen hatte, sich an Israel f\u00fcr\u00a0Pager-Anschlag in Libanaon zu [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-09-20T12:24:46+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/breaking3.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Hisbollah startet massiven Raketenangriff auf Israel","datePublished":"2024-09-20T12:24:46+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/"},"wordCount":374,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg","keywords":["AUF","Hisbollah","Israel","massiven","Raketenangriff","startet"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/","url":"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/","name":"Hisbollah startet massiven Raketenangriff auf Israel - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg","datePublished":"2024-09-20T12:24:46+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/China-beginnt-mit-Umzingelungsuebungen-rund-um-Taiwan.jpg","width":460,"height":259,"caption":"China beginnt mit Umzingelungs\u00fcbungen rund um Taiwan"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/hisbollah-startet-massiven-raketenangriff-auf-israel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Hisbollah startet massiven Raketenangriff auf Israel"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/69350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=69350"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/69350\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/58637"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=69350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=69350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=69350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}