{"id":69280,"date":"2024-09-19T16:11:55","date_gmt":"2024-09-19T14:11:55","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/"},"modified":"2024-09-19T16:11:55","modified_gmt":"2024-09-19T14:11:55","slug":"fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/","title":{"rendered":"FBI: Iranische Hacker greifen zugunsten der Demokraten in US-Wahlkampf ein"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/66ec116b48fbef7b3251a491.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Iranische Cyber-Akteure sollen geheimes Wahlkampf-Material des republikanischen Pr\u00e4sidentschaftskandidaten Trump erbeutet und an dessen Gegner und US-Medien geschickt haben.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p data-v-755f0215=\"\" data-v-678c1b1c=\"\">US-Geheimdienste und die Bundespolizei\u00a0FBI\u00a0haben neue Erkenntnisse \u00fcber den im August bekanntgewordenen Hacker-Zugriff aus Iran auf interne Kommunikation des Wahlkampfteams des republikanischen Pr\u00e4sidentschaftskandidaten Trump publik gemacht. Wie aus einer am Mittwoch ver\u00f6ffentlichten Mitteilung der Beh\u00f6rden hervorgeht, sollen die iranischen Hacker Ende Juni und Anfang Juli\u00a0erbeutetes Material an Personen weitergeleitet haben, die mit dem Wahlkampfteam von Joe Biden \u2013 damals noch Pr\u00e4sidentschaftskandidat der Demokraten \u2013 in Verbindung standen.<\/p>\n<p>Es gebe keine Anzeichen daf\u00fcr, dass einer der Empf\u00e4nger darauf reagiert habe. Die Pr\u00e4sidentschaftskampagne von Kamala Harris bezeichnete die E-Mails aus Iran als &#8220;unerw\u00fcnschte und inakzeptable b\u00f6swillige Aktivit\u00e4ten&#8221;, die nur von einigen wenigen Personen empfangen worden seien, die sie als Spam oder Phishing-Versuche betrachtet h\u00e4tten.\u00a0Die iranischen Hacker setzten demnach ihre Bem\u00fchungen fort, gestohlenes, nicht \u00f6ffentliches Material des Trump-Teams an US-Medien zu schicken.<\/p>\n<p>Die Trump-Kampagne gab am 10. August bekannt, dass sie gehackt worden sei und dass iranische Akteure sensible interne Dokumente gestohlen und verbreitet h\u00e4tten. Mindestens drei Nachrichtenagenturen \u2013\u00a0<em>Politico<\/em>, die\u00a0<em>New York Times<\/em>\u00a0und die\u00a0<em>Washington Post<\/em>\u00a0\u2013 wurden mit vertraulichem Material aus der Trump-Kampagne versorgt. Bisher haben sich alle geweigert, Einzelheiten \u00fcber das erhaltene Material preiszugeben.<\/p>\n<p>Das FBI informierte Trumps Mitarbeiter innerhalb der letzten 48 Stunden dar\u00fcber, dass vom Iran gehackte Informationen an die Biden-Kampagne gesendet wurden, so ein hochrangiger Beamter der Kampagne, der aufgrund der sensiblen Natur der Untersuchung anonym bleiben wollte.<\/p>\n<p>Ziel solcher Aktionen sei es, Zwietracht zu s\u00e4en, das Vertrauen in den Wahlprozess zu untergraben und den Ausgang der\u00a0US-Wahlen\u00a0zu beeinflussen, hei\u00dft es in der gemeinsamen Mitteilung von FBI, ODNI (B\u00fcro des nationalen Geheimdienstes) und Cisa (Beh\u00f6rde f\u00fcr Cybersicherheit).<\/p>\n<p>Die US-Beh\u00f6rden haben in den letzten Monaten mit Strafanzeigen, Sanktionen und \u00f6ffentlichen Hinweisen auf Aktionen ausl\u00e4ndischer Gegner zur Beeinflussung der Wahl hingewiesen, darunter eine Anklage, die angeblich auf &#8220;verdeckte russische Bem\u00fchungen zur Verbreitung russlandfreundlicher Inhalte in den USA abzielt&#8221;.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/218969-schlimmer-als-russland-und-iran\/\">&#8220;Schlimmer als Russland und Iran&#8221;: Grenell wirft Baerbock Einmischung in US-Wahl vor<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v5d48o5\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/219723-fbi-iranische-hacker-greifen-zugunsten\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iranische Cyber-Akteure sollen geheimes Wahlkampf-Material des republikanischen Pr\u00e4sidentschaftskandidaten Trump erbeutet und an dessen Gegner und US-Medien geschickt haben. US-Geheimdienste und die Bundespolizei\u00a0FBI\u00a0haben neue Erkenntnisse \u00fcber den im August bekanntgewordenen Hacker-Zugriff aus Iran auf interne Kommunikation des Wahlkampfteams des republikanischen Pr\u00e4sidentschaftskandidaten Trump publik gemacht. Wie aus einer am Mittwoch ver\u00f6ffentlichten Mitteilung der Beh\u00f6rden hervorgeht, sollen die [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":69281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1726758703"],"wp_automatic_camp":["217"],"36db8af0c6d73ea766a50f42d6adc5e6":["FBI: Iranische Hacker greifen zugunsten der Demokraten in US-Wahlkampf ein"],"original_link":["https:\/\/de.rt.com\/international\/219723-fbi-iranische-hacker-greifen-zugunsten\/"],"_thumbnail_id":["69281"],"jnews_social_counter_last_update":["1784096153"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-09-19 17:12:44\";}"]},"categories":[19,23],"tags":[3383,82,357,5103,9045,24832,21348,52691,18117],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FBI: Iranische Hacker greifen zugunsten der Demokraten in US-Wahlkampf ein - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FBI: Iranische Hacker greifen zugunsten der Demokraten in US-Wahlkampf ein\" \/>\n<meta property=\"og:description\" content=\"Iranische Cyber-Akteure sollen geheimes Wahlkampf-Material des republikanischen Pr\u00e4sidentschaftskandidaten Trump erbeutet und an dessen Gegner und US-Medien geschickt haben. US-Geheimdienste und die Bundespolizei\u00a0FBI\u00a0haben neue Erkenntnisse \u00fcber den im August bekanntgewordenen Hacker-Zugriff aus Iran auf interne Kommunikation des Wahlkampfteams des republikanischen Pr\u00e4sidentschaftskandidaten Trump publik gemacht. Wie aus einer am Mittwoch ver\u00f6ffentlichten Mitteilung der Beh\u00f6rden hervorgeht, sollen die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-19T14:11:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/66ec116b48fbef7b3251a491.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"FBI: Iranische Hacker greifen zugunsten der Demokraten in US-Wahlkampf ein\",\"datePublished\":\"2024-09-19T14:11:55+00:00\",\"dateModified\":\"2024-09-19T14:11:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/\"},\"wordCount\":368,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/FBI-Iranische-Hacker-greifen-zugunsten-der-Demokraten-in-US-Wahlkampf-ein.jpg\",\"keywords\":[\"Demokraten\",\"der\",\"ein\",\"fbi\",\"greifen\",\"Hacker\",\"Iranische\",\"USWahlkampf\",\"zugunsten\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/\",\"name\":\"FBI: Iranische Hacker greifen zugunsten der Demokraten in US-Wahlkampf ein - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/FBI-Iranische-Hacker-greifen-zugunsten-der-Demokraten-in-US-Wahlkampf-ein.jpg\",\"datePublished\":\"2024-09-19T14:11:55+00:00\",\"dateModified\":\"2024-09-19T14:11:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/FBI-Iranische-Hacker-greifen-zugunsten-der-Demokraten-in-US-Wahlkampf-ein.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/FBI-Iranische-Hacker-greifen-zugunsten-der-Demokraten-in-US-Wahlkampf-ein.jpg\",\"width\":460,\"height\":259,\"caption\":\"FBI: Iranische Hacker greifen zugunsten der Demokraten in US-Wahlkampf ein\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FBI: Iranische Hacker greifen zugunsten der Demokraten in US-Wahlkampf ein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FBI: Iranische Hacker greifen zugunsten der Demokraten in US-Wahlkampf ein - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/","og_locale":"de_DE","og_type":"article","og_title":"FBI: Iranische Hacker greifen zugunsten der Demokraten in US-Wahlkampf ein","og_description":"Iranische Cyber-Akteure sollen geheimes Wahlkampf-Material des republikanischen Pr\u00e4sidentschaftskandidaten Trump erbeutet und an dessen Gegner und US-Medien geschickt haben. US-Geheimdienste und die Bundespolizei\u00a0FBI\u00a0haben neue Erkenntnisse \u00fcber den im August bekanntgewordenen Hacker-Zugriff aus Iran auf interne Kommunikation des Wahlkampfteams des republikanischen Pr\u00e4sidentschaftskandidaten Trump publik gemacht. Wie aus einer am Mittwoch ver\u00f6ffentlichten Mitteilung der Beh\u00f6rden hervorgeht, sollen die [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-09-19T14:11:55+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/66ec116b48fbef7b3251a491.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"FBI: Iranische Hacker greifen zugunsten der Demokraten in US-Wahlkampf ein","datePublished":"2024-09-19T14:11:55+00:00","dateModified":"2024-09-19T14:11:55+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/"},"wordCount":368,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/FBI-Iranische-Hacker-greifen-zugunsten-der-Demokraten-in-US-Wahlkampf-ein.jpg","keywords":["Demokraten","der","ein","fbi","greifen","Hacker","Iranische","USWahlkampf","zugunsten"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/","url":"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/","name":"FBI: Iranische Hacker greifen zugunsten der Demokraten in US-Wahlkampf ein - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/FBI-Iranische-Hacker-greifen-zugunsten-der-Demokraten-in-US-Wahlkampf-ein.jpg","datePublished":"2024-09-19T14:11:55+00:00","dateModified":"2024-09-19T14:11:55+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/FBI-Iranische-Hacker-greifen-zugunsten-der-Demokraten-in-US-Wahlkampf-ein.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/FBI-Iranische-Hacker-greifen-zugunsten-der-Demokraten-in-US-Wahlkampf-ein.jpg","width":460,"height":259,"caption":"FBI: Iranische Hacker greifen zugunsten der Demokraten in US-Wahlkampf ein"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/fbi-iranische-hacker-greifen-zugunsten-der-demokraten-in-us-wahlkampf-ein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"FBI: Iranische Hacker greifen zugunsten der Demokraten in US-Wahlkampf ein"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/69280"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=69280"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/69280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/69281"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=69280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=69280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=69280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}