{"id":68317,"date":"2024-09-05T20:12:26","date_gmt":"2024-09-05T18:12:26","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/"},"modified":"2024-09-05T20:12:26","modified_gmt":"2024-09-05T18:12:26","slug":"kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/","title":{"rendered":"Kanzlergespr\u00e4ch: Scholz meint, Zuwanderung h\u00e4tte nichts mit Wohnungsmangel zu tun"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/66d9c8e348fbef5e063539d4.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Das sagte er beim Kanzlergespr\u00e4ch in Berlin. Und auch auf X. Aber das Publikum ist nicht wirklich seiner Meinung, sondern emp\u00f6rt sich vielstimmig. Scholz selbst hat eine Wohnung im Kanzleramt und damit keine Schwierigkeiten auf dem Wohnungsmarkt.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>&#8220;Die gro\u00dfen Herausforderungen auf dem Wohnungsmarkt haben nichts zu tun mit den Zuwanderungsbewegungen f\u00fcr Fl\u00fcchtlinge&#8221;, erkl\u00e4rte Bundeskanzler Olaf Scholz am Mittwoch im Kanzlergespr\u00e4ch. Die gleiche Behauptung lie\u00df er dann auch auf X posten \u2013 und erntete einen Shitstorm.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">Zuwanderung ist nicht der Grund f\u00fcr unsere Probleme auf dem Wohnungsmarkt &#8211; eine meiner Antworten beim KanzlerGESPR\u00c4CH in Berlin. Wir m\u00fcssen bauen: Ohne zus\u00e4tzliche Wohnungen gibt es keine Entlastung auf dem Markt. Danke f\u00fcr diese und die vielen weiteren Fragen! <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/bu3fBX1tYu\">pic.twitter.com\/bu3fBX1tYu<\/a><\/p>\n<p>\u2014 Bundeskanzler Olaf Scholz (@Bundeskanzler) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/Bundeskanzler\/status\/1831407018458149344?ref_src=twsrc%5Etfw\">September 4, 2024<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Eine ganze Reihe der Kommentatoren m\u00fchten sich, dem Bundeskanzler die Zusammenh\u00e4nge zu erkl\u00e4ren. &#8220;Viele Autos sind nicht der Grund f\u00fcr den Stau&#8221; hei\u00dft es da beispielsweise, oder &#8220;Fritz hat 11 Autos und 10 Garagen, Timo hat 15 Autos und 10 Garagen. Wer hat die gr\u00f6\u00dferen Probleme?&#8221;<\/p>\n<p>Die Hilfsbereitschaft reichte bis zu statistischen Daten:<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">Zuwanderung ist nicht der Grund f\u00fcr unsere Probleme auf dem Wohnungsmarkt. Nat\u00fcrlich nicht. Danken sie mir sp\u00e4ter. <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/ijkr45LphG\">pic.twitter.com\/ijkr45LphG<\/a><\/p>\n<p>\u2014 Morlock Nr.2 (@MGGA2021h) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/MGGA2021h\/status\/1831418557214945460?ref_src=twsrc%5Etfw\">September 4, 2024<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">Halten Sie uns eigentlich f\u00fcr bescheuert?Eine Studie des IW K\u00f6ln zeigt, dass die Zuwanderung 2016-2020 einen zus\u00e4tzlichen Wohnungsbedarf von 340k bis 480k Einheiten verursacht hat. Die Folge: Immobilienpreise in \ud83c\udde9\ud83c\uddea sind im Vergleich zum europ\u00e4ischen Ausland erheblich gestiegen.<\/p>\n<p>\u2014 Unbequemer Faktencheck (@Faktencheck_) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/Faktencheck_\/status\/1831581887854240200?ref_src=twsrc%5Etfw\">September 5, 2024<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Andere Nutzer reagierten unfreundlich bis komisch. &#8220;Halten Sie ihre W\u00e4hler f\u00fcr so dumm?&#8221; oder &#8220;Geht es Ihnen gut? Glas Wasser? Wollen Sie sich hinsetzen?&#8221; &#8220;War Lack wieder im Sonderangebot?&#8221; &#8220;Wenn es regnet, dann wird es drau\u00dfen nass.&#8221; Manche griffen auch zu praktischen Vorschl\u00e4gen: &#8220;Vielleicht einfach mal weniger twittern und mehr arbeiten&#8221;, oder:<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">Wenn die rund 1 Million Abgelehnten das Land verlassen w\u00fcrden, erg\u00e4be das eine Entspannung auf dem Wohnungsmarkt. Echte Sozialdemokraten, wie in D\u00e4nemark haben das erkannt. Sprechen Sie mit den Genossen!<\/p>\n<p>\u2014 Critical Cat | (@Critical__Cat) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/Critical__Cat\/status\/1831413083652419730?ref_src=twsrc%5Etfw\">September 4, 2024<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Erstaunlicherweise hatte er f\u00fcr seine Aussage am Mittwoch sogar Beifall bekommen. Aber bei diesen Veranstaltungen findet schlie\u00dflich eine Vorauswahl statt. Auf X jedoch fand sich keine einzige zustimmende Reaktion. F\u00fcr die Bundestagswahl 2025 hat der Kanzler, der \u00fcber die Wahlergebnisse der AfD &#8220;bedr\u00fcckt&#8221; ist, damit keinen Stich gemacht.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/meinung\/217111-deutschland-im-nichtstun-modus-oder\/\">Deutschland im Nichtstun-Modus: Vieles wird &#8220;auf den Weg gebracht&#8221; \u2013 und dort bleibt es <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2FWagenknecht--Viele-L%C3%A4nder-haben-die-unkontrollierte-Migration-gestoppt-%E2%80%93-nur-wir-nicht%3Af\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/218220-scholz-meint-zuwanderung-haette-nichts\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das sagte er beim Kanzlergespr\u00e4ch in Berlin. Und auch auf X. Aber das Publikum ist nicht wirklich seiner Meinung, sondern emp\u00f6rt sich vielstimmig. Scholz selbst hat eine Wohnung im Kanzleramt und damit keine Schwierigkeiten auf dem Wohnungsmarkt. &#8220;Die gro\u00dfen Herausforderungen auf dem Wohnungsmarkt haben nichts zu tun mit den Zuwanderungsbewegungen f\u00fcr Fl\u00fcchtlinge&#8221;, erkl\u00e4rte Bundeskanzler Olaf [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":68319,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1725560202"],"_wptgpro_p2tg_delay_for_override":["a:1:{i:23737;d:0.5;}"],"_wptgpro_p2tg_instances":["a:1:{i:23737;a:26:{s:6:\"active\";b:1;s:3:\"bot\";s:0:\"\";s:8:\"channels\";a:1:{i:0;s:13:\"@justnow_news\";}s:8:\"use_when\";a:1:{i:0;s:3:\"new\";}s:10:\"post_types\";a:1:{i:0;s:4:\"post\";}s:5:\"rules\";a:1:{i:0;a:1:{i:0;a:3:{s:5:\"param\";s:11:\"post_author\";s:6:\"values\";a:2:{i:0;a:2:{s:5:\"value\";s:1:\"3\";s:5:\"label\";s:5:\"rnews\";}i:1;a:2:{s:5:\"value\";s:1:\"1\";s:5:\"label\";s:5:\"admin\";}}s:8:\"operator\";s:2:\"in\";}}}s:16:\"message_template\";s:131:\"\"**{post_title}**\\n\\n{post_excerpt}\\n\\nRead: {full_url}\\n======\\n24h News Ticker - JUST-NOW News \\n\\u27a1\\ufe0f t.me\\\/justnow_news\"\";s:14:\"excerpt_length\";i:25;s:20:\"excerpt_preserve_eol\";b:1;s:14:\"excerpt_source\";s:12:\"post_content\";s:19:\"send_featured_image\";b:0;s:14:\"image_position\";s:6:\"before\";s:14:\"single_message\";b:1;s:12:\"cats_as_tags\";b:0;s:10:\"parse_mode\";s:4:\"none\";s:24:\"disable_web_page_preview\";b:0;s:16:\"additional_media\";a:0:{}s:15:\"send_wc_gallery\";b:0;s:18:\"wc_gallery_caption\";s:0:\"\";s:19:\"send_content_images\";b:0;s:22:\"content_images_caption\";s:0:\"\";s:15:\"inline_keyboard\";a:0:{}s:5:\"delay\";i:0;s:20:\"disable_notification\";b:0;s:15:\"protect_content\";b:0;s:2:\"id\";i:23737;}}"],"wp_automatic_camp":["217"],"02de2acd994c3378ffb2ed8e4ccf5881":["Kanzlergespr\u00e4ch: Scholz meint, Zuwanderung h\u00e4tte nichts mit Wohnungsmangel zu tun"],"original_link":["https:\/\/de.rt.com\/inland\/218220-scholz-meint-zuwanderung-haette-nichts\/"],"_thumbnail_id":["68319"],"jnews_social_counter_last_update":["1788266868"]},"categories":[19,23],"tags":[5373,50367,43894,419,3095,1001,1042,58275,32264],"class_list":["post-68317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-haette","tag-kanzlergespraech","tag-meint","tag-mit","tag-nichts","tag-scholz","tag-tun","tag-wohnungsmangel","tag-zuwanderung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kanzlergespr\u00e4ch: Scholz meint, Zuwanderung h\u00e4tte nichts mit Wohnungsmangel zu tun - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kanzlergespr\u00e4ch: Scholz meint, Zuwanderung h\u00e4tte nichts mit Wohnungsmangel zu tun\" \/>\n<meta property=\"og:description\" content=\"Das sagte er beim Kanzlergespr\u00e4ch in Berlin. Und auch auf X. Aber das Publikum ist nicht wirklich seiner Meinung, sondern emp\u00f6rt sich vielstimmig. Scholz selbst hat eine Wohnung im Kanzleramt und damit keine Schwierigkeiten auf dem Wohnungsmarkt. &#8220;Die gro\u00dfen Herausforderungen auf dem Wohnungsmarkt haben nichts zu tun mit den Zuwanderungsbewegungen f\u00fcr Fl\u00fcchtlinge&#8221;, erkl\u00e4rte Bundeskanzler Olaf [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-05T18:12:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/66d9c8e348fbef5e063539d4.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Kanzlergespr\u00e4ch: Scholz meint, Zuwanderung h\u00e4tte nichts mit Wohnungsmangel zu tun\",\"datePublished\":\"2024-09-05T18:12:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\\\/\"},\"wordCount\":444,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/09\\\/Kanzlergespraech-Scholz-meint-Zuwanderung-haette-nichts-mit-Wohnungsmangel-zu-tun.jpg\",\"keywords\":[\"h\u00e4tte\",\"Kanzlergespr\u00e4ch\",\"meint\",\"mit\",\"Nichts\",\"Scholz\",\"tun\",\"Wohnungsmangel\",\"Zuwanderung\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\\\/\",\"name\":\"Kanzlergespr\u00e4ch: Scholz meint, Zuwanderung h\u00e4tte nichts mit Wohnungsmangel zu tun - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/09\\\/Kanzlergespraech-Scholz-meint-Zuwanderung-haette-nichts-mit-Wohnungsmangel-zu-tun.jpg\",\"datePublished\":\"2024-09-05T18:12:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/09\\\/Kanzlergespraech-Scholz-meint-Zuwanderung-haette-nichts-mit-Wohnungsmangel-zu-tun.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/09\\\/Kanzlergespraech-Scholz-meint-Zuwanderung-haette-nichts-mit-Wohnungsmangel-zu-tun.jpg\",\"width\":460,\"height\":259,\"caption\":\"Kanzlergespr\u00e4ch: Scholz meint, Zuwanderung h\u00e4tte nichts mit Wohnungsmangel zu tun\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kanzlergespr\u00e4ch: Scholz meint, Zuwanderung h\u00e4tte nichts mit Wohnungsmangel zu tun\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kanzlergespr\u00e4ch: Scholz meint, Zuwanderung h\u00e4tte nichts mit Wohnungsmangel zu tun - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/","og_locale":"de_DE","og_type":"article","og_title":"Kanzlergespr\u00e4ch: Scholz meint, Zuwanderung h\u00e4tte nichts mit Wohnungsmangel zu tun","og_description":"Das sagte er beim Kanzlergespr\u00e4ch in Berlin. Und auch auf X. Aber das Publikum ist nicht wirklich seiner Meinung, sondern emp\u00f6rt sich vielstimmig. Scholz selbst hat eine Wohnung im Kanzleramt und damit keine Schwierigkeiten auf dem Wohnungsmarkt. &#8220;Die gro\u00dfen Herausforderungen auf dem Wohnungsmarkt haben nichts zu tun mit den Zuwanderungsbewegungen f\u00fcr Fl\u00fcchtlinge&#8221;, erkl\u00e4rte Bundeskanzler Olaf [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-09-05T18:12:26+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/66d9c8e348fbef5e063539d4.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Kanzlergespr\u00e4ch: Scholz meint, Zuwanderung h\u00e4tte nichts mit Wohnungsmangel zu tun","datePublished":"2024-09-05T18:12:26+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/"},"wordCount":444,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Kanzlergespraech-Scholz-meint-Zuwanderung-haette-nichts-mit-Wohnungsmangel-zu-tun.jpg","keywords":["h\u00e4tte","Kanzlergespr\u00e4ch","meint","mit","Nichts","Scholz","tun","Wohnungsmangel","Zuwanderung"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/","url":"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/","name":"Kanzlergespr\u00e4ch: Scholz meint, Zuwanderung h\u00e4tte nichts mit Wohnungsmangel zu tun - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Kanzlergespraech-Scholz-meint-Zuwanderung-haette-nichts-mit-Wohnungsmangel-zu-tun.jpg","datePublished":"2024-09-05T18:12:26+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Kanzlergespraech-Scholz-meint-Zuwanderung-haette-nichts-mit-Wohnungsmangel-zu-tun.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Kanzlergespraech-Scholz-meint-Zuwanderung-haette-nichts-mit-Wohnungsmangel-zu-tun.jpg","width":460,"height":259,"caption":"Kanzlergespr\u00e4ch: Scholz meint, Zuwanderung h\u00e4tte nichts mit Wohnungsmangel zu tun"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/kanzlergespraech-scholz-meint-zuwanderung-haette-nichts-mit-wohnungsmangel-zu-tun-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Kanzlergespr\u00e4ch: Scholz meint, Zuwanderung h\u00e4tte nichts mit Wohnungsmangel zu tun"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/68317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=68317"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/68317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/68319"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=68317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=68317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=68317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}