{"id":68104,"date":"2024-09-03T13:04:01","date_gmt":"2024-09-03T11:04:01","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/"},"modified":"2024-09-03T13:04:01","modified_gmt":"2024-09-03T11:04:01","slug":"bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/","title":{"rendered":"Bericht: Wladimir Putin schenkt Kim Jong-un 24 Pferde"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/66d6d56a48fbef299b7d2f00.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Wie The Times berichtet, hat der nordkoreanische Staatschef Kim Jong-un vergangene Woche 24 Pferde seiner Lieblingsrasse der Orlow-Traber aus Russland erhalten. Bei dem Geschenk handelt es sich angeblich um eine Teilzahlung an Pj\u00f6ngjang f\u00fcr Artilleriegranaten.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Wie <em>The Times<\/em> berichtet,\u00a0hat Russland 24 Pferde der Rasse Orlow-Traber, angeblich die Lieblingsrasse von Kim Jong-un, als Geschenk nach Nordkorea geschickt. Der nordkoreanische Staatschef wird regelm\u00e4\u00dfig hoch zu Ross auf diesen Pferden fotografiert.<\/p>\n<p>Die 19 Hengste und f\u00fcnf Stuten wurden in der Region Wladimir unter Quarant\u00e4ne gestellt, bevor sie nach Osten in die Region Primorje transportiert wurden, teilte die russische Beh\u00f6rde f\u00fcr Veterin\u00e4r- und Pflanzenschutzkontrolle Rosselchosnadsor mit. Demnach wurden am Eisenbahnkontrollpunkt Chasan die Pferde auf alle notwendigen Dokumente und Chips \u00fcberpr\u00fcft und am 25. August nach Nordkorea transportiert.<\/p>\n<p>Medienberichten zufolge handelt es sich bei der Lieferung der Tiere um eine Teilzahlung f\u00fcr die Lieferung nordkoreanischer Artilleriegranaten an Moskau.\u00a0Die Zusammenarbeit zwischen den beiden L\u00e4ndern erhielt nach\u00a0Kims\u00a0Besuch in Russland im September 2023 neue Impulse. Im Juni besuchte Putin erstmals seit 24 Jahren Nordkorea. Bei diesem Treffen unterzeichneten die beiden Staatschefs einen Verteidigungspakt, in dem sich die L\u00e4nder verpflichten, sich im Falle eines Angriffs gegenseitig zu sch\u00fctzen.<\/p>\n<p>Bereits vor zwei Jahren hatte Russland 30 Orlow-Traber\u00a0an Kim \u00fcbergeben.\u00a0&#8220;Es ist bekannt, dass Kim Jong-un und sein Gefolge sehr gerne reiten&#8221;, erkl\u00e4rte Andrei Lankow, Historiker und Professor an der Kunming-Universit\u00e4t in Seoul, damals gegen\u00fcber dem Nachrichtenportal <em>RBK<\/em>.\u00a0&#8220;Orlow-Traber sind ein fester Bestandteil des Lebens der Herrscherfamilie und ihres inneren Kreises. Eine gewisse Rolle spielt dabei die Tatsache, dass sie im Westen ausgebildet wurden, wo der Pferdesport fest mit dem Leben der privilegierten Klasse verbunden ist&#8221;, sagte der Professor.<\/p>\n<p>Der Orlow-Traber ist eine russische Pferderasse, die im 18. und 19. Jahrhundert im Gebiet\u00a0Woronesch unter der Leitung des Grafen Alexei Orlow gez\u00fcchtet wurde.\u00a0<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/212013-europaeischer-gerichtshof-bestaetigt-verbot-von-wolfsjagd-in-oesterreich\/\">Europ\u00e4ischer Gerichtshof best\u00e4tigt Verbot von Wolfsjagd in \u00d6sterreich<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/217850-bericht-wladimir-putin-schenkt-kim\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie The Times berichtet, hat der nordkoreanische Staatschef Kim Jong-un vergangene Woche 24 Pferde seiner Lieblingsrasse der Orlow-Traber aus Russland erhalten. Bei dem Geschenk handelt es sich angeblich um eine Teilzahlung an Pj\u00f6ngjang f\u00fcr Artilleriegranaten. Wie The Times berichtet,\u00a0hat Russland 24 Pferde der Rasse Orlow-Traber, angeblich die Lieblingsrasse von Kim Jong-un, als Geschenk nach Nordkorea [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":68105,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1725362324"],"wp_automatic_camp":["217"],"7ee34abbdfd95aa5368c807ac77fb1f7":["Bericht: Wladimir Putin schenkt Kim Jong-un 24 Pferde"],"original_link":["https:\/\/de.rt.com\/international\/217850-bericht-wladimir-putin-schenkt-kim\/"],"_thumbnail_id":["68105"],"jnews_social_counter_last_update":["1784116863"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-09-03 13:19:56\";}"]},"categories":[19,23],"tags":[667,29532,349,58172,125,44010,6987],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bericht: Wladimir Putin schenkt Kim Jong-un 24 Pferde - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bericht: Wladimir Putin schenkt Kim Jong-un 24 Pferde\" \/>\n<meta property=\"og:description\" content=\"Wie The Times berichtet, hat der nordkoreanische Staatschef Kim Jong-un vergangene Woche 24 Pferde seiner Lieblingsrasse der Orlow-Traber aus Russland erhalten. Bei dem Geschenk handelt es sich angeblich um eine Teilzahlung an Pj\u00f6ngjang f\u00fcr Artilleriegranaten. Wie The Times berichtet,\u00a0hat Russland 24 Pferde der Rasse Orlow-Traber, angeblich die Lieblingsrasse von Kim Jong-un, als Geschenk nach Nordkorea [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-03T11:04:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/66d6d56a48fbef299b7d2f00.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Bericht: Wladimir Putin schenkt Kim Jong-un 24 Pferde\",\"datePublished\":\"2024-09-03T11:04:01+00:00\",\"dateModified\":\"2024-09-03T11:04:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/\"},\"wordCount\":329,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Bericht-Wladimir-Putin-schenkt-Kim-Jong-un-24-Pferde.jpg\",\"keywords\":[\"Bericht\",\"Jongun\",\"Kim\",\"Pferde\",\"putin\",\"schenkt\",\"Wladimir\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/\",\"name\":\"Bericht: Wladimir Putin schenkt Kim Jong-un 24 Pferde - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Bericht-Wladimir-Putin-schenkt-Kim-Jong-un-24-Pferde.jpg\",\"datePublished\":\"2024-09-03T11:04:01+00:00\",\"dateModified\":\"2024-09-03T11:04:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Bericht-Wladimir-Putin-schenkt-Kim-Jong-un-24-Pferde.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Bericht-Wladimir-Putin-schenkt-Kim-Jong-un-24-Pferde.jpg\",\"width\":460,\"height\":259,\"caption\":\"Bericht: Wladimir Putin schenkt Kim Jong-un 24 Pferde\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bericht: Wladimir Putin schenkt Kim Jong-un 24 Pferde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bericht: Wladimir Putin schenkt Kim Jong-un 24 Pferde - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/","og_locale":"de_DE","og_type":"article","og_title":"Bericht: Wladimir Putin schenkt Kim Jong-un 24 Pferde","og_description":"Wie The Times berichtet, hat der nordkoreanische Staatschef Kim Jong-un vergangene Woche 24 Pferde seiner Lieblingsrasse der Orlow-Traber aus Russland erhalten. Bei dem Geschenk handelt es sich angeblich um eine Teilzahlung an Pj\u00f6ngjang f\u00fcr Artilleriegranaten. Wie The Times berichtet,\u00a0hat Russland 24 Pferde der Rasse Orlow-Traber, angeblich die Lieblingsrasse von Kim Jong-un, als Geschenk nach Nordkorea [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-09-03T11:04:01+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/66d6d56a48fbef299b7d2f00.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Bericht: Wladimir Putin schenkt Kim Jong-un 24 Pferde","datePublished":"2024-09-03T11:04:01+00:00","dateModified":"2024-09-03T11:04:01+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/"},"wordCount":329,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Bericht-Wladimir-Putin-schenkt-Kim-Jong-un-24-Pferde.jpg","keywords":["Bericht","Jongun","Kim","Pferde","putin","schenkt","Wladimir"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/","url":"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/","name":"Bericht: Wladimir Putin schenkt Kim Jong-un 24 Pferde - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Bericht-Wladimir-Putin-schenkt-Kim-Jong-un-24-Pferde.jpg","datePublished":"2024-09-03T11:04:01+00:00","dateModified":"2024-09-03T11:04:01+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Bericht-Wladimir-Putin-schenkt-Kim-Jong-un-24-Pferde.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/09\/Bericht-Wladimir-Putin-schenkt-Kim-Jong-un-24-Pferde.jpg","width":460,"height":259,"caption":"Bericht: Wladimir Putin schenkt Kim Jong-un 24 Pferde"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-wladimir-putin-schenkt-kim-jong-un-24-pferde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Bericht: Wladimir Putin schenkt Kim Jong-un 24 Pferde"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/68104"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=68104"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/68104\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/68105"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=68104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=68104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=68104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}