{"id":67895,"date":"2024-08-30T21:30:27","date_gmt":"2024-08-30T19:30:27","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/"},"modified":"2024-08-30T21:30:27","modified_gmt":"2024-08-30T19:30:27","slug":"nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/","title":{"rendered":"Nach Verlust einer F-16: Selenskij entl\u00e4sst Chef der ukrainischen Luftwaffe"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/66d21951b480cc6d2e3a163b.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der ukrainische Machthaber Wladimir Selenskij hat am Freitag seinen Luftwaffenchef gefeuert. Grund daf\u00fcr ist offensichtlich der Verlust einer F-16 unter ungekl\u00e4rten Umst\u00e4nden vor einigen Tagen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Wladimir Selenskij, der Machthaber in Kiew, dessen regul\u00e4re Amtszeit als ukrainischer Pr\u00e4sident im Mai dieses Jahres abgelaufen ist, hat am Freitag den Kommandeur der ukrainischen Luftstreitkr\u00e4fte, Nikolai Oleschtschuk, mit sofortiger Wirkung entlassen. Das geht aus einem auf der Website des Chefs des Kiewer Regimes ver\u00f6ffentlichten Erlass hervor.<\/p>\n<p>Sp\u00e4ter teilte der ukrainische Generalstab mit, dass Oberbefehlshaber Alexander Syrski einen Erlass zur Ernennung von Generalleutnant Anatoli Kriwonoschko zum kommissarischen Befehlshaber der Luftstreitkr\u00e4fte des Landes erlassen habe. Kriwonoschko war zuletzt Kommandeur des Luftkommandos Zentrum der Luftwaffe der Ukraine.<\/p>\n<p>Das <em>Wall Street Journal<\/em> hatte in einem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/217348-wall-street-journal-bestaetigt-ukraine-verliert-erste-f-16\/\">Artikel vom Donnerstag<\/a> Quellen zitiert, wonach einer der an die Ukraine \u00fcbergebenen F-16-Kampfjets am 23. August abgest\u00fcrzt sei. Dies wurde sp\u00e4ter auch vom ukrainischen Generalstab best\u00e4tigt. \u00dcberdies wurde mitgeteilt, wonach eine Sonderkommission des ukrainischen Verteidigungsministeriums, die in dem Absturzgebiet arbeitet, die Ursachen des &#8220;Unfalls&#8221; untersucht. Das Pentagon hat sich jedoch geweigert, den Vorfall zu best\u00e4tigen.<\/p>\n<p>Sp\u00e4ter am selben Tag erkl\u00e4rte die Abgeordnete der Werchowna Rada, Marjana Besuglaja, unter Berufung auf ihre eigenen Erkenntnisse, dass das US-Flugzeug von einem ukrainischen Patriot-Boden-Luft-Raketensystem abgeschossen worden sei, und zwar aufgrund einer fehlenden Abstimmung zwischen Einheiten des ukrainischen Milit\u00e4rs.<\/p>\n<p>Kenner der politischen &#8220;K\u00fcche&#8221; in Kiew mutma\u00dfen, dass der Rausschmiss des Luftwaffenchefs mit dem beschriebenen Verlust des Kampfflugzeugs zu tun hat. Selenskij soll dar\u00fcber sehr erbost gewesen sein und regelrecht getobt haben, ist auf ukrainischen Telegram-Kan\u00e4len zu lesen, die sich auf Insider berufen.<\/p>\n<p>Anfang August hatte Selenskij verk\u00fcndet, dass die ersten F-16 in der Ukraine eingetroffen seien. Einen Tag zuvor schrieb der <em>Economist<\/em>, die ukrainischen Streitkr\u00e4fte h\u00e4tten die ersten zehn der 79 US-Kampfjets erhalten. Die Kampfflugzeuge werden von Selenskij als eine Art &#8220;Wunderwaffe&#8221; dargestellt, die die Wende im Krieg gegen Russland bringen soll. Milit\u00e4rexperten bezweifeln dies nahezu einhellig.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/217177-einsatz-westlicher-waffen-in-russland\/\">Einsatz westlicher Waffen in Russland durch Kiew \u2013 Westen ist sich uneinig<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/217477-nach-verlust-f-16-selenskij\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der ukrainische Machthaber Wladimir Selenskij hat am Freitag seinen Luftwaffenchef gefeuert. Grund daf\u00fcr ist offensichtlich der Verlust einer F-16 unter ungekl\u00e4rten Umst\u00e4nden vor einigen Tagen. Wladimir Selenskij, der Machthaber in Kiew, dessen regul\u00e4re Amtszeit als ukrainischer Pr\u00e4sident im Mai dieses Jahres abgelaufen ist, hat am Freitag den Kommandeur der ukrainischen Luftstreitkr\u00e4fte, Nikolai Oleschtschuk, mit sofortiger [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":67896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1725046793"],"wp_automatic_camp":["217"],"7f67294a4fa99fe24b6f87d325f461cb":["Nach Verlust einer F-16: Selenskij entl\u00e4sst Chef der ukrainischen Luftwaffe"],"original_link":["https:\/\/de.rt.com\/international\/217477-nach-verlust-f-16-selenskij\/"],"_thumbnail_id":["67896"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-08-30 21:41:56\";}"],"jnews_social_counter_last_update":["1788384552"]},"categories":[19,23],"tags":[18111,82,212,22666,26456,571,979,6158,2332,1372],"class_list":["post-67895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-chef","tag-der","tag-einer","tag-entlaesst","tag-f16","tag-luftwaffe","tag-nach","tag-selenskij","tag-ukrainischen","tag-verlust"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nach Verlust einer F-16: Selenskij entl\u00e4sst Chef der ukrainischen Luftwaffe - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nach Verlust einer F-16: Selenskij entl\u00e4sst Chef der ukrainischen Luftwaffe\" \/>\n<meta property=\"og:description\" content=\"Der ukrainische Machthaber Wladimir Selenskij hat am Freitag seinen Luftwaffenchef gefeuert. Grund daf\u00fcr ist offensichtlich der Verlust einer F-16 unter ungekl\u00e4rten Umst\u00e4nden vor einigen Tagen. Wladimir Selenskij, der Machthaber in Kiew, dessen regul\u00e4re Amtszeit als ukrainischer Pr\u00e4sident im Mai dieses Jahres abgelaufen ist, hat am Freitag den Kommandeur der ukrainischen Luftstreitkr\u00e4fte, Nikolai Oleschtschuk, mit sofortiger [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-30T19:30:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/66d21951b480cc6d2e3a163b.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Nach Verlust einer F-16: Selenskij entl\u00e4sst Chef der ukrainischen Luftwaffe\",\"datePublished\":\"2024-08-30T19:30:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\\\/\"},\"wordCount\":361,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/Nach-Verlust-einer-F-16-Selenskij-entlaesst-Chef-der-ukrainischen-Luftwaffe.jpg\",\"keywords\":[\"Chef\",\"der\",\"einer\",\"entl\u00e4sst\",\"F16\",\"Luftwaffe\",\"nach\",\"Selenskij\",\"ukrainischen\",\"Verlust\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\\\/\",\"name\":\"Nach Verlust einer F-16: Selenskij entl\u00e4sst Chef der ukrainischen Luftwaffe - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/Nach-Verlust-einer-F-16-Selenskij-entlaesst-Chef-der-ukrainischen-Luftwaffe.jpg\",\"datePublished\":\"2024-08-30T19:30:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/Nach-Verlust-einer-F-16-Selenskij-entlaesst-Chef-der-ukrainischen-Luftwaffe.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/Nach-Verlust-einer-F-16-Selenskij-entlaesst-Chef-der-ukrainischen-Luftwaffe.jpg\",\"width\":460,\"height\":259,\"caption\":\"Nach Verlust einer F-16: Selenskij entl\u00e4sst Chef der ukrainischen Luftwaffe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nach Verlust einer F-16: Selenskij entl\u00e4sst Chef der ukrainischen Luftwaffe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nach Verlust einer F-16: Selenskij entl\u00e4sst Chef der ukrainischen Luftwaffe - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/","og_locale":"de_DE","og_type":"article","og_title":"Nach Verlust einer F-16: Selenskij entl\u00e4sst Chef der ukrainischen Luftwaffe","og_description":"Der ukrainische Machthaber Wladimir Selenskij hat am Freitag seinen Luftwaffenchef gefeuert. Grund daf\u00fcr ist offensichtlich der Verlust einer F-16 unter ungekl\u00e4rten Umst\u00e4nden vor einigen Tagen. Wladimir Selenskij, der Machthaber in Kiew, dessen regul\u00e4re Amtszeit als ukrainischer Pr\u00e4sident im Mai dieses Jahres abgelaufen ist, hat am Freitag den Kommandeur der ukrainischen Luftstreitkr\u00e4fte, Nikolai Oleschtschuk, mit sofortiger [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-08-30T19:30:27+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/66d21951b480cc6d2e3a163b.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Nach Verlust einer F-16: Selenskij entl\u00e4sst Chef der ukrainischen Luftwaffe","datePublished":"2024-08-30T19:30:27+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/"},"wordCount":361,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Nach-Verlust-einer-F-16-Selenskij-entlaesst-Chef-der-ukrainischen-Luftwaffe.jpg","keywords":["Chef","der","einer","entl\u00e4sst","F16","Luftwaffe","nach","Selenskij","ukrainischen","Verlust"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/","url":"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/","name":"Nach Verlust einer F-16: Selenskij entl\u00e4sst Chef der ukrainischen Luftwaffe - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Nach-Verlust-einer-F-16-Selenskij-entlaesst-Chef-der-ukrainischen-Luftwaffe.jpg","datePublished":"2024-08-30T19:30:27+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Nach-Verlust-einer-F-16-Selenskij-entlaesst-Chef-der-ukrainischen-Luftwaffe.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Nach-Verlust-einer-F-16-Selenskij-entlaesst-Chef-der-ukrainischen-Luftwaffe.jpg","width":460,"height":259,"caption":"Nach Verlust einer F-16: Selenskij entl\u00e4sst Chef der ukrainischen Luftwaffe"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/nach-verlust-einer-f-16-selenskij-entlaesst-chef-der-ukrainischen-luftwaffe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Nach Verlust einer F-16: Selenskij entl\u00e4sst Chef der ukrainischen Luftwaffe"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/67895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=67895"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/67895\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/67896"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=67895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=67895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=67895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}