{"id":67877,"date":"2024-08-30T17:14:27","date_gmt":"2024-08-30T15:14:27","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/"},"modified":"2024-08-30T17:14:27","modified_gmt":"2024-08-30T15:14:27","slug":"donald-trump-gott-will-dass-ich-die-welt-rette","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/","title":{"rendered":"Donald Trump: Gott will, dass ich die Welt rette"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/66d1bb4db480cc7ea3038efb.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Donald Trump f\u00fchrt sein \u00dcberleben des Attentats auf eine g\u00f6ttliche Intervention zur\u00fcck. Gott habe ihn gerettet, weil Gott die USA liebe und weil Gott glaube, Trump werde nicht nur die USA retten, sondern die ganze Welt, behauptet der Republikaner.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Der republikanische Pr\u00e4sidentschaftskandidat der USA Donald Trump erkl\u00e4rte, es sei Gott gewesen, der ihn bei dem Attentat im vergangenen Monat auf einer Kundgebung in Butler, Pennsylvania, verschont habe. Nach Ansicht Trumps hat er den Auftrag, die USA \u2013 und vielleicht die ganze Welt \u2013 zu retten.<\/p>\n<p>Als der 20-j\u00e4hrige Thomas Matthew Crooks am 13.\u00a0Juli das Feuer auf ihn er\u00f6ffnet hatte, war Trump nur knapp dem Tod entgangen. Der potenzielle Attent\u00e4ter hatte auf einem nahegelegenen Dach Stellung bezogen, von dem aus er einen ungehinderten Blick auf sein Ziel gehabt hatte. Crooks hatte mehrere Sch\u00fcsse abgefeuert, von denen einer das rechte Ohr des ehemaligen Pr\u00e4sidenten gestreift hatte. Ein Teilnehmer der Kundgebung war get\u00f6tet und zwei weitere schwer verletzt worden. Der Sch\u00fctze war anschlie\u00dfend durch das Gegenfeuer des Secret Service get\u00f6tet worden.<\/p>\n<p>In einem Interview mit dem Psychologen und Fernsehmoderator Phil McGraw, besser bekannt als Dr.\u00a0Phil, erkl\u00e4rte Trump am Dienstag, dass an jenem schicksalhaften Tag &#8220;eine gro\u00dfe Macht&#8221; im Spiel gewesen sein m\u00fcsse. Zu den Motiven von Gottes mutma\u00dflicher Einmischung erkl\u00e4rte Trump:<\/p>\n<blockquote>\n<p><em>&#8220;Das Einzige, was ich mir vorstellen kann, ist, dass Gott unser Land liebt und dass er glaubt, wir werden unser Land zur\u00fcckbringen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Sein \u00dcberleben bei dem Attentat k\u00f6nne nur Gott zugeschrieben werden. &#8220;Es muss Gott sein. Ich meine, wie kann man sagen, dass es Gl\u00fcck ist, wenn es zwanzig Millionen zu eins steht&#8221;, so Trumps Begr\u00fcndung. In seinem Kommentar zur Abl\u00f6sung von Joe Biden durch Kamala Harris als Pr\u00e4sidentschaftskandidat der Demokraten f\u00fcr die Wahl am 5.\u00a0November beklagte Trump, dass er nun einem &#8220;netten neuen Gegner&#8221; gegen\u00fcberstehe. Sollte er bei den US-Wahlen siegen, w\u00fcrde das Trump zufolge bedeuten,<\/p>\n<blockquote>\n<p><em> dass es &#8220;eine unglaubliche Macht da oben gibt, die will, dass ich bei der Rettung mitmache, und vielleicht ist es mehr als die Rettung der Nation, vielleicht ist es die Rettung der Welt&#8221;.<\/em><\/p>\n<\/blockquote>\n<p>Den Secret-Service-Agenten dr\u00fcckte Trump in Bezug auf ihre Leistung w\u00e4hrend des Anschlags seine Dankbarkeit und seine Bewunderung f\u00fcr ihre Tapferkeit aus. Allerdings mangelte es seiner Meinung nach bei der Kommunikation zwischen ihnen und den \u00f6rtlichen Strafverfolgungsbeh\u00f6rden. Der republikanische Kandidat machte Vizepr\u00e4sidentin Harris und Pr\u00e4sident Biden f\u00fcr den Anschlag auf ihn mitverantwortlich. Er beschuldigte die ranghohen Demokraten, &#8220;es sehr schwierig zu machen, den Secret Service angemessen zu besetzen&#8221;.<\/p>\n<p>Nach Ansicht des ehemaligen Pr\u00e4sidenten haben Harris und Biden ihn zudem routinem\u00e4\u00dfig als &#8220;Bedrohung f\u00fcr die Demokratie&#8221; dargestellt&#8221;. Das k\u00f6nne &#8220;Attent\u00e4ter oder potenzielle Attent\u00e4ter auf den Plan rufen&#8221; \u2013 &#8220;vielleicht kommt diese Kugel von ihrer Rhetorik&#8221;, mutma\u00dfte Trump. Der ehemalige Pr\u00e4sident wiederholte gegen\u00fcber Dr.\u00a0Phil seine Behauptungen \u00fcber angeblichen Wahlbetrug bei den Pr\u00e4sidentschaftswahlen 2020 und erkl\u00e4rte, er habe in Kalifornien gewonnen.<\/p>\n<blockquote>\n<p><em>&#8220;Wenn Jesus k\u00e4me und die Stimmen ausz\u00e4hlen w\u00fcrde, h\u00e4tte ich in Kalifornien gewonnen&#8221;, betonte Trump.<\/em><\/p>\n<\/blockquote>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/dert.online\/kurzclips\/video\/216498-trump-ich-freundlich-zu-russland\/\">Trump: Ich, freundlich zu Russland? Ich habe Nord Stream 2 gestoppt <\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/nordamerika\/217419-donald-trump-gott-will-dass-ich-die-welt-rette\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Donald Trump f\u00fchrt sein \u00dcberleben des Attentats auf eine g\u00f6ttliche Intervention zur\u00fcck. Gott habe ihn gerettet, weil Gott die USA liebe und weil Gott glaube, Trump werde nicht nur die USA retten, sondern die ganze Welt, behauptet der Republikaner. Der republikanische Pr\u00e4sidentschaftskandidat der USA Donald Trump erkl\u00e4rte, es sei Gott gewesen, der ihn bei dem [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":67878,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1725034246"],"wp_automatic_camp":["217"],"b461581a90373ac3c606f848035e6c45":["Donald Trump: Gott will, dass ich die Welt rette"],"original_link":["https:\/\/de.rt.com\/nordamerika\/217419-donald-trump-gott-will-dass-ich-die-welt-rette\/"],"_thumbnail_id":["67878"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-08-30 18:11:45\";}"],"jnews_social_counter_last_update":["1784129906"]},"categories":[19,23],"tags":[42,45,3129,164,410,13746,1639,778],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Donald Trump: Gott will, dass ich die Welt rette - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Donald Trump: Gott will, dass ich die Welt rette\" \/>\n<meta property=\"og:description\" content=\"Donald Trump f\u00fchrt sein \u00dcberleben des Attentats auf eine g\u00f6ttliche Intervention zur\u00fcck. Gott habe ihn gerettet, weil Gott die USA liebe und weil Gott glaube, Trump werde nicht nur die USA retten, sondern die ganze Welt, behauptet der Republikaner. Der republikanische Pr\u00e4sidentschaftskandidat der USA Donald Trump erkl\u00e4rte, es sei Gott gewesen, der ihn bei dem [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-30T15:14:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/66d1bb4db480cc7ea3038efb.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Donald Trump: Gott will, dass ich die Welt rette\",\"datePublished\":\"2024-08-30T15:14:27+00:00\",\"dateModified\":\"2024-08-30T15:14:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/\"},\"wordCount\":553,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Donald-Trump-Gott-will-dass-ich-die-Welt-rette.jpg\",\"keywords\":[\"dass\",\"die\",\"Donald\",\"Gott\",\"Ich\",\"Rette\",\"trump\",\"Welt\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/\",\"name\":\"Donald Trump: Gott will, dass ich die Welt rette - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Donald-Trump-Gott-will-dass-ich-die-Welt-rette.jpg\",\"datePublished\":\"2024-08-30T15:14:27+00:00\",\"dateModified\":\"2024-08-30T15:14:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Donald-Trump-Gott-will-dass-ich-die-Welt-rette.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Donald-Trump-Gott-will-dass-ich-die-Welt-rette.jpg\",\"width\":460,\"height\":259,\"caption\":\"Donald Trump: Gott will, dass ich die Welt rette\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Donald Trump: Gott will, dass ich die Welt rette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Donald Trump: Gott will, dass ich die Welt rette - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/","og_locale":"de_DE","og_type":"article","og_title":"Donald Trump: Gott will, dass ich die Welt rette","og_description":"Donald Trump f\u00fchrt sein \u00dcberleben des Attentats auf eine g\u00f6ttliche Intervention zur\u00fcck. Gott habe ihn gerettet, weil Gott die USA liebe und weil Gott glaube, Trump werde nicht nur die USA retten, sondern die ganze Welt, behauptet der Republikaner. Der republikanische Pr\u00e4sidentschaftskandidat der USA Donald Trump erkl\u00e4rte, es sei Gott gewesen, der ihn bei dem [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-08-30T15:14:27+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/66d1bb4db480cc7ea3038efb.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Donald Trump: Gott will, dass ich die Welt rette","datePublished":"2024-08-30T15:14:27+00:00","dateModified":"2024-08-30T15:14:27+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/"},"wordCount":553,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Donald-Trump-Gott-will-dass-ich-die-Welt-rette.jpg","keywords":["dass","die","Donald","Gott","Ich","Rette","trump","Welt"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/","url":"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/","name":"Donald Trump: Gott will, dass ich die Welt rette - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Donald-Trump-Gott-will-dass-ich-die-Welt-rette.jpg","datePublished":"2024-08-30T15:14:27+00:00","dateModified":"2024-08-30T15:14:27+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Donald-Trump-Gott-will-dass-ich-die-Welt-rette.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Donald-Trump-Gott-will-dass-ich-die-Welt-rette.jpg","width":460,"height":259,"caption":"Donald Trump: Gott will, dass ich die Welt rette"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/donald-trump-gott-will-dass-ich-die-welt-rette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Donald Trump: Gott will, dass ich die Welt rette"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/67877"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=67877"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/67877\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/67878"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=67877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=67877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=67877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}