{"id":66820,"date":"2024-08-15T21:31:43","date_gmt":"2024-08-15T19:31:43","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/"},"modified":"2024-08-15T21:31:43","modified_gmt":"2024-08-15T19:31:43","slug":"medienberichte-faeser-beharrt-auf-compact-verbot","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/","title":{"rendered":"Medienberichte: Faeser beharrt auf Compact-Verbot"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/66be4b65b480cc5f13725e73.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Laut Berichten deutscher Medien h\u00e4lt Bundesinnenministerin Nancy Faeser (SPD) weiter am Verbot der Zeitschrift Compact fest. Das von ihrem Ministerium verf\u00fcgte Verbot war vom Bundesverwaltungsgericht in Leipzig am Dienstag in wesentlichen Teilen bis zur Hauptsacheentscheidung au\u00dfer Vollzug gesetzt worden.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Trotz des Beschlusses des Bundesverwaltungsgerichts im Eilverfahren, der Nancy Faesers Verbot des Nachrichtenmagazins <em>Compact<\/em> \u2013 vorl\u00e4ufig zumindest \u2013 aufhob und mit deutlichen Worten die Unverh\u00e4ltnism\u00e4\u00dfigkeit der Ma\u00dfnahme kritisierte, h\u00e4lt die Bundesinnenministerin an dem Vorhaben fest. Es sei &#8220;ein ganz normaler Vorgang in einem Rechtsstaat, dass man vor Gericht mal best\u00e4tigt wird&#8221;, sagte sie bei einem Termin in Berlin. Jetzt habe man &#8220;mal&#8221; verloren.<\/p>\n<p>Mit diesen Worten wird die Sozialdemokratin von diversen deutschen Medien zitiert, unter anderem von der <em>Tagesschau<\/em>. Weiter hei\u00dft es in den Berichten, die Innenministerin sehe trotz des Gerichtsentscheids keinen Anlass f\u00fcr eine Kurskorrektur. &#8220;Das Grundgesetz sieht ja das Instrument des Vereinsverbots ausdr\u00fccklich vor, um die Demokratie vor Verfassungsfeinden zu sch\u00fctzen&#8221;, zitiert die <em>Tagesschau<\/em> Faeser.<\/p>\n<p>Dem Beschluss des Bundesverwaltungsgerichts versucht die Innenministerin dabei Gutes f\u00fcr sich abzugewinnen. Das Gericht habe die Rechtsauffassung des Innenministeriums best\u00e4tigt, dass das Vereinsverbot ein m\u00f6gliches Instrument sei, meinte Faeser heute. Das Bundesinnenministerium halte deshalb mit Blick auf das Hauptsacheverfahren an seiner Auffassung fest.<\/p>\n<p>Faeser hatte die das Nachrichtenmagazin herausgebende GmbH am 16.\u00a0Juli nach vereinsrechtlichen Regeln verboten. <em>Compact<\/em> sei ein &#8220;zentrales Sprachrohr der rechtsextremistischen Szene&#8221;, hei\u00dft es in der Begr\u00fcndung der Verbotsverf\u00fcgung.<\/p>\n<p>Mit der vorl\u00e4ufigen Entscheidung des Bundesverwaltungsgerichts kann das <em>Compact<\/em>-Magazin unter Auflagen vorerst wieder erscheinen. Die August-Ausgabe sei vor dem Verbot in Druck gegangen und fertig produziert, erkl\u00e4rte Chefredakteur J\u00fcrgen Els\u00e4sser unmittelbar nach Bekanntwerden der Gerichtsentscheidung. Die Hefte w\u00fcrden &#8220;in K\u00fcrze ausgeliefert&#8221;.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/215690-faeser-nach-compact-niederlage-unter\/\">&#8220;B\u00f6se Klatsche&#8221;: Faeser nach &#8220;Compact&#8221;-Niederlage in der Kritik<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/215802-medienberichte-faeser-beharrt-auf-compact-verbot\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Laut Berichten deutscher Medien h\u00e4lt Bundesinnenministerin Nancy Faeser (SPD) weiter am Verbot der Zeitschrift Compact fest. Das von ihrem Ministerium verf\u00fcgte Verbot war vom Bundesverwaltungsgericht in Leipzig am Dienstag in wesentlichen Teilen bis zur Hauptsacheentscheidung au\u00dfer Vollzug gesetzt worden. Trotz des Beschlusses des Bundesverwaltungsgerichts im Eilverfahren, der Nancy Faesers Verbot des Nachrichtenmagazins Compact \u2013 vorl\u00e4ufig [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":66821,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1723750709"],"wp_automatic_camp":["217"],"53773b7e82b41e93561d8935bc1e5a50":["Medienberichte: Faeser beharrt auf Compact-Verbot"],"original_link":["https:\/\/de.rt.com\/inland\/215802-medienberichte-faeser-beharrt-auf-compact-verbot\/"],"_thumbnail_id":["66821"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-08-15 21:39:37\";}"],"jnews_social_counter_last_update":["1784126795"]},"categories":[19,23],"tags":[133,20611,56664,16802,373],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Medienberichte: Faeser beharrt auf Compact-Verbot - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medienberichte: Faeser beharrt auf Compact-Verbot\" \/>\n<meta property=\"og:description\" content=\"Laut Berichten deutscher Medien h\u00e4lt Bundesinnenministerin Nancy Faeser (SPD) weiter am Verbot der Zeitschrift Compact fest. Das von ihrem Ministerium verf\u00fcgte Verbot war vom Bundesverwaltungsgericht in Leipzig am Dienstag in wesentlichen Teilen bis zur Hauptsacheentscheidung au\u00dfer Vollzug gesetzt worden. Trotz des Beschlusses des Bundesverwaltungsgerichts im Eilverfahren, der Nancy Faesers Verbot des Nachrichtenmagazins Compact \u2013 vorl\u00e4ufig [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-15T19:31:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/66be4b65b480cc5f13725e73.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Medienberichte: Faeser beharrt auf Compact-Verbot\",\"datePublished\":\"2024-08-15T19:31:43+00:00\",\"dateModified\":\"2024-08-15T19:31:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/\"},\"wordCount\":312,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Medienberichte-Faeser-beharrt-auf-Compact-Verbot.jpg\",\"keywords\":[\"AUF\",\"beharrt\",\"CompactVerbot\",\"Faeser\",\"Medienberichte\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/\",\"name\":\"Medienberichte: Faeser beharrt auf Compact-Verbot - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Medienberichte-Faeser-beharrt-auf-Compact-Verbot.jpg\",\"datePublished\":\"2024-08-15T19:31:43+00:00\",\"dateModified\":\"2024-08-15T19:31:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Medienberichte-Faeser-beharrt-auf-Compact-Verbot.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Medienberichte-Faeser-beharrt-auf-Compact-Verbot.jpg\",\"width\":460,\"height\":259,\"caption\":\"Medienberichte: Faeser beharrt auf Compact-Verbot\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medienberichte: Faeser beharrt auf Compact-Verbot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Medienberichte: Faeser beharrt auf Compact-Verbot - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/","og_locale":"de_DE","og_type":"article","og_title":"Medienberichte: Faeser beharrt auf Compact-Verbot","og_description":"Laut Berichten deutscher Medien h\u00e4lt Bundesinnenministerin Nancy Faeser (SPD) weiter am Verbot der Zeitschrift Compact fest. Das von ihrem Ministerium verf\u00fcgte Verbot war vom Bundesverwaltungsgericht in Leipzig am Dienstag in wesentlichen Teilen bis zur Hauptsacheentscheidung au\u00dfer Vollzug gesetzt worden. Trotz des Beschlusses des Bundesverwaltungsgerichts im Eilverfahren, der Nancy Faesers Verbot des Nachrichtenmagazins Compact \u2013 vorl\u00e4ufig [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-08-15T19:31:43+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/66be4b65b480cc5f13725e73.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Medienberichte: Faeser beharrt auf Compact-Verbot","datePublished":"2024-08-15T19:31:43+00:00","dateModified":"2024-08-15T19:31:43+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/"},"wordCount":312,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Medienberichte-Faeser-beharrt-auf-Compact-Verbot.jpg","keywords":["AUF","beharrt","CompactVerbot","Faeser","Medienberichte"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/","url":"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/","name":"Medienberichte: Faeser beharrt auf Compact-Verbot - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Medienberichte-Faeser-beharrt-auf-Compact-Verbot.jpg","datePublished":"2024-08-15T19:31:43+00:00","dateModified":"2024-08-15T19:31:43+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Medienberichte-Faeser-beharrt-auf-Compact-Verbot.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Medienberichte-Faeser-beharrt-auf-Compact-Verbot.jpg","width":460,"height":259,"caption":"Medienberichte: Faeser beharrt auf Compact-Verbot"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/medienberichte-faeser-beharrt-auf-compact-verbot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Medienberichte: Faeser beharrt auf Compact-Verbot"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/66820"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=66820"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/66820\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/66821"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=66820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=66820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=66820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}