{"id":66466,"date":"2024-08-10T14:17:48","date_gmt":"2024-08-10T12:17:48","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/"},"modified":"2024-08-10T14:17:48","modified_gmt":"2024-08-10T12:17:48","slug":"moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/","title":{"rendered":"Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video)"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/66b7427d48fbef323d23510e.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Kiew verlor zw\u00f6lf Soldaten und zwei Boote bei einem versuchten Sturm auf die Nehrung der Kinburn-Halbinsel, teilte das russische Verteidigungsministerium mit.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die russische Armee hat eine Einheit von ukrainischen Spezialkr\u00e4ften ausgel\u00f6scht, die versucht hatten, eine Landeoperation in der Region Nikolajew durchzuf\u00fchren, sagte das Verteidigungsministerium in Moskau und ver\u00f6ffentlichte ein Video, das die Hinterlassenschaften eines heftigen Gefechts zeigt.<\/p>\n<p>In der Erkl\u00e4rung am Freitag teilte das Ministerium mit, dass die russischen Truppen den Versuch einer ukrainischen Erkundungs- und Sabotageeinheit vereitelt haben, auf der Kinburn-Nehrung zu landen, einem schmalen Landstreifen, der sich von der russischen Region Cherson ins Schwarze Meer erstreckt.<\/p>\n<p>Die Ministeriumsvertreter erkl\u00e4rten, die Gruppe, die aus 16 Soldaten auf zwei Hochgeschwindigkeitsmotorbooten bestand, habe versucht, unter der Deckung durch zwei weitere Boote auf der Landzunge zu landen. Sie f\u00fcgten hinzu, dass die Truppe bereits am Strand die ersten Verluste hatte, als sie auf ein Minenfeld traf. Diejenigen, denen es gelang, trockenen Boden zu erreichen, wurden, so die Erkl\u00e4rung, durch Feuer aus Kleinwaffen niedergestreckt.<\/p>\n<p>Nachdem sie schwere Verluste erlitten hatten, versuchten die ukrainischen Soldaten, sich von der K\u00fcste zur\u00fcckzuziehen. Bei dem Versuch seien jedoch zwei Boote durch Artillerie und Raketenfeuer zerst\u00f6rt, hie\u00df es aus dem Ministerium, das hinzuf\u00fcgte, die Gesamtzahl der ukrainischen Verluste betrage zw\u00f6lf Mann.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-video\">\n<div class=\"VideoEmbed\"><script src=\"https:\/\/de.russiatoday.com\/static\/libs\/jwplayer\/jwplayer-7.8.4\/jwplayer.js\"><\/script><\/p>\n<div class=\"mediaplayer\" id=\"mediaplayer-js-mediaplayer-66b7599648fbef323d235120-block\">\n<div id=\"js-mediaplayer-66b7599648fbef323d235120\"><\/div>\n<p><script src=\"https:\/\/de.russiatoday.com\/static\/js\/streamsense.4.1411.18.min.js\" type=\"text\/javascript\"><\/script><script type=\"text\/javascript\">\n            var myStreamingTag = new ns_.StreamingTag( { customerC2: '17935924', C3: 'deutsch' } );\n                                                var metadata = {\n                ns_st_ci: \"66b7599648fbef323d235120\", \/\/ \u0438\u0434\u0435\u043d\u0442\u0438\u0444\u0438\u043a\u0430\u0442\u043e\u0440 \u043a\u043e\u043d\u0442\u0435\u043d\u0442\u0430 (\u0432\u0438\u0434\u0435\u043e)\n                c3: \"deutsch\",\n                c4: \"*null\",\n                c6: \"*null\"\n            };\n        <\/script><\/div>\n<p><script>\n    jwplayer.key=\"kESrsgULvYO7r2MfUelqj3vs+2i8JdQBqjGNmA==\";\n            jwplayer(\"js-mediaplayer-66b7599648fbef323d235120\").setup({\n            advertising: {\n                client: \"googima\",\n                                                tag: 'https:\/\/googleads.g.doubleclick.net\/pagead\/ads?client=ca-video-pub-5925172396047466&slotname=7341516193&ad_type=video_text_image_flash&description_url=\"+encodeURIComponent(location.href)+\"&max_ad_duration=30000&videoad_start_delay=0',\n                            },\n            file: \"https:\/\/mf.b37mrtl.ru\/deutsch\/video\/2024.08\/66b7599648fbef323d235120.mp4\",\n                                    image: \"https:\/\/mf.b37mrtl.ru\/deutsch\/images\/2024.08\/article\/66b7427d48fbef323d23510e.jpg\",\n            \/\/ stretching: 'fill',\n                        \/\/ title: \"Angriff\\u0020auf\\u0020ukrainische\\u0020Landungsgruppe\",\n            aspectratio: \"16:9\",\n            skin: {\n                name: \"five\",\n                active: \"#77bd1e\",\n                background: \"rgba(0, 0, 0, 0.5)\",\n                inactive: \"#FFFFFF\"\n            },\n            width: \"100%\",\n            autostart: false,\n            mute: false,\n            startparam: \"start\",\n            ga: {},\n                        sharing: {\n                code: encodeURI('\n<div style=\"position: relative;padding-bottom: 56.25%; padding-top: 25px; height: 0;\"><iframe style=\"position: absolute;top: 0;left: 0;width: 100%;height: 100%;\" src=\"' +\n                    location.protocol + '\/\/' + location.host + '\/russland\/215158-moskau-ukrainische-spezialeinheiten-bei-verpatztem\/\/video\/66b7599648fbef323d235120\" frameborder=\"0\" allowfullscreen><\/script><\/div>\n<p>&#8216;),<br \/>\n                link: &#8220;\/russland\/215158-moskau-ukrainische-spezialeinheiten-bei-verpatztem\/&#8221;<br \/>\n            },<br \/>\n                        events: {<br \/>\n                onPlay: function(){<br \/>\n                    myStreamingTag.playVideoContentPart(metadata);<br \/>\n                    var playingVideoId = &#8216;js-mediaplayer-66b7599648fbef323d235120&#8217;; \/\/ id \u0442\u0435\u043a\u0443\u0449\u0435\u0433\u043e \u043f\u043b\u0435\u0435\u0440\u0430<br \/>\n                    playersTmplBehavior.pauseMedia(playingVideoId); \/\/\u0437\u0430\u043f\u0443\u0441\u043a\u0430\u0435\u043c \u0444\u0443\u043d\u043a\u0446\u0438\u044e \u043e\u0441\u0442\u0430\u043d\u043e\u0432\u043a\u0438 \u0432\u0441\u0435\u0445 \u0438\u0433\u0440\u0430\u044e\u0449\u0438\u0445 \u043f\u043b\u0435\u0435\u0440\u043e\u0432 \u043a\u0440\u043e\u043c\u0435 \u044d\u0442\u043e\u0433\u043e \u041a\u043e\u043b<\/p>\n<p>                    if(ga) {<br \/>\n                        ga(&#8216;send&#8217;, &#8216;event&#8217;, &#8216;jwplayer-ga&#8217;, &#8216;click play&#8217;, &#8216;Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video) &#8211; 66b7599648fbef323d235120&#8217;);<br \/>\n                    }<\/p>\n<p>                    if(gtag) gtag(&#8216;event&#8217;, &#8216;Play-click&#8217;, { url: &#8216;\/russland\/215158-moskau-ukrainische-spezialeinheiten-bei-verpatztem\/&#8217; });<br \/>\n                },<br \/>\n                onPause: function(){<br \/>\n                    myStreamingTag.stop();<\/p>\n<p>                    if(ga) {<br \/>\n                        ga(&#8216;send&#8217;, &#8216;event&#8217;, &#8216;jwplayer-ga&#8217;, &#8216;click pause&#8217;, &#8216;Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video) &#8211; 66b7599648fbef323d235120&#8217;);<br \/>\n                    }<br \/>\n                },<br \/>\n                onComplete: function(){<br \/>\n                    myStreamingTag.stop();<\/p>\n<p>                    if (ga) {<br \/>\n                        ga(&#8216;send&#8217;, &#8216;event&#8217;, &#8216;jwplayer-ga&#8217;, &#8216;complete&#8217;, &#8216;Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video) &#8211; 66b7599648fbef323d235120&#8217;);<br \/>\n                    }<br \/>\n                },<\/p>\n<p>                onTime() {<br \/>\n                    this.onceState = this.onceState || &#8216;3&#8217;<br \/>\n                    var videoDuration = this.getPosition();<\/p>\n<p>                    if (videoDuration &gt; 3 &amp;&amp; this.onceState === &#8216;3&#8217; &amp;&amp; ga) {<br \/>\n                        this.onceState=&#8221;15&#8243;<br \/>\n                        ga(&#8216;send&#8217;, &#8216;event&#8217;, &#8216;jwplayer-ga&#8217;, &#8216;3 sec&#8217;, &#8216;Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video) &#8211; 66b7599648fbef323d235120&#8242;);<br \/>\n                    }<\/p>\n<p>                    if (videoDuration &gt; 15 &amp;&amp; this.onceState === &#8217;15&#8217; &amp;&amp; ga) {<br \/>\n                        this.onceState=&#8221;60&#8243;<br \/>\n                        ga(&#8216;send&#8217;, &#8216;event&#8217;, &#8216;jwplayer-ga&#8217;, &#8217;15 sec&#8217;, &#8216;Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video) &#8211; 66b7599648fbef323d235120&#8242;);<br \/>\n                    }<\/p>\n<p>                    if (videoDuration &gt; 60 &amp;&amp; this.onceState === &#8217;60&#8217; &amp;&amp; ga) {<br \/>\n                        this.onceState=&#8221;180&#8243;<br \/>\n                        ga(&#8216;send&#8217;, &#8216;event&#8217;, &#8216;jwplayer-ga&#8217;, &#8216;1 min&#8217;, &#8216;Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video) &#8211; 66b7599648fbef323d235120&#8217;);<br \/>\n                    }<\/p>\n<p>                    if (videoDuration &gt; 180 &amp;&amp; this.onceState === &#8216;180&#8217; &amp;&amp; ga) {<br \/>\n                        this.onceState=&#8221;300&#8243;<br \/>\n                        ga(&#8216;send&#8217;, &#8216;event&#8217;, &#8216;jwplayer-ga&#8217;, &#8216;3 min&#8217;, &#8216;Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video) &#8211; 66b7599648fbef323d235120&#8217;);<br \/>\n                    }<\/p>\n<p>                    if (videoDuration &gt; 300 &amp;&amp; this.onceState === &#8216;300&#8217; &amp;&amp; ga) {<br \/>\n                        this.onceState=&#8221;600&#8243;<br \/>\n                        ga(&#8216;send&#8217;, &#8216;event&#8217;, &#8216;jwplayer-ga&#8217;, &#8216;5 min&#8217;, &#8216;Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video) &#8211; 66b7599648fbef323d235120&#8217;);<br \/>\n                    }<\/p>\n<p>                    if (videoDuration &gt; 600 &amp;&amp; this.onceState === &#8216;600&#8217; &amp;&amp; ga) {<br \/>\n                        this.onceState=&#8221;&#8221;<br \/>\n                        ga(&#8216;send&#8217;, &#8216;event&#8217;, &#8216;jwplayer-ga&#8217;, &#8217;10 min&#8217;, &#8216;Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video) &#8211; 66b7599648fbef323d235120&#8217;);<br \/>\n                    }<br \/>\n                }<br \/>\n            }<br \/>\n        });<\/p>\n<p>    var playersTmplBehavior = {};<\/p>\n<p>    \/\/\u0424\u0443\u043d\u043a\u0446\u0438\u044f \u043f\u0440\u043e\u0431\u0435\u0433\u0430\u0435\u0442 \u043f\u043e \u0432\u0441\u0435\u043c \u043f\u043b\u0435\u0435\u0440\u0430\u043c jwplayer, \u043a\u0440\u043e\u043c\u0435 \u043f\u0435\u0440\u0435\u0434\u0430\u043d\u043d\u043e\u0433\u043e, \u0438 \u0441\u0442\u0430\u0432\u0438\u0442 \u0438\u0445 \u043d\u0430 \u043f\u0430\u0443\u0437\u0443<br \/>\n    playersTmplBehavior.pauseMedia = function(playingMediaId) {<br \/>\n        var players = document.querySelectorAll(&#8216;.jwplayer, object&#8217;);<\/p>\n<p>        for (var i = 0, max = players.length; i <\/p><\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/russland\/215158-moskau-ukrainische-spezialeinheiten-bei-verpatztem\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kiew verlor zw\u00f6lf Soldaten und zwei Boote bei einem versuchten Sturm auf die Nehrung der Kinburn-Halbinsel, teilte das russische Verteidigungsministerium mit. Die russische Armee hat eine Einheit von ukrainischen Spezialkr\u00e4ften ausgel\u00f6scht, die versucht hatten, eine Landeoperation in der Region Nikolajew durchzuf\u00fchren, sagte das Verteidigungsministerium in Moskau und ver\u00f6ffentlichte ein Video, das die Hinterlassenschaften eines heftigen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":66467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1723292966"],"wp_automatic_camp":["217"],"af50fda159a4ee9272a7c7d3cb43f2a2":["Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video)"],"original_link":["https:\/\/de.rt.com\/russland\/215158-moskau-ukrainische-spezialeinheiten-bei-verpatztem\/"],"_thumbnail_id":["66467"],"enclosure":["https:\/\/mf.b37mrtl.ru\/deutsch\/video\/2024.08\/66b7599648fbef323d235120.mp4\n4315139\nvideo\/mp4\n"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-08-10 14:30:41\";}"],"jnews_social_counter_last_update":["1788216924"]},"categories":[19,23],"tags":[363,57413,57412,946,22785,905,57411,173],"class_list":["post-66466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-bei","tag-dezimiert","tag-landeeinsatz","tag-moskau","tag-spezialeinheiten","tag-ukrainische","tag-verpatztem","tag-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video) - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video)\" \/>\n<meta property=\"og:description\" content=\"Kiew verlor zw\u00f6lf Soldaten und zwei Boote bei einem versuchten Sturm auf die Nehrung der Kinburn-Halbinsel, teilte das russische Verteidigungsministerium mit. Die russische Armee hat eine Einheit von ukrainischen Spezialkr\u00e4ften ausgel\u00f6scht, die versucht hatten, eine Landeoperation in der Region Nikolajew durchzuf\u00fchren, sagte das Verteidigungsministerium in Moskau und ver\u00f6ffentlichte ein Video, das die Hinterlassenschaften eines heftigen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-10T12:17:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/66b7427d48fbef323d23510e.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video)\",\"datePublished\":\"2024-08-10T12:17:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\\\/\"},\"wordCount\":547,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/Moskau-Ukrainische-Spezialeinheiten-bei-verpatztem-Landeeinsatz-dezimiert-Video.jpg\",\"keywords\":[\"bei\",\"dezimiert\",\"Landeeinsatz\",\"Moskau\",\"Spezialeinheiten\",\"Ukrainische\",\"verpatztem\",\"Video\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\\\/\",\"name\":\"Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video) - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/Moskau-Ukrainische-Spezialeinheiten-bei-verpatztem-Landeeinsatz-dezimiert-Video.jpg\",\"datePublished\":\"2024-08-10T12:17:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/Moskau-Ukrainische-Spezialeinheiten-bei-verpatztem-Landeeinsatz-dezimiert-Video.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/Moskau-Ukrainische-Spezialeinheiten-bei-verpatztem-Landeeinsatz-dezimiert-Video.jpg\",\"width\":460,\"height\":259,\"caption\":\"Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video) - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/","og_locale":"de_DE","og_type":"article","og_title":"Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video)","og_description":"Kiew verlor zw\u00f6lf Soldaten und zwei Boote bei einem versuchten Sturm auf die Nehrung der Kinburn-Halbinsel, teilte das russische Verteidigungsministerium mit. Die russische Armee hat eine Einheit von ukrainischen Spezialkr\u00e4ften ausgel\u00f6scht, die versucht hatten, eine Landeoperation in der Region Nikolajew durchzuf\u00fchren, sagte das Verteidigungsministerium in Moskau und ver\u00f6ffentlichte ein Video, das die Hinterlassenschaften eines heftigen [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-08-10T12:17:48+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/66b7427d48fbef323d23510e.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video)","datePublished":"2024-08-10T12:17:48+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/"},"wordCount":547,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Moskau-Ukrainische-Spezialeinheiten-bei-verpatztem-Landeeinsatz-dezimiert-Video.jpg","keywords":["bei","dezimiert","Landeeinsatz","Moskau","Spezialeinheiten","Ukrainische","verpatztem","Video"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/","url":"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/","name":"Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video) - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Moskau-Ukrainische-Spezialeinheiten-bei-verpatztem-Landeeinsatz-dezimiert-Video.jpg","datePublished":"2024-08-10T12:17:48+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Moskau-Ukrainische-Spezialeinheiten-bei-verpatztem-Landeeinsatz-dezimiert-Video.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Moskau-Ukrainische-Spezialeinheiten-bei-verpatztem-Landeeinsatz-dezimiert-Video.jpg","width":460,"height":259,"caption":"Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video)"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/moskau-ukrainische-spezialeinheiten-bei-verpatztem-landeeinsatz-dezimiert-video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Moskau: Ukrainische Spezialeinheiten bei verpatztem Landeeinsatz dezimiert (Video)"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/66466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=66466"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/66466\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/66467"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=66466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=66466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=66466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}