{"id":66462,"date":"2024-08-10T13:09:41","date_gmt":"2024-08-10T11:09:41","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/"},"modified":"2024-08-10T13:09:41","modified_gmt":"2024-08-10T11:09:41","slug":"reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/","title":{"rendered":"Reuters: Drohnenangriff auf US-Luftwaffenst\u00fctzpunkt in Syrien"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/66b738ca48fbef323d235101.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Das ist der zweite Angriff auf US-Truppen im Nahen Osten, inmitten zunehmender Spannungen. Am Montag erst war der St\u00fctzpunkt Al-Asad im Irak angegriffen worden. Die US-Regierung rechnet mit einer Zunahme derartiger Angriffe.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Reuters<\/em> berichtete am Samstag unter Berufung auf einen US-Milit\u00e4r, dass die US-Truppen bei der Landezone Rumalyn in Nordost-Syrien von einer Drohne angegriffen worden seien.<\/p>\n<p>Das ist der zweite Angriff auf US-Truppen im Nahen Osten binnen einer Woche, w\u00e4hrend die Spannungen zwischen Iran und Israel zunehmen. Bei dem Raketenangriff auf den Luftwaffenst\u00fctzpunkt Al-Asad im Irak am Montag wurden den Berichten nach mehrere Soldaten verwundet.<\/p>\n<p>&#8220;Die ersten Berichte sprechen nicht von Verletzungen, aber die medizinischen Untersuchungen laufen noch. Wir nehmen gegenw\u00e4rtig die Sch\u00e4den auf&#8221;, berichtete Reuter und zitierte einen anonymen US-Milit\u00e4r zum Drohenangriff in Syrien.<\/p>\n<p>Bei der Landezone Rumalyn sind US-Truppen sowie mit den USA verb\u00fcndete Truppen aus der Region stationiert. Wie im Irak, dessen Regierung die US-Truppen l\u00e4ngst zum Abzug aufgefordert hat, halten sie sich in Syrien v\u00f6lkerrechtswidrig auf.<\/p>\n<p>Videoaufnahmen nach, die online geteilt worden sind, k\u00f6nnte der Drohnenangriff in der Einrichtung einen Brand ausgel\u00f6st haben.<\/p>\n<p>Washington erwarte mehr Angriffe, nachdem einige seiner Soldaten bei dem Angriff auf Al-Asad verwundet wurden, war auf <em>Axios<\/em> am Montag zu lesen. Gleichzeitig bereite sich Israel auf einen Angriff aus dem Iran vor, nachdem vergangene Woche der Chef des Politb\u00fcros der Hamas, Ismail Haniyya, in Teheran ermordet worden ist. W\u00e4hrend sowohl die Hamas als auch die iranische F\u00fchrung Israel daf\u00fcr verantwortlich machen, hat dieses eine Beteiligung weder best\u00e4tigt noch abgestritten.<\/p>\n<p>Die Regierung in Westjerusalem hat nach dem Angriff der Hamas auf Israel am 7. Oktober, bei dem 1.200 Menschen get\u00f6tet und mehr als 250 als Geiseln genommen wurden, geschworen, deren F\u00fchrung zu eliminieren.<\/p>\n<p>Das letzte Aufflammen des Konflikts zwischen Teheran und Westjerusalem im April, das mit einem Angriff auf die iranische Botschaft in Damaskus begann, endete mit einem gro\u00dfangelegten Angriff mit Drohnen und Raketen aus Iran gegen Israel. Die Luftabwehr Israels wurde damals durch die USA, die Briten und andere regionale Verb\u00fcndete unterst\u00fctzt.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/der-nahe-osten\/215147-gaza-ueber-100-tote-nach\/\">Gaza: \u00dcber 100 Tote nach israelischem Angriff auf Schule <\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/der-nahe-osten\/215154-reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das ist der zweite Angriff auf US-Truppen im Nahen Osten, inmitten zunehmender Spannungen. Am Montag erst war der St\u00fctzpunkt Al-Asad im Irak angegriffen worden. Die US-Regierung rechnet mit einer Zunahme derartiger Angriffe. Reuters berichtete am Samstag unter Berufung auf einen US-Milit\u00e4r, dass die US-Truppen bei der Landezone Rumalyn in Nordost-Syrien von einer Drohne angegriffen worden [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":66463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1723289132"],"wp_automatic_camp":["217"],"5fc3e08dc01e6f8cdf17007fcf113793":["Reuters: Drohnenangriff auf US-Luftwaffenst\u00fctzpunkt in Syrien"],"original_link":["https:\/\/de.rt.com\/der-nahe-osten\/215154-reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt\/"],"_thumbnail_id":["66463"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-08-10 13:26:32\";}"],"jnews_social_counter_last_update":["1788189245"]},"categories":[19,23],"tags":[133,31122,40,783,10011],"class_list":["post-66462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-auf","tag-drohnenangriff","tag-reuters","tag-syrien","tag-usluftwaffenstuetzpunkt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Reuters: Drohnenangriff auf US-Luftwaffenst\u00fctzpunkt in Syrien - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reuters: Drohnenangriff auf US-Luftwaffenst\u00fctzpunkt in Syrien\" \/>\n<meta property=\"og:description\" content=\"Das ist der zweite Angriff auf US-Truppen im Nahen Osten, inmitten zunehmender Spannungen. Am Montag erst war der St\u00fctzpunkt Al-Asad im Irak angegriffen worden. Die US-Regierung rechnet mit einer Zunahme derartiger Angriffe. Reuters berichtete am Samstag unter Berufung auf einen US-Milit\u00e4r, dass die US-Truppen bei der Landezone Rumalyn in Nordost-Syrien von einer Drohne angegriffen worden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-10T11:09:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/66b738ca48fbef323d235101.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Reuters: Drohnenangriff auf US-Luftwaffenst\u00fctzpunkt in Syrien\",\"datePublished\":\"2024-08-10T11:09:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\\\/\"},\"wordCount\":370,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/Reuters-Drohnenangriff-auf-US-Luftwaffenstuetzpunkt-in-Syrien.jpg\",\"keywords\":[\"AUF\",\"Drohnenangriff\",\"Reuters\",\"Syrien\",\"USLuftwaffenst\u00fctzpunkt\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\\\/\",\"name\":\"Reuters: Drohnenangriff auf US-Luftwaffenst\u00fctzpunkt in Syrien - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/Reuters-Drohnenangriff-auf-US-Luftwaffenstuetzpunkt-in-Syrien.jpg\",\"datePublished\":\"2024-08-10T11:09:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/Reuters-Drohnenangriff-auf-US-Luftwaffenstuetzpunkt-in-Syrien.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/08\\\/Reuters-Drohnenangriff-auf-US-Luftwaffenstuetzpunkt-in-Syrien.jpg\",\"width\":460,\"height\":259,\"caption\":\"Reuters: Drohnenangriff auf US-Luftwaffenst\u00fctzpunkt in Syrien\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reuters: Drohnenangriff auf US-Luftwaffenst\u00fctzpunkt in Syrien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Reuters: Drohnenangriff auf US-Luftwaffenst\u00fctzpunkt in Syrien - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/","og_locale":"de_DE","og_type":"article","og_title":"Reuters: Drohnenangriff auf US-Luftwaffenst\u00fctzpunkt in Syrien","og_description":"Das ist der zweite Angriff auf US-Truppen im Nahen Osten, inmitten zunehmender Spannungen. Am Montag erst war der St\u00fctzpunkt Al-Asad im Irak angegriffen worden. Die US-Regierung rechnet mit einer Zunahme derartiger Angriffe. Reuters berichtete am Samstag unter Berufung auf einen US-Milit\u00e4r, dass die US-Truppen bei der Landezone Rumalyn in Nordost-Syrien von einer Drohne angegriffen worden [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-08-10T11:09:41+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/66b738ca48fbef323d235101.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Reuters: Drohnenangriff auf US-Luftwaffenst\u00fctzpunkt in Syrien","datePublished":"2024-08-10T11:09:41+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/"},"wordCount":370,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Reuters-Drohnenangriff-auf-US-Luftwaffenstuetzpunkt-in-Syrien.jpg","keywords":["AUF","Drohnenangriff","Reuters","Syrien","USLuftwaffenst\u00fctzpunkt"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/","url":"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/","name":"Reuters: Drohnenangriff auf US-Luftwaffenst\u00fctzpunkt in Syrien - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Reuters-Drohnenangriff-auf-US-Luftwaffenstuetzpunkt-in-Syrien.jpg","datePublished":"2024-08-10T11:09:41+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Reuters-Drohnenangriff-auf-US-Luftwaffenstuetzpunkt-in-Syrien.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/08\/Reuters-Drohnenangriff-auf-US-Luftwaffenstuetzpunkt-in-Syrien.jpg","width":460,"height":259,"caption":"Reuters: Drohnenangriff auf US-Luftwaffenst\u00fctzpunkt in Syrien"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/reuters-drohnenangriff-auf-us-luftwaffenstuetzpunkt-in-syrien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Reuters: Drohnenangriff auf US-Luftwaffenst\u00fctzpunkt in Syrien"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/66462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=66462"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/66462\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/66463"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=66462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=66462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=66462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}