{"id":64481,"date":"2024-07-10T19:24:14","date_gmt":"2024-07-10T17:24:14","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/"},"modified":"2024-07-10T19:24:14","modified_gmt":"2024-07-10T17:24:14","slug":"habeck-kuendigt-neue-stromumlage-an","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/","title":{"rendered":"Habeck k\u00fcndigt neue Stromumlage an"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/668eb28d48fbef63ec34b849.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Das Wirtschaftsministerium plant eine neue Umlage auf den Strompreis, um Gaskraftwerke aufzubauen und bereits bestehende zu modernisieren. Habecks Begr\u00fcndung f\u00fcr die aktuelle Umlage: Dies sei auch in anderen L\u00e4ndern so \u00fcblich.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Wie das Bundeswirtschaftsministerium bekannt gab, plant die Bundesregierung f\u00fcr den Bau neuer und die Modernisierung bestehender Gaskraftwerke eine\u00a0Aktualisierung der\u00a0Umlage auf den Strompreis. Die modernen Anlagen sollen dazu dienen, die Stromversorgung auch bei einem wachsenden Anteil erneuerbarer Energien stabil zu halten.<\/p>\n<p>Bundeswirtschaftsminister Robert Habeck (B\u00fcndnis 90\/Die Gr\u00fcnen) sagte, die Finanzierung \u00fcber eine Umlage sei bei solchen Kapazit\u00e4ten in Europa &#8220;g\u00e4ngige Praxis&#8221;. Er behauptete weiterhin:<\/p>\n<blockquote>\n<p><em>&#8220;Es kommt allerdings erst mal auf die Verbraucherinnen gar nichts zu.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Der Minister fuhr fort:<\/p>\n<blockquote>\n<p><em>&#8220;Wir reden jetzt von den Zeitr\u00e4umen in den Drei\u00dfigerjahren. Und dann wird man sehen, wie man den Strompreis von anderen Umlagen befreit.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Es sei spekulativ, auszurechnen, was dies kosten w\u00fcrde, so Habeck.<\/p>\n<p>Laut Vergleichsportalen machen Steuern, Abgaben und Umlagen im laufenden Monat rund 31 Prozent des Strompreises aus. Au\u00dferdem entfallen 39 Prozent auf Stromnetzgeb\u00fchren, 39 Prozent auf die Strombeschaffung und die Marge der Stromversorger. Der staatliche Anteil am Strompreis ist seit dem Wegfall der EEG-Umlage, \u00fcber die der Ausbau erneuerbarer Energien finanziert wurde, gesunken.<\/p>\n<p>Das Vorhaben ist Teil der Pl\u00e4ne f\u00fcr ein neues Kraftwerksicherheitsgesetz, auf das sich Bundeskanzler Olaf Scholz (SPD), Wirtschaftsminister Robert Habeck (B\u00fcndnis 90\/Die Gr\u00fcnen) und Finanzminister Christian Lindner (FDP) in der vergangenen Woche geeinigt hatten. Insgesamt sollen Kapazit\u00e4ten von 12 Gigawatt (GW) sowie 500 Megawatt an Speicher entstehen.<\/p>\n<p>Kraftwerke sollen in der Bundesrepublik in Zukunft mit &#8220;klimafreundlichem&#8221; Wasserstoff betrieben werden k\u00f6nnen. Dazu w\u00fcrden neue Kraftwerke gebaut und bestehende umger\u00fcstet. Ein Anteil von f\u00fcnf Gigawatt soll dabei aus dem Klima- und Transformationsfonds der Bundesregierung und der genannten Umlage finanziert werden.<\/p>\n<p>In den sozialen Medien zeigten sich die Nutzer wenig begeistert von Habecks Ank\u00fcndigung. So hie\u00df es beispielsweise:<\/p>\n<blockquote>\n<p><em>&#8220;Ist das jetzt wieder so ein Test vom Robert, wie weit er bei der Bev\u00f6lkerung gehen kann?&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Ein anderer Nutzer schrieb:<\/p>\n<blockquote>\n<p><em>&#8220;Eine neue Kugel Eis?<\/em><\/p>\n<p><em>Will ja nicht unken, aber der Spruch geh\u00f6rt angepasst:<\/em><\/p>\n<p><em>Die Sonne schickt keine Rechnung, sie schickt Umlagen!&#8221;<\/em><\/p>\n<\/blockquote>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/kurzclips\/video\/207155-habeck-zum-heizhammer-test-wie\/\">Habeck zum Heizhammer: &#8220;Ein Test, wie bereit die Gesellschaft ist \u2013 da bin ich zu weit gegangen&#8221; <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2FHabeck-zum-Heizhammer---Ein-Test%2C-wie-bereit-die-Gesellschaft-ist-%E2%80%93-da-bin-ich-zu-weit-gegangen-%3A1\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/211929-habeck-kuendigt-neue-stromumlage-an\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Wirtschaftsministerium plant eine neue Umlage auf den Strompreis, um Gaskraftwerke aufzubauen und bereits bestehende zu modernisieren. Habecks Begr\u00fcndung f\u00fcr die aktuelle Umlage: Dies sei auch in anderen L\u00e4ndern so \u00fcblich. Wie das Bundeswirtschaftsministerium bekannt gab, plant die Bundesregierung f\u00fcr den Bau neuer und die Modernisierung bestehender Gaskraftwerke eine\u00a0Aktualisierung der\u00a0Umlage auf den Strompreis. Die modernen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":64482,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1720633096"],"wp_automatic_camp":["217"],"7d3c232e5b82779a0f71058509527a61":["Habeck k\u00fcndigt neue Stromumlage an"],"original_link":["https:\/\/de.rt.com\/inland\/211929-habeck-kuendigt-neue-stromumlage-an\/"],"_thumbnail_id":["64482"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-07-10 19:39:20\";}"],"jnews_social_counter_last_update":["1784026865"]},"categories":[19,23],"tags":[911,4224,1227,56496],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Habeck k\u00fcndigt neue Stromumlage an - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Habeck k\u00fcndigt neue Stromumlage an\" \/>\n<meta property=\"og:description\" content=\"Das Wirtschaftsministerium plant eine neue Umlage auf den Strompreis, um Gaskraftwerke aufzubauen und bereits bestehende zu modernisieren. Habecks Begr\u00fcndung f\u00fcr die aktuelle Umlage: Dies sei auch in anderen L\u00e4ndern so \u00fcblich. Wie das Bundeswirtschaftsministerium bekannt gab, plant die Bundesregierung f\u00fcr den Bau neuer und die Modernisierung bestehender Gaskraftwerke eine\u00a0Aktualisierung der\u00a0Umlage auf den Strompreis. Die modernen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-10T17:24:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/668eb28d48fbef63ec34b849.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Habeck k\u00fcndigt neue Stromumlage an\",\"datePublished\":\"2024-07-10T17:24:14+00:00\",\"dateModified\":\"2024-07-10T17:24:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/\"},\"wordCount\":391,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/Habeck-kuendigt-neue-Stromumlage-an.jpg\",\"keywords\":[\"Habeck\",\"k\u00fcndigt\",\"NEUE\",\"Stromumlage\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/\",\"name\":\"Habeck k\u00fcndigt neue Stromumlage an - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/Habeck-kuendigt-neue-Stromumlage-an.jpg\",\"datePublished\":\"2024-07-10T17:24:14+00:00\",\"dateModified\":\"2024-07-10T17:24:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/Habeck-kuendigt-neue-Stromumlage-an.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/Habeck-kuendigt-neue-Stromumlage-an.jpg\",\"width\":460,\"height\":259,\"caption\":\"Habeck k\u00fcndigt neue Stromumlage an\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Habeck k\u00fcndigt neue Stromumlage an\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Habeck k\u00fcndigt neue Stromumlage an - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/","og_locale":"de_DE","og_type":"article","og_title":"Habeck k\u00fcndigt neue Stromumlage an","og_description":"Das Wirtschaftsministerium plant eine neue Umlage auf den Strompreis, um Gaskraftwerke aufzubauen und bereits bestehende zu modernisieren. Habecks Begr\u00fcndung f\u00fcr die aktuelle Umlage: Dies sei auch in anderen L\u00e4ndern so \u00fcblich. Wie das Bundeswirtschaftsministerium bekannt gab, plant die Bundesregierung f\u00fcr den Bau neuer und die Modernisierung bestehender Gaskraftwerke eine\u00a0Aktualisierung der\u00a0Umlage auf den Strompreis. Die modernen [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-07-10T17:24:14+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/668eb28d48fbef63ec34b849.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Habeck k\u00fcndigt neue Stromumlage an","datePublished":"2024-07-10T17:24:14+00:00","dateModified":"2024-07-10T17:24:14+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/"},"wordCount":391,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/Habeck-kuendigt-neue-Stromumlage-an.jpg","keywords":["Habeck","k\u00fcndigt","NEUE","Stromumlage"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/","url":"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/","name":"Habeck k\u00fcndigt neue Stromumlage an - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/Habeck-kuendigt-neue-Stromumlage-an.jpg","datePublished":"2024-07-10T17:24:14+00:00","dateModified":"2024-07-10T17:24:14+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/Habeck-kuendigt-neue-Stromumlage-an.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/Habeck-kuendigt-neue-Stromumlage-an.jpg","width":460,"height":259,"caption":"Habeck k\u00fcndigt neue Stromumlage an"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/habeck-kuendigt-neue-stromumlage-an\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Habeck k\u00fcndigt neue Stromumlage an"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/64481"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=64481"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/64481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/64482"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=64481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=64481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=64481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}