{"id":64338,"date":"2024-07-08T21:44:15","date_gmt":"2024-07-08T19:44:15","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/"},"modified":"2024-07-08T21:44:15","modified_gmt":"2024-07-08T19:44:15","slug":"deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/","title":{"rendered":"&quot;Deutlich weniger bekommen, als ich angemeldet habe&quot;: Pistorius ver\u00e4rgert \u00fcber R\u00fcstungsetat"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/668c3b0248fbef1d843cfa0a.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Nachdem sich die Ampel-Spitzen auf einen neuen Haushaltsentwurf geeinigt hatten, kritisierte Verteidigungsminister Boris Pistorius die aus seiner Sicht geringen Steigerungen f\u00fcr den Bundeswehretat deutlich. Den Pl\u00e4nen zufolge soll der Verteidigungshaushalt von derzeit rund 52 Milliarden Euro um etwa 1,2 Milliarden Euro anwachsen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Nach der Einigung der Ampel-Spitzen auf einen Haushaltsentwurf kritisierte Verteidigungsminister Boris Pistorius (SPD) die aus seiner Sicht geringen Steigerungen f\u00fcr die Bundeswehr deutlich. Pistorius, der derzeit in Alaska das Man\u00f6ver Arctic Defender 2024 besucht und anschlie\u00dfend zum NATO-Gipfel nach Washington weiterreist, sagte:<\/p>\n<blockquote>\n<p><em>&#8220;Ja, ich habe deutlich weniger bekommen, als ich angemeldet habe. Das ist \u00e4rgerlich f\u00fcr mich, weil ich bestimmte Dinge dann nicht in der Geschwindigkeit ansto\u00dfen kann, wie es Zeitenwende und Bedrohungslage erforderlich machen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Auch der Generalinspekteur der Bundeswehr, Carsten Breuer, erwartet nun Garantien f\u00fcr eine deutliche Aufstockung in den kommenden Jahren.<\/p>\n<p>Bundeskanzler Olaf Scholz (SPD), Wirtschaftsminister Robert Habeck (B\u00fcndnis 90\/ Die Gr\u00fcnen) und Finanzminister Christian Lindner (FDP) hatten in der Nacht zum Freitag den seit Monaten schwelenden Haushaltsstreit beigelegt und sich auf Eckpunkte f\u00fcr den Bundeshaushalt 2025 geeinigt. Demnach ist vorgesehen, dass die Schuldenbremse eingehalten wird. Der FDP und ihrem Finanzminister war zudem wichtig, dass keine Haushaltsnotlage etwa wegen der Ausgaben f\u00fcr die milit\u00e4rische und humanit\u00e4re Unterst\u00fctzung der Ukraine festgestellt wird.<\/p>\n<p>Der Verteidigungshaushalt von derzeit rund 52 Milliarden Euro soll demnach um etwa 1,2 Milliarden Euro anwachsen. Pistorius hatte deutlich mehr und eine Ausnahme dieser Ausgaben von der Schuldenbremse gefordert. Dies hatte f\u00fcr deutliche Kritik gesorgt, auch aus der Ampel-Koalition.<\/p>\n<p>Habeck verteidigte den Haushaltsentwurf und erkl\u00e4rte, die Debatte dar\u00fcber, welche Notwendigkeiten Deutschland in der Zukunft im Sicherheitsbereich, aber beispielsweise auch im Infrastrukturbereich erf\u00fcllen muss, werde sicherlich in der Zukunft gef\u00fchrt werden \u2013 allerdings nicht mehr in dieser Legislaturperiode. Generalinspekteur Breuer sagte der <em>S\u00fcddeutschen Zeitung<\/em>, das 100-Milliarden-Sonderverm\u00f6gen werde bis Ende des Jahres vertraglich komplett gebunden sein. Mit der Anschaffung von neuen Waffensystemen stiegen auch die Betriebskosten.<\/p>\n<p>SPD-Generalsekret\u00e4r Kevin K\u00fchnert hofft in der Debatte hingegen erst einmal auf Ruhe. &#8220;Konkrete Diskussionen \u00fcber Korrekturen am Haushalt ergeben erst Sinn, sobald der ausgefertigte Haushaltsentwurf des Kabinetts beschlossen wurde. Das wird am 17. Juli der Fall sein&#8221;, sagte K\u00fchnert der D\u00fcsseldorfer <em>Rheinischen Post.<\/em> &#8220;Zumindest bis dahin sollte der Berliner Politikbetrieb sich und den Menschen im Land eine kleine Sommerpause g\u00f6nnen.&#8221;<\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/211571-zeitenende-statt-zeitenwende-bundeswehrverband-attackiert\/\">Zeitenende statt Zeitenwende \u2013 Bundeswehrverband attackiert Ampel-Haushaltspl\u00e4ne <\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/211702-deutlich-weniger-bekommen-als-ich\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachdem sich die Ampel-Spitzen auf einen neuen Haushaltsentwurf geeinigt hatten, kritisierte Verteidigungsminister Boris Pistorius die aus seiner Sicht geringen Steigerungen f\u00fcr den Bundeswehretat deutlich. Den Pl\u00e4nen zufolge soll der Verteidigungshaushalt von derzeit rund 52 Milliarden Euro um etwa 1,2 Milliarden Euro anwachsen. Nach der Einigung der Ampel-Spitzen auf einen Haushaltsentwurf kritisierte Verteidigungsminister Boris Pistorius (SPD) [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":64339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1720468165"],"wp_automatic_camp":["217"],"3426d8a9b16b9c4786fba2226cc70dc9":["&quot;Deutlich weniger bekommen, als ich angemeldet habe&quot;: Pistorius ver\u00e4rgert \u00fcber R\u00fcstungsetat"],"original_link":["https:\/\/de.rt.com\/inland\/211702-deutlich-weniger-bekommen-als-ich\/"],"_thumbnail_id":["64339"],"jnews_social_counter_last_update":["1778548074"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-07-08 21:50:30\";}"]},"categories":[19,23],"tags":[273,56435,7755,56436,410,39179,56434,56437,139,14985,3840],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Deutlich weniger bekommen, als ich angemeldet habe&quot;: Pistorius ver\u00e4rgert \u00fcber R\u00fcstungsetat - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Deutlich weniger bekommen, als ich angemeldet habe&quot;: Pistorius ver\u00e4rgert \u00fcber R\u00fcstungsetat\" \/>\n<meta property=\"og:description\" content=\"Nachdem sich die Ampel-Spitzen auf einen neuen Haushaltsentwurf geeinigt hatten, kritisierte Verteidigungsminister Boris Pistorius die aus seiner Sicht geringen Steigerungen f\u00fcr den Bundeswehretat deutlich. Den Pl\u00e4nen zufolge soll der Verteidigungshaushalt von derzeit rund 52 Milliarden Euro um etwa 1,2 Milliarden Euro anwachsen. Nach der Einigung der Ampel-Spitzen auf einen Haushaltsentwurf kritisierte Verteidigungsminister Boris Pistorius (SPD) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-08T19:44:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/668c3b0248fbef1d843cfa0a.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"&quot;Deutlich weniger bekommen, als ich angemeldet habe&quot;: Pistorius ver\u00e4rgert \u00fcber R\u00fcstungsetat\",\"datePublished\":\"2024-07-08T19:44:15+00:00\",\"dateModified\":\"2024-07-08T19:44:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/\"},\"wordCount\":416,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/quotDeutlich-weniger-bekommen-als-ich-angemeldet-habequot-Pistorius-veraergert-ueber.jpg\",\"keywords\":[\"als\",\"angemeldet\",\"bekommen\",\"habequot\",\"Ich\",\"Pistorius\",\"quotDeutlich\",\"R\u00fcstungsetat\",\"\u00fcber\",\"ver\u00e4rgert\",\"weniger\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/\",\"name\":\"&quot;Deutlich weniger bekommen, als ich angemeldet habe&quot;: Pistorius ver\u00e4rgert \u00fcber R\u00fcstungsetat - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/quotDeutlich-weniger-bekommen-als-ich-angemeldet-habequot-Pistorius-veraergert-ueber.jpg\",\"datePublished\":\"2024-07-08T19:44:15+00:00\",\"dateModified\":\"2024-07-08T19:44:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/quotDeutlich-weniger-bekommen-als-ich-angemeldet-habequot-Pistorius-veraergert-ueber.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/quotDeutlich-weniger-bekommen-als-ich-angemeldet-habequot-Pistorius-veraergert-ueber.jpg\",\"width\":460,\"height\":259,\"caption\":\"&quot;Deutlich weniger bekommen, als ich angemeldet habe&quot;: Pistorius ver\u00e4rgert \u00fcber R\u00fcstungsetat\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&quot;Deutlich weniger bekommen, als ich angemeldet habe&quot;: Pistorius ver\u00e4rgert \u00fcber R\u00fcstungsetat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"&quot;Deutlich weniger bekommen, als ich angemeldet habe&quot;: Pistorius ver\u00e4rgert \u00fcber R\u00fcstungsetat - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/","og_locale":"de_DE","og_type":"article","og_title":"&quot;Deutlich weniger bekommen, als ich angemeldet habe&quot;: Pistorius ver\u00e4rgert \u00fcber R\u00fcstungsetat","og_description":"Nachdem sich die Ampel-Spitzen auf einen neuen Haushaltsentwurf geeinigt hatten, kritisierte Verteidigungsminister Boris Pistorius die aus seiner Sicht geringen Steigerungen f\u00fcr den Bundeswehretat deutlich. Den Pl\u00e4nen zufolge soll der Verteidigungshaushalt von derzeit rund 52 Milliarden Euro um etwa 1,2 Milliarden Euro anwachsen. Nach der Einigung der Ampel-Spitzen auf einen Haushaltsentwurf kritisierte Verteidigungsminister Boris Pistorius (SPD) [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-07-08T19:44:15+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/668c3b0248fbef1d843cfa0a.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"&quot;Deutlich weniger bekommen, als ich angemeldet habe&quot;: Pistorius ver\u00e4rgert \u00fcber R\u00fcstungsetat","datePublished":"2024-07-08T19:44:15+00:00","dateModified":"2024-07-08T19:44:15+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/"},"wordCount":416,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/quotDeutlich-weniger-bekommen-als-ich-angemeldet-habequot-Pistorius-veraergert-ueber.jpg","keywords":["als","angemeldet","bekommen","habequot","Ich","Pistorius","quotDeutlich","R\u00fcstungsetat","\u00fcber","ver\u00e4rgert","weniger"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/","url":"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/","name":"&quot;Deutlich weniger bekommen, als ich angemeldet habe&quot;: Pistorius ver\u00e4rgert \u00fcber R\u00fcstungsetat - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/quotDeutlich-weniger-bekommen-als-ich-angemeldet-habequot-Pistorius-veraergert-ueber.jpg","datePublished":"2024-07-08T19:44:15+00:00","dateModified":"2024-07-08T19:44:15+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/quotDeutlich-weniger-bekommen-als-ich-angemeldet-habequot-Pistorius-veraergert-ueber.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/07\/quotDeutlich-weniger-bekommen-als-ich-angemeldet-habequot-Pistorius-veraergert-ueber.jpg","width":460,"height":259,"caption":"&quot;Deutlich weniger bekommen, als ich angemeldet habe&quot;: Pistorius ver\u00e4rgert \u00fcber R\u00fcstungsetat"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/deutlich-weniger-bekommen-als-ich-angemeldet-habe-pistorius-veraergert-ueber-ruestungsetat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"&quot;Deutlich weniger bekommen, als ich angemeldet habe&quot;: Pistorius ver\u00e4rgert \u00fcber R\u00fcstungsetat"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/64338"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=64338"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/64338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/64339"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=64338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=64338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=64338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}