{"id":62526,"date":"2024-06-20T22:12:02","date_gmt":"2024-06-20T20:12:02","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/"},"modified":"2024-06-20T22:12:02","modified_gmt":"2024-06-20T20:12:02","slug":"tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/","title":{"rendered":"TikTok l\u00f6scht Werbung f\u00fcr Sportbekleidungsmarke, die auf zwei Geschlechtern besteht"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/667461a148fbef74fd45d52d.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Ein &#8220;beleidigender Inhalt&#8221; soll es sein, wenn ein Werbefilm darauf besteht, die Rechte von Frauen auf eigene Sportwettbewerbe zu verteidigen. So zumindest die Entscheidung von TikTok. F\u00fcr die Inhaberin der betroffenen Firma ein Versuch, die Rechte von Frauen und M\u00e4dchen abzuschaffen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Es ist eine ziemlich junge Sportbekleidungsfirma; sie nennt sich XX-XY, in Anspielung auf die Geschlechtschromosome, und <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.xx-xyathletics.com\/pages\/our-ambassadors\">wirbt<\/a> mit dem Spruch &#8220;Rettet den Frauensport&#8221;. Die Gr\u00fcnderin der Firma ist eine ehemalige Turnerin, Mitglied der US-Nationalmannschaft, die im Jahr 2020 mit einem Dokumentarfilm \u00fcber Missbrauch in der Sportgymnastik einen Emmy gewann und sich jetzt mit ihrer Bekleidungsmarke daf\u00fcr einsetzt, Transfrauen nicht an Frauensportwettbewerben teilnehmen zu lassen. Sie bezeichnet sich selbst als &#8220;Feministin alter Schule&#8221;.<\/p>\n<p>Die Werbung und der Account dieses Unternehmens wurden nun von TikTok entfernt. &#8220;Unsere \u00dcberpr\u00fcfung legt nahe, dass Ihr Werbeinhalt die Werbepolitik von TikTok verletzen k\u00f6nnte, weil er beleidigende Inhalte zeigt.&#8221; Jennifer Sey hat nun den Text des Werbefilms, der die Sperrung ausl\u00f6ste, ver\u00f6ffentlicht:<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">This is the script of our ad that got us banned from <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/tiktok_us?ref_src=twsrc%5Etfw\">@tiktok_us<\/a> Inspiring. Stand up. <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/eut6eENUiU\">https:\/\/t.co\/eut6eENUiU<\/a><\/p>\n<p>\u2014 Jennifer Sey (@JenniferSey) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/JenniferSey\/status\/1803805517850018128?ref_src=twsrc%5Etfw\">June 20, 2024<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>&#8220;Wenn du denkst, dass die Gleichheit von M\u00e4dchen und Frauen wichtig ist, steh auf.<br \/> Wenn Frauensport wichtig ist, und du m\u00f6chtest, dass deine T\u00f6chter die gleichen M\u00f6glichkeiten haben, die du hattest, steh auf.<br \/> Wenn du wei\u00dft, dass es weder fair noch sicher ist, wenn M\u00e4nnern erlaubt wird, am M\u00e4dchensport teilzunehmen, steh auf.<br \/> Lass dich nicht von Leuten einsch\u00fcchtern, die dich bigott nennen.<br \/> Lass sie uns nicht vorschreiben, wie ein &#8220;gutes M\u00e4dchen&#8221; zu sein hat.<br \/> Lass dir nicht von anderen sagen, sei still, setz dich, sei nett.<br \/> Es ist nicht &#8220;nett&#8221;, eine L\u00fcge zu verbreiten.<br \/> Es ist nicht hart, an die Gleichberechtigung von Frauen zu glauben.<br \/> Wir haben ein Recht auf unseren eigenen Sport, unsere Privatsph\u00e4re, Fairness, Sicherheit.<br \/> Wir haben ein Recht auf eine Chance im Wettkampf. Und auf den Sieg.<br \/> Also sei ehrlich.<br \/> Sei tapfer.<br \/> K\u00e4mpfe f\u00fcr Frauen.<br \/> Wir sind zu weit gekommen, um jetzt aufzugeben.<br \/> Steh auf und steh mit uns.&#8221;<\/p>\n<p>Eine der F\u00fcrsprecherin der Marke ist Riley Gaines, eine Schwimmerin, die sich gegen die Zulassung von Lia Thomas, einer Transfrau, zu den Universit\u00e4tswettbewerben wandte. Inzwischen hat ein Sportgericht entschieden, dass biologische M\u00e4nner nicht an den Frauenwettbewerben teilnehmen d\u00fcrfen. Sie postete den Werbespot:<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">TikTok removed this ad from their platform for violating community guidelines. Shocker. Should would be a shame if everyone shared this clip and bought from <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/xx_xyathletics?ref_src=twsrc%5Etfw\">@xx_xyathletics<\/a> \ud83d\ude42<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/UVq3XaDsFN\">pic.twitter.com\/UVq3XaDsFN<\/a><\/p>\n<p>\u2014 Riley Gaines (@Riley_Gaines_) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/Riley_Gaines_\/status\/1803565165838807299?ref_src=twsrc%5Etfw\">June 19, 2024<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Auch eine junge Frau, die als Zw\u00f6lfj\u00e4hrige einen Geschlechtswechsel hatte und als Sechzehnj\u00e4hrige wieder ein M\u00e4dchen sein wollte, findet sich unter den Werbegesichtern.<\/p>\n<p>In den USA ist die Auseinandersetzung, wer als Frau an Sportwettk\u00e4mpfen teilnehmen darf, deutlich sch\u00e4rfer als in Europa, weil eine der wenigen M\u00f6glichkeiten f\u00fcr \u00e4rmere Jugendliche, an einer Universit\u00e4t zu studieren, ein Sportstipendium ist. In dem Moment, in dem biologische M\u00e4nner in den entsprechenden Sportarten zugelassen werden, reduziert sich die Chance f\u00fcr M\u00e4dchen, ein Stipendium zu erhalten, auf wenige Sportarten, wie Rhythmische Sportgymnastik und Synchronschwimmen. Es geht also nicht nur um den Sport oder die M\u00f6glichkeit, in der Umkleide nicht bel\u00e4stigt zu werden, sondern um Zukunftschancen. M\u00e4nner, die unter ihren Geschlechtsgenossen keine Chance auf ein derartiges Stipendium h\u00e4tten, k\u00f6nnen es immer noch jungen Frauen nehmen.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/nordamerika\/209182-olympia-traeume-passe-trans-schwimmer\/\">Olympia-Tr\u00e4ume pass\u00e9 \u2013 &#8220;Trans&#8221;-Schwimmer Lia Thomas erleidet Niederlage vor Sportgerichtshof<\/a><\/p>\n<\/p>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/gesellschaft\/209833-tiktok-loescht-werbung-fuer-sportkleidungsmarke\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein &#8220;beleidigender Inhalt&#8221; soll es sein, wenn ein Werbefilm darauf besteht, die Rechte von Frauen auf eigene Sportwettbewerbe zu verteidigen. So zumindest die Entscheidung von TikTok. F\u00fcr die Inhaberin der betroffenen Firma ein Versuch, die Rechte von Frauen und M\u00e4dchen abzuschaffen. Es ist eine ziemlich junge Sportbekleidungsfirma; sie nennt sich XX-XY, in Anspielung auf die [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":62527,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1718914484"],"wp_automatic_camp":["217"],"d959f590470e86a790967f9e8f58e437":["TikTok l\u00f6scht Werbung f\u00fcr Sportbekleidungsmarke, die auf zwei Geschlechtern besteht"],"original_link":["https:\/\/de.rt.com\/gesellschaft\/209833-tiktok-loescht-werbung-fuer-sportkleidungsmarke\/"],"_thumbnail_id":["62527"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-06-20 22:16:01\";}"],"jnews_social_counter_last_update":["1788390411"]},"categories":[19,23],"tags":[133,6450,45,221,55930,26611,55929,14908,23240,1003],"class_list":["post-62526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-auf","tag-besteht","tag-die","tag-fuer","tag-geschlechtern","tag-loescht","tag-sportbekleidungsmarke","tag-tiktok","tag-werbung","tag-zwei"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>TikTok l\u00f6scht Werbung f\u00fcr Sportbekleidungsmarke, die auf zwei Geschlechtern besteht - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TikTok l\u00f6scht Werbung f\u00fcr Sportbekleidungsmarke, die auf zwei Geschlechtern besteht\" \/>\n<meta property=\"og:description\" content=\"Ein &#8220;beleidigender Inhalt&#8221; soll es sein, wenn ein Werbefilm darauf besteht, die Rechte von Frauen auf eigene Sportwettbewerbe zu verteidigen. So zumindest die Entscheidung von TikTok. F\u00fcr die Inhaberin der betroffenen Firma ein Versuch, die Rechte von Frauen und M\u00e4dchen abzuschaffen. Es ist eine ziemlich junge Sportbekleidungsfirma; sie nennt sich XX-XY, in Anspielung auf die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-20T20:12:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/667461a148fbef74fd45d52d.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"TikTok l\u00f6scht Werbung f\u00fcr Sportbekleidungsmarke, die auf zwei Geschlechtern besteht\",\"datePublished\":\"2024-06-20T20:12:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\\\/\"},\"wordCount\":611,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/06\\\/TikTok-loescht-Werbung-fuer-Sportbekleidungsmarke-die-auf-zwei-Geschlechtern-besteht.jpg\",\"keywords\":[\"AUF\",\"besteht\",\"die\",\"f\u00fcr\",\"Geschlechtern\",\"l\u00f6scht\",\"Sportbekleidungsmarke\",\"Tiktok\",\"Werbung\",\"zwei\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\\\/\",\"name\":\"TikTok l\u00f6scht Werbung f\u00fcr Sportbekleidungsmarke, die auf zwei Geschlechtern besteht - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/06\\\/TikTok-loescht-Werbung-fuer-Sportbekleidungsmarke-die-auf-zwei-Geschlechtern-besteht.jpg\",\"datePublished\":\"2024-06-20T20:12:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/06\\\/TikTok-loescht-Werbung-fuer-Sportbekleidungsmarke-die-auf-zwei-Geschlechtern-besteht.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/06\\\/TikTok-loescht-Werbung-fuer-Sportbekleidungsmarke-die-auf-zwei-Geschlechtern-besteht.jpg\",\"width\":460,\"height\":259,\"caption\":\"TikTok l\u00f6scht Werbung f\u00fcr Sportbekleidungsmarke, die auf zwei Geschlechtern besteht\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TikTok l\u00f6scht Werbung f\u00fcr Sportbekleidungsmarke, die auf zwei Geschlechtern besteht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"TikTok l\u00f6scht Werbung f\u00fcr Sportbekleidungsmarke, die auf zwei Geschlechtern besteht - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/","og_locale":"de_DE","og_type":"article","og_title":"TikTok l\u00f6scht Werbung f\u00fcr Sportbekleidungsmarke, die auf zwei Geschlechtern besteht","og_description":"Ein &#8220;beleidigender Inhalt&#8221; soll es sein, wenn ein Werbefilm darauf besteht, die Rechte von Frauen auf eigene Sportwettbewerbe zu verteidigen. So zumindest die Entscheidung von TikTok. F\u00fcr die Inhaberin der betroffenen Firma ein Versuch, die Rechte von Frauen und M\u00e4dchen abzuschaffen. Es ist eine ziemlich junge Sportbekleidungsfirma; sie nennt sich XX-XY, in Anspielung auf die [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-06-20T20:12:02+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/667461a148fbef74fd45d52d.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"TikTok l\u00f6scht Werbung f\u00fcr Sportbekleidungsmarke, die auf zwei Geschlechtern besteht","datePublished":"2024-06-20T20:12:02+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/"},"wordCount":611,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/TikTok-loescht-Werbung-fuer-Sportbekleidungsmarke-die-auf-zwei-Geschlechtern-besteht.jpg","keywords":["AUF","besteht","die","f\u00fcr","Geschlechtern","l\u00f6scht","Sportbekleidungsmarke","Tiktok","Werbung","zwei"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/","url":"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/","name":"TikTok l\u00f6scht Werbung f\u00fcr Sportbekleidungsmarke, die auf zwei Geschlechtern besteht - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/TikTok-loescht-Werbung-fuer-Sportbekleidungsmarke-die-auf-zwei-Geschlechtern-besteht.jpg","datePublished":"2024-06-20T20:12:02+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/TikTok-loescht-Werbung-fuer-Sportbekleidungsmarke-die-auf-zwei-Geschlechtern-besteht.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/TikTok-loescht-Werbung-fuer-Sportbekleidungsmarke-die-auf-zwei-Geschlechtern-besteht.jpg","width":460,"height":259,"caption":"TikTok l\u00f6scht Werbung f\u00fcr Sportbekleidungsmarke, die auf zwei Geschlechtern besteht"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/tiktok-loescht-werbung-fuer-sportbekleidungsmarke-die-auf-zwei-geschlechtern-besteht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"TikTok l\u00f6scht Werbung f\u00fcr Sportbekleidungsmarke, die auf zwei Geschlechtern besteht"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/62526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=62526"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/62526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/62527"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=62526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=62526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=62526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}