{"id":61912,"date":"2024-06-17T13:34:33","date_gmt":"2024-06-17T11:34:33","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/"},"modified":"2024-06-17T13:34:33","modified_gmt":"2024-06-17T11:34:33","slug":"polens-praesident-fordert-dekolonisierung-russlands","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/","title":{"rendered":"Polens Pr\u00e4sident fordert &quot;Dekolonisierung&quot; Russlands"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/666ff5a8b480cc0bb251cf8d.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Russland f\u00fchre in der Ukraine einen Kolonialkrieg und versuche, sich neue Gebiete anzueignen, erkl\u00e4rte der polnische Pr\u00e4sident in der Schweiz. Gleichzeitig berichtet die New York Times, dass Warschau einen Frieden im Jahr 2022 verhindern wollte.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Polens\u00a0Pr\u00e4sident Andrzej Duda hat beim j\u00fcngsten &#8220;Friedensgipfel&#8221; in der Schweiz eine &#8220;Dekolonisierung&#8221; Russlands gefordert. Ethnische Minderheiten sollten sich von der Herrschaft Moskaus befreien und eigene Staaten gr\u00fcnden, forderte er. Das Land beherberge &#8220;fast 200 ethnische Gruppen&#8221;, die &#8220;durch die Methoden, die heute in der Ukraine angewandt werden, zu Einwohnern Russlands gemacht wurden&#8221;.\u00a0<em><\/em>Duda sagte, Russland werde als &#8220;Gef\u00e4ngnis der Nationen&#8221; bezeichnet. Die internationale Gemeinschaft m\u00fcsse zeigen, dass es in der Welt keinen Platz mehr f\u00fcr Kolonialismus gebe.<\/p>\n<blockquote>\n<p><em>&#8220;Russland ist immer noch das gr\u00f6\u00dfte Kolonialreich der Welt, das im Gegensatz zu den europ\u00e4ischen Staaten nie den Prozess der Entkolonialisierung durchlaufen hat und nie in der Lage war, die D\u00e4monen seiner Vergangenheit zu \u00fcberwinden&#8221;.<\/em><\/p>\n<\/blockquote>\n<p>Russland ist eines der vielf\u00e4ltigsten L\u00e4nder der Welt und umfasst laut einer Volksz\u00e4hlung aus dem Jahr 2021 \u00fcber 190 ethnische Gruppen, die mehr als 270 Sprachen und Dialekte sprechen. Fast 78 Prozent der Bev\u00f6lkerung sind russischer Abstammung, der Rest setzt sich aus Tataren, Ukrainern, Baschkiren, Tschuwaschen, Tschetschenen und anderen Ethnien zusammen. In Russland gibt es rund 5.000 registrierte religi\u00f6se Vereinigungen. Mehr als die H\u00e4lfte davon geh\u00f6rt der Russisch-Orthodoxen Kirche an. Die zweitgr\u00f6\u00dfte Religion ist der Islam.<\/p>\n<p>Duda\u00a0f\u00fcgte hinzu, dass die Ukraine das uneingeschr\u00e4nkte Recht habe, ihre Souver\u00e4nit\u00e4t und Unabh\u00e4ngigkeit im Einklang mit dem V\u00f6lkerrecht zu verteidigen, und dass die internationale Gemeinschaft die Pflicht habe, Kiew die notwendige Unterst\u00fctzung zu gew\u00e4hren. Der Weg zum Frieden werde lang sein, aber man m\u00fcsse sich &#8220;auf weniger kontroverse Themen konzentrieren&#8221;, deren Fortschritte es erm\u00f6glichen w\u00fcrden, &#8220;mehr Druck auf den Kreml auszu\u00fcben, damit er seine Truppen aus der Ukraine abzieht&#8221;. Der Erfolg dieser Initiative h\u00e4nge von einer breiten Beteiligung der UN-Mitgliedsstaaten ab.<\/p>\n<p>Polen ist einer der lautesten Bef\u00fcrworter der Hilfe f\u00fcr die Ukraine. Anfang des Jahres hatte Premierminister Donald Tusk die Bereitschaft angedeutet, US-Atomwaffen in Polen zu stationieren, was Moskau als &#8220;Provokation&#8221; und &#8220;zutiefst feindselige Politik&#8221; bezeichnete. Der russische Pr\u00e4sident Wladimir Putin erkl\u00e4rte, Moskau habe nicht die Absicht, NATO-Mitglieder anzugreifen.<\/p>\n<p>Vergangene Woche hatte die <em>New York Times<\/em> den vollst\u00e4ndigen Text eines Friedensvertrags zwischen Russland und der Ukraine ver\u00f6ffentlicht, der jedoch nie zu Stande kam. Die Verhandlungen fanden von Februar bis April 2022 statt. Einem Diplomaten zufolge bef\u00fcrchtete Warschau w\u00e4hrend der Gespr\u00e4che, dass die westlichen Partner Kiew dazu bringen k\u00f6nnten, die Bedingungen Russlands zu akzeptieren. Duda habe diese Bef\u00fcrchtungen bei einem Treffen mit mehreren NATO-Vertretern in Br\u00fcssel am 24. M\u00e4rz 2022 ge\u00e4u\u00dfert. Dem Bericht zufolge fragte er seine Kollegen: &#8220;Wer von Ihnen wird das unterschreiben?&#8221; Keiner der anwesenden Politiker habe eine klare Antwort gegeben.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/meinung\/197408-heuchelei-und-voelkermord-wen-der-westen-tatsaechlich-entkolonialisieren-sollte\/\">Heuchelei und V\u00f6lkermord: Wen der Westen tats\u00e4chlich entkolonialisieren sollte<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/209403-polens-praesident-fordert-dekolonisierung-russlands\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Russland f\u00fchre in der Ukraine einen Kolonialkrieg und versuche, sich neue Gebiete anzueignen, erkl\u00e4rte der polnische Pr\u00e4sident in der Schweiz. Gleichzeitig berichtet die New York Times, dass Warschau einen Frieden im Jahr 2022 verhindern wollte. Polens\u00a0Pr\u00e4sident Andrzej Duda hat beim j\u00fcngsten &#8220;Friedensgipfel&#8221; in der Schweiz eine &#8220;Dekolonisierung&#8221; Russlands gefordert. Ethnische Minderheiten sollten sich von der [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":61913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1718629309"],"wp_automatic_camp":["217"],"87281f97c337a0712d2507556f862040":["Polens Pr\u00e4sident fordert &quot;Dekolonisierung&quot; Russlands"],"original_link":["https:\/\/de.rt.com\/europa\/209403-polens-praesident-fordert-dekolonisierung-russlands\/"],"_thumbnail_id":["61913"],"jnews_social_counter_last_update":["1783983712"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-06-17 15:02:49\";}"]},"categories":[19,23],"tags":[355,14418,3464,26695,142],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Polens Pr\u00e4sident fordert &quot;Dekolonisierung&quot; Russlands - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Polens Pr\u00e4sident fordert &quot;Dekolonisierung&quot; Russlands\" \/>\n<meta property=\"og:description\" content=\"Russland f\u00fchre in der Ukraine einen Kolonialkrieg und versuche, sich neue Gebiete anzueignen, erkl\u00e4rte der polnische Pr\u00e4sident in der Schweiz. Gleichzeitig berichtet die New York Times, dass Warschau einen Frieden im Jahr 2022 verhindern wollte. Polens\u00a0Pr\u00e4sident Andrzej Duda hat beim j\u00fcngsten &#8220;Friedensgipfel&#8221; in der Schweiz eine &#8220;Dekolonisierung&#8221; Russlands gefordert. Ethnische Minderheiten sollten sich von der [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-17T11:34:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/666ff5a8b480cc0bb251cf8d.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Polens Pr\u00e4sident fordert &quot;Dekolonisierung&quot; Russlands\",\"datePublished\":\"2024-06-17T11:34:33+00:00\",\"dateModified\":\"2024-06-17T11:34:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/\"},\"wordCount\":511,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Polens-Praesident-fordert-quotDekolonisierungquot-Russlands.jpg\",\"keywords\":[\"fordert\",\"Polens\",\"Pr\u00e4sident\",\"quotDekolonisierungquot\",\"Russlands\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/\",\"name\":\"Polens Pr\u00e4sident fordert &quot;Dekolonisierung&quot; Russlands - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Polens-Praesident-fordert-quotDekolonisierungquot-Russlands.jpg\",\"datePublished\":\"2024-06-17T11:34:33+00:00\",\"dateModified\":\"2024-06-17T11:34:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Polens-Praesident-fordert-quotDekolonisierungquot-Russlands.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Polens-Praesident-fordert-quotDekolonisierungquot-Russlands.jpg\",\"width\":460,\"height\":259,\"caption\":\"Polens Pr\u00e4sident fordert &quot;Dekolonisierung&quot; Russlands\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Polens Pr\u00e4sident fordert &quot;Dekolonisierung&quot; Russlands\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Polens Pr\u00e4sident fordert &quot;Dekolonisierung&quot; Russlands - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/","og_locale":"de_DE","og_type":"article","og_title":"Polens Pr\u00e4sident fordert &quot;Dekolonisierung&quot; Russlands","og_description":"Russland f\u00fchre in der Ukraine einen Kolonialkrieg und versuche, sich neue Gebiete anzueignen, erkl\u00e4rte der polnische Pr\u00e4sident in der Schweiz. Gleichzeitig berichtet die New York Times, dass Warschau einen Frieden im Jahr 2022 verhindern wollte. Polens\u00a0Pr\u00e4sident Andrzej Duda hat beim j\u00fcngsten &#8220;Friedensgipfel&#8221; in der Schweiz eine &#8220;Dekolonisierung&#8221; Russlands gefordert. Ethnische Minderheiten sollten sich von der [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-06-17T11:34:33+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/666ff5a8b480cc0bb251cf8d.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Polens Pr\u00e4sident fordert &quot;Dekolonisierung&quot; Russlands","datePublished":"2024-06-17T11:34:33+00:00","dateModified":"2024-06-17T11:34:33+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/"},"wordCount":511,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Polens-Praesident-fordert-quotDekolonisierungquot-Russlands.jpg","keywords":["fordert","Polens","Pr\u00e4sident","quotDekolonisierungquot","Russlands"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/","url":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/","name":"Polens Pr\u00e4sident fordert &quot;Dekolonisierung&quot; Russlands - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Polens-Praesident-fordert-quotDekolonisierungquot-Russlands.jpg","datePublished":"2024-06-17T11:34:33+00:00","dateModified":"2024-06-17T11:34:33+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Polens-Praesident-fordert-quotDekolonisierungquot-Russlands.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Polens-Praesident-fordert-quotDekolonisierungquot-Russlands.jpg","width":460,"height":259,"caption":"Polens Pr\u00e4sident fordert &quot;Dekolonisierung&quot; Russlands"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-fordert-dekolonisierung-russlands\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Polens Pr\u00e4sident fordert &quot;Dekolonisierung&quot; Russlands"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/61912"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=61912"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/61912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/61913"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=61912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=61912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=61912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}