{"id":59983,"date":"2024-06-12T17:10:58","date_gmt":"2024-06-12T15:10:58","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/"},"modified":"2024-06-12T17:10:58","modified_gmt":"2024-06-12T15:10:58","slug":"fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/","title":{"rendered":"Fly me to the Moon: Putin unterzeichnet Abkommen mit China \u00fcber Mondstation"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/6669a1f1b480cc2ebc4b9af9.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                W\u00e4hrend Moskau sich gegen ein Wettr\u00fcsten im Weltall ausspricht, treibt es seine eigenen Pl\u00e4ne zu einer\u00a0kooperativen und friedlichen Nutzung des Kosmos voran.\u00a0 Wichtigster Partner ist dabei China, mit dem es auf dem Mond innerhalb der n\u00e4chsten Dekade eine Forschungsstation errichten will.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Wladimir Putin hat ein Gesetz zur Ratifizierung eines zwischenstaatlichen Abkommens zwischen Russland und China \u00fcber die Zusammenarbeit beim Bau einer Internationalen Mondforschungsstation (ILRS) unterzeichnet.<\/p>\n<p>Das Dokument, mit dem der russische Pr\u00e4sident ein Abkommen best\u00e4tigt, das Moskau und Peking erstmals 2022 geschlossen hatten, wurde am Mittwoch auf dem offiziellen russischen Portal f\u00fcr Rechtsinformationen ver\u00f6ffentlicht.<\/p>\n<p>Das Ratifizierungsgesetz passierte im vergangenen Monat das Unterhaus des russischen Parlaments, die Staatsduma, und wurde letzte Woche vom Oberhaus, dem F\u00f6derationsrat, gebilligt.<\/p>\n<p>Das Abkommen \u00fcber die Zusammenarbeit bei der Mondstation &#8220;entspricht den Interessen Russlands, da es zur St\u00e4rkung der strategischen Partnerschaft zwischen Russland und China beitr\u00e4gt&#8221; und &#8220;die f\u00fchrende Rolle Russlands bei der Erforschung des Weltraums, einschlie\u00dflich der Erforschung und Nutzung des Mondes, festigt&#8221;, hei\u00dft es in einer Erl\u00e4uterung zum Gesetz.<\/p>\n<p>Die Zusammenarbeit mit Peking werde auch die Effizienz der am ILRS durchgef\u00fchrten Forschung erh\u00f6hen und die potenziellen technischen und finanziellen Risiken im Zusammenhang mit der Erforschung und Nutzung des Mondes mindern sowie die Ausbildung von Wissenschaftlern und anderem Personal f\u00fcr k\u00fcnftige Raumfahrtprojekte erleichtern, hei\u00dft es weiter.<\/p>\n<p>Die ILRS wird von der russischen Raumfahrtbeh\u00f6rde Roskosmos und der chinesischen Raumfahrtbeh\u00f6rde CNSA entwickelt. Nach Angaben Moskaus und Pekings steht das Projekt, das die &#8220;Erforschung und Nutzung des Weltraums durch die Menschheit zu friedlichen Zwecken&#8221; f\u00f6rdern soll, jedoch weiterhin allen interessierten L\u00e4ndern und internationalen Partnern offen. Neun weitere L\u00e4nder, darunter S\u00fcdafrika, \u00c4gypten und Pakistan, haben sich bereits angeschlossen.<\/p>\n<p>Zugleich spricht sich Russland gegen ein\u00a0Wettr\u00fcsten im All aus. Doch eine entsprechende vor Wochen von Moskau im UN-Sicherheitsrat eingebrachte Resolution\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/206468-moskau-usa-wollen-weltraum-in\/\">scheiterte am Widerstand<\/a>\u00a0der USA und ihrer Verb\u00fcndeten.\u00a0<\/p>\n<p>Eine von Russland eingebrachte Resolution gegen ein Wettr\u00fcsten im All ist im UN-Sicherheitsrat am Montag gescheitert. Die USA und ihre Verb\u00fcndeten stimmten dagegen.\u00a0<\/p>\n<p>Die geplante Anlage soll aus einer Station in einer Mondumlaufbahn und einer Mondbasis auf der Oberfl\u00e4che bestehen. Sie soll von mehreren &#8220;intelligenten&#8221; Fahrzeugen und einem sprungf\u00e4higen Roboter unterst\u00fctzt werden, wie CNSA und Roskosmos zuvor mitteilten.<\/p>\n<p>Nach einem von der russischen Raumfahrtbeh\u00f6rde vorgelegten Fahrplan soll die ILRS bis 2035 einsatzbereit sein. Da das Projekt in mehrere Phasen unterteilt ist, planen Russland und China, bis 2025 einen Standort f\u00fcr die Mondbasis auszuw\u00e4hlen, wobei mit den Bauarbeiten ab 2026 begonnen werden soll.<\/p>\n<p>Nach ihrer Fertigstellung wird die Station die Topografie, die Geologie und die innere Struktur des Mondes erforschen und gleichzeitig die weitere Erforschung des Weltraums, einschlie\u00dflich bemannter Missionen zum Mond, unterst\u00fctzen.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/nordamerika\/197180-erste-us-mondlandung-seit-jahrzehnten\/\">Erste US-Mondlandung seit Jahrzehnten: Private Raumsonde weich aufgesetzt und umgekippt<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2FHistorischer-Meilenstein-Chinas-Chang%27e-6-hebt-mit-ersten-Proben-von-der-Mondr%C3%BCckseite-ab%3A7\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/russland\/208977-fly-me-to-the-moon\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend Moskau sich gegen ein Wettr\u00fcsten im Weltall ausspricht, treibt es seine eigenen Pl\u00e4ne zu einer\u00a0kooperativen und friedlichen Nutzung des Kosmos voran.\u00a0 Wichtigster Partner ist dabei China, mit dem es auf dem Mond innerhalb der n\u00e4chsten Dekade eine Forschungsstation errichten will. Wladimir Putin hat ein Gesetz zur Ratifizierung eines zwischenstaatlichen Abkommens zwischen Russland und China [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":59984,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1718206000"],"wp_automatic_camp":["217"],"25f0f7483401ed6de44b38475de053ea":["Fly me to the Moon: Putin unterzeichnet Abkommen mit China \u00fcber Mondstation"],"original_link":["https:\/\/de.rt.com\/russland\/208977-fly-me-to-the-moon\/"],"_thumbnail_id":["59984"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-06-12 17:27:41\";}"],"jnews_social_counter_last_update":["1778355286"]},"categories":[19,23],"tags":[6385,192,21287,419,55693,2266,125,139,7589],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fly me to the Moon: Putin unterzeichnet Abkommen mit China \u00fcber Mondstation - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fly me to the Moon: Putin unterzeichnet Abkommen mit China \u00fcber Mondstation\" \/>\n<meta property=\"og:description\" content=\"W\u00e4hrend Moskau sich gegen ein Wettr\u00fcsten im Weltall ausspricht, treibt es seine eigenen Pl\u00e4ne zu einer\u00a0kooperativen und friedlichen Nutzung des Kosmos voran.\u00a0 Wichtigster Partner ist dabei China, mit dem es auf dem Mond innerhalb der n\u00e4chsten Dekade eine Forschungsstation errichten will. Wladimir Putin hat ein Gesetz zur Ratifizierung eines zwischenstaatlichen Abkommens zwischen Russland und China [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-12T15:10:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/6669a1f1b480cc2ebc4b9af9.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Fly me to the Moon: Putin unterzeichnet Abkommen mit China \u00fcber Mondstation\",\"datePublished\":\"2024-06-12T15:10:58+00:00\",\"dateModified\":\"2024-06-12T15:10:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/\"},\"wordCount\":494,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Fly-me-to-the-Moon-Putin-unterzeichnet-Abkommen-mit-China.jpg\",\"keywords\":[\"Abkommen\",\"China\",\"Fly\",\"mit\",\"Mondstation\",\"moon\",\"putin\",\"\u00fcber\",\"unterzeichnet\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/\",\"name\":\"Fly me to the Moon: Putin unterzeichnet Abkommen mit China \u00fcber Mondstation - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Fly-me-to-the-Moon-Putin-unterzeichnet-Abkommen-mit-China.jpg\",\"datePublished\":\"2024-06-12T15:10:58+00:00\",\"dateModified\":\"2024-06-12T15:10:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Fly-me-to-the-Moon-Putin-unterzeichnet-Abkommen-mit-China.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Fly-me-to-the-Moon-Putin-unterzeichnet-Abkommen-mit-China.jpg\",\"width\":460,\"height\":259,\"caption\":\"Fly me to the Moon: Putin unterzeichnet Abkommen mit China \u00fcber Mondstation\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fly me to the Moon: Putin unterzeichnet Abkommen mit China \u00fcber Mondstation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fly me to the Moon: Putin unterzeichnet Abkommen mit China \u00fcber Mondstation - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/","og_locale":"de_DE","og_type":"article","og_title":"Fly me to the Moon: Putin unterzeichnet Abkommen mit China \u00fcber Mondstation","og_description":"W\u00e4hrend Moskau sich gegen ein Wettr\u00fcsten im Weltall ausspricht, treibt es seine eigenen Pl\u00e4ne zu einer\u00a0kooperativen und friedlichen Nutzung des Kosmos voran.\u00a0 Wichtigster Partner ist dabei China, mit dem es auf dem Mond innerhalb der n\u00e4chsten Dekade eine Forschungsstation errichten will. Wladimir Putin hat ein Gesetz zur Ratifizierung eines zwischenstaatlichen Abkommens zwischen Russland und China [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-06-12T15:10:58+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/6669a1f1b480cc2ebc4b9af9.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Fly me to the Moon: Putin unterzeichnet Abkommen mit China \u00fcber Mondstation","datePublished":"2024-06-12T15:10:58+00:00","dateModified":"2024-06-12T15:10:58+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/"},"wordCount":494,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Fly-me-to-the-Moon-Putin-unterzeichnet-Abkommen-mit-China.jpg","keywords":["Abkommen","China","Fly","mit","Mondstation","moon","putin","\u00fcber","unterzeichnet"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/","url":"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/","name":"Fly me to the Moon: Putin unterzeichnet Abkommen mit China \u00fcber Mondstation - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Fly-me-to-the-Moon-Putin-unterzeichnet-Abkommen-mit-China.jpg","datePublished":"2024-06-12T15:10:58+00:00","dateModified":"2024-06-12T15:10:58+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Fly-me-to-the-Moon-Putin-unterzeichnet-Abkommen-mit-China.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Fly-me-to-the-Moon-Putin-unterzeichnet-Abkommen-mit-China.jpg","width":460,"height":259,"caption":"Fly me to the Moon: Putin unterzeichnet Abkommen mit China \u00fcber Mondstation"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/fly-me-to-the-moon-putin-unterzeichnet-abkommen-mit-china-ueber-mondstation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Fly me to the Moon: Putin unterzeichnet Abkommen mit China \u00fcber Mondstation"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/59983"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=59983"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/59983\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/59984"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=59983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=59983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=59983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}