{"id":59638,"date":"2024-06-06T20:16:11","date_gmt":"2024-06-06T18:16:11","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/"},"modified":"2024-06-06T20:16:11","modified_gmt":"2024-06-06T18:16:11","slug":"podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/","title":{"rendered":"Podoljaka: Kiews Gegenoffensive im Norden erfolglos \u2013 Russland kommt methodisch voran"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/6661fb1548fbef733b2c7876.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Im Norden des Gebiets Charkow verheizt das ukrainische Milit\u00e4r bei seiner Gegenoffensive unver\u00e4ndert seine besten Einheiten ebenso wie frisch rekrutiertes Personal. Erreicht hat es damit auch bei diesem Versuch immer noch nichts, analysiert Juri Podoljaka.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Unver\u00e4ndert verheizt das ukrainische Milit\u00e4r seine besten Einheiten ebenso wie frisch rekrutiertes Personal bei seiner Gegenoffensive im Norden des Gebiets Charkow. Erreicht hat es damit auch bei diesem Versuch immer noch nichts.<br \/> Wegen dieser Konzentration von Truppen und Material im Norden fehlen diese dem Kiewer Kommando an allen anderen Frontabschnitten, h\u00e4lt Juri Podoljaka fest. Das Tempo, mit dem Russlands Milit\u00e4r vorr\u00fcckt, ist deswegen nicht viel schneller geworden \u2013 doch die Fortschritte erfassen nunmehr alle Abschnitte, mit der Ausnahme des eben erw\u00e4hnten Abschnitts Charkow-Nord und des schon l\u00e4nger nahezu inaktiven Abschnitts Cherson.<br \/> Erfahren Sie mehr in Juri Podoljakas Analyse der Gefechtslageentwicklung im Ukraine-Krieg zum 5. Juni 2024.<\/p>\n<p>Juri Podoljaka ist ein ukrainisch-russischer politischer Blogger und Journalist aus Sumy, dessen Ansichten seit dem Beginn der Sonderoperation in den russischen Medien immer gefragter wurden. Seine Analysen beinhalten nur wenige Zahlenangaben, daf\u00fcr vermittelt Podoljaka anhand von Karten ein gutes Verst\u00e4ndnis vom r\u00e4umlichen Umfang der jeweiligen Entwicklungen und bietet von Zeit zu Zeit kurzfristige Prognosen.<\/p>\n<p>Podoljaka st\u00fctzt sich dazu einerseits auf offen zug\u00e4ngliche Daten. Dies sind Meldungen von Augenzeugen in den sozialen Medien sowie Meldungen des russischen, aber auch des ukrainischen Verteidigungsministeriums. Andererseits analysiert er Insiderquellen. Neben Quellen in den Volksmilizen und Sicherheitsorganen der russischen Volksrepubliken Donezk und Lugansk sind dies nach eigenen Angaben auch solche in den ukrainischen Sicherheits- und Regierungsbeh\u00f6rden, zu denen er aufgrund alter Beziehungen aus seiner Zeit als ukrainischer Journalist noch in Kontakt steht. Um es im Jargon der Aufkl\u00e4rungsdienste auszudr\u00fccken: Juri Podoljaka ist vornehmlich ein OSINT-Analyst.<\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/205627-podoljaka-russland-eroeffnet-neuen-frontabschnitt\/\">Podoljaka: Russland er\u00f6ffnet neuen Frontabschnitt im Norden des Gebiets Charkow <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2FPodoljaka--Kiews-Gegenoffensive-im-Norden-erfolglos-%E2%80%93-Russland-kommt-methodisch-voran%3A0\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/208420-podoljaka-kiews-gegenoffensive-im-norden\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Norden des Gebiets Charkow verheizt das ukrainische Milit\u00e4r bei seiner Gegenoffensive unver\u00e4ndert seine besten Einheiten ebenso wie frisch rekrutiertes Personal. Erreicht hat es damit auch bei diesem Versuch immer noch nichts, analysiert Juri Podoljaka. Unver\u00e4ndert verheizt das ukrainische Milit\u00e4r seine besten Einheiten ebenso wie frisch rekrutiertes Personal bei seiner Gegenoffensive im Norden des Gebiets [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":59639,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1717698364"],"wp_automatic_camp":["217"],"c4ec4aecf3d0f6b17b1b729ca544f9b3":["Podoljaka: Kiews Gegenoffensive im Norden erfolglos \u2013 Russland kommt methodisch voran"],"original_link":["https:\/\/de.rt.com\/europa\/208420-podoljaka-kiews-gegenoffensive-im-norden\/"],"_thumbnail_id":["59639"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-06-06 20:27:05\";}"],"jnews_social_counter_last_update":["1778593182"]},"categories":[19,23],"tags":[29644,33957,6313,310,30484,9182,34692,126,19219],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Podoljaka: Kiews Gegenoffensive im Norden erfolglos \u2013 Russland kommt methodisch voran - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Podoljaka: Kiews Gegenoffensive im Norden erfolglos \u2013 Russland kommt methodisch voran\" \/>\n<meta property=\"og:description\" content=\"Im Norden des Gebiets Charkow verheizt das ukrainische Milit\u00e4r bei seiner Gegenoffensive unver\u00e4ndert seine besten Einheiten ebenso wie frisch rekrutiertes Personal. Erreicht hat es damit auch bei diesem Versuch immer noch nichts, analysiert Juri Podoljaka. Unver\u00e4ndert verheizt das ukrainische Milit\u00e4r seine besten Einheiten ebenso wie frisch rekrutiertes Personal bei seiner Gegenoffensive im Norden des Gebiets [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-06T18:16:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/6661fb1548fbef733b2c7876.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Podoljaka: Kiews Gegenoffensive im Norden erfolglos \u2013 Russland kommt methodisch voran\",\"datePublished\":\"2024-06-06T18:16:11+00:00\",\"dateModified\":\"2024-06-06T18:16:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/\"},\"wordCount\":323,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Podoljaka-Kiews-Gegenoffensive-im-Norden-erfolglos-\u2013-Russland-kommt-methodisch.jpg\",\"keywords\":[\"erfolglos\",\"Gegenoffensive\",\"Kiews\",\"kommt\",\"methodisch\",\"Norden\",\"Podoljaka\",\"russland\",\"voran\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/\",\"name\":\"Podoljaka: Kiews Gegenoffensive im Norden erfolglos \u2013 Russland kommt methodisch voran - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Podoljaka-Kiews-Gegenoffensive-im-Norden-erfolglos-\u2013-Russland-kommt-methodisch.jpg\",\"datePublished\":\"2024-06-06T18:16:11+00:00\",\"dateModified\":\"2024-06-06T18:16:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Podoljaka-Kiews-Gegenoffensive-im-Norden-erfolglos-\u2013-Russland-kommt-methodisch.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Podoljaka-Kiews-Gegenoffensive-im-Norden-erfolglos-\u2013-Russland-kommt-methodisch.jpg\",\"width\":460,\"height\":259,\"caption\":\"Podoljaka: Kiews Gegenoffensive im Norden erfolglos \u2013 Russland kommt methodisch voran\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podoljaka: Kiews Gegenoffensive im Norden erfolglos \u2013 Russland kommt methodisch voran\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Podoljaka: Kiews Gegenoffensive im Norden erfolglos \u2013 Russland kommt methodisch voran - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/","og_locale":"de_DE","og_type":"article","og_title":"Podoljaka: Kiews Gegenoffensive im Norden erfolglos \u2013 Russland kommt methodisch voran","og_description":"Im Norden des Gebiets Charkow verheizt das ukrainische Milit\u00e4r bei seiner Gegenoffensive unver\u00e4ndert seine besten Einheiten ebenso wie frisch rekrutiertes Personal. Erreicht hat es damit auch bei diesem Versuch immer noch nichts, analysiert Juri Podoljaka. Unver\u00e4ndert verheizt das ukrainische Milit\u00e4r seine besten Einheiten ebenso wie frisch rekrutiertes Personal bei seiner Gegenoffensive im Norden des Gebiets [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-06-06T18:16:11+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/6661fb1548fbef733b2c7876.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Podoljaka: Kiews Gegenoffensive im Norden erfolglos \u2013 Russland kommt methodisch voran","datePublished":"2024-06-06T18:16:11+00:00","dateModified":"2024-06-06T18:16:11+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/"},"wordCount":323,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Podoljaka-Kiews-Gegenoffensive-im-Norden-erfolglos-\u2013-Russland-kommt-methodisch.jpg","keywords":["erfolglos","Gegenoffensive","Kiews","kommt","methodisch","Norden","Podoljaka","russland","voran"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/","url":"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/","name":"Podoljaka: Kiews Gegenoffensive im Norden erfolglos \u2013 Russland kommt methodisch voran - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Podoljaka-Kiews-Gegenoffensive-im-Norden-erfolglos-\u2013-Russland-kommt-methodisch.jpg","datePublished":"2024-06-06T18:16:11+00:00","dateModified":"2024-06-06T18:16:11+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Podoljaka-Kiews-Gegenoffensive-im-Norden-erfolglos-\u2013-Russland-kommt-methodisch.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Podoljaka-Kiews-Gegenoffensive-im-Norden-erfolglos-\u2013-Russland-kommt-methodisch.jpg","width":460,"height":259,"caption":"Podoljaka: Kiews Gegenoffensive im Norden erfolglos \u2013 Russland kommt methodisch voran"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/podoljaka-kiews-gegenoffensive-im-norden-erfolglos-russland-kommt-methodisch-voran\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Podoljaka: Kiews Gegenoffensive im Norden erfolglos \u2013 Russland kommt methodisch voran"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/59638"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=59638"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/59638\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/59639"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=59638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=59638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=59638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}