{"id":59468,"date":"2024-06-04T14:46:19","date_gmt":"2024-06-04T12:46:19","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/"},"modified":"2024-06-04T14:46:19","modified_gmt":"2024-06-04T12:46:19","slug":"trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/","title":{"rendered":"Trotz Abkommen von Prespa: Neue Konflikte zwischen Griechenland und Nordmazedonien"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/665efd4b48fbef1e917c03de.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die in Br\u00fcssel wie auch in Athen unerwartet zustande gekommene Regierung von Nordmazedonien versucht Schritt um Schritt, die nationalen Gef\u00fchle der Bewohner entgegen den fr\u00fcheren Kompromissen mit Griechenland wie mit der NATO und der EU-Kommission st\u00e4rker zu ber\u00fccksichtigen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Marinko U\u010dur<\/em><\/p>\n<p>Trotz der Tatsache, dass Griechenland und Nordmazedonien als &#8220;gute Sch\u00fcler&#8221; der EU-Administration in Br\u00fcssel ihre Bereitschaft gezeigt haben, gute nachbarschaftliche Beziehungen aufzubauen, und dass die jahrzehntelangen Spannungen allein schon wegen des Namens der ehemaligen jugoslawischen Republik Mazedonien durch das Abkommen von Prespa ad acta gelegt wurden, kommt es zwischen den Regierenden in Athen und Skopje erneut zu un\u00fcberh\u00f6rbaren Misst\u00f6nen.<\/p>\n<p>Nach den j\u00fcngsten Pr\u00e4sidentschafts- und Parlamentswahlen in, bei denen Kandidaten und Parteien mit nationaler und souver\u00e4ner Ausrichtung gewonnen haben, sind sofort Identit\u00e4tsfrustrationen der Mazedonier in den Vordergrund geraten, die im Zeitraum davor \u2013 im Interesse der &#8220;europ\u00e4ischen Zukunft&#8221; \u2013 in den Hintergrund gedr\u00e4ngt werden mussten. Die Herrschaften in Br\u00fcssel und Washington, D.C. taten alles, um Griechenland davon zu \u00fcberzeugen, die Blockade der euroatlantischen Pl\u00e4ne Nordmazedoniens aufzugeben.<\/p>\n<p>Dieses Land, das nach dem Zerfall Jugoslawiens als ehemalige jugoslawische Republik Mazedonien in die Vereinten Nationen aufgenommen worden war, wurde gegen den Willen der Mehrheit der B\u00fcrger, aber gem\u00e4\u00df dem Willen der Regierung in Athen zu Nordmazedonien. Als Ausdruck des guten Willens wurden in Skopje diese Pl\u00e4ne zur Er\u00f6ffnung von Aktivit\u00e4ten im Hinblick auf eine m\u00f6gliche EU-Mitgliedschaft freigegeben. Ebenso wurde im beschleunigten Verfahren auch Nordmazedonien unter die Schirmherrschaft des westlichen NATO-Milit\u00e4rb\u00fcndnisses &#8220;aufgenommen&#8221; \u2013 nicht etwa nach dem Wunsch seiner B\u00fcrger, sondern wegen der Pl\u00e4ne der NATO, auch dort so nahe wie m\u00f6glich an die russischen Grenzen heranzukommen.<\/p>\n<p>Was die europ\u00e4ische Zukunft angeht, steht Nordmazedonien allerdings noch am Anfang, denn in Br\u00fcssel sind keinerlei Expansionsambitionen zu erkennen. Und auch die L\u00e4nder des Westbalkans erwarten nicht, in naher Zukunft Mitglied dieses unerreichbaren Klubs zu werden.<\/p>\n<p>Zahlreiche eurofanatische Schritte der vorherigen Regierung in Skopje fallen nun wie ein Bumerang auf sie zur\u00fcck, und deshalb hat die vorherige Regierung des Pr\u00e4sidenten Dimitar Kova\u010devski, deren Mehrheit im Parlament von den Sozialdemokraten SDSM gestellt wurde, im vergangenen Monat die Wahlen \u00fcberzeugend verloren. Sein Nachfolger auf dem Sitz des Premierministers und neuer Mandatstr\u00e4ger zur Bildung der Regierung Nordmazedoniens, der Vorsitzende Hristijan Mickoski der siegreichen Partei VMRO-DPMNE, betont im Einklang mit seinen Wahlversprechen und den Trends in der mazedonischen Gesellschaft, dass er sein Land trotz des Widerstands Griechenlands, mit dem die Politiker in Skopje 2018 eine Einigung \u00fcber die Namens\u00e4nderung erzielt hatten, weiterhin &#8220;Mazedonien&#8221; nennen wird.<\/p>\n<p>Mickoski zeigte damit laut dissonante Misst\u00f6ne gegen\u00fcber dem, was Nordmazedonien einst nach Br\u00fcssel und Athen als Versprechen signalisiert hatte. Er ist somit der zweite hochrangige Staatsbeamte, der den alten und heute verfassungswidrigen Namen \u00a0&#8220;Mazedonien&#8221; f\u00fcr das Land wieder \u00f6ffentlich verwendet. Die neu gew\u00e4hlte Pr\u00e4sidentin des Landes Gordana Siljanovska-Davkova hatte es bereits vor ihm getan.<\/p>\n<p>Das offizielle Athen reagierte umgehend und erinnerte die neue Regierung an die Verpflichtungen aus dem sogenannten <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.wikipedia.org\/wiki\/Streit_um_den_Namen_Mazedonien#Abkommen_von_Prespa\">Abkommen von Prespa<\/a>. Einst unterzeichneten mazedonische Sozialdemokraten und griechische Linke dieses Abkommen, das schlie\u00dflich im Jahr 2020 Nordmazedonien den Beitritt zur NATO erm\u00f6glichte. Offensichtlich laufen derzeit Versuche, die damals von Nordmazedonien \u00fcbernommenen Verpflichtungen zu minimieren. In den Kommentaren des griechischen Premierministers Kyriakos Mitsotakis wurde betont, dass das Agieren der neuen nordmazedonischen F\u00fchrung inakzeptabel sei. <br \/> Allerdings baute die neue Regierung zuvor ihren gesamten Wahlkampf auf der Bekr\u00e4ftigung der mazedonischen Identit\u00e4t und der R\u00fcckkehr zu den urspr\u00fcnglichen nationalen Werten auf, die einst unter ausl\u00e4ndischem Druck in den Hintergrund gerieten. Dabei geht es nicht nur um den jahrzehntelangen Streit mit Griechenland, sondern das Land wird auch von Bulgarien erpresst, das im Zuge der europ\u00e4ischen Integration ebenfalls konkrete Forderungen an Skopje richtet. Die Bulgaren im Lande fordern n\u00e4mlich ihre Aufnahme in die Pr\u00e4ambel der Verfassung sowie die Anerkennung aller ihrer nationalen Rechte, einschlie\u00dflich ihrer Sprache. Die Vorg\u00e4ngerregierung hat sich dazu verpflichtet und die Frist zur Realisierung auf Ende 2024 festgelegt.<\/p>\n<p>Der neuen Regierung in Skopje stehen schwierige Herausforderungen bevor, und Br\u00fcssel zeigt kein Verst\u00e4ndnis f\u00fcr die erw\u00e4hnten Schritte und die &#8220;Sprachgymnastik&#8221; der neuen Regierung. Zuerst wurden voller Unglauben die Wahlergebnisse zur Kenntnis genommen, dann wurden die Wahlgewinner gewarnt, dass sie sich im Falle des Namens des Staates auf die Einhaltung der Verfassung und des Abkommens von Prespa fokussieren m\u00fcssten. Die derzeitige Pr\u00e4sidentin der Europ\u00e4ischen Kommission Ursula von der Leyen wie auch der Pr\u00e4sident des Europ\u00e4ischen Rates Charles Michel warnten die Regierung in Skopje, dass durch die Nichteinhaltung der bisherigen Vereinbarungen &#8220;die Zukunft Nordmazedoniens untergraben&#8221; werde.<\/p>\n<p>Trotz allem bleibt die offizielle Priorit\u00e4t des Landes weiterhin die Integration in die Europ\u00e4ische Union, die ihrerseits offenbar den W\u00fcnschen der Mehrheit der B\u00fcrger und ihre Identit\u00e4tsfrustrationen kein Geh\u00f6r schenken will. Es ist klar, dass sich in Nordmazedonien seit Jahren kaum etwas ge\u00e4ndert hat \u2013 abgesehen vom Namen des Landes.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freeassange.rtde.life\/international\/206840-russland-ruegt-deutschland-wegen-srebrenica\/\">Russland r\u00fcgt Deutschland wegen Srebrenica-Resolution <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2FDeutsche-Vertretung-dr%C3%A4ngte-L%C3%A4nder-in-Afrika-und-Asien-Kritik-an-UN-Resolution-zu-Srebrenica%3A9\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/208080-trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die in Br\u00fcssel wie auch in Athen unerwartet zustande gekommene Regierung von Nordmazedonien versucht Schritt um Schritt, die nationalen Gef\u00fchle der Bewohner entgegen den fr\u00fcheren Kompromissen mit Griechenland wie mit der NATO und der EU-Kommission st\u00e4rker zu ber\u00fccksichtigen. Von Marinko U\u010dur Trotz der Tatsache, dass Griechenland und Nordmazedonien als &#8220;gute Sch\u00fcler&#8221; der EU-Administration in Br\u00fcssel [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":59469,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1717508166"],"wp_automatic_camp":["217"],"440191cb153cf262e5d8ed6e92eff3b6":["Trotz Abkommen von Prespa: Neue Konflikte zwischen Griechenland und Nordmazedonien"],"original_link":["https:\/\/de.rt.com\/international\/208080-trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/"],"_thumbnail_id":["59469"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-06-04 15:37:28\";}"],"jnews_social_counter_last_update":["1778568376"]},"categories":[19,23],"tags":[6385,22004,3649,1227,27418,55492,1381,140,50,436],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trotz Abkommen von Prespa: Neue Konflikte zwischen Griechenland und Nordmazedonien - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trotz Abkommen von Prespa: Neue Konflikte zwischen Griechenland und Nordmazedonien\" \/>\n<meta property=\"og:description\" content=\"Die in Br\u00fcssel wie auch in Athen unerwartet zustande gekommene Regierung von Nordmazedonien versucht Schritt um Schritt, die nationalen Gef\u00fchle der Bewohner entgegen den fr\u00fcheren Kompromissen mit Griechenland wie mit der NATO und der EU-Kommission st\u00e4rker zu ber\u00fccksichtigen. Von Marinko U\u010dur Trotz der Tatsache, dass Griechenland und Nordmazedonien als &#8220;gute Sch\u00fcler&#8221; der EU-Administration in Br\u00fcssel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-04T12:46:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/665efd4b48fbef1e917c03de.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Trotz Abkommen von Prespa: Neue Konflikte zwischen Griechenland und Nordmazedonien\",\"datePublished\":\"2024-06-04T12:46:19+00:00\",\"dateModified\":\"2024-06-04T12:46:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/\"},\"wordCount\":863,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Trotz-Abkommen-von-Prespa-Neue-Konflikte-zwischen-Griechenland-und-Nordmazedonien.jpg\",\"keywords\":[\"Abkommen\",\"Griechenland\",\"Konflikte\",\"NEUE\",\"Nordmazedonien\",\"Prespa\",\"Trotz\",\"und\",\"von\",\"zwischen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/\",\"name\":\"Trotz Abkommen von Prespa: Neue Konflikte zwischen Griechenland und Nordmazedonien - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Trotz-Abkommen-von-Prespa-Neue-Konflikte-zwischen-Griechenland-und-Nordmazedonien.jpg\",\"datePublished\":\"2024-06-04T12:46:19+00:00\",\"dateModified\":\"2024-06-04T12:46:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Trotz-Abkommen-von-Prespa-Neue-Konflikte-zwischen-Griechenland-und-Nordmazedonien.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Trotz-Abkommen-von-Prespa-Neue-Konflikte-zwischen-Griechenland-und-Nordmazedonien.jpg\",\"width\":460,\"height\":259,\"caption\":\"Trotz Abkommen von Prespa: Neue Konflikte zwischen Griechenland und Nordmazedonien\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trotz Abkommen von Prespa: Neue Konflikte zwischen Griechenland und Nordmazedonien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Trotz Abkommen von Prespa: Neue Konflikte zwischen Griechenland und Nordmazedonien - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/","og_locale":"de_DE","og_type":"article","og_title":"Trotz Abkommen von Prespa: Neue Konflikte zwischen Griechenland und Nordmazedonien","og_description":"Die in Br\u00fcssel wie auch in Athen unerwartet zustande gekommene Regierung von Nordmazedonien versucht Schritt um Schritt, die nationalen Gef\u00fchle der Bewohner entgegen den fr\u00fcheren Kompromissen mit Griechenland wie mit der NATO und der EU-Kommission st\u00e4rker zu ber\u00fccksichtigen. Von Marinko U\u010dur Trotz der Tatsache, dass Griechenland und Nordmazedonien als &#8220;gute Sch\u00fcler&#8221; der EU-Administration in Br\u00fcssel [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-06-04T12:46:19+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/665efd4b48fbef1e917c03de.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Trotz Abkommen von Prespa: Neue Konflikte zwischen Griechenland und Nordmazedonien","datePublished":"2024-06-04T12:46:19+00:00","dateModified":"2024-06-04T12:46:19+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/"},"wordCount":863,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Trotz-Abkommen-von-Prespa-Neue-Konflikte-zwischen-Griechenland-und-Nordmazedonien.jpg","keywords":["Abkommen","Griechenland","Konflikte","NEUE","Nordmazedonien","Prespa","Trotz","und","von","zwischen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/","url":"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/","name":"Trotz Abkommen von Prespa: Neue Konflikte zwischen Griechenland und Nordmazedonien - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Trotz-Abkommen-von-Prespa-Neue-Konflikte-zwischen-Griechenland-und-Nordmazedonien.jpg","datePublished":"2024-06-04T12:46:19+00:00","dateModified":"2024-06-04T12:46:19+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Trotz-Abkommen-von-Prespa-Neue-Konflikte-zwischen-Griechenland-und-Nordmazedonien.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Trotz-Abkommen-von-Prespa-Neue-Konflikte-zwischen-Griechenland-und-Nordmazedonien.jpg","width":460,"height":259,"caption":"Trotz Abkommen von Prespa: Neue Konflikte zwischen Griechenland und Nordmazedonien"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/trotz-abkommen-von-prespa-neue-konflikte-zwischen-griechenland-und-nordmazedonien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Trotz Abkommen von Prespa: Neue Konflikte zwischen Griechenland und Nordmazedonien"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/59468"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=59468"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/59468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/59469"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=59468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=59468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=59468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}