{"id":59393,"date":"2024-06-03T16:00:36","date_gmt":"2024-06-03T14:00:36","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/"},"modified":"2024-06-03T16:00:36","modified_gmt":"2024-06-03T14:00:36","slug":"asylantrag-des-mannheimer-messertaeters-2014-abgelehnt","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/","title":{"rendered":"Asylantrag des Mannheimer Messert\u00e4ters 2014 abgelehnt"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/665dc33ab480cc536a0e24cc.jpeg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der Asylantrag des Mannheimer Messert\u00e4ters Sulaiman A. wurde laut einem Medienbericht bereits im Jahr 2014 abgelehnt. Demnach erhielt der Afghane erst im Jahr 2022 eine befristete Aufenthaltsgenehmigung \u2013 nachdem er in Deutschland Vater eines Kindes geworden war.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Der Asylantrag des Messert\u00e4ters von Mannheim wurde bereits im Jahr 2014 abgelehnt. Das berichtet das Springerblatt <em>Welt,\u00a0<\/em>unter Berufung auf Beh\u00f6rdendokumente. Demnach erhielt der Afghane erst im Jahr 2022 eine befristete Aufenthaltsgenehmigung \u2013 nachdem er in Deutschland Vater eines Kindes geworden war.<\/p>\n<p>Der Afghane, dessen Name mit Sulaiman A. angegeben wird, attackierte am Freitag mit offensichtlicher T\u00f6tungsabsicht mehrere Menschen in Mannheim. Ein 29-j\u00e4hriger Polizist erlag am Sonntag seinen schweren Verletzungen.\u00a0<\/p>\n<p>Laut den der <em>Welt<\/em>\u00a0vorliegenden Dokumenten kam A. im Jahr 2013 aus Afghanistan nach Deutschland, wo er zun\u00e4chst in Frankfurt am Main gemeldet war. Es folgte der Umzug nach Mannheim, wobei jedoch zuvor im Jahr 2014 ein erster Antrag auf Asyl abgelehnt wurde. Der Ablehnung folgte keine Abschiebung. Im Jahr 2017 legte der Afghane laut <em>Welt<\/em>-Artikel an seinem neuen Wohnort einen erweiterten Hauptschulabschluss ab.\u00a0\u00a0<\/p>\n<p>Ebenfalls in Mannheim wurde Sulaiman A. Vater eines Kindes,\u00a0das die deutsche Staatsb\u00fcrgerschaft besitzt &#8220;und f\u00fcr das A. offenbar das Sorgerecht tr\u00e4gt \u2013 das gen\u00fcgte f\u00fcr ein Bleiberecht&#8221;, so der <em>Welt<\/em>-Artikel erl\u00e4uternd. Weiter hei\u00dft es in dem Artikel:<\/p>\n<p><em>&#8220;Fotos, die Welt vorliegen, zeigen, dass der Afghane sich optisch zwischen 2020 und 2023 deutlich ver\u00e4nderte \u2013 und sich einen Vollbart wachsen lie\u00df. Eine Spur im Internet k\u00f6nnte zudem das bislang st\u00e4rkste Indiz darstellen, dass A. eine islamistische Radikalisierungslaufbahn hinter sich hat.&#8221;<\/em><\/p>\n<p>Die Dokumente belegen daher, dass Sulaiman A. erst neun Jahre nach seiner Einreise, also im Jahr 2022, durch die zust\u00e4ndigen Beh\u00f6rden eine befristete Aufenthaltsgenehmigung nach Paragraf 28 des Aufenthaltsgesetzes erhielt.\u00a0<\/p>\n<p>Der Staatsanwaltschaft Karlsruhe lagen laut Beh\u00f6rdenangaben am Montagmorgen gegen\u00fcber der <em>Welt<\/em>-Redaktion keinerlei Informationen dazu vor, dass der Messert\u00e4ter sich in radikal islamistischen Kreisen bewegt h\u00e4tte. Dazu hei\u00dft es weiter:<\/p>\n<p><em>&#8220;Laut einer Pressemitteilung vom Samstag wurden in A.s Wohnung auch elektronische Datentr\u00e4ger sichergestellt, die nun ausgewertet werden.&#8221;<\/em><\/p>\n<p>W\u00fcrde sich &#8220;ein islamistisches Tatmotiv&#8221; nun im Nachhinein best\u00e4tigen, k\u00f6nnte der Generalbundesanwalt &#8220;die Ermittlungen an sich ziehen&#8221;, so der <em>Welt<\/em>-Artikel. Suleiman A. gilt weiterhin durch\u00a0die Schussverletzung durch einen Polizisten nicht als vernehmungsf\u00e4hig.<\/p>\n<p><strong>Mehr zum Thema &#8211;\u00a0<\/strong><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freeassange.rtde.life\/inland\/207243-berlin-abschiebung-clan-mitglieds-sollte\/\">Berlin: Abschiebung eines Clan-Mitglieds sollte durch Autoblockade verhindert werden<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2FMannheim--Mann-sticht-auf-Islamkritiker-St%C3%BCrzenberger-und-Polizisten-ein%3A8\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/207990-asylantrag-mannheimer-messermoerders-wurde-2014\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Asylantrag des Mannheimer Messert\u00e4ters Sulaiman A. wurde laut einem Medienbericht bereits im Jahr 2014 abgelehnt. Demnach erhielt der Afghane erst im Jahr 2022 eine befristete Aufenthaltsgenehmigung \u2013 nachdem er in Deutschland Vater eines Kindes geworden war. Der Asylantrag des Messert\u00e4ters von Mannheim wurde bereits im Jahr 2014 abgelehnt. Das berichtet das Springerblatt Welt,\u00a0unter Berufung [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":59394,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1717423456"],"wp_automatic_camp":["217"],"d33343ed47b5b152a4c5a439b2d438f1":["Asylantrag des Mannheimer Messert\u00e4ters 2014 abgelehnt"],"original_link":["https:\/\/de.rt.com\/inland\/207990-asylantrag-mannheimer-messermoerders-wurde-2014\/"],"_thumbnail_id":["59394"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-06-03 16:05:16\";}"],"jnews_social_counter_last_update":["1778439966"]},"categories":[19,23],"tags":[21457,55447,583,55390,55448],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Asylantrag des Mannheimer Messert\u00e4ters 2014 abgelehnt - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asylantrag des Mannheimer Messert\u00e4ters 2014 abgelehnt\" \/>\n<meta property=\"og:description\" content=\"Der Asylantrag des Mannheimer Messert\u00e4ters Sulaiman A. wurde laut einem Medienbericht bereits im Jahr 2014 abgelehnt. Demnach erhielt der Afghane erst im Jahr 2022 eine befristete Aufenthaltsgenehmigung \u2013 nachdem er in Deutschland Vater eines Kindes geworden war. Der Asylantrag des Messert\u00e4ters von Mannheim wurde bereits im Jahr 2014 abgelehnt. Das berichtet das Springerblatt Welt,\u00a0unter Berufung [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-03T14:00:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/665dc33ab480cc536a0e24cc.jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Asylantrag des Mannheimer Messert\u00e4ters 2014 abgelehnt\",\"datePublished\":\"2024-06-03T14:00:36+00:00\",\"dateModified\":\"2024-06-03T14:00:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/\"},\"wordCount\":396,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Asylantrag-des-Mannheimer-Messertaeters-2014-abgelehnt.jpeg\",\"keywords\":[\"abgelehnt\",\"Asylantrag\",\"des\",\"Mannheimer\",\"Messert\u00e4ters\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/\",\"name\":\"Asylantrag des Mannheimer Messert\u00e4ters 2014 abgelehnt - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Asylantrag-des-Mannheimer-Messertaeters-2014-abgelehnt.jpeg\",\"datePublished\":\"2024-06-03T14:00:36+00:00\",\"dateModified\":\"2024-06-03T14:00:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Asylantrag-des-Mannheimer-Messertaeters-2014-abgelehnt.jpeg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Asylantrag-des-Mannheimer-Messertaeters-2014-abgelehnt.jpeg\",\"width\":460,\"height\":259,\"caption\":\"Asylantrag des Mannheimer Messert\u00e4ters 2014 abgelehnt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asylantrag des Mannheimer Messert\u00e4ters 2014 abgelehnt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Asylantrag des Mannheimer Messert\u00e4ters 2014 abgelehnt - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/","og_locale":"de_DE","og_type":"article","og_title":"Asylantrag des Mannheimer Messert\u00e4ters 2014 abgelehnt","og_description":"Der Asylantrag des Mannheimer Messert\u00e4ters Sulaiman A. wurde laut einem Medienbericht bereits im Jahr 2014 abgelehnt. Demnach erhielt der Afghane erst im Jahr 2022 eine befristete Aufenthaltsgenehmigung \u2013 nachdem er in Deutschland Vater eines Kindes geworden war. Der Asylantrag des Messert\u00e4ters von Mannheim wurde bereits im Jahr 2014 abgelehnt. Das berichtet das Springerblatt Welt,\u00a0unter Berufung [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-06-03T14:00:36+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/665dc33ab480cc536a0e24cc.jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Asylantrag des Mannheimer Messert\u00e4ters 2014 abgelehnt","datePublished":"2024-06-03T14:00:36+00:00","dateModified":"2024-06-03T14:00:36+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/"},"wordCount":396,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Asylantrag-des-Mannheimer-Messertaeters-2014-abgelehnt.jpeg","keywords":["abgelehnt","Asylantrag","des","Mannheimer","Messert\u00e4ters"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/","url":"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/","name":"Asylantrag des Mannheimer Messert\u00e4ters 2014 abgelehnt - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Asylantrag-des-Mannheimer-Messertaeters-2014-abgelehnt.jpeg","datePublished":"2024-06-03T14:00:36+00:00","dateModified":"2024-06-03T14:00:36+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Asylantrag-des-Mannheimer-Messertaeters-2014-abgelehnt.jpeg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/06\/Asylantrag-des-Mannheimer-Messertaeters-2014-abgelehnt.jpeg","width":460,"height":259,"caption":"Asylantrag des Mannheimer Messert\u00e4ters 2014 abgelehnt"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/asylantrag-des-mannheimer-messertaeters-2014-abgelehnt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Asylantrag des Mannheimer Messert\u00e4ters 2014 abgelehnt"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/59393"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=59393"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/59393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/59394"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=59393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=59393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=59393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}