{"id":59194,"date":"2024-05-30T20:04:21","date_gmt":"2024-05-30T18:04:21","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/"},"modified":"2024-05-30T20:04:21","modified_gmt":"2024-05-30T18:04:21","slug":"oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/","title":{"rendered":"Oberst a. D. zur Ukraine: &quot;Ein Waffenstillstand wird dringlich. Die Alternativen sind Wunschdenken&quot;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/66587d38b480cc16e8670020.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Oberst a. D. Ralph Thiele sch\u00e4tzt die Lage der Ukraine als prek\u00e4r ein. Kiew kann ihm zufolge auch mit westlicher Hilfe keinen Sieg erringen. Es braucht einen Waffenstillstand, fordert er. Beim Entsenden von NATO-Truppen drohte eine Eskalation in Richtung Dritter Weltkrieg, ist seine Warnung.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die Antworten deutscher Politiker und deutscher Milit\u00e4rexperten auf die Frage, was die Ukraine braucht, sind diametral gesetzt. Die Antwort der Mehrzahl unter den deutschen Politikern ist: mehr Waffen, mehr Munition, mehr Flugabwehrsysteme. Die Antwort, die immer mehr Milit\u00e4rexperten geben, ist: Die Ukraine braucht einen Waffenstillstand und Verhandlungen.<\/p>\n<p>Der Unterschied liegt im unterschiedlichen Grad der Expertise, macht ein <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.focus.de\/politik\/ausland\/ukraine-krise\/gastbeitrag-von-ralph-d-thiele-alternativen-sind-wunschdenken-ukraine-kann-nur-auf-einem-weg-gerettet-werden_id_259984765.html\">Interview<\/a> mit Oberst a.\u00a0D. Ralph Thiele deutlich.<\/p>\n<blockquote>\n<p><em>&#8220;So wie die Ukraine Leopard- und Abrams-Panzer angefordert hat, um dann zu erkennen, dass diese auf dem Schlachtfeld nicht \u00fcberlebensf\u00e4hig sind, sind auch Patriot-Systeme kein Allheilmittel, um die extreme Verwundbarkeit der Ukraine zu beheben. Ein f\u00fcr die Ukraine positiver Ausgang dieses Konflikts ist nicht mit milit\u00e4rischer Hilfe m\u00f6glich&#8221;, sagt Thiele und setzt sich damit der Gefahr aus, von selbst ernannten Waffenexperten unter den deutschen Politikern belehrt zu werden.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Der Glaube, die Ukraine k\u00f6nnte mit Waffenlieferungen in den Stand versetzt werden, einen strategischen Sieg \u00fcber Russland zu erzielen, ist unter deutschen Politikern, aber auch im deutschen Mainstream eine gern gehegte Illusion, von der Abschied zu nehmen man noch nicht bereit ist. Dabei sind die Fakten eindeutig.<\/p>\n<blockquote>\n<p><em>&#8220;Angesichts einer zunehmend por\u00f6sen ukrainischen Front und keiner rosigen Unterst\u00fctzungsperspektiven des Westens \u2013 der braucht bis in die Jahre 2027\/2028, bis die r\u00fcstungsindustrielle Basis die &#8216;Zeitenwende&#8217; umsetzen kann \u2013 ist es eher Zeit f\u00fcr Waffenstillstandsverhandlungen als f\u00fcr eine Ausweitung und Intensivierung der K\u00e4mpfe.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Thiele belegt seine Forderung nach Verhandlungen auch mit dem Mangel an verf\u00fcgbaren Patriot-Systemen. Die Ukraine ben\u00f6tige insgesamt 25 Patriot-Systeme zum Schutz des Luftraums, besitzt aber nur drei. Die Anforderungen der Ukraine \u00fcbersteigen schlicht die Menge, die von der Herstellerfirma in einem angemessenen Zeitrahmen \u00fcberhaupt produziert werden kann. Gleiches gilt f\u00fcr die f\u00fcr den Betrieb ben\u00f6tigte Munition.<\/p>\n<blockquote>\n<p><em>&#8220;W\u00e4hrend die US-Industrie auf absehbare Zeit nicht in der Lage ist, die teuren Patriot-Abfangraketen in gro\u00dfen Mengen zu produzieren, beschafft Russland am laufenden Band Shahed-Drohnen, produziert Iskander- oder Kinschal-Raketen und stattet seine Flugzeuge mit preiswert aufger\u00fcsteten Gleitbomben aus der Sowjet-\u00c4ra aus. Auch die europ\u00e4ischen Verb\u00fcndeten k\u00f6nnen die L\u00fccke der Ukrainer nicht schlie\u00dfen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Das Entsenden von NATO-Milit\u00e4rs in die Ukraine w\u00fcrde zudem den Konflikt weiter in Richtung Dritter Weltkrieg eskalieren. Die entsendenden L\u00e4nder w\u00e4ren Kriegspartei und w\u00fcrden absehbar Ziel russischer Angriffe, meint Thiele.<\/p>\n<p>Es steht allerdings zu bef\u00fcrchten, dass die deutsche Politik gegen\u00fcber all diesen Fakten resistent bleibt und weiterhin auf eine Verl\u00e4ngerung des Krieges dr\u00e4ngt. F\u00fcr die Ukraine hat die deutsche Realit\u00e4tsverweigerung weitreichende, bittere Konsequenzen.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/207324-oberst-reisner-us-gefuehrter-angriff\/\">Oberst Reisner: US-gef\u00fchrter Angriff auf Armawir k\u00f6nnte Atomkrieg ausl\u00f6sen<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2FStarikow-Selenskij-wird-f%C3%BCr-Westen-illegitim%2C-sollte-er-Abkommen-mit-Russland-unterzeichnen%3Ad\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/207606-oberst-a-d-zur-ukraine-waffenstillstand-wird-dringlich-alternativen-sind-wunschdenken\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oberst a. D. Ralph Thiele sch\u00e4tzt die Lage der Ukraine als prek\u00e4r ein. Kiew kann ihm zufolge auch mit westlicher Hilfe keinen Sieg erringen. Es braucht einen Waffenstillstand, fordert er. Beim Entsenden von NATO-Truppen drohte eine Eskalation in Richtung Dritter Weltkrieg, ist seine Warnung. Die Antworten deutscher Politiker und deutscher Milit\u00e4rexperten auf die Frage, was [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":59195,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1717092296"],"wp_automatic_camp":["217"],"698ae1b1e4eb13fbdddb898206fbf90e":["Oberst a. D. zur Ukraine: &quot;Ein Waffenstillstand wird dringlich. Die Alternativen sind Wunschdenken&quot;"],"original_link":["https:\/\/de.rt.com\/inland\/207606-oberst-a-d-zur-ukraine-waffenstillstand-wird-dringlich-alternativen-sind-wunschdenken\/"],"_thumbnail_id":["59195"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-05-30 20:09:53\";}"],"jnews_social_counter_last_update":["1784091199"]},"categories":[19,23],"tags":[11395,45,55355,28090,19368,1046,127,23024,374,55356,581],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Oberst a. D. zur Ukraine: &quot;Ein Waffenstillstand wird dringlich. Die Alternativen sind Wunschdenken&quot; - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oberst a. D. zur Ukraine: &quot;Ein Waffenstillstand wird dringlich. Die Alternativen sind Wunschdenken&quot;\" \/>\n<meta property=\"og:description\" content=\"Oberst a. D. Ralph Thiele sch\u00e4tzt die Lage der Ukraine als prek\u00e4r ein. Kiew kann ihm zufolge auch mit westlicher Hilfe keinen Sieg erringen. Es braucht einen Waffenstillstand, fordert er. Beim Entsenden von NATO-Truppen drohte eine Eskalation in Richtung Dritter Weltkrieg, ist seine Warnung. Die Antworten deutscher Politiker und deutscher Milit\u00e4rexperten auf die Frage, was [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-30T18:04:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/66587d38b480cc16e8670020.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Oberst a. D. zur Ukraine: &quot;Ein Waffenstillstand wird dringlich. Die Alternativen sind Wunschdenken&quot;\",\"datePublished\":\"2024-05-30T18:04:21+00:00\",\"dateModified\":\"2024-05-30T18:04:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/\"},\"wordCount\":507,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Oberst-a-D-zur-Ukraine-quotEin-Waffenstillstand-wird-dringlich-Die.jpg\",\"keywords\":[\"Alternativen\",\"die\",\"dringlich\",\"Oberst\",\"quotEin\",\"sind\",\"ukraine\",\"Waffenstillstand\",\"wird\",\"Wunschdenkenquot\",\"zur\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/\",\"name\":\"Oberst a. D. zur Ukraine: &quot;Ein Waffenstillstand wird dringlich. Die Alternativen sind Wunschdenken&quot; - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Oberst-a-D-zur-Ukraine-quotEin-Waffenstillstand-wird-dringlich-Die.jpg\",\"datePublished\":\"2024-05-30T18:04:21+00:00\",\"dateModified\":\"2024-05-30T18:04:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Oberst-a-D-zur-Ukraine-quotEin-Waffenstillstand-wird-dringlich-Die.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Oberst-a-D-zur-Ukraine-quotEin-Waffenstillstand-wird-dringlich-Die.jpg\",\"width\":460,\"height\":259,\"caption\":\"Oberst a. D. zur Ukraine: &quot;Ein Waffenstillstand wird dringlich. Die Alternativen sind Wunschdenken&quot;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oberst a. D. zur Ukraine: &quot;Ein Waffenstillstand wird dringlich. Die Alternativen sind Wunschdenken&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Oberst a. D. zur Ukraine: &quot;Ein Waffenstillstand wird dringlich. Die Alternativen sind Wunschdenken&quot; - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/","og_locale":"de_DE","og_type":"article","og_title":"Oberst a. D. zur Ukraine: &quot;Ein Waffenstillstand wird dringlich. Die Alternativen sind Wunschdenken&quot;","og_description":"Oberst a. D. Ralph Thiele sch\u00e4tzt die Lage der Ukraine als prek\u00e4r ein. Kiew kann ihm zufolge auch mit westlicher Hilfe keinen Sieg erringen. Es braucht einen Waffenstillstand, fordert er. Beim Entsenden von NATO-Truppen drohte eine Eskalation in Richtung Dritter Weltkrieg, ist seine Warnung. Die Antworten deutscher Politiker und deutscher Milit\u00e4rexperten auf die Frage, was [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-05-30T18:04:21+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/66587d38b480cc16e8670020.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Oberst a. D. zur Ukraine: &quot;Ein Waffenstillstand wird dringlich. Die Alternativen sind Wunschdenken&quot;","datePublished":"2024-05-30T18:04:21+00:00","dateModified":"2024-05-30T18:04:21+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/"},"wordCount":507,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Oberst-a-D-zur-Ukraine-quotEin-Waffenstillstand-wird-dringlich-Die.jpg","keywords":["Alternativen","die","dringlich","Oberst","quotEin","sind","ukraine","Waffenstillstand","wird","Wunschdenkenquot","zur"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/","url":"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/","name":"Oberst a. D. zur Ukraine: &quot;Ein Waffenstillstand wird dringlich. Die Alternativen sind Wunschdenken&quot; - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Oberst-a-D-zur-Ukraine-quotEin-Waffenstillstand-wird-dringlich-Die.jpg","datePublished":"2024-05-30T18:04:21+00:00","dateModified":"2024-05-30T18:04:21+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Oberst-a-D-zur-Ukraine-quotEin-Waffenstillstand-wird-dringlich-Die.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Oberst-a-D-zur-Ukraine-quotEin-Waffenstillstand-wird-dringlich-Die.jpg","width":460,"height":259,"caption":"Oberst a. D. zur Ukraine: &quot;Ein Waffenstillstand wird dringlich. Die Alternativen sind Wunschdenken&quot;"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/oberst-a-d-zur-ukraine-ein-waffenstillstand-wird-dringlich-die-alternativen-sind-wunschdenken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Oberst a. D. zur Ukraine: &quot;Ein Waffenstillstand wird dringlich. Die Alternativen sind Wunschdenken&quot;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/59194"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=59194"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/59194\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/59195"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=59194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=59194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=59194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}