{"id":59068,"date":"2024-05-29T13:05:37","date_gmt":"2024-05-29T11:05:37","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/"},"modified":"2024-05-29T13:05:37","modified_gmt":"2024-05-29T11:05:37","slug":"macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/","title":{"rendered":"Macron will Einsatzgebiet westlicher Waffen im Ukraine-Krieg ausweiten \u2013 Scholz widerspricht nicht"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/6656f570b480cc464f2f2c1f.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Frankreichs Pr\u00e4sident sprach sich in Berlin daf\u00fcr aus, der Ukraine Angriffe auf russische Stellungen mit westlichen Waffen zu erlauben. Scholz widersprach dem nicht. &#8220;Wir m\u00fcssen ihnen erlauben, milit\u00e4rische St\u00fctzpunkte zu neutralisieren, von denen aus Raketen abgefeuert werden&#8221;, sagte Macron.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Zum Abschluss seines dreit\u00e4gigen Staatsbesuchs traf Frankreichs Pr\u00e4sident Emmanuel Macron mit Bundeskanzler Olaf Scholz in Meseberg f\u00fcr Beratungen zusammen. In einem gemeinsamen Pressestatement sprechen beide Regierungschefs, Berichten zufolge, &#8220;\u00fcber den deutsch-franz\u00f6sischen Beitrag f\u00fcr Europas Sicherheit&#8221;.<\/p>\n<p>Frankreichs\u00a0Pr\u00e4sident will der Ukraine\u00a0Angriffe auf Stellungen in Russland erm\u00f6glichen. &#8220;Wir m\u00fcssen ihnen erlauben,\u00a0milit\u00e4rische St\u00fctzpunkte zu neutralisieren, von denen aus Raketen abgefeuert werden&#8221;, sagte Macron bei einem deutsch-franz\u00f6sischen Regierungstreffen auf Schloss Meseberg bei Berlin.\u00a0&#8220;Wir liefern euch Waffen, aber ihr d\u00fcrft euch nicht verteidigen&#8221;\u00a0\u2013 mit diesem Satz bem\u00e4ngelte Macron die bisherige Strategie des Westens. Das war der Moment, an dem Frankreichs Pr\u00e4sident\u00a0eine Karte von der Front in der Ukraine hervorholte und sie den Journalisten zeigte. Scholz widersprach\u00a0den Ausf\u00fchrungen\u00a0nicht. Er verwies\u00a0lediglich auf das V\u00f6lkerrecht, das stehe solchen Eins\u00e4tzen nach allgemeiner Auffassung nicht entgegen. Scholz sagte also, die Ukraine habe v\u00f6lkerrechtlich alle M\u00f6glichkeiten f\u00fcr das, was sie gegen die russische Armee tue.\u00a0<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">In Meseberg betonen Macron und Scholz, dass die Ukraine sehr wohl gelieferte Waffen einsetzen darf, um Ziele in Russland zu beschie\u00dfen, von denen aus sie angegriffen wird. Macron will aber auch eine M\u00f6glichkeit f\u00fcr die Attacke auf solche Ziele im russischen Hinterland \ud83c\uddfa\ud83c\udde6 \ud83c\udde9\ud83c\uddea \ud83c\uddeb\ud83c\uddf7 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/waeYUlFZiO\">pic.twitter.com\/waeYUlFZiO<\/a><\/p>\n<p>\u2014 Andreas Rinke (@Andreas__Rinke) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/Andreas__Rinke\/status\/1795535137880297880?ref_src=twsrc%5Etfw\">May 28, 2024<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Eine Kapitulation der Ukraine sei nicht hinnehmbar, beteuerte Macron. &#8220;Dieser Krieg hat uns wachger\u00fcttelt&#8221;, so der Pr\u00e4sident. Die Ukraine sei dabei, die Sicherheit Europas zu verteidigen, behauptete der franz\u00f6sische Staatschef. Er lobte, dass Deutschland fortan bereit sei, viel in seine Verteidigung zu investieren.<\/p>\n<p>Macron verk\u00fcndete, dass der ukrainische Pr\u00e4sident Selenskij an den Feierlichkeiten zum 80. Jahrestag der Landung der Alliierten in der Normandie teilnehmen werde. Er werde ihm bei dieser Gelegenheit &#8220;sehr genau&#8221; mitteilen, was die westlichen Verb\u00fcndeten zur Unterst\u00fctzung der Ukraine unternehmen w\u00fcrden.\u00a0<\/p>\n<p>Bei dem Treffen in Meseberg wurde verk\u00fcndet, dass Deutschland\u00a0und\u00a0Frankreich gemeinsam Langstreckenraketen entwickeln wollen: In einer Erkl\u00e4rung des deutsch-franz\u00f6sischen Sicherheits- und Verteidigungsrates haben die beiden L\u00e4nder zum Abschluss des dreit\u00e4gigen Staatsbesuchs von Macron in Deutschland angek\u00fcndigt, angesichts der ver\u00e4nderten sicherheitspolitischen Lage die\u00a0europ\u00e4ischen Verteidigungsf\u00e4higkeiten auszubauen. Gemeinsam mit weiteren Partnern soll daf\u00fcr unter anderem eine umfassende Zusammenarbeit im Bereich der\u00a0Entwicklung von Langstreckenwaffen\u00a0eingegangen werden, teilte der Rat\u00a0mit. Damit soll auch die R\u00fcstungsindustrie gest\u00e4rkt werden.\u00a0<\/p>\n<p>Beide L\u00e4nder seien sich \u00fcber &#8220;die zentrale Bedeutung der nuklearen Abschreckung f\u00fcr die Sicherheit Europas und der\u00a0NATO&#8221; einig, hei\u00dft es in der Erkl\u00e4rung weiter. Dies gelte auch f\u00fcr die Abschreckungsrolle der strategischen franz\u00f6sischen Nuklearstreitkr\u00e4fte.\u00a0Paris und Berlin\u00a0unterst\u00fctzten demnach eine Mischung aus nuklearen, konventionellen und Raketenabwehrf\u00e4higkeiten, erkl\u00e4rte der Sicherheitsrat. Diese sollen zudem durch F\u00e4higkeiten im Bereich der Weltraum- und Cyberabwehr erg\u00e4nzt werden.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freeassange.rtde.life\/inland\/207212-bilderstrecke-besten-bilder-von-macrons\/\">Bilderstrecke: Die &#8220;besten&#8221; Bilder von Macrons Besuch in Bellevue<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2F-Der-in-die-Ukraine-einmarschieren-will---%E2%80%93-Macron-erh%C3%A4lt-Friedenspreis-in-M%C3%BCnster%3A1\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/207404-macron-will-einsatzgebiet-westlicher-waffen\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frankreichs Pr\u00e4sident sprach sich in Berlin daf\u00fcr aus, der Ukraine Angriffe auf russische Stellungen mit westlichen Waffen zu erlauben. Scholz widersprach dem nicht. &#8220;Wir m\u00fcssen ihnen erlauben, milit\u00e4rische St\u00fctzpunkte zu neutralisieren, von denen aus Raketen abgefeuert werden&#8221;, sagte Macron. Zum Abschluss seines dreit\u00e4gigen Staatsbesuchs traf Frankreichs Pr\u00e4sident Emmanuel Macron mit Bundeskanzler Olaf Scholz in Meseberg [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":59069,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1716981097"],"wp_automatic_camp":["217"],"f4b202e1c89602127f6b76ffee429280":["Macron will Einsatzgebiet westlicher Waffen im Ukraine-Krieg ausweiten \u2013 Scholz widerspricht nicht"],"original_link":["https:\/\/de.rt.com\/international\/207404-macron-will-einsatzgebiet-westlicher-waffen\/"],"_thumbnail_id":["59069"],"jnews_social_counter_last_update":["1788336502"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-05-29 13:14:07\";}"]},"categories":[19,23],"tags":[1080,55299,1711,800,1001,566,1023,16696,3932],"class_list":["post-59068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-ausweiten","tag-einsatzgebiet","tag-macron","tag-nicht","tag-scholz","tag-ukrainekrieg","tag-waffen","tag-westlicher","tag-widerspricht"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Macron will Einsatzgebiet westlicher Waffen im Ukraine-Krieg ausweiten \u2013 Scholz widerspricht nicht - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Macron will Einsatzgebiet westlicher Waffen im Ukraine-Krieg ausweiten \u2013 Scholz widerspricht nicht\" \/>\n<meta property=\"og:description\" content=\"Frankreichs Pr\u00e4sident sprach sich in Berlin daf\u00fcr aus, der Ukraine Angriffe auf russische Stellungen mit westlichen Waffen zu erlauben. Scholz widersprach dem nicht. &#8220;Wir m\u00fcssen ihnen erlauben, milit\u00e4rische St\u00fctzpunkte zu neutralisieren, von denen aus Raketen abgefeuert werden&#8221;, sagte Macron. Zum Abschluss seines dreit\u00e4gigen Staatsbesuchs traf Frankreichs Pr\u00e4sident Emmanuel Macron mit Bundeskanzler Olaf Scholz in Meseberg [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-29T11:05:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/6656f570b480cc464f2f2c1f.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Macron will Einsatzgebiet westlicher Waffen im Ukraine-Krieg ausweiten \u2013 Scholz widerspricht nicht\",\"datePublished\":\"2024-05-29T11:05:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\\\/\"},\"wordCount\":550,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Macron-will-Einsatzgebiet-westlicher-Waffen-im-Ukraine-Krieg-ausweiten-\u2013-Scholz.jpg\",\"keywords\":[\"ausweiten\",\"Einsatzgebiet\",\"macron\",\"nicht\",\"Scholz\",\"UkraineKrieg\",\"Waffen\",\"westlicher\",\"widerspricht\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\\\/\",\"name\":\"Macron will Einsatzgebiet westlicher Waffen im Ukraine-Krieg ausweiten \u2013 Scholz widerspricht nicht - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Macron-will-Einsatzgebiet-westlicher-Waffen-im-Ukraine-Krieg-ausweiten-\u2013-Scholz.jpg\",\"datePublished\":\"2024-05-29T11:05:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Macron-will-Einsatzgebiet-westlicher-Waffen-im-Ukraine-Krieg-ausweiten-\u2013-Scholz.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Macron-will-Einsatzgebiet-westlicher-Waffen-im-Ukraine-Krieg-ausweiten-\u2013-Scholz.jpg\",\"width\":460,\"height\":259,\"caption\":\"Macron will Einsatzgebiet westlicher Waffen im Ukraine-Krieg ausweiten \u2013 Scholz widerspricht nicht\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Macron will Einsatzgebiet westlicher Waffen im Ukraine-Krieg ausweiten \u2013 Scholz widerspricht nicht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Macron will Einsatzgebiet westlicher Waffen im Ukraine-Krieg ausweiten \u2013 Scholz widerspricht nicht - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/","og_locale":"de_DE","og_type":"article","og_title":"Macron will Einsatzgebiet westlicher Waffen im Ukraine-Krieg ausweiten \u2013 Scholz widerspricht nicht","og_description":"Frankreichs Pr\u00e4sident sprach sich in Berlin daf\u00fcr aus, der Ukraine Angriffe auf russische Stellungen mit westlichen Waffen zu erlauben. Scholz widersprach dem nicht. &#8220;Wir m\u00fcssen ihnen erlauben, milit\u00e4rische St\u00fctzpunkte zu neutralisieren, von denen aus Raketen abgefeuert werden&#8221;, sagte Macron. Zum Abschluss seines dreit\u00e4gigen Staatsbesuchs traf Frankreichs Pr\u00e4sident Emmanuel Macron mit Bundeskanzler Olaf Scholz in Meseberg [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-05-29T11:05:37+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/6656f570b480cc464f2f2c1f.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Macron will Einsatzgebiet westlicher Waffen im Ukraine-Krieg ausweiten \u2013 Scholz widerspricht nicht","datePublished":"2024-05-29T11:05:37+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/"},"wordCount":550,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Macron-will-Einsatzgebiet-westlicher-Waffen-im-Ukraine-Krieg-ausweiten-\u2013-Scholz.jpg","keywords":["ausweiten","Einsatzgebiet","macron","nicht","Scholz","UkraineKrieg","Waffen","westlicher","widerspricht"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/","url":"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/","name":"Macron will Einsatzgebiet westlicher Waffen im Ukraine-Krieg ausweiten \u2013 Scholz widerspricht nicht - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Macron-will-Einsatzgebiet-westlicher-Waffen-im-Ukraine-Krieg-ausweiten-\u2013-Scholz.jpg","datePublished":"2024-05-29T11:05:37+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Macron-will-Einsatzgebiet-westlicher-Waffen-im-Ukraine-Krieg-ausweiten-\u2013-Scholz.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Macron-will-Einsatzgebiet-westlicher-Waffen-im-Ukraine-Krieg-ausweiten-\u2013-Scholz.jpg","width":460,"height":259,"caption":"Macron will Einsatzgebiet westlicher Waffen im Ukraine-Krieg ausweiten \u2013 Scholz widerspricht nicht"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/macron-will-einsatzgebiet-westlicher-waffen-im-ukraine-krieg-ausweiten-scholz-widerspricht-nicht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Macron will Einsatzgebiet westlicher Waffen im Ukraine-Krieg ausweiten \u2013 Scholz widerspricht nicht"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/59068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=59068"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/59068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/59069"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=59068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=59068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=59068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}