{"id":58881,"date":"2024-05-27T08:21:56","date_gmt":"2024-05-27T06:21:56","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/"},"modified":"2024-05-27T08:21:56","modified_gmt":"2024-05-27T06:21:56","slug":"frankreichs-neokoloniales-imperium-zeigt-risse","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/","title":{"rendered":"Frankreichs neokoloniales Imperium zeigt Risse"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/664c9fa948fbef2953510a12.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Paris will in der Ukraine-Krise zwischen den Gro\u00dfen mitmischen, dabei hat es genug Probleme im eigenen Land. In Afrika verliert Frankreich immer mehr Kontrolle \u00fcber die ehemaligen Kolonien und auch in anderen Teilen der Welt schwindet seine Macht.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Jewgeni Balakin<\/em><\/p>\n<p>Die Zeit der Kolonialreiche ist vorbei, aber Paris glaubt, dass die Zeit keine Macht \u00fcber Frankreich hat. In diesem Augenblick unterdr\u00fccken die franz\u00f6sischen Streitkr\u00e4fte Proteste in Neukaledonien (einer Inselgruppe in Ozeanien). Findet vor unseren Augen eine Invasion in einem fernen Land am anderen Ende der Welt statt?<\/p>\n<p>In der Tat kann eine solche Meinung entstehen. Rechtlich gesehen ist der Fall jedoch komplizierter: Neukaledonien ist eines der &#8220;\u00dcberseegebiete&#8221; Frankreichs und steht unter dessen Verwaltung. Au\u00dferdem sind die Besitzt\u00fcmer dieser europ\u00e4ischen Macht au\u00dferhalb des Kontinents nicht auf einen einzigen Punkt auf der Landkarte beschr\u00e4nkt, sondern umfassen dreizehn &#8220;\u00dcberseegebiete&#8221; mit unterschiedlichem Rechtsstatus, von denen Neukaledonien das unabh\u00e4ngigste ist. Es ist nicht das erste Mal, dass sich Neukaledonien gegen Paris auflehnt und versucht, unabh\u00e4ngig zu werden.<\/p>\n<p>Es sei daran erinnert, dass Frankreich Neukaledonien im Jahr 1853 zu seinem Besitz erkl\u00e4rte und seither seine Vorherrschaft auf den Inseln ziemlich rigide aufrechterhielt. Unter dem Druck der antikolonialen Prozesse, die durch die Ergebnisse des Zweiten Weltkriegs ausgel\u00f6st wurden, erhielt die Inselgruppe 1946 den Status eines &#8220;\u00dcberseegebiets&#8221;, was sich jedoch als reines Wortspiel erwies. In den 1980er-Jahren bildete sich eine Unabh\u00e4ngigkeitsbewegung, und als Ergebnis einer langen Auseinandersetzung (die sogar die Form eines bewaffneten Konflikts annahm) wurde 1998 das Abkommen von Noum\u00e9a geschlossen, das die Autonomie der Gebiete ausweitet und eine zwanzigj\u00e4hrige \u00dcbergangszeit vorsieht, gefolgt von einem Referendum im Jahr 2018. F\u00fcr den Fall, dass die Abspaltung abgelehnt wird, war die M\u00f6glichkeit von zwei weiteren Volksabstimmungen bis 2022 vorgesehen.<\/p>\n<p>Zugegebenerma\u00dfen wurden alle drei von der franz\u00f6sischen Regierung versprochenen Volksabstimmungen durchgef\u00fchrt. Allerdings haben die Beh\u00f6rden des Mutterlandes immer wieder zu T\u00e4uschungsman\u00f6vern gegriffen, um die ehemalige Kolonie unter ihrer Verwaltung zu halten. So wurde unter anderem allen Einwohnern Neukaledoniens, die bereits vor 1994 dort lebten, das Stimmrecht einger\u00e4umt und nicht nur den Kanaken, die seit jeher das Land bewohnten. Und da Frankreich die Quote der einheimischen Bev\u00f6lkerung seit dem 19. Jahrhundert gezielt durch die Ansiedlung von Migranten (insbesondere von 1864 bis 1896 durch die \u00dcbersiedlung von Kriminellen auf das Archipel) verringert hat, ist es Paris bisher gelungen, eine formale Mehrheit gegen eine Abspaltung zu erreichen, wenn auch nur mit minimalem Vorsprung. In diesem Zusammenhang w\u00fcrde die Verfassungsreform, die die franz\u00f6sischen Beh\u00f6rden seit dem 13. Mai 2024 in Erw\u00e4gung ziehen, um die Rechte der Migranten in Neukaledonien zu erweitern, jeden Versuch der einheimischen Bev\u00f6lkerung, auf friedlichem Wege die Unabh\u00e4ngigkeit zu erlangen, zunichtemachen, was der Grund f\u00fcr die aktuellen Proteste ist.<\/p>\n<p>Die einheimische Bev\u00f6lkerung Neukaledoniens ist jedoch nicht die einzige, die von den (neo-)kolonialen Praktiken Frankreichs betroffen ist. Die franz\u00f6sischen Beh\u00f6rden nutzen die Migration als Mittel, um ihren Willen durchzusetzen, und halten Korsika weiterhin unter ihrer Kontrolle. Im Fall von Neukaledonien f\u00fcrchten die Franzosen, die Kontrolle \u00fcber die zweitgr\u00f6\u00dften Nickelreserven der Welt zu verlieren, die etwa elf Prozent der Gesamtreserven ausmachen; im Fall von Korsika \u00fcber einen Vorposten im Mittelmeer. Zu diesem Zweck haben sie lange und hartn\u00e4ckig versucht, die V\u00f6lker dieser Inseln durch eine &#8220;Masse von Arbeitern&#8221; zu ersetzen, was, wie der britische Soziologe Michael Mann treffend formuliert, nicht nur eine Perversion der Demokratie ist (die die franz\u00f6sischen Gesetzgeber nun theatralisch beschw\u00f6ren), sondern auch eine Form von V\u00f6lkermord.<\/p>\n<p>Das Arsenal der franz\u00f6sischen Beh\u00f6rden zum Machterhalt in den ehemaligen Kolonien umfasst nicht nur &#8220;sanften V\u00f6lkermord&#8221;, sondern ebenso perverse Formen der Unterwerfung. Um die Kontrolle \u00fcber afrikanische L\u00e4nder aufrechtzuerhalten, zwangen sie deren Regierungen im Jahr 1945 den sogenannten CFA-Franc auf. Obwohl das Akronym CFA im Laufe der Zeit eine recht neutrale Bedeutung erhielt, spiegelte seine urspr\u00fcngliche Bedeutung (colonies fran\u00e7aises d\u2019Afrique \u2013 Kolonien Frankreichs in Afrika) die wahren Absichten von Paris wider. Durch die Kontrolle des Wechselkurses der W\u00e4hrungen formal unabh\u00e4ngiger L\u00e4nder mithilfe des CFA (was wohlgemerkt den UN-Grunds\u00e4tzen widerspricht), entzieht Frankreich ihnen nicht nur j\u00e4hrlich etwa eine Billion US-Dollar, sondern verschafft sich auch leichten Zugang zu Ressourcen. Es versteht sich von selbst, was aus der Wirtschaft des ehemaligen Mutterlandes ohne afrikanisches Uran und Gold werden w\u00fcrde.<\/p>\n<p>Koloniale Gewohnheiten sind schwer zu \u00fcberwinden. Da die franz\u00f6sischen Beh\u00f6rden vierzehn afrikanische L\u00e4nder mit dem CFA-Franc kontrollieren, k\u00fcmmert es sie kaum, dass elf von ihnen zu den weltweit am wenigsten entwickelten L\u00e4ndern geh\u00f6ren. Doch es gibt f\u00fcr Paris genug Grund zur Sorge: Seit der Erfindung des CFA haben bereits acht L\u00e4nder diese &#8220;stabile W\u00e4hrung&#8221; aufgegeben. Au\u00dferdem k\u00f6nnten Niger, Burkina Faso und Mali diesem Beispiel bald folgen. Angesichts der raschen Verringerung der milit\u00e4rischen Pr\u00e4senz Frankreichs auf dem Kontinent und einer Reihe von antifranz\u00f6sischen Rebellionen ist es unwahrscheinlich, dass das ehemalige Mutterland in der Lage sein wird, seinen &#8220;guten Willen&#8221; durchzusetzen und diese Prozesse aufzuhalten.<\/p>\n<p>Die Vergangenheit Frankreichs ist gepr\u00e4gt von schillernder Gr\u00f6\u00dfe, aber seine Zukunft k\u00f6nnte d\u00fcster ausfallen. In fast allen Teilen der Welt gibt es Fragmente des franz\u00f6sischen Kolonialreichs, allerdings gibt es immer weniger Macht, um sie zu halten. Paris will zu den f\u00fchrenden M\u00e4chten in der Ukraine-Krise geh\u00f6ren, setzt seine eigenen Interessen in Armenien, Moldawien und Kasachstan durch, hat aber Schwierigkeiten, mit den Protesten in Neukaledonien fertig zu werden, das es rechtlich als sein Territorium betrachtet. Und die Migration, die Paris als Waffe in seiner Au\u00dfenpolitik einsetzt, bereitet ihm im eigenen Land bereits gro\u00dfe Probleme.<\/p>\n<p>Wenn Frankreich seine Besitzt\u00fcmer au\u00dferhalb des Kontinents verlieren sollte, wird es zu einer der gew\u00f6hnlichen M\u00e4chte der europ\u00e4ischen Halbinsel, deren geopolitisches Gewicht in den kommenden Jahrzehnten nur noch abnehmen wird. Das ehemalige Imperium hat seinen Untertanen einfach nichts mehr zu bieten: weder Soft Power, noch eine starke Hand, noch die Illusion eines ges\u00e4ttigten Wohlstandes. Die Zeit der (neo-)kolonialen Imperien ist vorbei, ganz gleich, wie sehr sich die Pariser Beh\u00f6rden vom Gegenteil zu \u00fcberzeugen versuchen.<\/p>\n<p><em>\u00dcbersetzt aus dem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/ria.ru\/20240521\/frantsiya-1947323138.html\">Russischen<\/a>. Zuerst erschienen bei RIA Nowosti am 21. Mai 2024.<\/em><\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/asien\/206286-polizei-raeumt-strasse-zum-flughafen\/\">Polizei r\u00e4umt Stra\u00dfe zum Flughafen \u2013 Frankreich leitet Gro\u00dfeinsatz in Neukaledonien ein <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2FGewaltt%C3%A4tige-Proteste-in-Neukaledonien--B%C3%BCrger-kommen-zum-Schutz-ihrer-Viertel-zusammen%3A2\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/206515-frankreichs-neokoloniales-imperium-zeigt-risse\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paris will in der Ukraine-Krise zwischen den Gro\u00dfen mitmischen, dabei hat es genug Probleme im eigenen Land. In Afrika verliert Frankreich immer mehr Kontrolle \u00fcber die ehemaligen Kolonien und auch in anderen Teilen der Welt schwindet seine Macht. Von Jewgeni Balakin Die Zeit der Kolonialreiche ist vorbei, aber Paris glaubt, dass die Zeit keine Macht [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":58882,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1716791282"],"wp_automatic_camp":["217"],"bfa6ff300da8eb1c1712d480bd09d142":["Frankreichs neokoloniales Imperium zeigt Risse"],"original_link":["https:\/\/de.rt.com\/international\/206515-frankreichs-neokoloniales-imperium-zeigt-risse\/"],"_thumbnail_id":["58882"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-05-27 08:30:37\";}"],"jnews_social_counter_last_update":["1784117197"]},"categories":[19,23],"tags":[19886,13261,48406,6251,5315],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Frankreichs neokoloniales Imperium zeigt Risse - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frankreichs neokoloniales Imperium zeigt Risse\" \/>\n<meta property=\"og:description\" content=\"Paris will in der Ukraine-Krise zwischen den Gro\u00dfen mitmischen, dabei hat es genug Probleme im eigenen Land. In Afrika verliert Frankreich immer mehr Kontrolle \u00fcber die ehemaligen Kolonien und auch in anderen Teilen der Welt schwindet seine Macht. Von Jewgeni Balakin Die Zeit der Kolonialreiche ist vorbei, aber Paris glaubt, dass die Zeit keine Macht [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-27T06:21:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/664c9fa948fbef2953510a12.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Frankreichs neokoloniales Imperium zeigt Risse\",\"datePublished\":\"2024-05-27T06:21:56+00:00\",\"dateModified\":\"2024-05-27T06:21:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/\"},\"wordCount\":1065,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Frankreichs-neokoloniales-Imperium-zeigt-Risse.jpg\",\"keywords\":[\"Frankreichs\",\"Imperium\",\"neokoloniales\",\"Risse\",\"zeigt\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/\",\"name\":\"Frankreichs neokoloniales Imperium zeigt Risse - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Frankreichs-neokoloniales-Imperium-zeigt-Risse.jpg\",\"datePublished\":\"2024-05-27T06:21:56+00:00\",\"dateModified\":\"2024-05-27T06:21:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Frankreichs-neokoloniales-Imperium-zeigt-Risse.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Frankreichs-neokoloniales-Imperium-zeigt-Risse.jpg\",\"width\":460,\"height\":259,\"caption\":\"Frankreichs neokoloniales Imperium zeigt Risse\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frankreichs neokoloniales Imperium zeigt Risse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frankreichs neokoloniales Imperium zeigt Risse - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/","og_locale":"de_DE","og_type":"article","og_title":"Frankreichs neokoloniales Imperium zeigt Risse","og_description":"Paris will in der Ukraine-Krise zwischen den Gro\u00dfen mitmischen, dabei hat es genug Probleme im eigenen Land. In Afrika verliert Frankreich immer mehr Kontrolle \u00fcber die ehemaligen Kolonien und auch in anderen Teilen der Welt schwindet seine Macht. Von Jewgeni Balakin Die Zeit der Kolonialreiche ist vorbei, aber Paris glaubt, dass die Zeit keine Macht [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-05-27T06:21:56+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/664c9fa948fbef2953510a12.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Frankreichs neokoloniales Imperium zeigt Risse","datePublished":"2024-05-27T06:21:56+00:00","dateModified":"2024-05-27T06:21:56+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/"},"wordCount":1065,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Frankreichs-neokoloniales-Imperium-zeigt-Risse.jpg","keywords":["Frankreichs","Imperium","neokoloniales","Risse","zeigt"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/","url":"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/","name":"Frankreichs neokoloniales Imperium zeigt Risse - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Frankreichs-neokoloniales-Imperium-zeigt-Risse.jpg","datePublished":"2024-05-27T06:21:56+00:00","dateModified":"2024-05-27T06:21:56+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Frankreichs-neokoloniales-Imperium-zeigt-Risse.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Frankreichs-neokoloniales-Imperium-zeigt-Risse.jpg","width":460,"height":259,"caption":"Frankreichs neokoloniales Imperium zeigt Risse"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/frankreichs-neokoloniales-imperium-zeigt-risse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Frankreichs neokoloniales Imperium zeigt Risse"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/58881"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=58881"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/58881\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/58882"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=58881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=58881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=58881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}