{"id":58712,"date":"2024-05-23T21:10:49","date_gmt":"2024-05-23T19:10:49","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/"},"modified":"2024-05-23T21:10:49","modified_gmt":"2024-05-23T19:10:49","slug":"slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/","title":{"rendered":"Slowakischer Politiker: Fico-Attent\u00e4ter ist ein proukrainischer Terrorist aus Lager der US-Medien"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/664f5d43b480cc66b96d6049.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Juraj Cintula, der den slowakischen Premier Robert Fico t\u00f6ten wollte, sei ein &#8220;politischer Fanatiker&#8221; aus dem Lager der liberalen US-Medien, meint \u013dubo\u0161 Blaha, der Vizesprecher des Nationalrats der Slowakischen Republik. Diese Tatsache wollten sie nun vertuschen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>\u013dubo\u0161 Blaha, der stellvertretende Sprecher des Nationalrats der Slowakischen Republik, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/LubosBlahaSmer\/1838\">wirft<\/a>\u00a0den liberalen Medien in den USA vor, Falschinformationen zu verbreiten. Hierbei \u00e4u\u00dfert er sich in einem auf Telegram ver\u00f6ffentlichten Beitrag dazu, was die <em>New York Times<\/em> (<em>NYT<\/em>) \u00fcber Juraj Cintula berichtet, der k\u00fcrzlich ein Attentat auf den slowakischen Ministerpr\u00e4sidenten Robert Fico ver\u00fcbt hat.<\/p>\n<p>Die liberale US-Zeitung gebe zwar zu, dass der Fico-Attent\u00e4ter proukrainisch sei, bringe dies aber &#8220;demagogisch mit seinen angeblichen Sympathien f\u00fcr ukrainische extreme Rechte&#8221; in Verbindung, betont Blaha. Dabei sei Cintula ein Anh\u00e4nger der liberalen Partei Progressive Slowakei (PS), die von der Staatspr\u00e4sidentin Zuzana \u010caputov\u00e1 gegr\u00fcndet wurde.<\/p>\n<p>Ferner betont der Politiker, dass die <em>NYT<\/em> unter anderem auch die Tatsache verschweige, dass Cintula den fr\u00fcheren US-Pr\u00e4sidenten Donald Trump kritisiert habe. Diese Kritik sei ein Thema, das ihm und den slowakischen Progressiven gemeinsam sei, f\u00fcgte Blaha hinzu. Und weiter:<\/p>\n<blockquote>\n<p><em>&#8220;Die amerikanischen liberalen Medien versuchen zu vertuschen, dass der Attent\u00e4ter und potenzielle Terrorist Cintula ein politischer Fanatiker aus ihrem eigenen Lager ist \u2013 proukrainisch, gegen Trump, progressiv.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Wie der Vizesprecher des slowakischen Parlaments feststellt, verschweigt die liberale Gemeinschaft in den Vereinigten Staaten von Amerika, dass ihre eigenen Aktivisten auf politischen Terror zur\u00fcckgreifen w\u00fcrden.<\/p>\n<p>Die slowakische Tageszeitung <em>SME<\/em> habe in einem Artikel den russischen Medien vorgeworfen, eine Desinformationskampagne zum Mordanschlag auf Robert Fico gestartet zu haben, schreibt Blaha weiter. Tats\u00e4chlich w\u00fcrden die Falschinformationen von den liberalen Medien der USA verbreitet, stellte er klar.<\/p>\n<p>Am 15. Mai war Fico mehrfach angeschossen worden. Der Ministerpr\u00e4sident wurde ins Krankenhaus eingeliefert und operiert. Sein Zustand wurde als ernst eingesch\u00e4tzt. Der Sch\u00fctze, der 71-j\u00e4hrige Schriftsteller Juraj Cintula, der am Tatort festgenommen wurde, erkl\u00e4rte seine Tat mit politischen Motiven. Ihm droht eine lebenslange Haftstrafe. Das slowakische Innenministerium r\u00e4umte ein, dass der Sch\u00fctze nicht allein gehandelt haben k\u00f6nnte.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/206635-russlands-auslandsgeheimdienst-zu-mordanschlag-auf-fico\/\">Russlands Auslandsgeheimdienst zum Mordanschlag auf Fico: Westen greift zu politischem Terror<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/206817-slowakischer-politiker-fico-attentaeter-ist\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juraj Cintula, der den slowakischen Premier Robert Fico t\u00f6ten wollte, sei ein &#8220;politischer Fanatiker&#8221; aus dem Lager der liberalen US-Medien, meint \u013dubo\u0161 Blaha, der Vizesprecher des Nationalrats der Slowakischen Republik. Diese Tatsache wollten sie nun vertuschen. \u013dubo\u0161 Blaha, der stellvertretende Sprecher des Nationalrats der Slowakischen Republik, wirft\u00a0den liberalen Medien in den USA vor, Falschinformationen zu [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":58713,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1716492366"],"wp_automatic_camp":["217"],"8ffc344e98d237f80b15da4eb1ebfeb9":["Slowakischer Politiker: Fico-Attent\u00e4ter ist ein proukrainischer Terrorist aus Lager der US-Medien"],"original_link":["https:\/\/de.rt.com\/europa\/206817-slowakischer-politiker-fico-attentaeter-ist\/"],"_thumbnail_id":["58713"],"jnews_social_counter_last_update":["1788219575"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-05-23 21:33:18\";}"]},"categories":[19,23],"tags":[679,82,357,55119,414,30132,5679,50223,41148,33286,18617],"class_list":["post-58712","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-aus","tag-der","tag-ein","tag-ficoattentaeter","tag-ist","tag-lager","tag-politiker","tag-proukrainischer","tag-slowakischer","tag-terrorist","tag-usmedien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Slowakischer Politiker: Fico-Attent\u00e4ter ist ein proukrainischer Terrorist aus Lager der US-Medien - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slowakischer Politiker: Fico-Attent\u00e4ter ist ein proukrainischer Terrorist aus Lager der US-Medien\" \/>\n<meta property=\"og:description\" content=\"Juraj Cintula, der den slowakischen Premier Robert Fico t\u00f6ten wollte, sei ein &#8220;politischer Fanatiker&#8221; aus dem Lager der liberalen US-Medien, meint \u013dubo\u0161 Blaha, der Vizesprecher des Nationalrats der Slowakischen Republik. Diese Tatsache wollten sie nun vertuschen. \u013dubo\u0161 Blaha, der stellvertretende Sprecher des Nationalrats der Slowakischen Republik, wirft\u00a0den liberalen Medien in den USA vor, Falschinformationen zu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-23T19:10:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/664f5d43b480cc66b96d6049.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Slowakischer Politiker: Fico-Attent\u00e4ter ist ein proukrainischer Terrorist aus Lager der US-Medien\",\"datePublished\":\"2024-05-23T19:10:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\\\/\"},\"wordCount\":381,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Slowakischer-Politiker-Fico-Attentaeter-ist-ein-proukrainischer-Terrorist-aus-Lager-der.jpg\",\"keywords\":[\"aus\",\"der\",\"ein\",\"FicoAttent\u00e4ter\",\"ist\",\"Lager\",\"Politiker\",\"Proukrainischer\",\"Slowakischer\",\"Terrorist\",\"USMedien\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\\\/\",\"name\":\"Slowakischer Politiker: Fico-Attent\u00e4ter ist ein proukrainischer Terrorist aus Lager der US-Medien - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Slowakischer-Politiker-Fico-Attentaeter-ist-ein-proukrainischer-Terrorist-aus-Lager-der.jpg\",\"datePublished\":\"2024-05-23T19:10:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Slowakischer-Politiker-Fico-Attentaeter-ist-ein-proukrainischer-Terrorist-aus-Lager-der.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/05\\\/Slowakischer-Politiker-Fico-Attentaeter-ist-ein-proukrainischer-Terrorist-aus-Lager-der.jpg\",\"width\":460,\"height\":259,\"caption\":\"Slowakischer Politiker: Fico-Attent\u00e4ter ist ein proukrainischer Terrorist aus Lager der US-Medien\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slowakischer Politiker: Fico-Attent\u00e4ter ist ein proukrainischer Terrorist aus Lager der US-Medien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Slowakischer Politiker: Fico-Attent\u00e4ter ist ein proukrainischer Terrorist aus Lager der US-Medien - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/","og_locale":"de_DE","og_type":"article","og_title":"Slowakischer Politiker: Fico-Attent\u00e4ter ist ein proukrainischer Terrorist aus Lager der US-Medien","og_description":"Juraj Cintula, der den slowakischen Premier Robert Fico t\u00f6ten wollte, sei ein &#8220;politischer Fanatiker&#8221; aus dem Lager der liberalen US-Medien, meint \u013dubo\u0161 Blaha, der Vizesprecher des Nationalrats der Slowakischen Republik. Diese Tatsache wollten sie nun vertuschen. \u013dubo\u0161 Blaha, der stellvertretende Sprecher des Nationalrats der Slowakischen Republik, wirft\u00a0den liberalen Medien in den USA vor, Falschinformationen zu [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-05-23T19:10:49+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/664f5d43b480cc66b96d6049.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Slowakischer Politiker: Fico-Attent\u00e4ter ist ein proukrainischer Terrorist aus Lager der US-Medien","datePublished":"2024-05-23T19:10:49+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/"},"wordCount":381,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Slowakischer-Politiker-Fico-Attentaeter-ist-ein-proukrainischer-Terrorist-aus-Lager-der.jpg","keywords":["aus","der","ein","FicoAttent\u00e4ter","ist","Lager","Politiker","Proukrainischer","Slowakischer","Terrorist","USMedien"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/","url":"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/","name":"Slowakischer Politiker: Fico-Attent\u00e4ter ist ein proukrainischer Terrorist aus Lager der US-Medien - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Slowakischer-Politiker-Fico-Attentaeter-ist-ein-proukrainischer-Terrorist-aus-Lager-der.jpg","datePublished":"2024-05-23T19:10:49+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Slowakischer-Politiker-Fico-Attentaeter-ist-ein-proukrainischer-Terrorist-aus-Lager-der.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/05\/Slowakischer-Politiker-Fico-Attentaeter-ist-ein-proukrainischer-Terrorist-aus-Lager-der.jpg","width":460,"height":259,"caption":"Slowakischer Politiker: Fico-Attent\u00e4ter ist ein proukrainischer Terrorist aus Lager der US-Medien"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/slowakischer-politiker-fico-attentaeter-ist-ein-proukrainischer-terrorist-aus-lager-der-us-medien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Slowakischer Politiker: Fico-Attent\u00e4ter ist ein proukrainischer Terrorist aus Lager der US-Medien"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/58712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=58712"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/58712\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/58713"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=58712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=58712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=58712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}