{"id":58255,"date":"2024-04-03T15:51:24","date_gmt":"2024-04-03T13:51:24","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/"},"modified":"2024-04-03T15:51:24","modified_gmt":"2024-04-03T13:51:24","slug":"das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/","title":{"rendered":"Das IOC, seine Stasi und seine HiWis: Was Thomas Bach gegen\u00fcber russischen Prankstern ausplauderte"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/660d2f51b480cc19a24a443d.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Thomas Bach, Chef des IOC, wurde Opfer der ber\u00fcchtigten russischen Prankster Wowan und Lexus: In dem Glauben, mit einem afrikanischen Staatschef zu sprechen, plauderte er was das Zeug h\u00e4lt. Marina Achmedowa hat die dicksten Glasperlen, die Bach vor dem &#8220;Afrikaner&#8221; ausbreitete, unter die Lupe genommen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Marina Achmedowa<\/em>\u00a0<\/p>\n<p>Ein afrikanischer Staatschef, vor\u00fcbergehend von den Prankstern Wowan und Lexus verk\u00f6rpert, hatte ein Gespr\u00e4ch mit dem Pr\u00e4sidenten des Internationalen Olympischen Komitees (IOC), Thomas Bach. Lassen wir die Tatsache unbeachtet, dass Bach in dem Gespr\u00e4ch best\u00e4tigte, dass die Sanktionen gegen russische Sportler eine politische Angelegenheit sind.<\/p>\n<p>Das ist l\u00e4ngst f\u00fcr jedermann offensichtlich. Nachdem Israel mit seiner Flagge und seiner Hymne an den Olympischen Spielen teilnehmen darf und Russland wegen seiner &#8220;Aggression gegen die Ukraine&#8221; nicht, er\u00fcbrigen sich alle Fragen \u00fcber die politische Voreingenommenheit des IOC.<\/p>\n<p>Ich w\u00fcrde sogar der Passage des olympischen Offiziellen wenig Beachtung schenken, in der er dem &#8220;afrikanischen F\u00fchrer&#8221; r\u00e4t, sich auf jede erdenkliche Weise der Anhaltung der Welt-Freundschaftsspiele in Russland entgegenzustemmen. Er bittet die afrikanischen L\u00e4nder, ihre Athleten nicht zu den Spielen in Russland zu schicken, und das IOC w\u00e4re dem &#8220;afrikanischen F\u00fchrer&#8221; daf\u00fcr sehr dankbar.<\/p>\n<p>Dabei bleibt es jedoch nicht: Bach droht, indem er andeutet, dass Athleten, die nach Russland fahren, von den Olympischen Spielen ausgeschlossen werden. Nichts in seinem ruhigen, leicht ger\u00f6tetem Gesicht verr\u00e4t nerv\u00f6se Aufregung. Nur die Augen unter seiner Brille leuchten in Vorfreude darauf, es Putin pers\u00f6nlich zu zeigen. &#8220;Das sind Spiele des russischen Pr\u00e4sidenten&#8221;, sagt er. Und er hat schon einen Plan:\u00a0<\/p>\n<blockquote>\n<p><em>&#8220;Ich werde den Vizepr\u00e4sidenten der Europ\u00e4ischen Kommission anrufen, damit sie sich mit ihm in Verbindung setzen und sich auf eine gemeinsame Erkl\u00e4rung zu den Freundschaftsspielen einigen. Und ich werde auch daf\u00fcr sorgen, dass Pr\u00e4sident Macron diesen Schritt der Europ\u00e4ischen Union unterst\u00fctzt.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Bach rattert gro\u00dfe Namen und Titel herunter, als ob er vor einem &#8220;afrikanischen H\u00e4uptling&#8221; sch\u00f6ne, billige Perlen auslegen w\u00fcrde. Er bringt den griechischen Vertreter ins Spiel, mit dem zusammen Macron und die Europ\u00e4ische Kommission ihr politisches Gewicht gegen die Spiele in Moskau und Jekaterinburg in die Waagschale werfen werden.<\/p>\n<p>Nein, ganz unpolitisch ist das IOC! Wir sollten uns immer vor Augen halten, dass es ein schlechter Stil ist, das anzusprechen.<\/p>\n<p>Ja, Bach ist nat\u00fcrlich ein harter Brocken \u2013 das sieht man seinem Funktion\u00e4rsgesicht an. Er ist gut darin, Dinge zu tun, die nichts mit Sport zu tun haben. Aber der &#8220;afrikanische F\u00fchrer&#8221; ist auch nicht von schlechten Eltern. Als der Deutsche sagt, dass patriotische russische Sportler nicht an den Olympischen Spielen teilnehmen d\u00fcrfen, wirft der &#8220;afrikanische F\u00fchrer&#8221; eine scharfe Frage ein:<\/p>\n<blockquote>\n<p><em>&#8220;Wie k\u00f6nnen wir feststellen, ob diese Menschen die russische Regierung unterst\u00fctzen oder nicht?&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Und hier ist er \u2013 der Moment des Gespr\u00e4chs, der alles bisher Geh\u00f6rte \u00fcbertrifft. Der Pr\u00e4sident des Internationalen Olympischen Komitees, Thomas Bach, ist nicht eine Sekunde verlegen und antwortet:<\/p>\n<blockquote>\n<p><em>&#8220;Wir haben eine spezielle Aufsichtskommission auf IOC-Ebene, die das Internet und \u00f6ffentliche \u00c4u\u00dferungen \u00fcberwacht. Wenn also ein Athlet irgendwo mit solchen Aussagen auftaucht, kann er nicht mehr an den Spielen teilnehmen. Wir haben der ukrainischen Seite angeboten \u2013 nicht nur angeboten, sondern auch gebeten \u2013 uns Informationen \u00fcber das Verhalten solcher Athleten zu geben.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Ah, das ist es also! Das IOC hat eine eigene Stasi eingerichtet und zudem die ukrainische Seite gebeten, russische Sportler im Internet zu verfolgen und sie zu denunzieren?<\/p>\n<p>Die schlechten alten Zeiten wiederholen sich! Wie in der Vergangenheit, wie zu Zeiten des Gro\u00dfen Vaterl\u00e4ndischen Krieges, schrecken die Ukrainer nicht vor der Rolle der Hilfswilligen zur\u00fcck, nur dass sie jetzt die Menschen nicht in den D\u00f6rfern, sondern in den sozialen Netzwerken beobachten. Und nat\u00fcrlich sind sie besonders eifrig bei der Suche in den sozialen Netzwerken starker sportlicher Konkurrenten \u2013 derjenigen, die das gr\u00f6\u00dfte Hindernis auf dem Weg zum Sieg darstellen.<\/p>\n<p>Wie, sagen Sie mir, unterscheidet sich das von der Denunziation eines Nachbarn, dessen Frau Sie den Hof gemacht haben, aber sie hat sich f\u00fcr einen anderen entschieden? Und wenn der Ehemann im Hinterhof erschossen wird, weil er die Partisanen unterst\u00fctzt, kann man die Frau mit Gewalt zur &#8220;Liebe&#8221; zwingen.<\/p>\n<p>Ein schmutziger Job, nat\u00fcrlich. Aber Europ\u00e4er wie Bach wissen aus historischer Erfahrung gut, wem man ihn anvertrauen kann. Und aus derselben Erfahrung glauben sie zu wissen, wie sie &#8220;afrikanischen H\u00e4uptlingen&#8221; Glasperlen andrehen k\u00f6nnen. Was sie nicht wissen, ist, dass nicht jeder afrikanische F\u00fchrer das ist, was er vorgibt zu sein.<\/p>\n<p><em>\u00dcbersetzt aus dem Russischen. Die Kolumne wurde f\u00fcr den TG-Kanal &#8220;Speziell f\u00fcr RT&#8221; verfasst.<\/em>\u00a0<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/201348-russische-prankster-wowan-und-lexus-veroeffentlichen-gespraech-mit-ioc-chef-bach\/\">Neuer Coup: Russische Prankster Wowan und Lexus interviewen IOC-Chef Thomas Bach<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/201439-ioc-seine-stasi-und-seine-hiwis\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thomas Bach, Chef des IOC, wurde Opfer der ber\u00fcchtigten russischen Prankster Wowan und Lexus: In dem Glauben, mit einem afrikanischen Staatschef zu sprechen, plauderte er was das Zeug h\u00e4lt. Marina Achmedowa hat die dicksten Glasperlen, die Bach vor dem &#8220;Afrikaner&#8221; ausbreitete, unter die Lupe genommen. Von Marina Achmedowa\u00a0 Ein afrikanischer Staatschef, vor\u00fcbergehend von den Prankstern [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":58256,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1712152523"],"wp_automatic_camp":["217"],"f24734b3cb533c60a11eff72a24464f4":["Das IOC, seine Stasi und seine HiWis: Was Thomas Bach gegen\u00fcber russischen Prankstern ausplauderte"],"original_link":["https:\/\/de.rt.com\/meinung\/201439-ioc-seine-stasi-und-seine-hiwis\/"],"_thumbnail_id":["58256"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-04-03 15:56:22\";}"],"jnews_social_counter_last_update":["1778673668"]},"categories":[19,23],"tags":[54922,36175,427,8962,54921,39953,50329,973,265,54920,1171,140],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Das IOC, seine Stasi und seine HiWis: Was Thomas Bach gegen\u00fcber russischen Prankstern ausplauderte - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das IOC, seine Stasi und seine HiWis: Was Thomas Bach gegen\u00fcber russischen Prankstern ausplauderte\" \/>\n<meta property=\"og:description\" content=\"Thomas Bach, Chef des IOC, wurde Opfer der ber\u00fcchtigten russischen Prankster Wowan und Lexus: In dem Glauben, mit einem afrikanischen Staatschef zu sprechen, plauderte er was das Zeug h\u00e4lt. Marina Achmedowa hat die dicksten Glasperlen, die Bach vor dem &#8220;Afrikaner&#8221; ausbreitete, unter die Lupe genommen. Von Marina Achmedowa\u00a0 Ein afrikanischer Staatschef, vor\u00fcbergehend von den Prankstern [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-03T13:51:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Das-IOC-seine-Stasi-und-seine-HiWis-Was-Thomas-Bach.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Das IOC, seine Stasi und seine HiWis: Was Thomas Bach gegen\u00fcber russischen Prankstern ausplauderte\",\"datePublished\":\"2024-04-03T13:51:24+00:00\",\"dateModified\":\"2024-04-03T13:51:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/\"},\"wordCount\":817,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Das-IOC-seine-Stasi-und-seine-HiWis-Was-Thomas-Bach.jpg\",\"keywords\":[\"ausplauderte\",\"Bach\",\"das\",\"gegen\u00fcber\",\"HiWis\",\"IOC\",\"Prankstern\",\"russischen\",\"seine\",\"Stasi\",\"Thomas\",\"und\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/\",\"name\":\"Das IOC, seine Stasi und seine HiWis: Was Thomas Bach gegen\u00fcber russischen Prankstern ausplauderte - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Das-IOC-seine-Stasi-und-seine-HiWis-Was-Thomas-Bach.jpg\",\"datePublished\":\"2024-04-03T13:51:24+00:00\",\"dateModified\":\"2024-04-03T13:51:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Das-IOC-seine-Stasi-und-seine-HiWis-Was-Thomas-Bach.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Das-IOC-seine-Stasi-und-seine-HiWis-Was-Thomas-Bach.jpg\",\"width\":460,\"height\":259,\"caption\":\"Das IOC, seine Stasi und seine HiWis: Was Thomas Bach gegen\u00fcber russischen Prankstern ausplauderte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Das IOC, seine Stasi und seine HiWis: Was Thomas Bach gegen\u00fcber russischen Prankstern ausplauderte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Das IOC, seine Stasi und seine HiWis: Was Thomas Bach gegen\u00fcber russischen Prankstern ausplauderte - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/","og_locale":"de_DE","og_type":"article","og_title":"Das IOC, seine Stasi und seine HiWis: Was Thomas Bach gegen\u00fcber russischen Prankstern ausplauderte","og_description":"Thomas Bach, Chef des IOC, wurde Opfer der ber\u00fcchtigten russischen Prankster Wowan und Lexus: In dem Glauben, mit einem afrikanischen Staatschef zu sprechen, plauderte er was das Zeug h\u00e4lt. Marina Achmedowa hat die dicksten Glasperlen, die Bach vor dem &#8220;Afrikaner&#8221; ausbreitete, unter die Lupe genommen. Von Marina Achmedowa\u00a0 Ein afrikanischer Staatschef, vor\u00fcbergehend von den Prankstern [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-04-03T13:51:24+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Das-IOC-seine-Stasi-und-seine-HiWis-Was-Thomas-Bach.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Das IOC, seine Stasi und seine HiWis: Was Thomas Bach gegen\u00fcber russischen Prankstern ausplauderte","datePublished":"2024-04-03T13:51:24+00:00","dateModified":"2024-04-03T13:51:24+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/"},"wordCount":817,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Das-IOC-seine-Stasi-und-seine-HiWis-Was-Thomas-Bach.jpg","keywords":["ausplauderte","Bach","das","gegen\u00fcber","HiWis","IOC","Prankstern","russischen","seine","Stasi","Thomas","und"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/","url":"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/","name":"Das IOC, seine Stasi und seine HiWis: Was Thomas Bach gegen\u00fcber russischen Prankstern ausplauderte - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Das-IOC-seine-Stasi-und-seine-HiWis-Was-Thomas-Bach.jpg","datePublished":"2024-04-03T13:51:24+00:00","dateModified":"2024-04-03T13:51:24+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Das-IOC-seine-Stasi-und-seine-HiWis-Was-Thomas-Bach.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Das-IOC-seine-Stasi-und-seine-HiWis-Was-Thomas-Bach.jpg","width":460,"height":259,"caption":"Das IOC, seine Stasi und seine HiWis: Was Thomas Bach gegen\u00fcber russischen Prankstern ausplauderte"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/das-ioc-seine-stasi-und-seine-hiwis-was-thomas-bach-gegenueber-russischen-prankstern-ausplauderte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Das IOC, seine Stasi und seine HiWis: Was Thomas Bach gegen\u00fcber russischen Prankstern ausplauderte"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/58255"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=58255"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/58255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/58256"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=58255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=58255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=58255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}