{"id":58150,"date":"2024-04-02T09:18:07","date_gmt":"2024-04-02T07:18:07","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/"},"modified":"2024-04-02T09:18:07","modified_gmt":"2024-04-02T07:18:07","slug":"erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/","title":{"rendered":"Erfahrungen der 1990er Jahre erschweren es, reale wirtschaftliche Prozesse zu erkennen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/660adc88b480cc43806a4324.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Das Katastrophendenken, das jedes Risiko zu einer existenziellen Bedrohung ausweitet, wird zu einem Hindernis bei der Wahrnehmung neuer Risiken, ihrer Natur und der Gr\u00fcnde f\u00fcr ihr Auftreten. Es hindert uns daran  unter den neuartigen Bedingungen L\u00f6sungen zu finden.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Oksana Sinjawskaja<\/em><\/p>\n<p>Wie schwierig es doch ist, sich von der Gewohnheit zu l\u00f6sen, die vielgestaltige, widerspr\u00fcchliche Wirklichkeit in historischen Analogien und etablierten Mustern zu denken. Wir alle, die die 1990er Jahre erlebt haben, haben diese Zeit als Kammerton in unseren K\u00f6pfen \u2013 zumindest im wirtschaftlichen Bereich. Wir haben sowohl die Pandemie als auch die milit\u00e4rische Sonderoperation in der Ukraine an ihm gemessen.<\/p>\n<p>Und das ist eine Erfahrung, die ihren bedingungslosen Wert hat, auch weil sie uns ermutigt, in einer zun\u00e4chst ausweglos erscheinenden Situation nach Auswegen und L\u00f6sungen zu suchen. Gleichzeitig ist sie aber ein Schleier, der uns daran hindert, die realen Prozesse zu sehen, die derzeit in Wirtschaft und Gesellschaft ablaufen.<\/p>\n<p>So schrieben wir im &#8220;Barometer f\u00fcr das wirtschaftliche Verhalten privater Haushalte&#8221; im Dezember, dass die Arbeitslosigkeit sinkt und die Einkommen steigen. Vor diesem Hintergrund glaubten zwei Drittel der Befragten, dass sich ihr Realeinkommen in den n\u00e4chsten drei Monaten nicht ver\u00e4ndern w\u00fcrde, w\u00e4hrend jeder Sechste sogar einen Anstieg erwartete. Und mehrere Bekannte haben mir vorgeworfen, wir w\u00fcrden eine &#8220;rosarote Brille&#8221; tragen und die Realit\u00e4t besch\u00f6nigen, denn es gebe Inflation, &#8220;Eier&#8221;-Probleme, Sortimentswechsel, und generell sei alles instabil, und bald werde es sogar noch viel schlimmer sein.<\/p>\n<p>In der neuen &#8220;Barometer&#8221;-Ausgabe konstatieren wir einen weiteren Anstieg der Verbraucherstimmung, eine gute Versorgung der Bev\u00f6lkerung mit einer Grundausstattung an langlebigen G\u00fctern und gleichzeitig einen Anstieg der Ausgaben f\u00fcr Bau-, Reparatur- und Renovierungsarbeiten. Letzteres stimmt mit der im letzten Jahr beobachteten Zunahme der Kreditaufnahme und der K\u00e4ufe von im Bau befindlichen Wohnungen \u00fcberein. Und weiter schreiben wir, dass die finanzielle Instabilit\u00e4t der Haushalte, definiert als der Mangel an liquiden Ersparnissen in Verbindung mit Anzeichen von Kredit\u00fcberschreitung, in sechs Monaten um sechs Prozentpunkte gestiegen ist und Anfang 2024 62 Prozent erreicht hat. Meiner Meinung nach sind dies alles sehr gut zusammenh\u00e4ngende Trends, die als Ganzes wahrgenommen und analysiert werden sollten, denn die Hauptursache f\u00fcr finanzielle Instabilit\u00e4t ist der Mangel an liquiden Ersparnissen.<\/p>\n<p>Aber es ist bedauerlich festzustellen, dass nur die j\u00fcngste Nachricht \u2013 \u00fcber die Nichtnachhaltigkeit \u2013 die Aufmerksamkeit der Presse auf sich gezogen hat und dort losgel\u00f6st von allem anderen betrachtet wird. Und nun h\u00f6rt man Beschwerden von zwei Seiten: sowohl von denen, die nicht glauben, dass wir ein Konsumwachstum haben k\u00f6nnen, als auch von denen, die die Risiken der aktuellen Situation nicht wahrnehmen wollen. Beide Positionen spiegeln eine pauschale, eindimensionale Wahrnehmung des Geschehens wider: &#8220;Alles ist schlecht und es kann nichts Gutes passieren&#8221; oder &#8220;alles ist gut und es kann nichts Schlechtes passieren&#8221;.<\/p>\n<p>Zugleich wird das Katastrophendenken, das jedes Risiko zu einer Bedrohung der Existenzf\u00e4higkeit ausweitet, selbst zu einem Hindernis \u2013 bei der Wahrnehmung neu auftretender Risiken, bei der Untersuchung ihrer Natur und der Gr\u00fcnde f\u00fcr ihr Auftreten. Es wird selbst zu einer Bedrohung, weil es uns daran hindert, unter den heutigen einzigartigen Bedingungen nach L\u00f6sungen zu suchen, indem es uns st\u00e4ndig in die Vergangenheit zur\u00fcckversetzt: Es gibt schlie\u00dflich kein solches Defizit wie in der sp\u00e4ten UdSSR, und es gibt keine Inflation und Zahlungsausf\u00e4lle wie in den 1990er Jahren &#8230;<\/p>\n<p><em>Oksana Sinjawskaja ist s<\/em><em>tellvertretende Direktorin des Instituts f\u00fcr Sozialpolitik der Hochschule f\u00fcr Internationale Wirtschaft und Au\u00dfenpolitik (HSE).<\/em><\/p>\n<p><em>\u00dcbersetzt aus dem Russischen. Der Artikel ist am 29. M\u00e4rz 2024 zuerst auf der Zeitung Wsgljad <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/vz.ru\/opinions\/2024\/3\/29\/1260711.html\">erschienen<\/a>.<\/em><\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/wirtschaft\/196440-fakten-widerlegen-vorhersagen-zum-wirtschaftlichen-zusammenbruch\/\">Die Fakten widerlegen die Vorhersagen zum wirtschaftlichen Zusammenbruch Russlands<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/wirtschaft\/201237-erfahrungen-1990er-jahre-erschweren-es\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Katastrophendenken, das jedes Risiko zu einer existenziellen Bedrohung ausweitet, wird zu einem Hindernis bei der Wahrnehmung neuer Risiken, ihrer Natur und der Gr\u00fcnde f\u00fcr ihr Auftreten. Es hindert uns daran unter den neuartigen Bedingungen L\u00f6sungen zu finden. Von Oksana Sinjawskaja Wie schwierig es doch ist, sich von der Gewohnheit zu l\u00f6sen, die vielgestaltige, widerspr\u00fcchliche [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":58151,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1712043544"],"wp_automatic_camp":["217"],"c1b7f88d71c0ba9373b871369788f2c9":["Erfahrungen der 1990er Jahre erschweren es, reale wirtschaftliche Prozesse zu erkennen"],"original_link":["https:\/\/de.rt.com\/wirtschaft\/201237-erfahrungen-1990er-jahre-erschweren-es\/"],"_thumbnail_id":["58151"],"jnews_social_counter_last_update":["1788328594"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-04-02 09:40:04\";}"]},"categories":[19,23],"tags":[24696,82,11363,13412,30074,7530,37482,38761,4852],"class_list":["post-58150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-1990er","tag-der","tag-erfahrungen","tag-erkennen","tag-erschweren","tag-jahre","tag-prozesse","tag-reale","tag-wirtschaftliche"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Erfahrungen der 1990er Jahre erschweren es, reale wirtschaftliche Prozesse zu erkennen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erfahrungen der 1990er Jahre erschweren es, reale wirtschaftliche Prozesse zu erkennen\" \/>\n<meta property=\"og:description\" content=\"Das Katastrophendenken, das jedes Risiko zu einer existenziellen Bedrohung ausweitet, wird zu einem Hindernis bei der Wahrnehmung neuer Risiken, ihrer Natur und der Gr\u00fcnde f\u00fcr ihr Auftreten. Es hindert uns daran unter den neuartigen Bedingungen L\u00f6sungen zu finden. Von Oksana Sinjawskaja Wie schwierig es doch ist, sich von der Gewohnheit zu l\u00f6sen, die vielgestaltige, widerspr\u00fcchliche [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-02T07:18:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Erfahrungen-der-1990er-Jahre-erschweren-es-reale-wirtschaftliche-Prozesse-zu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Erfahrungen der 1990er Jahre erschweren es, reale wirtschaftliche Prozesse zu erkennen\",\"datePublished\":\"2024-04-02T07:18:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\\\/\"},\"wordCount\":632,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/04\\\/Erfahrungen-der-1990er-Jahre-erschweren-es-reale-wirtschaftliche-Prozesse-zu.jpg\",\"keywords\":[\"1990er\",\"der\",\"Erfahrungen\",\"erkennen\",\"erschweren\",\"Jahre\",\"Prozesse\",\"reale\",\"wirtschaftliche\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\\\/\",\"name\":\"Erfahrungen der 1990er Jahre erschweren es, reale wirtschaftliche Prozesse zu erkennen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/04\\\/Erfahrungen-der-1990er-Jahre-erschweren-es-reale-wirtschaftliche-Prozesse-zu.jpg\",\"datePublished\":\"2024-04-02T07:18:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/04\\\/Erfahrungen-der-1990er-Jahre-erschweren-es-reale-wirtschaftliche-Prozesse-zu.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/04\\\/Erfahrungen-der-1990er-Jahre-erschweren-es-reale-wirtschaftliche-Prozesse-zu.jpg\",\"width\":460,\"height\":259,\"caption\":\"Erfahrungen der 1990er Jahre erschweren es, reale wirtschaftliche Prozesse zu erkennen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erfahrungen der 1990er Jahre erschweren es, reale wirtschaftliche Prozesse zu erkennen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Erfahrungen der 1990er Jahre erschweren es, reale wirtschaftliche Prozesse zu erkennen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/","og_locale":"de_DE","og_type":"article","og_title":"Erfahrungen der 1990er Jahre erschweren es, reale wirtschaftliche Prozesse zu erkennen","og_description":"Das Katastrophendenken, das jedes Risiko zu einer existenziellen Bedrohung ausweitet, wird zu einem Hindernis bei der Wahrnehmung neuer Risiken, ihrer Natur und der Gr\u00fcnde f\u00fcr ihr Auftreten. Es hindert uns daran unter den neuartigen Bedingungen L\u00f6sungen zu finden. Von Oksana Sinjawskaja Wie schwierig es doch ist, sich von der Gewohnheit zu l\u00f6sen, die vielgestaltige, widerspr\u00fcchliche [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-04-02T07:18:07+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Erfahrungen-der-1990er-Jahre-erschweren-es-reale-wirtschaftliche-Prozesse-zu.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Erfahrungen der 1990er Jahre erschweren es, reale wirtschaftliche Prozesse zu erkennen","datePublished":"2024-04-02T07:18:07+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/"},"wordCount":632,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Erfahrungen-der-1990er-Jahre-erschweren-es-reale-wirtschaftliche-Prozesse-zu.jpg","keywords":["1990er","der","Erfahrungen","erkennen","erschweren","Jahre","Prozesse","reale","wirtschaftliche"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/","url":"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/","name":"Erfahrungen der 1990er Jahre erschweren es, reale wirtschaftliche Prozesse zu erkennen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Erfahrungen-der-1990er-Jahre-erschweren-es-reale-wirtschaftliche-Prozesse-zu.jpg","datePublished":"2024-04-02T07:18:07+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Erfahrungen-der-1990er-Jahre-erschweren-es-reale-wirtschaftliche-Prozesse-zu.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/04\/Erfahrungen-der-1990er-Jahre-erschweren-es-reale-wirtschaftliche-Prozesse-zu.jpg","width":460,"height":259,"caption":"Erfahrungen der 1990er Jahre erschweren es, reale wirtschaftliche Prozesse zu erkennen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/erfahrungen-der-1990er-jahre-erschweren-es-reale-wirtschaftliche-prozesse-zu-erkennen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Erfahrungen der 1990er Jahre erschweren es, reale wirtschaftliche Prozesse zu erkennen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/58150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=58150"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/58150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/58151"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=58150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=58150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=58150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}