{"id":57923,"date":"2024-03-28T20:43:44","date_gmt":"2024-03-28T18:43:44","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/"},"modified":"2024-03-28T20:43:44","modified_gmt":"2024-03-28T18:43:44","slug":"russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/","title":{"rendered":"Russische K\u00fcnstler unterst\u00fctzen Opfer des Terroranschlags auf Crocus-Konzerthalle"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/6605528d48fbef3a382259b6.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Russische Popmusiker und Rapper wollen die Opfer des Terroranschlags auf die Crocus City Hall unterst\u00fctzen. Sie haben ein Musikalbum aufgenommen, welches auf Streaming-Plattformen verbreitet wird. Der gesamte Erl\u00f6s geht an die Opfer und ihre Familien.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Wie die Nachrichtenagentur <em>R<\/em><em>IA Nowosti<\/em> von der Medienholding VK, die das Album auf den Markt bringt, erfuhr, tr\u00e4gt es den Titel &#8220;H\u00f6re meine Stimme&#8221;. Es umfasst 12 Lieder des legend\u00e4ren sowjetischen S\u00e4ngers Muslim Magomajew, die von russischen K\u00fcnstlern neu interpretiert wurden. Alle Erl\u00f6se aus dem Verkauf der Lieder werden den Opfern des Terroranschlags vom 22. M\u00e4rz auf die Konzerthalle in der Crocus City Hall, die den Namen des gro\u00dfen S\u00e4ngers Muslim Magomajew tr\u00e4gt, zugute kommen. Die Initiative wird von allen russischen Musik-Streaming-Diensten unterst\u00fctzt, berichtet die Agentur <em>RIA Nowosti<\/em> weiter. Das Portal <em>RBK<\/em> schreibt dar\u00fcber:<\/p>\n<blockquote>\n<p><em>&#8220;Zum Album wird berichtet, dass die Projektteilnehmer, K\u00fcnstler verschiedener Generationen, sich bem\u00fcht haben, die ber\u00fchmten Lieder sorgf\u00e4ltig zu interpretieren und ihren Melodienreichtum zu bewahren. Dabei wurde eine vielf\u00e4ltige Palette von Arrangements verwendet: Von urbaner Romantik bis hin zum Symphonieorchester und modernem Sound.<\/em><\/p>\n<p><em>Basta, Walerija, Wanja Dmitrienko, Polina Gagarina, MACAN, Stas Michailow, HammAli, Navai, Ljusja Tschebotina, Wladimir Presnjakow und die Musikgruppen Lube, Tri Dnja Doschdja und andere haben sich an der Aufnahme beteiligt. Das Gedicht im Vorspann wird von dem Schauspieler und Regisseur Fjodor Bondartschuk gesprochen. Die Aufnahme des Albums wurde von dem Holding VK Music organisiert.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Zuvor hatten russische Medien berichtet, dass Kunden nach dem Terroranschlag massenweise Eintrittskarten f\u00fcr Konzert- und Theaterveranstaltungen zur\u00fcckgeben. So wurden beispielsweise in den f\u00fcnf Tagen nach dem Terroranschlag auf die Crocus-Konzerthalle 100.000 Eintrittskarten f\u00fcr Gro\u00dfveranstaltungen zur\u00fcckgegeben. Die Verk\u00e4ufe gingen um 60 Prozent zur\u00fcck.<\/p>\n<\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/200582-beileid-aus-deutschland-hoechstadt-will-krasnogorsk-nach-terroranschlang-unterstuetzen\/\">Beileid aus Deutschland: H\u00f6chstadt an der Aisch will Krasnogorsk nach Terroranschlag unterst\u00fctzen<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/russland\/200889-crocus-russische-kuenstler-nehmen-album\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Russische Popmusiker und Rapper wollen die Opfer des Terroranschlags auf die Crocus City Hall unterst\u00fctzen. Sie haben ein Musikalbum aufgenommen, welches auf Streaming-Plattformen verbreitet wird. Der gesamte Erl\u00f6s geht an die Opfer und ihre Familien. Wie die Nachrichtenagentur RIA Nowosti von der Medienholding VK, die das Album auf den Markt bringt, erfuhr, tr\u00e4gt es den [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":57924,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1711651726"],"wp_automatic_camp":["217"],"32030e13eced8f0af08625ef2a2d6836":["Russische K\u00fcnstler unterst\u00fctzen Opfer des Terroranschlags auf Crocus-Konzerthalle"],"original_link":["https:\/\/de.rt.com\/russland\/200889-crocus-russische-kuenstler-nehmen-album\/"],"_thumbnail_id":["57924"],"jnews_social_counter_last_update":["1778551533"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-03-28 20:49:44\";}"]},"categories":[19,23],"tags":[133,54654,583,6680,497,570,6318,1190],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Russische K\u00fcnstler unterst\u00fctzen Opfer des Terroranschlags auf Crocus-Konzerthalle - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Russische K\u00fcnstler unterst\u00fctzen Opfer des Terroranschlags auf Crocus-Konzerthalle\" \/>\n<meta property=\"og:description\" content=\"Russische Popmusiker und Rapper wollen die Opfer des Terroranschlags auf die Crocus City Hall unterst\u00fctzen. Sie haben ein Musikalbum aufgenommen, welches auf Streaming-Plattformen verbreitet wird. Der gesamte Erl\u00f6s geht an die Opfer und ihre Familien. Wie die Nachrichtenagentur RIA Nowosti von der Medienholding VK, die das Album auf den Markt bringt, erfuhr, tr\u00e4gt es den [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-28T18:43:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Russische-Kuenstler-unterstuetzen-Opfer-des-Terroranschlags-auf-Crocus-Konzerthalle.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Russische K\u00fcnstler unterst\u00fctzen Opfer des Terroranschlags auf Crocus-Konzerthalle\",\"datePublished\":\"2024-03-28T18:43:44+00:00\",\"dateModified\":\"2024-03-28T18:43:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/\"},\"wordCount\":322,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Russische-Kuenstler-unterstuetzen-Opfer-des-Terroranschlags-auf-Crocus-Konzerthalle.jpg\",\"keywords\":[\"AUF\",\"CrocusKonzerthalle\",\"des\",\"K\u00fcnstler\",\"Opfer\",\"Russische\",\"Terroranschlags\",\"unterst\u00fctzen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/\",\"name\":\"Russische K\u00fcnstler unterst\u00fctzen Opfer des Terroranschlags auf Crocus-Konzerthalle - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Russische-Kuenstler-unterstuetzen-Opfer-des-Terroranschlags-auf-Crocus-Konzerthalle.jpg\",\"datePublished\":\"2024-03-28T18:43:44+00:00\",\"dateModified\":\"2024-03-28T18:43:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Russische-Kuenstler-unterstuetzen-Opfer-des-Terroranschlags-auf-Crocus-Konzerthalle.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Russische-Kuenstler-unterstuetzen-Opfer-des-Terroranschlags-auf-Crocus-Konzerthalle.jpg\",\"width\":460,\"height\":259,\"caption\":\"Russische K\u00fcnstler unterst\u00fctzen Opfer des Terroranschlags auf Crocus-Konzerthalle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Russische K\u00fcnstler unterst\u00fctzen Opfer des Terroranschlags auf Crocus-Konzerthalle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Russische K\u00fcnstler unterst\u00fctzen Opfer des Terroranschlags auf Crocus-Konzerthalle - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/","og_locale":"de_DE","og_type":"article","og_title":"Russische K\u00fcnstler unterst\u00fctzen Opfer des Terroranschlags auf Crocus-Konzerthalle","og_description":"Russische Popmusiker und Rapper wollen die Opfer des Terroranschlags auf die Crocus City Hall unterst\u00fctzen. Sie haben ein Musikalbum aufgenommen, welches auf Streaming-Plattformen verbreitet wird. Der gesamte Erl\u00f6s geht an die Opfer und ihre Familien. Wie die Nachrichtenagentur RIA Nowosti von der Medienholding VK, die das Album auf den Markt bringt, erfuhr, tr\u00e4gt es den [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-03-28T18:43:44+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Russische-Kuenstler-unterstuetzen-Opfer-des-Terroranschlags-auf-Crocus-Konzerthalle.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Russische K\u00fcnstler unterst\u00fctzen Opfer des Terroranschlags auf Crocus-Konzerthalle","datePublished":"2024-03-28T18:43:44+00:00","dateModified":"2024-03-28T18:43:44+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/"},"wordCount":322,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Russische-Kuenstler-unterstuetzen-Opfer-des-Terroranschlags-auf-Crocus-Konzerthalle.jpg","keywords":["AUF","CrocusKonzerthalle","des","K\u00fcnstler","Opfer","Russische","Terroranschlags","unterst\u00fctzen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/","url":"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/","name":"Russische K\u00fcnstler unterst\u00fctzen Opfer des Terroranschlags auf Crocus-Konzerthalle - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Russische-Kuenstler-unterstuetzen-Opfer-des-Terroranschlags-auf-Crocus-Konzerthalle.jpg","datePublished":"2024-03-28T18:43:44+00:00","dateModified":"2024-03-28T18:43:44+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Russische-Kuenstler-unterstuetzen-Opfer-des-Terroranschlags-auf-Crocus-Konzerthalle.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Russische-Kuenstler-unterstuetzen-Opfer-des-Terroranschlags-auf-Crocus-Konzerthalle.jpg","width":460,"height":259,"caption":"Russische K\u00fcnstler unterst\u00fctzen Opfer des Terroranschlags auf Crocus-Konzerthalle"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/russische-kuenstler-unterstuetzen-opfer-des-terroranschlags-auf-crocus-konzerthalle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Russische K\u00fcnstler unterst\u00fctzen Opfer des Terroranschlags auf Crocus-Konzerthalle"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/57923"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=57923"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/57923\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/57924"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=57923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=57923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=57923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}