{"id":56941,"date":"2024-03-12T14:29:49","date_gmt":"2024-03-12T12:29:49","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/"},"modified":"2024-03-12T14:29:49","modified_gmt":"2024-03-12T12:29:49","slug":"us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/","title":{"rendered":"US-Geheimdienste: Russland sucht keine direkte Konfrontation zum Westen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/65f034a648fbef08a24ce294.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                In ihrer j\u00e4hrlichen Bewertung der nationalen Sicherheitsbedrohungen kommen die US-Geheimdienste zu dem Schluss, dass Moskau zwar weiterhin seine Interessen durchsetzen, dabei aber einen Krieg mit der NATO vermeiden wolle.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Russland ist &#8220;mit ziemlicher Sicherheit&#8221; bestrebt, einen direkten milit\u00e4rischen Konflikt mit der NATO zu vermeiden, und wird seine Politik so kalibrieren, dass ein globaler Krieg vermieden wird, lautet die Schlussfolgerung der US-Geheimdienste in ihrer j\u00e4hrlichen Bewertung der nationalen Sicherheitsbedrohungen.<\/p>\n<p>Das Office of the Director of National Intelligence (ODNI) hat am Montag in einem Bericht an den US-Kongress seine Einsch\u00e4tzung der Bedrohungslage f\u00fcr 2024 vorgestellt. Die Studie, in die Beitr\u00e4ge der CIA und von 17 weiteren Geheimdiensten eingeflossen sind, prognostiziert, dass Moskau &#8220;seine asymmetrischen Aktivit\u00e4ten unterhalb der Schwelle eines weltweiten milit\u00e4rischen Konflikts fortsetzen wird&#8221;.<\/p>\n<p>In dem Bericht hei\u00dft es:<\/p>\n<blockquote>\n<p><em>&#8220;Russland bleibt ein widerstandsf\u00e4higer und f\u00e4higer Gegner in einem breiten Spektrum von Bereichen und versucht, seine Interessen weltweit durchzusetzen und zu verteidigen und die Vereinigten Staaten und den Westen zu untergraben.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Der US-Geheimdienstbericht behauptet, der Ukraine-Konflikt habe zwar Russland &#8220;enormen Schaden&#8221; zugef\u00fcgt, r\u00e4umte aber ein, dass die Krise allerdings auch zu st\u00e4rkeren Allianzen gegen die USA gef\u00fchrt habe:<\/p>\n<blockquote>\n<p><em>&#8220;Russlands zunehmende Verbindungen zu China, Iran und Nordkorea, um seine R\u00fcstungsproduktion und Wirtschaft zu st\u00e4rken, sind eine gro\u00dfe Herausforderung f\u00fcr den Westen und seine Partner.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Der russische Pr\u00e4sident Wladimir Putin &#8220;glaubt wahrscheinlich&#8221;, dass sich seine Strategie in der Ukraine auszahlt und dass die westliche Hilfe f\u00fcr Kiew nachlassen werde, teilweise wegen des Krieges zwischen Israel und Hamas, sch\u00e4tz das ODNI weiter die Lage ein. Die US-Spionagebeh\u00f6rden r\u00e4umen ein, dass die russischen Streitkr\u00e4fte seit Ende letzten Jahres auf dem Schlachtfeld Gewinne erzielt haben und von der &#8220;Unsicherheit \u00fcber die Zukunft der westlichen Milit\u00e4rhilfe&#8221; profitieren.<\/p>\n<p>Der Regierung unter dem US-Pr\u00e4sidenten Joe Biden gingen im Januar die Finanzmittel f\u00fcr die Ukraine aus, nachdem die 113 Milliarden US-Dollar der vom Kongress genehmigten Hilfspakete verbraucht waren. Die von der Regierung beantragten zus\u00e4tzlichen Mittel in H\u00f6he von 60 Milliarden US-Dollar sind im Kongress wegen des Widerstands der Republikaner ins Stocken geraten.<\/p>\n<p>Biden machte deshalb f\u00fcr den Fall von Awdejewka, einer wichtigen Hochburg im Donbass, an die russischen Streitkr\u00e4fte im vergangenen Monat die US-Parlamentarier verantwortlich und erkl\u00e4rte das damit, dass die ukrainischen Truppen nicht die n\u00f6tige Munition erhalten h\u00e4tten.<\/p>\n<p>Der CIA-Direktor William Burns sagte am Montag vor Mitgliedern des Geheimdienstausschusses des US-Senats:<\/p>\n<blockquote>\n<p><em>&#8220;Ich denke, ohne zus\u00e4tzliche Hilfe im Jahr 2024 wird es noch mehr Awdejewkas geben, und das \u2013 so scheint es mir \u2013 w\u00e4re ein massiver und historischer Fehler f\u00fcr die Vereinigten Staaten.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Wenn mehr US-Hilfen bewilligt w\u00fcrden, versicherte Burns, k\u00f6nnten die ukrainischen Streitkr\u00e4fte bis Ende 2024 oder Anfang 2025 &#8220;die Offensivinitiative zur\u00fcckgewinnen&#8221;.<\/p>\n<p>In der Geheimdienstbewertung wird einger\u00e4umt, dass sich das Momentum in der Ukraine derzeit zunehmend zu Gunsten Russlands verschiebt.<\/p>\n<p>&#8220;Russlands Verteidigungsindustrie f\u00e4hrt die Produktion einer ganzen Reihe von Langstreckenwaffen, Artilleriemunition und anderen F\u00e4higkeiten erheblich hoch, die es ihr erm\u00f6glichen, einen langen Krieg mit hoher Intensit\u00e4t zu f\u00fchren&#8221;, hei\u00dft es in dem Bericht.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freeassange.rtde.life\/international\/199048-ukraine-droht-mit-ernsthafter-operation-krim\/\">Ukraine droht mit &#8220;ernsthafter Operation&#8221; gegen die Krim <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2FNicht-nur-schlagkr%C3%A4ftig%2C-sondern-auch-pr%C3%A4zise--Neue-Bomben-im-Dienst-der-russischen-Armee%3A2\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/199098-us-geheimdienste-russland-sucht-keine-direkte-konfrontation-mit-westen\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In ihrer j\u00e4hrlichen Bewertung der nationalen Sicherheitsbedrohungen kommen die US-Geheimdienste zu dem Schluss, dass Moskau zwar weiterhin seine Interessen durchsetzen, dabei aber einen Krieg mit der NATO vermeiden wolle. Russland ist &#8220;mit ziemlicher Sicherheit&#8221; bestrebt, einen direkten milit\u00e4rischen Konflikt mit der NATO zu vermeiden, und wird seine Politik so kalibrieren, dass ein globaler Krieg vermieden [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":56942,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1710247554"],"wp_automatic_camp":["217"],"d5d8bbf80ddfaef01465bbf0a9253746":["US-Geheimdienste: Russland sucht keine direkte Konfrontation zum Westen"],"original_link":["https:\/\/de.rt.com\/international\/199098-us-geheimdienste-russland-sucht-keine-direkte-konfrontation-mit-westen\/"],"_thumbnail_id":["56942"],"jnews_social_counter_last_update":["1784125483"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-03-12 14:47:12\";}"]},"categories":[19,23],"tags":[4486,375,4487,126,26422,1474,378,565],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>US-Geheimdienste: Russland sucht keine direkte Konfrontation zum Westen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"US-Geheimdienste: Russland sucht keine direkte Konfrontation zum Westen\" \/>\n<meta property=\"og:description\" content=\"In ihrer j\u00e4hrlichen Bewertung der nationalen Sicherheitsbedrohungen kommen die US-Geheimdienste zu dem Schluss, dass Moskau zwar weiterhin seine Interessen durchsetzen, dabei aber einen Krieg mit der NATO vermeiden wolle. Russland ist &#8220;mit ziemlicher Sicherheit&#8221; bestrebt, einen direkten milit\u00e4rischen Konflikt mit der NATO zu vermeiden, und wird seine Politik so kalibrieren, dass ein globaler Krieg vermieden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-12T12:29:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/US-Geheimdienste-Russland-sucht-keine-direkte-Konfrontation-zum-Westen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"US-Geheimdienste: Russland sucht keine direkte Konfrontation zum Westen\",\"datePublished\":\"2024-03-12T12:29:49+00:00\",\"dateModified\":\"2024-03-12T12:29:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/\"},\"wordCount\":545,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/US-Geheimdienste-Russland-sucht-keine-direkte-Konfrontation-zum-Westen.jpg\",\"keywords\":[\"direkte\",\"keine\",\"Konfrontation\",\"russland\",\"sucht\",\"USGeheimdienste\",\"Westen\",\"zum\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/\",\"name\":\"US-Geheimdienste: Russland sucht keine direkte Konfrontation zum Westen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/US-Geheimdienste-Russland-sucht-keine-direkte-Konfrontation-zum-Westen.jpg\",\"datePublished\":\"2024-03-12T12:29:49+00:00\",\"dateModified\":\"2024-03-12T12:29:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/US-Geheimdienste-Russland-sucht-keine-direkte-Konfrontation-zum-Westen.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/US-Geheimdienste-Russland-sucht-keine-direkte-Konfrontation-zum-Westen.jpg\",\"width\":460,\"height\":259,\"caption\":\"US-Geheimdienste: Russland sucht keine direkte Konfrontation zum Westen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"US-Geheimdienste: Russland sucht keine direkte Konfrontation zum Westen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"US-Geheimdienste: Russland sucht keine direkte Konfrontation zum Westen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/","og_locale":"de_DE","og_type":"article","og_title":"US-Geheimdienste: Russland sucht keine direkte Konfrontation zum Westen","og_description":"In ihrer j\u00e4hrlichen Bewertung der nationalen Sicherheitsbedrohungen kommen die US-Geheimdienste zu dem Schluss, dass Moskau zwar weiterhin seine Interessen durchsetzen, dabei aber einen Krieg mit der NATO vermeiden wolle. Russland ist &#8220;mit ziemlicher Sicherheit&#8221; bestrebt, einen direkten milit\u00e4rischen Konflikt mit der NATO zu vermeiden, und wird seine Politik so kalibrieren, dass ein globaler Krieg vermieden [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-03-12T12:29:49+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/US-Geheimdienste-Russland-sucht-keine-direkte-Konfrontation-zum-Westen.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"US-Geheimdienste: Russland sucht keine direkte Konfrontation zum Westen","datePublished":"2024-03-12T12:29:49+00:00","dateModified":"2024-03-12T12:29:49+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/"},"wordCount":545,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/US-Geheimdienste-Russland-sucht-keine-direkte-Konfrontation-zum-Westen.jpg","keywords":["direkte","keine","Konfrontation","russland","sucht","USGeheimdienste","Westen","zum"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/","url":"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/","name":"US-Geheimdienste: Russland sucht keine direkte Konfrontation zum Westen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/US-Geheimdienste-Russland-sucht-keine-direkte-Konfrontation-zum-Westen.jpg","datePublished":"2024-03-12T12:29:49+00:00","dateModified":"2024-03-12T12:29:49+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/US-Geheimdienste-Russland-sucht-keine-direkte-Konfrontation-zum-Westen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/US-Geheimdienste-Russland-sucht-keine-direkte-Konfrontation-zum-Westen.jpg","width":460,"height":259,"caption":"US-Geheimdienste: Russland sucht keine direkte Konfrontation zum Westen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/us-geheimdienste-russland-sucht-keine-direkte-konfrontation-zum-westen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"US-Geheimdienste: Russland sucht keine direkte Konfrontation zum Westen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/56941"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=56941"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/56941\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/56942"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=56941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=56941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=56941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}