{"id":56937,"date":"2024-03-12T13:34:56","date_gmt":"2024-03-12T11:34:56","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/"},"modified":"2024-03-12T13:34:56","modified_gmt":"2024-03-12T11:34:56","slug":"haiti-interimspremier-henry-tritt-zurueck","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/","title":{"rendered":"Haiti: Interimspremier Henry tritt zur\u00fcck"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/65f01681b480cc12d25a889e.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Vor dem Hintergrund der anhaltenden Unruhen im Land k\u00fcndigte der haitianische Interimsregierungschef Ariel Henry seinen R\u00fccktritt an. F\u00fcr die \u00dcbergangszeit soll ein Pr\u00e4sidialrat gegr\u00fcndet werden, der die Macht vor\u00fcbergehend \u00fcbernehmen soll.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Angesichts der Eskalation der Bandengewalt hat die Regierung in Haiti den Ausnahmezustand und eine n\u00e4chtliche Ausgangssperre f\u00fcr die Hauptstadt Port-au-Prince verh\u00e4ngt. Nun will Ariel Henry, der im Land seit der Ermordung des letzten gew\u00e4hlten Pr\u00e4sidenten Jovenel Mo\u00efse im Sommer 2021 regierte, sein Amt niederlegen. Damit soll er sich bereit erkl\u00e4rt haben, einem Vorschlag der karibischen Staatengemeinschaft Caricom zu folgen.<\/p>\n<p>Henry habe in einer Videoansprache bekanntgegeben, dass seine Regierung sofort nach der Einsetzung eines \u00dcbergangs-Pr\u00e4sidialrates zur\u00fccktreten werde, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.reuters.com\/world\/americas\/blinken-travel-jamaica-caricom-meeting-haiti-us-state-dept-says-2024-03-11\/\">berichtete<\/a> Reuters. &#8220;Ich m\u00f6chte dem haitianischen Volk f\u00fcr die Chance danken, die mir gew\u00e4hrt wurde&#8221;, so der Premier. Er rief die Haitianer dazu auf, &#8220;Ruhe zu bewahren und alles zu tun, damit Frieden und Stabilit\u00e4t so schnell wie m\u00f6glich zur\u00fcckkehren&#8221;.<\/p>\n<p>Guyanas Pr\u00e4sident Mohamed Irfaan Ali soll inzwischen mitgeteilt haben, dass ein siebenk\u00f6pfiger Pr\u00e4sidialrat f\u00fcr den \u00dcbergang bis zu Wahlen in Haiti gegr\u00fcndet werde. Dieser Rat solle einen neuen Interimspremierminister bestimmen. Im Anschluss an die j\u00fcngsten Verhandlungen der karibischen Staatengemeinschaft in Jamaika erkl\u00e4rte Ali, dass &#8220;wir in diesem Zusammenhang den R\u00fccktritt von Premierminister Ariel Henry anerkennen&#8221;.<\/p>\n<p>Haiti steckt seit langem in einer sozialen und politischen Krise, die nach der Ermordung von Pr\u00e4sident Jovenel Moise am 7. Juli 2021 eskalierte. Das Land war mit einem beispiellosen Anstieg der Aktivit\u00e4ten krimineller Gruppen konfrontiert worden, w\u00e4hrend sich die humanit\u00e4re Lage aufgrund mehrerer Naturkatastrophen verschlechterte.<\/p>\n<p>Ende Februar spitzte sich die Lage zu. W\u00e4hrend sich Henry auf einer Auslandsreise in Kenia befand, um dort ein Abkommen \u00fcber die Entsendung einer Eingreiftruppe zu unterzeichnen, mit der Haiti die Bandenkriege unter Kontrolle bekommen wollte, kam es zum Aufstand. Eine bewaffnete Bande st\u00fcrmte Haitis gr\u00f6\u00dftes Gef\u00e4ngnis und befreite Hunderte H\u00e4ftlinge. Ausufernde Bandengewalt sorgte f\u00fcr Tote und Verletzte. Die bewaffneten Gruppen forderten den R\u00fccktritt von Ariel Henry.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/kurzclips\/video\/198881-haiti-banden-greifen-regierungsgebaeude-an\/\">Haiti: Banden greifen Regierungsgeb\u00e4ude an<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/nordamerika\/199079-haiti-interimspremier-henry-tritt-zurueck\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vor dem Hintergrund der anhaltenden Unruhen im Land k\u00fcndigte der haitianische Interimsregierungschef Ariel Henry seinen R\u00fccktritt an. F\u00fcr die \u00dcbergangszeit soll ein Pr\u00e4sidialrat gegr\u00fcndet werden, der die Macht vor\u00fcbergehend \u00fcbernehmen soll. Angesichts der Eskalation der Bandengewalt hat die Regierung in Haiti den Ausnahmezustand und eine n\u00e4chtliche Ausgangssperre f\u00fcr die Hauptstadt Port-au-Prince verh\u00e4ngt. Nun will Ariel [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":56938,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1710243758"],"wp_automatic_camp":["217"],"d6c51e2155c477fb45087af1ff56e9e8":["Haiti: Interimspremier Henry tritt zur\u00fcck"],"original_link":["https:\/\/de.rt.com\/nordamerika\/199079-haiti-interimspremier-henry-tritt-zurueck\/"],"_thumbnail_id":["56938"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-03-12 13:43:47\";}"],"jnews_social_counter_last_update":["1778651697"]},"categories":[19,23],"tags":[21898,8112,54347,3470,3337],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Haiti: Interimspremier Henry tritt zur\u00fcck - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Haiti: Interimspremier Henry tritt zur\u00fcck\" \/>\n<meta property=\"og:description\" content=\"Vor dem Hintergrund der anhaltenden Unruhen im Land k\u00fcndigte der haitianische Interimsregierungschef Ariel Henry seinen R\u00fccktritt an. F\u00fcr die \u00dcbergangszeit soll ein Pr\u00e4sidialrat gegr\u00fcndet werden, der die Macht vor\u00fcbergehend \u00fcbernehmen soll. Angesichts der Eskalation der Bandengewalt hat die Regierung in Haiti den Ausnahmezustand und eine n\u00e4chtliche Ausgangssperre f\u00fcr die Hauptstadt Port-au-Prince verh\u00e4ngt. Nun will Ariel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-12T11:34:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Haiti-Interimspremier-Henry-tritt-zurueck.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Haiti: Interimspremier Henry tritt zur\u00fcck\",\"datePublished\":\"2024-03-12T11:34:56+00:00\",\"dateModified\":\"2024-03-12T11:34:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/\"},\"wordCount\":370,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Haiti-Interimspremier-Henry-tritt-zurueck.jpg\",\"keywords\":[\"Haiti\",\"Henry\",\"Interimspremier\",\"tritt\",\"zur\u00fcck\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/\",\"name\":\"Haiti: Interimspremier Henry tritt zur\u00fcck - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Haiti-Interimspremier-Henry-tritt-zurueck.jpg\",\"datePublished\":\"2024-03-12T11:34:56+00:00\",\"dateModified\":\"2024-03-12T11:34:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Haiti-Interimspremier-Henry-tritt-zurueck.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Haiti-Interimspremier-Henry-tritt-zurueck.jpg\",\"width\":460,\"height\":259,\"caption\":\"Haiti: Interimspremier Henry tritt zur\u00fcck\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Haiti: Interimspremier Henry tritt zur\u00fcck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Haiti: Interimspremier Henry tritt zur\u00fcck - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/","og_locale":"de_DE","og_type":"article","og_title":"Haiti: Interimspremier Henry tritt zur\u00fcck","og_description":"Vor dem Hintergrund der anhaltenden Unruhen im Land k\u00fcndigte der haitianische Interimsregierungschef Ariel Henry seinen R\u00fccktritt an. F\u00fcr die \u00dcbergangszeit soll ein Pr\u00e4sidialrat gegr\u00fcndet werden, der die Macht vor\u00fcbergehend \u00fcbernehmen soll. Angesichts der Eskalation der Bandengewalt hat die Regierung in Haiti den Ausnahmezustand und eine n\u00e4chtliche Ausgangssperre f\u00fcr die Hauptstadt Port-au-Prince verh\u00e4ngt. Nun will Ariel [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-03-12T11:34:56+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Haiti-Interimspremier-Henry-tritt-zurueck.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Haiti: Interimspremier Henry tritt zur\u00fcck","datePublished":"2024-03-12T11:34:56+00:00","dateModified":"2024-03-12T11:34:56+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/"},"wordCount":370,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Haiti-Interimspremier-Henry-tritt-zurueck.jpg","keywords":["Haiti","Henry","Interimspremier","tritt","zur\u00fcck"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/","url":"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/","name":"Haiti: Interimspremier Henry tritt zur\u00fcck - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Haiti-Interimspremier-Henry-tritt-zurueck.jpg","datePublished":"2024-03-12T11:34:56+00:00","dateModified":"2024-03-12T11:34:56+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Haiti-Interimspremier-Henry-tritt-zurueck.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/03\/Haiti-Interimspremier-Henry-tritt-zurueck.jpg","width":460,"height":259,"caption":"Haiti: Interimspremier Henry tritt zur\u00fcck"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/haiti-interimspremier-henry-tritt-zurueck\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Haiti: Interimspremier Henry tritt zur\u00fcck"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/56937"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=56937"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/56937\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/56938"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=56937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=56937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=56937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}