{"id":56259,"date":"2024-02-29T19:09:35","date_gmt":"2024-02-29T17:09:35","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/"},"modified":"2024-02-29T19:09:35","modified_gmt":"2024-02-29T17:09:35","slug":"was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/","title":{"rendered":"Was bedeuten Macrons \u00c4u\u00dferungen zur Entsendung von Bodentruppen?"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2024\/02\/65e0724648fbef4d531e44b7.jpeg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Noch erh\u00e4lt Frankreichs Staatschef kaum Zuspruch f\u00fcr seine Aussage, dass man alles tun m\u00fcsse, um Russlands Sieg zu verhindern, und deshalb &#8220;nichts ausgeschlossen&#8221; werden solle. Dass einige f\u00fcr die Verteidigung der NATO offensichtlich alles tun w\u00fcrden, ist be\u00e4ngstigend.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Pierre L\u00e9vy<\/em><\/p>\n<p>Emmanuel Macrons \u00c4u\u00dferungen \u00fcber den weiteren Verlauf des Krieges in der Ukraine blieben nicht unbemerkt. Nach der Konferenz, an der am 26. Februar rund 20 seiner westlichen Amtskollegen in Paris teilnahmen, schloss der franz\u00f6sische Pr\u00e4sident die Entsendung von Bodentruppen zur Unterst\u00fctzung der sich in einer schwierigen Lage befindenden ukrainischen Armee nicht aus.<\/p>\n<p>In Bezug auf die Arbeiten dieses informellen Gipfels, der sich mit der Frage befasste, wie die Milit\u00e4rhilfe f\u00fcr Kiew aufgestockt werden kann, erkl\u00e4rte der \u00c9lys\u00e9e-Palast vor Journalisten unter anderem: &#8220;Es gibt heute keinen Konsens, um auf offizielle, best\u00e4tigte und unterst\u00fctzte Weise Bodentruppen zu entsenden; aber in der Dynamik darf nichts ausgeschlossen werden.&#8221; Dieser Satz k\u00f6nnte indirekt best\u00e4tigen, dass westliche Spezialtruppen vor Ort schon Unterst\u00fctzung leisten, allerdings auf &#8220;inoffizielle und nicht best\u00e4tigte Weise&#8221;, was in Wirklichkeit ein offenes Geheimnis ist.<\/p>\n<p>Er f\u00fcgte hinzu: &#8220;Aber nichts darf ausgeschlossen werden, (denn) wir werden alles tun, damit Russland diesen Krieg nicht gewinnen kann.&#8221; Was die m\u00f6gliche Beteiligung franz\u00f6sischer Truppen an potenziellen Operationen angeht, stellte der Staatschef klar: &#8220;Ich habe absolut nicht gesagt, dass Frankreich dies nicht bef\u00fcrwortet.&#8221; Dies ist eine geschraubte Formulierung, die die T\u00fcr \u00f6ffnet.<\/p>\n<p>Bisher handelt es sich nur um Worte. Aber in diesem Zusammenhang wiegen sie schwer und stellen einen Wendepunkt dar. Viele Analysten stellten fest, dass ein &#8220;Tabu gebrochen&#8221; wurde. Denn bislang hatten die westlichen Politiker immer darauf geachtet, die Haltung der &#8220;Nicht-Beteiligung&#8221; der NATO gegen\u00fcber Russland zu pflegen, auch wenn dies angesichts der Waffen- und Munitionslieferungen an Kiew im Wert von zig Milliarden Euro eher ein Mythos war.<\/p>\n<p>Emmanuel Macron r\u00e4umte jedoch ein, dass es keinen Konsens \u00fcber seinen Vorschlag gab. Um es gelinde auszudr\u00fccken &#8230; Der deutsche Bundeskanzler Olaf Scholz reagierte umgehend und schloss den Einsatz von Bodentruppen aus. Der scheidende niederl\u00e4ndische Premierminister Mark Rutte, der als n\u00e4chster NATO-Generalsekret\u00e4r gehandelt wird, tat das Gleiche.<\/p>\n<p>Danach folgte eine Ablehnung nach der anderen, von Spanien, Italien, Schweden, dem Vereinigten K\u00f6nigreich und sogar von Polen. Der slowakische Regierungschef Robert Fico, dem seine Gegner vorwerfen, genauso &#8220;prorussisch&#8221; zu sein wie sein ungarischer Kollege, erkl\u00e4rte, er sei nach Paris gereist, um die, wie er es nannte, &#8220;schlimmstm\u00f6gliche Entscheidung&#8221; abzulehnen.<\/p>\n<p>Nur das kleine Litauen zeigte sich interessiert. Was Estland, einen anderen baltischen Staat, betrifft, so erw\u00e4hnte der ehemalige Kommandeur der Streitkr\u00e4fte, der jetzt Europaabgeordneter ist, &#8220;die M\u00f6glichkeit, dass Macron dies gesagt hat, weil er wei\u00df, dass Scholz dagegen ist&#8221;.<\/p>\n<p>Besonders bemerkenswert ist, dass der derzeitige NATO-Generalsekret\u00e4r Jens Stoltenberg sich h\u00fctete, den Vorschlag Macrons zu billigen. Der US-Pr\u00e4sident seinerseits wies den Vorschlag offen zur\u00fcck. Auch auf der innenpolitischen B\u00fchne, wo alle Oppositionen dieses Abenteurertum verurteilten, fand der Pr\u00e4sident keine Unterst\u00fctzung.<\/p>\n<p>Schlie\u00dflich haben viele Analysten auf ein Paradoxon hingewiesen. Im Jahr 2022 hatte Emmanuel Macron bekr\u00e4ftigt, dass es von Interesse sei, einen Dialog mit seinem russischen Amtskollegen aufrechtzuerhalten, und damit die Spottlust und Kritik der Ultraatlantiker auf sich gezogen. Letztere beschuldigten ihn auch, bei den Waffenlieferungen an Kiew zu z\u00f6gern.<\/p>\n<p>Der Pr\u00e4sident des \u00c9lys\u00e9e-Palastes \u00fcbte also eine Art Selbstkritik und stellte fest: &#8220;Viele von denen, die heute &#8216;nie, nie&#8217; sagen, waren dieselben, die vor zwei Jahren &#8216;nie Panzer, nie Flugzeuge, nie Langstreckenraketen&#8217; sagten.&#8221; Von nun an will er zeigen, dass er sich ge\u00e4ndert hat, und beschreibt seine Geisteshaltung folgenderma\u00dfen: &#8220;Alles ist m\u00f6glich, wenn es f\u00fcr die Erreichung unseres Ziels n\u00fctzlich ist.&#8221; Mit einem zentralen Zweck: &#8220;Wir werden alles tun, was n\u00f6tig ist, damit Russland diesen Krieg nicht gewinnen kann.&#8221;<\/p>\n<p>Man kann sich die Reaktionen des Westens vorstellen, wenn ein russischer F\u00fchrer gesagt h\u00e4tte: &#8220;Alles ist m\u00f6glich, wenn es unserem Ziel dient.&#8221; Der Medienchor h\u00e4tte sofort eine kaum verh\u00fcllte nukleare Erpressung angeprangert. Selbst wenn dies nicht die Absicht des franz\u00f6sischen Pr\u00e4sidenten gewesen sein sollte, so wei\u00df doch jeder, dass Frankreich \u00fcber Atomwaffen verf\u00fcgt, was es erforderlich machen sollte, zweimal dar\u00fcber nachzudenken, bevor man mit einem direkten Einsatz der Streitkr\u00e4fte droht.<\/p>\n<p>Wie l\u00e4sst sich also eine solche Radikalisierung von Emmanuel Macron erkl\u00e4ren?<\/p>\n<p>Man muss die innenpolitischen Gr\u00fcnde, die einige angef\u00fchrt haben, beiseiteschieben. Sicherlich ist der Pr\u00e4sident in Schwierigkeiten und bef\u00fcrchtet, dass seine Freunde bei den Europawahlen am 9. Juni sehr weit hinter die Liste des Rassemblement National (RN) zur\u00fcckfallen werden. Es ist jedoch unwahrscheinlich, dass der \u00c9lys\u00e9e-Palast darauf hofft, viele Stimmen zu ergattern, indem er angesichts der Kandidaten von Marine Le Pen, die beschuldigt werden, Moskau zu unterst\u00fctzen, auf Krieg dr\u00e4ngt. Im Gegenteil &#8230;<\/p>\n<p><strong>Diplomatie ein Gebot der Vernunft<\/strong><\/p>\n<p>Eine erste wahrscheinliche Erkl\u00e4rung ist diese Einsicht: Die Hoffnungen des Westens, Russland eine dem\u00fctigende Niederlage beizubringen, sind heute v\u00f6llig vergeblich. W\u00e4hrend dieser Ausgang noch vor wenigen Monaten von den Mainstream-Medien als sicher dargestellt wurde, mussten diese eine spektakul\u00e4re Kehrtwende vollziehen: Trotz der massiven Unterst\u00fctzung f\u00fcr Kiew und der Sanktionen gegen Moskau (die schwersten, die je gegen ein Land verh\u00e4ngt wurden), k\u00f6nnen die Euro-Atlantiker nun nur noch ihr dreifaches Scheitern feststellen. Die russische Armee ist wieder in die Offensive gegangen; die russische Wirtschaft ist keineswegs &#8220;in die Knie gegangen&#8221;, wie der franz\u00f6sische Wirtschaftsminister vorhergesagt hatte; und der &#8220;globale S\u00fcden&#8221; hat sich keineswegs unter das diplomatische Banner des Westens gestellt und prangert stattdessen die &#8220;Doppelstandards&#8221; der von Uncle Sam dominierten Allianz an.<\/p>\n<p>Unter diesen Umst\u00e4nden w\u00e4re es ein Gebot der Vernunft, der Diplomatie den Vorrang zu geben. Die macronsche Antwort ist im Gegensatz dazu eine Flucht nach vorn.<\/p>\n<p>Eine zweite, erg\u00e4nzende Erkl\u00e4rung ist wahrscheinlich in den internen Machtverh\u00e4ltnissen der EU zu suchen. Bei vielen Themen sind die Differenzen zwischen Paris und Berlin kein Geheimnis und werden sogar noch gr\u00f6\u00dfer (Kernenergie, Anwendung des Stabilit\u00e4tspakts, gemeinsame Anleihen, Handel mit China und generell freier Welthandel, Integration und Priorit\u00e4t des europ\u00e4ischen milit\u00e4risch-industriellen Komplexes &#8230;).<\/p>\n<p>Es ist nicht auszuschlie\u00dfen, dass der franz\u00f6sische Staatschef versucht, eine globale Machtposition unter den 27 gegen\u00fcber seinem deutschen Amtskollegen zu etablieren, insbesondere mithilfe einiger osteurop\u00e4ischer L\u00e4nder, und sich deshalb auf einen gewissen \u00dcberbietungswettbewerb einl\u00e4sst. In diesem Fall w\u00fcrde sich die EU \u2013 und das Prinzip der europ\u00e4ischen Integration an sich \u2013 durch die Rivalit\u00e4ten, die sie hervorruft, als ein weiterer sch\u00e4dlicher Faktor best\u00e4tigen.<\/p>\n<p>Wie dem auch sei, eines scheint sicher: Unabh\u00e4ngig von der Haltung der einen oder anderen Seite wissen die gro\u00dfen F\u00fchrer des atlantischen B\u00fcndnisses, dass die Glaubw\u00fcrdigkeit der NATO auf dem Spiel steht. Dass einige &#8220;nichts ausschlie\u00dfen&#8221;, um sie zu verteidigen, ist nicht sehr beruhigend.<\/p>\n<p><strong>Mehr zum Thema &#8211; <\/strong><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/197800-wolodin-franzosen-droht-bei-truppenentsendung\/\">Wolodin: Franzosen droht bei Truppenentsendung in Ukraine \u00e4hnliches Schicksal wie 1812<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/197819-was-bedeuten-macrons-aeusserungen-zur\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noch erh\u00e4lt Frankreichs Staatschef kaum Zuspruch f\u00fcr seine Aussage, dass man alles tun m\u00fcsse, um Russlands Sieg zu verhindern, und deshalb &#8220;nichts ausgeschlossen&#8221; werden solle. Dass einige f\u00fcr die Verteidigung der NATO offensichtlich alles tun w\u00fcrden, ist be\u00e4ngstigend. Von Pierre L\u00e9vy Emmanuel Macrons \u00c4u\u00dferungen \u00fcber den weiteren Verlauf des Krieges in der Ukraine blieben nicht [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":56260,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1709227344"],"wp_automatic_camp":["217"],"5a9674a5e5e4af71719a6855ff26b2fa":["Was bedeuten Macrons \u00c4u\u00dferungen zur Entsendung von Bodentruppen?"],"original_link":["https:\/\/de.rt.com\/meinung\/197819-was-bedeuten-macrons-aeusserungen-zur\/"],"_thumbnail_id":["56260"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-02-29 19:23:23\";}"],"jnews_social_counter_last_update":["1784099439"]},"categories":[19,23],"tags":[19203,22292,45384,26691,24029,50,581],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Was bedeuten Macrons \u00c4u\u00dferungen zur Entsendung von Bodentruppen? - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Was bedeuten Macrons \u00c4u\u00dferungen zur Entsendung von Bodentruppen?\" \/>\n<meta property=\"og:description\" content=\"Noch erh\u00e4lt Frankreichs Staatschef kaum Zuspruch f\u00fcr seine Aussage, dass man alles tun m\u00fcsse, um Russlands Sieg zu verhindern, und deshalb &#8220;nichts ausgeschlossen&#8221; werden solle. Dass einige f\u00fcr die Verteidigung der NATO offensichtlich alles tun w\u00fcrden, ist be\u00e4ngstigend. Von Pierre L\u00e9vy Emmanuel Macrons \u00c4u\u00dferungen \u00fcber den weiteren Verlauf des Krieges in der Ukraine blieben nicht [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-29T17:09:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/02\/Was-bedeuten-Macrons-Aeusserungen-zur-Entsendung-von-Bodentruppen.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Was bedeuten Macrons \u00c4u\u00dferungen zur Entsendung von Bodentruppen?\",\"datePublished\":\"2024-02-29T17:09:35+00:00\",\"dateModified\":\"2024-02-29T17:09:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/\"},\"wordCount\":1189,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/02\/Was-bedeuten-Macrons-Aeusserungen-zur-Entsendung-von-Bodentruppen.jpeg\",\"keywords\":[\"\u00c4u\u00dferungen\",\"bedeuten\",\"Bodentruppen\",\"Entsendung\",\"Macrons\",\"von\",\"zur\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/\",\"name\":\"Was bedeuten Macrons \u00c4u\u00dferungen zur Entsendung von Bodentruppen? - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/02\/Was-bedeuten-Macrons-Aeusserungen-zur-Entsendung-von-Bodentruppen.jpeg\",\"datePublished\":\"2024-02-29T17:09:35+00:00\",\"dateModified\":\"2024-02-29T17:09:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/02\/Was-bedeuten-Macrons-Aeusserungen-zur-Entsendung-von-Bodentruppen.jpeg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/02\/Was-bedeuten-Macrons-Aeusserungen-zur-Entsendung-von-Bodentruppen.jpeg\",\"width\":460,\"height\":259,\"caption\":\"Was bedeuten Macrons \u00c4u\u00dferungen zur Entsendung von Bodentruppen?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Was bedeuten Macrons \u00c4u\u00dferungen zur Entsendung von Bodentruppen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Was bedeuten Macrons \u00c4u\u00dferungen zur Entsendung von Bodentruppen? - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/","og_locale":"de_DE","og_type":"article","og_title":"Was bedeuten Macrons \u00c4u\u00dferungen zur Entsendung von Bodentruppen?","og_description":"Noch erh\u00e4lt Frankreichs Staatschef kaum Zuspruch f\u00fcr seine Aussage, dass man alles tun m\u00fcsse, um Russlands Sieg zu verhindern, und deshalb &#8220;nichts ausgeschlossen&#8221; werden solle. Dass einige f\u00fcr die Verteidigung der NATO offensichtlich alles tun w\u00fcrden, ist be\u00e4ngstigend. Von Pierre L\u00e9vy Emmanuel Macrons \u00c4u\u00dferungen \u00fcber den weiteren Verlauf des Krieges in der Ukraine blieben nicht [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-02-29T17:09:35+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/02\/Was-bedeuten-Macrons-Aeusserungen-zur-Entsendung-von-Bodentruppen.jpeg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Was bedeuten Macrons \u00c4u\u00dferungen zur Entsendung von Bodentruppen?","datePublished":"2024-02-29T17:09:35+00:00","dateModified":"2024-02-29T17:09:35+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/"},"wordCount":1189,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/02\/Was-bedeuten-Macrons-Aeusserungen-zur-Entsendung-von-Bodentruppen.jpeg","keywords":["\u00c4u\u00dferungen","bedeuten","Bodentruppen","Entsendung","Macrons","von","zur"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/","url":"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/","name":"Was bedeuten Macrons \u00c4u\u00dferungen zur Entsendung von Bodentruppen? - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/02\/Was-bedeuten-Macrons-Aeusserungen-zur-Entsendung-von-Bodentruppen.jpeg","datePublished":"2024-02-29T17:09:35+00:00","dateModified":"2024-02-29T17:09:35+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/02\/Was-bedeuten-Macrons-Aeusserungen-zur-Entsendung-von-Bodentruppen.jpeg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/02\/Was-bedeuten-Macrons-Aeusserungen-zur-Entsendung-von-Bodentruppen.jpeg","width":460,"height":259,"caption":"Was bedeuten Macrons \u00c4u\u00dferungen zur Entsendung von Bodentruppen?"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/was-bedeuten-macrons-aeusserungen-zur-entsendung-von-bodentruppen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Was bedeuten Macrons \u00c4u\u00dferungen zur Entsendung von Bodentruppen?"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/56259"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=56259"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/56259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/56260"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=56259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=56259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=56259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}