{"id":54019,"date":"2024-01-26T13:48:57","date_gmt":"2024-01-26T11:48:57","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/"},"modified":"2024-01-26T13:48:57","modified_gmt":"2024-01-26T11:48:57","slug":"konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/","title":{"rendered":"Konfessionslose werden in der Schweiz zur gr\u00f6\u00dften Bev\u00f6lkerungsgruppe"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/65b3779a48fbef443f230ec5.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Auch in der Schweiz findest ein historischer Wandel in der Religionslandschaft statt: Jeder dritte B\u00fcrger der Schweiz ist konfessionslos, ausgel\u00f6st durch Austritte nach Skandalen und wachsende Distanzierung von religi\u00f6sen Prinzipien. Regionale Unterschiede in Alter, Bildung und Herkunft pr\u00e4gen diesen epochalen Paradigmenwechsel.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die neuesten Zahlen des schweizerischen <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bfs.admin.ch\/bfs\/de\/home\/statistiken\/bevoelkerung\/sprachen-religionen\/religionen.html#:~:text=Ein%20Drittel%20der%20Kinder%20ist,8%25%20einer%20anderen%20Religion%20an\">Bundesamtes<\/a> f\u00fcr Statistik zeigen einen bedeutenden Wandel in der religi\u00f6sen Landschaft der Eidgenossenschaft: Zum ersten Mal stellen Konfessionslose die gr\u00f6\u00dfte Bev\u00f6lkerungsgruppe dar, und zwar mit fast 34 Prozent Anteil an der Gesamtbev\u00f6lkerung. Der Anstieg der Zahl Konfessionsloser wird durch Austritte aus den traditionellen Landeskirchen, insbesondere nach Skandalen, und durch eine wachsende Distanzierung von religi\u00f6sen Prinzipien getrieben. Im Jahr 2022 verzeichnete die Schweiz einen Rekordwert von mehr als 60.000 Kirchenaustritten.<\/p>\n<p>Trotz der verst\u00e4rkten Austritte aus den Kirchen zeigen sich regionale Unterschiede, wobei die Romandie, also die franz\u00f6sischsprachige Schweiz, laut dem <em>Tages-Anzeiger<\/em> nun den h\u00f6chsten Anteil an konfessionslosen Menschen verzeichnet. St\u00e4dtische Kommunen weisen ebenfalls h\u00f6here Anteile auf als l\u00e4ndliche Gebiete. Basel f\u00fchrt mit einem beeindruckenden Anteil von 56 Prozent an Konfessionslosen. Das Alter spielt offenbar eine entscheidende Rolle, denn j\u00fcngere Generationen sind h\u00e4ufiger konfessionslos. Bildungsniveau und Herkunft beeinflussen ebenfalls die Religionszugeh\u00f6rigkeit, wobei sowohl Hochschulabschl\u00fcsse als auch Migrationshintergr\u00fcnde eine Rolle spielen.<\/p>\n<p>Im internationalen Vergleich liegt die Schweiz zwar \u00fcber dem europ\u00e4ischen Durchschnitt an Konfessionslosen, bleibt jedoch hinter L\u00e4ndern wie Frankreich und Deutschland noch zur\u00fcck. Dieser Wandel hat \u2013 wie \u00fcberall \u2013 direkte Auswirkungen auf die Kirchen, die mit r\u00fcckl\u00e4ufigen Mitgliederzahlen, geringerer Teilnahme an Gottesdiensten und finanziellen Einbu\u00dfen konfrontiert sind. Es wird erwartet, dass dieser Trend in den kommenden Jahren weiter anhalten wird, was zu einer Ver\u00e4nderung des gesellschaftlichen Engagements in religi\u00f6sen Institutionen f\u00fchren k\u00f6nnte.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0&#8211;\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/189256-cancel-culture-hamburger-kita-lehnt\/\">Cancel Culture: Hamburger Kita lehnt Weihnachtsbaum ab<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/schweiz\/194031-konfessionslose-werden-zur-groessten-gruppe\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auch in der Schweiz findest ein historischer Wandel in der Religionslandschaft statt: Jeder dritte B\u00fcrger der Schweiz ist konfessionslos, ausgel\u00f6st durch Austritte nach Skandalen und wachsende Distanzierung von religi\u00f6sen Prinzipien. Regionale Unterschiede in Alter, Bildung und Herkunft pr\u00e4gen diesen epochalen Paradigmenwechsel. Die neuesten Zahlen des schweizerischen Bundesamtes f\u00fcr Statistik zeigen einen bedeutenden Wandel in der [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":54020,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1706270081"],"wp_automatic_camp":["217"],"8e82a943f1b3bbf01fe4130e3f752283":["Konfessionslose werden in der Schweiz zur gr\u00f6\u00dften Bev\u00f6lkerungsgruppe"],"original_link":["https:\/\/de.rt.com\/schweiz\/194031-konfessionslose-werden-zur-groessten-gruppe\/"],"_thumbnail_id":["54020"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-01-26 13:56:04\";}"],"jnews_social_counter_last_update":["1784103848"]},"categories":[19,23],"tags":[52847,82,14435,52846,4207,1040,581],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Konfessionslose werden in der Schweiz zur gr\u00f6\u00dften Bev\u00f6lkerungsgruppe - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Konfessionslose werden in der Schweiz zur gr\u00f6\u00dften Bev\u00f6lkerungsgruppe\" \/>\n<meta property=\"og:description\" content=\"Auch in der Schweiz findest ein historischer Wandel in der Religionslandschaft statt: Jeder dritte B\u00fcrger der Schweiz ist konfessionslos, ausgel\u00f6st durch Austritte nach Skandalen und wachsende Distanzierung von religi\u00f6sen Prinzipien. Regionale Unterschiede in Alter, Bildung und Herkunft pr\u00e4gen diesen epochalen Paradigmenwechsel. Die neuesten Zahlen des schweizerischen Bundesamtes f\u00fcr Statistik zeigen einen bedeutenden Wandel in der [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-26T11:48:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Konfessionslose-werden-in-der-Schweiz-zur-groessten-Bevoelkerungsgruppe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Konfessionslose werden in der Schweiz zur gr\u00f6\u00dften Bev\u00f6lkerungsgruppe\",\"datePublished\":\"2024-01-26T11:48:57+00:00\",\"dateModified\":\"2024-01-26T11:48:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/\"},\"wordCount\":317,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Konfessionslose-werden-in-der-Schweiz-zur-groessten-Bevoelkerungsgruppe.jpg\",\"keywords\":[\"Bev\u00f6lkerungsgruppe\",\"der\",\"gr\u00f6\u00dften\",\"Konfessionslose\",\"schweiz\",\"Werden\",\"zur\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/\",\"name\":\"Konfessionslose werden in der Schweiz zur gr\u00f6\u00dften Bev\u00f6lkerungsgruppe - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Konfessionslose-werden-in-der-Schweiz-zur-groessten-Bevoelkerungsgruppe.jpg\",\"datePublished\":\"2024-01-26T11:48:57+00:00\",\"dateModified\":\"2024-01-26T11:48:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Konfessionslose-werden-in-der-Schweiz-zur-groessten-Bevoelkerungsgruppe.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Konfessionslose-werden-in-der-Schweiz-zur-groessten-Bevoelkerungsgruppe.jpg\",\"width\":460,\"height\":259,\"caption\":\"Konfessionslose werden in der Schweiz zur gr\u00f6\u00dften Bev\u00f6lkerungsgruppe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Konfessionslose werden in der Schweiz zur gr\u00f6\u00dften Bev\u00f6lkerungsgruppe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Konfessionslose werden in der Schweiz zur gr\u00f6\u00dften Bev\u00f6lkerungsgruppe - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/","og_locale":"de_DE","og_type":"article","og_title":"Konfessionslose werden in der Schweiz zur gr\u00f6\u00dften Bev\u00f6lkerungsgruppe","og_description":"Auch in der Schweiz findest ein historischer Wandel in der Religionslandschaft statt: Jeder dritte B\u00fcrger der Schweiz ist konfessionslos, ausgel\u00f6st durch Austritte nach Skandalen und wachsende Distanzierung von religi\u00f6sen Prinzipien. Regionale Unterschiede in Alter, Bildung und Herkunft pr\u00e4gen diesen epochalen Paradigmenwechsel. Die neuesten Zahlen des schweizerischen Bundesamtes f\u00fcr Statistik zeigen einen bedeutenden Wandel in der [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-01-26T11:48:57+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Konfessionslose-werden-in-der-Schweiz-zur-groessten-Bevoelkerungsgruppe.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Konfessionslose werden in der Schweiz zur gr\u00f6\u00dften Bev\u00f6lkerungsgruppe","datePublished":"2024-01-26T11:48:57+00:00","dateModified":"2024-01-26T11:48:57+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/"},"wordCount":317,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Konfessionslose-werden-in-der-Schweiz-zur-groessten-Bevoelkerungsgruppe.jpg","keywords":["Bev\u00f6lkerungsgruppe","der","gr\u00f6\u00dften","Konfessionslose","schweiz","Werden","zur"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/","url":"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/","name":"Konfessionslose werden in der Schweiz zur gr\u00f6\u00dften Bev\u00f6lkerungsgruppe - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Konfessionslose-werden-in-der-Schweiz-zur-groessten-Bevoelkerungsgruppe.jpg","datePublished":"2024-01-26T11:48:57+00:00","dateModified":"2024-01-26T11:48:57+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Konfessionslose-werden-in-der-Schweiz-zur-groessten-Bevoelkerungsgruppe.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Konfessionslose-werden-in-der-Schweiz-zur-groessten-Bevoelkerungsgruppe.jpg","width":460,"height":259,"caption":"Konfessionslose werden in der Schweiz zur gr\u00f6\u00dften Bev\u00f6lkerungsgruppe"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/konfessionslose-werden-in-der-schweiz-zur-groessten-bevoelkerungsgruppe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Konfessionslose werden in der Schweiz zur gr\u00f6\u00dften Bev\u00f6lkerungsgruppe"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/54019"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=54019"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/54019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/54020"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=54019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=54019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=54019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}