{"id":53209,"date":"2024-01-14T10:05:05","date_gmt":"2024-01-14T08:05:05","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/"},"modified":"2024-01-14T10:05:05","modified_gmt":"2024-01-14T08:05:05","slug":"paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/","title":{"rendered":"Paschinjan will Aserbaidschan zum Abschluss eines R\u00fcstungskontrollabkommens bewegen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/65a2ddca48fbef2f0d3decaa.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der armenische Premierminister hat behauptet, dass Baku Vorschl\u00e4ge zum spiegelbildlichen Truppenabzug und zur Entmilitarisierung der Grenzgebiete abgelehnt habe. In diesem Zusammenhang schlug Paschinjan die Unterzeichnung eines R\u00fcstungskontrollabkommens vor.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Armeniens Premierminister Nikol Paschinjan hat Aserbaidschan vorgeschlagen, ein R\u00fcstungskontrollabkommen zu unterzeichnen, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.aysor.am\/ru\/news\/2024\/01\/13\/%D0%BF%D0%B0%D1%88%D0%B8%D0%BD%D1%8F%D0%BD-%D0%B0%D0%BB%D0%B8%D0%B5%D0%B2%D1%83\/2211546\">zitierte<\/a> ihn die Nachrichtenagentur <em>Aysor<\/em>. Er sagte:<strong><em><\/em><\/strong><\/p>\n<blockquote>\n<p><em>&#8220;Wir schlagen vor, wir sagen: Um die Sicherheit zu gew\u00e4hrleisten, sollten wir einen spiegelbildlichen R\u00fcckzug der Truppen von der in der Alma-Ata-Erkl\u00e4rung festgelegten Grenzlinie durchf\u00fchren, um das Risiko von Zusammenst\u00f6\u00dfen zu neutralisieren.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Baku lehne dies jedoch ab, so Paschinjan. Der armenische Premierminister erinnerte auch an den Vorschlag, eine entmilitarisierte Zone in den Grenzgebieten einzurichten, was Baku ebenfalls verweigerte. Er merkte an:<\/p>\n<blockquote>\n<p><em>&#8220;Ich kann einen anderen Vorschlag machen: Lassen Sie uns ein R\u00fcstungskontrollabkommen unterzeichnen, damit Armenien und Aserbaidschan konkrete Vereinbarungen \u00fcber Waffen treffen und die M\u00f6glichkeit haben, die Umsetzung der gegenseitigen Vereinbarungen zu \u00fcberwachen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Im vergangenen September f\u00fchrte Aserbaidschan eine &#8220;Anti-Terror-Operation&#8221; in Bergkarabach durch. Sie endete mit einem Waffenstillstandsabkommen, der Entwaffnung der milit\u00e4rischen Formationen Karabachs und der Wiedereingliederung der Region in Aserbaidschan zusammen mit der armenischen Bev\u00f6lkerung. Mehr als 100.000 Armenier \u2013 die Mehrheit der Bev\u00f6lkerung in der Region \u2013 haben Bergkarabach seitdem verlassen. Im Oktober hisste der aserbaidschanische Pr\u00e4sident Ilcham Alijew die Flagge seines Landes in Chankendi (armenischer Name Stepanakert), der Hauptstadt von Bergkarabach. Im November fand in der Stadt eine Siegesparade statt.<\/p>\n<p>Im Dezember erkl\u00e4rte der Kremlsprecher Dmitri Peskow, dass Aserbaidschan und Armenien keine &#8220;gegnerischen Seiten&#8221; sind und bereit seien, einen Friedensvertrag zu schlie\u00dfen.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/189657-armenien-strebt-engere-zusammenarbeit-mit\/\">Armenien strebt engere Zusammenarbeit mit EU an<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/192716-paschinjan-will-aserbaidschan-zum-abschluss\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der armenische Premierminister hat behauptet, dass Baku Vorschl\u00e4ge zum spiegelbildlichen Truppenabzug und zur Entmilitarisierung der Grenzgebiete abgelehnt habe. In diesem Zusammenhang schlug Paschinjan die Unterzeichnung eines R\u00fcstungskontrollabkommens vor. Armeniens Premierminister Nikol Paschinjan hat Aserbaidschan vorgeschlagen, ein R\u00fcstungskontrollabkommen zu unterzeichnen, zitierte ihn die Nachrichtenagentur Aysor. Er sagte: &#8220;Wir schlagen vor, wir sagen: Um die Sicherheit zu [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":53210,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1705219548"],"wp_automatic_camp":["217"],"801691547ced7bd9dc0a2f7c1476c24c":["Paschinjan will Aserbaidschan zum Abschluss eines R\u00fcstungskontrollabkommens bewegen"],"original_link":["https:\/\/de.rt.com\/international\/192716-paschinjan-will-aserbaidschan-zum-abschluss\/"],"_thumbnail_id":["53210"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-01-14 10:06:58\";}"],"jnews_social_counter_last_update":["1784130044"]},"categories":[19,23],"tags":[27901,10003,17173,2111,37744,52419,565],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Paschinjan will Aserbaidschan zum Abschluss eines R\u00fcstungskontrollabkommens bewegen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paschinjan will Aserbaidschan zum Abschluss eines R\u00fcstungskontrollabkommens bewegen\" \/>\n<meta property=\"og:description\" content=\"Der armenische Premierminister hat behauptet, dass Baku Vorschl\u00e4ge zum spiegelbildlichen Truppenabzug und zur Entmilitarisierung der Grenzgebiete abgelehnt habe. In diesem Zusammenhang schlug Paschinjan die Unterzeichnung eines R\u00fcstungskontrollabkommens vor. Armeniens Premierminister Nikol Paschinjan hat Aserbaidschan vorgeschlagen, ein R\u00fcstungskontrollabkommen zu unterzeichnen, zitierte ihn die Nachrichtenagentur Aysor. Er sagte: &#8220;Wir schlagen vor, wir sagen: Um die Sicherheit zu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-14T08:05:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Paschinjan-will-Aserbaidschan-zum-Abschluss-eines-Ruestungskontrollabkommens-bewegen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Paschinjan will Aserbaidschan zum Abschluss eines R\u00fcstungskontrollabkommens bewegen\",\"datePublished\":\"2024-01-14T08:05:05+00:00\",\"dateModified\":\"2024-01-14T08:05:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/\"},\"wordCount\":277,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Paschinjan-will-Aserbaidschan-zum-Abschluss-eines-Ruestungskontrollabkommens-bewegen.jpg\",\"keywords\":[\"Abschluss\",\"Aserbaidschan\",\"bewegen\",\"eines\",\"Paschinjan\",\"R\u00fcstungskontrollabkommens\",\"zum\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/\",\"name\":\"Paschinjan will Aserbaidschan zum Abschluss eines R\u00fcstungskontrollabkommens bewegen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Paschinjan-will-Aserbaidschan-zum-Abschluss-eines-Ruestungskontrollabkommens-bewegen.jpg\",\"datePublished\":\"2024-01-14T08:05:05+00:00\",\"dateModified\":\"2024-01-14T08:05:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Paschinjan-will-Aserbaidschan-zum-Abschluss-eines-Ruestungskontrollabkommens-bewegen.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Paschinjan-will-Aserbaidschan-zum-Abschluss-eines-Ruestungskontrollabkommens-bewegen.jpg\",\"width\":460,\"height\":259,\"caption\":\"Paschinjan will Aserbaidschan zum Abschluss eines R\u00fcstungskontrollabkommens bewegen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paschinjan will Aserbaidschan zum Abschluss eines R\u00fcstungskontrollabkommens bewegen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Paschinjan will Aserbaidschan zum Abschluss eines R\u00fcstungskontrollabkommens bewegen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/","og_locale":"de_DE","og_type":"article","og_title":"Paschinjan will Aserbaidschan zum Abschluss eines R\u00fcstungskontrollabkommens bewegen","og_description":"Der armenische Premierminister hat behauptet, dass Baku Vorschl\u00e4ge zum spiegelbildlichen Truppenabzug und zur Entmilitarisierung der Grenzgebiete abgelehnt habe. In diesem Zusammenhang schlug Paschinjan die Unterzeichnung eines R\u00fcstungskontrollabkommens vor. Armeniens Premierminister Nikol Paschinjan hat Aserbaidschan vorgeschlagen, ein R\u00fcstungskontrollabkommen zu unterzeichnen, zitierte ihn die Nachrichtenagentur Aysor. Er sagte: &#8220;Wir schlagen vor, wir sagen: Um die Sicherheit zu [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-01-14T08:05:05+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Paschinjan-will-Aserbaidschan-zum-Abschluss-eines-Ruestungskontrollabkommens-bewegen.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Paschinjan will Aserbaidschan zum Abschluss eines R\u00fcstungskontrollabkommens bewegen","datePublished":"2024-01-14T08:05:05+00:00","dateModified":"2024-01-14T08:05:05+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/"},"wordCount":277,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Paschinjan-will-Aserbaidschan-zum-Abschluss-eines-Ruestungskontrollabkommens-bewegen.jpg","keywords":["Abschluss","Aserbaidschan","bewegen","eines","Paschinjan","R\u00fcstungskontrollabkommens","zum"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/","url":"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/","name":"Paschinjan will Aserbaidschan zum Abschluss eines R\u00fcstungskontrollabkommens bewegen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Paschinjan-will-Aserbaidschan-zum-Abschluss-eines-Ruestungskontrollabkommens-bewegen.jpg","datePublished":"2024-01-14T08:05:05+00:00","dateModified":"2024-01-14T08:05:05+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Paschinjan-will-Aserbaidschan-zum-Abschluss-eines-Ruestungskontrollabkommens-bewegen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Paschinjan-will-Aserbaidschan-zum-Abschluss-eines-Ruestungskontrollabkommens-bewegen.jpg","width":460,"height":259,"caption":"Paschinjan will Aserbaidschan zum Abschluss eines R\u00fcstungskontrollabkommens bewegen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/paschinjan-will-aserbaidschan-zum-abschluss-eines-ruestungskontrollabkommens-bewegen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Paschinjan will Aserbaidschan zum Abschluss eines R\u00fcstungskontrollabkommens bewegen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/53209"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=53209"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/53209\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/53210"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=53209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=53209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=53209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}