{"id":52610,"date":"2024-01-02T19:22:32","date_gmt":"2024-01-02T17:22:32","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/"},"modified":"2024-01-02T19:22:32","modified_gmt":"2024-01-02T17:22:32","slug":"razzia-in-russischer-oelraffinerie-in-einem-eu-staat","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/","title":{"rendered":"Razzia in russischer \u00d6lraffinerie in einem EU-Staat"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/6594272748fbef01c5694b05.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Am Montag f\u00fchrten bulgarische Beamte eine Razzia in der \u00d6lraffinerie Neftochim, die dem russischen Unternehmen Lukoil geh\u00f6rt, sowie in 50 Roh\u00f6llagern durch. Die Kontrollen standen im Zusammenhang mit antirussischen Sanktionen, die Sofia Mitte Dezember beschlossen hatte.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Bulgarische Beamte f\u00fchrten am Montag eine Razzia in der \u00d6lraffinerie Neftochim und in 50 Roh\u00f6llagern durch, wie auf der Website der bulgarischen Zollbeh\u00f6rde bekannt gegeben wurde.<\/p>\n<p>Die Razzien fielen mit dem Beginn des Verbots f\u00fcr russisches Roh\u00f6l im Rahmen der antirussischen Sanktionen zusammen. Die Raffinerie Neftochim, die dem russischen Unternehmen Lukoil geh\u00f6rt, ist f\u00fcr den Gro\u00dfteil der bulgarischen Diesel- und Benzinlieferungen verantwortlich.<\/p>\n<p>Die Zollbeh\u00f6rde erkl\u00e4rte, dass die Kontrollen darauf abzielten, eine Bestandsaufnahme der noch verf\u00fcgbaren Mengen an russischem \u00d6l und \u00d6lprodukten vorzunehmen.<\/p>\n<p>Urspr\u00fcnglich war Bulgarien von einem EU-Verbot f\u00fcr russisches Roh\u00f6l ausgenommen gewesen und h\u00e4tte bis Ende 2024 weiter Roh\u00f6l beziehen d\u00fcrfen, doch Mitte Dezember verabschiedete Sofia einen Antrag, der die Ausnahme vorzeitig aufhob und die Einfuhr russischen \u00d6ls einschr\u00e4nkte. Das Verbot wird in zwei Stufen umgesetzt: Ab dem 1. Januar darf Neftochim keine Erd\u00f6lprodukte mehr exportieren, die aus russischem Roh\u00f6l hergestellt wurden, und ab dem 1. M\u00e4rz muss das Werk die Verwendung russischen \u00d6ls f\u00fcr die Raffination vollst\u00e4ndig einstellen. Branchenexperten haben bereits davor gewarnt, dass die Einstellung der Ausfuhr von Erd\u00f6lprodukten aus russischem Roh\u00f6l zu einer \u00dcberf\u00fcllung der Lager und einem R\u00fcckgang der Treibstoffproduktion in den kommenden Monaten f\u00fchren k\u00f6nnte.<\/p>\n<p>Lukoil hat sich noch nicht zu den Razzien ge\u00e4u\u00dfert. Das Unternehmen hat jedoch bereits davor gewarnt, dass das Verbot f\u00fcr die Raffinerie, die auf die besondere Qualit\u00e4t des russischen \u00d6ls ausgerichtet ist, Schwierigkeiten mit sich bringen w\u00fcrde.<\/p>\n<p>In einer Erkl\u00e4rung vom letzten Monat bezeichnete Lukoil den Plan Bulgariens, die Verwendung russischen \u00d6ls in seiner Raffinerie zu verbieten, als &#8220;voreingenommen und diskriminierend&#8221; und deutete an, dass das Unternehmen gezwungen sein k\u00f6nnte, sich aus dem Land zur\u00fcckzuziehen und Neftochim zu verkaufen.<\/p>\n<p><strong>Mehr zum Thema \u2013 <\/strong><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/kurzclips\/video\/190358-bulgarien-handgreiflichkeiten-im-parlament-wegen\/\">Bulgarien: Handgreiflichkeiten im Parlament wegen Verbot von russischem \u00d6l <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2FBulgarien-Handgreiflichkeiten-im-Parlament-wegen-Verbot-von-russischem-%C3%96l%3A3\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/191541-razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Montag f\u00fchrten bulgarische Beamte eine Razzia in der \u00d6lraffinerie Neftochim, die dem russischen Unternehmen Lukoil geh\u00f6rt, sowie in 50 Roh\u00f6llagern durch. Die Kontrollen standen im Zusammenhang mit antirussischen Sanktionen, die Sofia Mitte Dezember beschlossen hatte. Bulgarische Beamte f\u00fchrten am Montag eine Razzia in der \u00d6lraffinerie Neftochim und in 50 Roh\u00f6llagern durch, wie auf der [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":52611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1704216354"],"wp_automatic_camp":["217"],"1b172c2e64c96e126e064fc8493ceaa9":["Razzia in russischer \u00d6lraffinerie in einem EU-Staat"],"original_link":["https:\/\/de.rt.com\/europa\/191541-razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/"],"_thumbnail_id":["52611"],"jnews_social_counter_last_update":["1784109458"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-01-02 19:27:13\";}"]},"categories":[19,23],"tags":[352,41110,16850,1749,793],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Razzia in russischer \u00d6lraffinerie in einem EU-Staat - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Razzia in russischer \u00d6lraffinerie in einem EU-Staat\" \/>\n<meta property=\"og:description\" content=\"Am Montag f\u00fchrten bulgarische Beamte eine Razzia in der \u00d6lraffinerie Neftochim, die dem russischen Unternehmen Lukoil geh\u00f6rt, sowie in 50 Roh\u00f6llagern durch. Die Kontrollen standen im Zusammenhang mit antirussischen Sanktionen, die Sofia Mitte Dezember beschlossen hatte. Bulgarische Beamte f\u00fchrten am Montag eine Razzia in der \u00d6lraffinerie Neftochim und in 50 Roh\u00f6llagern durch, wie auf der [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-02T17:22:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Razzia-in-russischer-Oelraffinerie-in-einem-EU-Staat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Razzia in russischer \u00d6lraffinerie in einem EU-Staat\",\"datePublished\":\"2024-01-02T17:22:32+00:00\",\"dateModified\":\"2024-01-02T17:22:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/\"},\"wordCount\":363,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Razzia-in-russischer-Oelraffinerie-in-einem-EU-Staat.jpg\",\"keywords\":[\"einem\",\"EUStaat\",\"\u00d6lraffinerie\",\"Razzia\",\"Russischer\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/\",\"name\":\"Razzia in russischer \u00d6lraffinerie in einem EU-Staat - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Razzia-in-russischer-Oelraffinerie-in-einem-EU-Staat.jpg\",\"datePublished\":\"2024-01-02T17:22:32+00:00\",\"dateModified\":\"2024-01-02T17:22:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Razzia-in-russischer-Oelraffinerie-in-einem-EU-Staat.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Razzia-in-russischer-Oelraffinerie-in-einem-EU-Staat.jpg\",\"width\":460,\"height\":259,\"caption\":\"Razzia in russischer \u00d6lraffinerie in einem EU-Staat\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Razzia in russischer \u00d6lraffinerie in einem EU-Staat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Razzia in russischer \u00d6lraffinerie in einem EU-Staat - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/","og_locale":"de_DE","og_type":"article","og_title":"Razzia in russischer \u00d6lraffinerie in einem EU-Staat","og_description":"Am Montag f\u00fchrten bulgarische Beamte eine Razzia in der \u00d6lraffinerie Neftochim, die dem russischen Unternehmen Lukoil geh\u00f6rt, sowie in 50 Roh\u00f6llagern durch. Die Kontrollen standen im Zusammenhang mit antirussischen Sanktionen, die Sofia Mitte Dezember beschlossen hatte. Bulgarische Beamte f\u00fchrten am Montag eine Razzia in der \u00d6lraffinerie Neftochim und in 50 Roh\u00f6llagern durch, wie auf der [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-01-02T17:22:32+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Razzia-in-russischer-Oelraffinerie-in-einem-EU-Staat.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Razzia in russischer \u00d6lraffinerie in einem EU-Staat","datePublished":"2024-01-02T17:22:32+00:00","dateModified":"2024-01-02T17:22:32+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/"},"wordCount":363,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Razzia-in-russischer-Oelraffinerie-in-einem-EU-Staat.jpg","keywords":["einem","EUStaat","\u00d6lraffinerie","Razzia","Russischer"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/","url":"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/","name":"Razzia in russischer \u00d6lraffinerie in einem EU-Staat - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Razzia-in-russischer-Oelraffinerie-in-einem-EU-Staat.jpg","datePublished":"2024-01-02T17:22:32+00:00","dateModified":"2024-01-02T17:22:32+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Razzia-in-russischer-Oelraffinerie-in-einem-EU-Staat.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Razzia-in-russischer-Oelraffinerie-in-einem-EU-Staat.jpg","width":460,"height":259,"caption":"Razzia in russischer \u00d6lraffinerie in einem EU-Staat"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/razzia-in-russischer-oelraffinerie-in-einem-eu-staat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Razzia in russischer \u00d6lraffinerie in einem EU-Staat"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/52610"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=52610"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/52610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/52611"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=52610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=52610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=52610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}