{"id":52608,"date":"2024-01-02T19:00:51","date_gmt":"2024-01-02T17:00:51","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/"},"modified":"2024-01-02T19:00:51","modified_gmt":"2024-01-02T17:00:51","slug":"staatsmedien-iran-entsendet-seine-marine-ins-rote-meer","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/","title":{"rendered":"Staatsmedien: Iran entsendet seine Marine ins Rote Meer"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/659422b148fbef6734052347.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die Entwicklung erfolgt inmitten einer von den USA gef\u00fchrten Operation gegen die militanten Huthi im Jemen, die in letzter Zeit Handelsschiffe angegriffen haben. Die Zerst\u00f6rung des Gazastreifens durch Israel war der Ausl\u00f6ser f\u00fcr die Spannungen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Der iranische Zerst\u00f6rer Alborz hat am Montag die Meerenge von Bab-el-Mandeb durchquert und ist in das Rote Meer eingelaufen, berichten die staatlichen Nachrichtenagenturen IRNA und Tasnim. Der Einsatz erfolgte nach einem t\u00f6dlichen Zusammensto\u00df zwischen US-Kriegsschiffen und jemenitischen Huthi-K\u00e4mpfern in der Meeresenge am Sonntag.<\/p>\n<p>Die mit dem Iran verb\u00fcndete schiitische Gruppe kontrolliert seit dem Ausbruch eines internen Konflikts im Jahr 2014 weite Teile des Jemens, darunter die Hauptstadt Sanaa und den Hafen von Al-Hudaida. Im November begannen die Huthis mit Angriffen auf Handelsschiffe, die das Rote Meer durchqueren und von denen sie glauben, dass sie sich in israelischem Besitz befinden oder nach Israel unterwegs sind. Die K\u00e4mpfer behaupten, aus Solidarit\u00e4t mit der Hamas in Gaza zu handeln.<\/p>\n<p>Wie IRNA am Montag berichtete, wurde der Zerst\u00f6rer Alborz aufgrund der &#8220;zunehmenden Spannungen&#8221; in die wichtige Handelsroute entsandt, \u00fcber die etwa 12 Prozent des gesamten Welthandels abgewickelt werden.<\/p>\n<p>Am Samstagabend und Sonntagmorgen reagierten die US-Zerst\u00f6rer USS Eisenhower und USS Gravely auf zwei aufeinanderfolgende Notrufe des unter der Flagge Singapurs fahrenden Containerschiffs Maersk Hangzhou, das sich im Besitz D\u00e4nemarks befindet und von diesem betrieben wird. Bei der zweiten Begegnung er\u00f6ffneten mehrere US-Hubschrauber das Feuer auf vier kleine, von Huthis besetzte Boote. Dabei wurden drei Boote zerst\u00f6rt, teilte das US Central Command (CENTCOM) in einem Beitrag auf X (fr\u00fcher Twitter) mit.<\/p>\n<p>Ein Sprecher der Huthis, Yahya Saree, best\u00e4tigte den Vorfall und teilte mit, dass zehn K\u00e4mpfer der Gruppe entweder get\u00f6tet worden oder verschwunden seien.<\/p>\n<p>Das Pentagon sch\u00e4tzt, dass seit dem 19. November 23 Handelsschiffe im Roten Meer von Huthis angegriffen oder gekapert wurden.<\/p>\n<p>Die US-Marine patrouilliert seit dem 19. Dezember zusammen mit Kriegsschiffen aus neun anderen Nationen im Rahmen der Operation Prosperity Guardian in der wichtigen Schifffahrtsstra\u00dfe. Die Huthis haben den Einsatz als &#8220;integralen Bestandteil der Aggression gegen das pal\u00e4stinensische Volk, den Gazastreifen und die arabische und islamische Nation&#8221; verurteilt.<\/p>\n<p>W\u00e4hrend Teheran die Anschuldigungen Washingtons, es sei an den Angriffen beteiligt, zur\u00fcckgewiesen hat, wies der iranische Au\u00dfenminister Hossein Amir-Abdollahian in einem Gespr\u00e4ch mit seinem britischen Amtskollegen David Cameron am Sonntag auf angebliche Doppelstandards hin.<\/p>\n<p>&#8220;Man kann nicht zulassen, dass Israel Frauen und Kinder massakriert, im Gazastreifen einen V\u00f6lkermord begeht und die Region in Brand setzt, aber das Aufhalten eines israelischen Schiffes im Roten Meer als Bedrohung f\u00fcr die Sicherheit dieses Wirtschaftsweges betrachten&#8221;, betonte der iranische Diplomat.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211;\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/190990-angriffe-auf-frachter-im-roten-meer-koennten-das-gleichgewicht-im-globalen-handel-veraendern\/\">Angriffe auf Frachter im Roten Meer k\u00f6nnten das Gleichgewicht im globalen Handel ver\u00e4ndern<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-odysee\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/odysee.com\/%24\/embed\/%40RTDE%3Ae%2FKrieg-in-Nahost-Warum-ist-die-Welt-so-still-Was-tun-die-Vereinten-Nationen%3Ac\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/der-nahe-osten\/191537-staatsmedien-iran-entsendet-seine-marine\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Entwicklung erfolgt inmitten einer von den USA gef\u00fchrten Operation gegen die militanten Huthi im Jemen, die in letzter Zeit Handelsschiffe angegriffen haben. Die Zerst\u00f6rung des Gazastreifens durch Israel war der Ausl\u00f6ser f\u00fcr die Spannungen. Der iranische Zerst\u00f6rer Alborz hat am Montag die Meerenge von Bab-el-Mandeb durchquert und ist in das Rote Meer eingelaufen, berichten [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":52609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1704215405"],"wp_automatic_camp":["217"],"8457ec593e3add7494a67aea2922f84e":["Staatsmedien: Iran entsendet seine Marine ins Rote Meer"],"original_link":["https:\/\/de.rt.com\/der-nahe-osten\/191537-staatsmedien-iran-entsendet-seine-marine\/"],"_thumbnail_id":["52609"],"jnews_social_counter_last_update":["1784109471"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-01-02 19:11:14\";}"]},"categories":[19,23],"tags":[29431,1678,1786,4290,1363,9540,265,29704],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Staatsmedien: Iran entsendet seine Marine ins Rote Meer - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Staatsmedien: Iran entsendet seine Marine ins Rote Meer\" \/>\n<meta property=\"og:description\" content=\"Die Entwicklung erfolgt inmitten einer von den USA gef\u00fchrten Operation gegen die militanten Huthi im Jemen, die in letzter Zeit Handelsschiffe angegriffen haben. Die Zerst\u00f6rung des Gazastreifens durch Israel war der Ausl\u00f6ser f\u00fcr die Spannungen. Der iranische Zerst\u00f6rer Alborz hat am Montag die Meerenge von Bab-el-Mandeb durchquert und ist in das Rote Meer eingelaufen, berichten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-02T17:00:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Staatsmedien-Iran-entsendet-seine-Marine-ins-Rote-Meer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Staatsmedien: Iran entsendet seine Marine ins Rote Meer\",\"datePublished\":\"2024-01-02T17:00:51+00:00\",\"dateModified\":\"2024-01-02T17:00:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/\"},\"wordCount\":468,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Staatsmedien-Iran-entsendet-seine-Marine-ins-Rote-Meer.jpg\",\"keywords\":[\"entsendet\",\"ins\",\"Iran\",\"Marine\",\"Meer\",\"rote\",\"seine\",\"Staatsmedien\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/\",\"name\":\"Staatsmedien: Iran entsendet seine Marine ins Rote Meer - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Staatsmedien-Iran-entsendet-seine-Marine-ins-Rote-Meer.jpg\",\"datePublished\":\"2024-01-02T17:00:51+00:00\",\"dateModified\":\"2024-01-02T17:00:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Staatsmedien-Iran-entsendet-seine-Marine-ins-Rote-Meer.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Staatsmedien-Iran-entsendet-seine-Marine-ins-Rote-Meer.jpg\",\"width\":460,\"height\":259,\"caption\":\"Staatsmedien: Iran entsendet seine Marine ins Rote Meer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Staatsmedien: Iran entsendet seine Marine ins Rote Meer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Staatsmedien: Iran entsendet seine Marine ins Rote Meer - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/","og_locale":"de_DE","og_type":"article","og_title":"Staatsmedien: Iran entsendet seine Marine ins Rote Meer","og_description":"Die Entwicklung erfolgt inmitten einer von den USA gef\u00fchrten Operation gegen die militanten Huthi im Jemen, die in letzter Zeit Handelsschiffe angegriffen haben. Die Zerst\u00f6rung des Gazastreifens durch Israel war der Ausl\u00f6ser f\u00fcr die Spannungen. Der iranische Zerst\u00f6rer Alborz hat am Montag die Meerenge von Bab-el-Mandeb durchquert und ist in das Rote Meer eingelaufen, berichten [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-01-02T17:00:51+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Staatsmedien-Iran-entsendet-seine-Marine-ins-Rote-Meer.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Staatsmedien: Iran entsendet seine Marine ins Rote Meer","datePublished":"2024-01-02T17:00:51+00:00","dateModified":"2024-01-02T17:00:51+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/"},"wordCount":468,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Staatsmedien-Iran-entsendet-seine-Marine-ins-Rote-Meer.jpg","keywords":["entsendet","ins","Iran","Marine","Meer","rote","seine","Staatsmedien"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/","url":"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/","name":"Staatsmedien: Iran entsendet seine Marine ins Rote Meer - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Staatsmedien-Iran-entsendet-seine-Marine-ins-Rote-Meer.jpg","datePublished":"2024-01-02T17:00:51+00:00","dateModified":"2024-01-02T17:00:51+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Staatsmedien-Iran-entsendet-seine-Marine-ins-Rote-Meer.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/01\/Staatsmedien-Iran-entsendet-seine-Marine-ins-Rote-Meer.jpg","width":460,"height":259,"caption":"Staatsmedien: Iran entsendet seine Marine ins Rote Meer"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/staatsmedien-iran-entsendet-seine-marine-ins-rote-meer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Staatsmedien: Iran entsendet seine Marine ins Rote Meer"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/52608"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=52608"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/52608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/52609"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=52608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=52608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=52608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}