{"id":51086,"date":"2023-12-06T22:58:11","date_gmt":"2023-12-06T20:58:11","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/"},"modified":"2023-12-06T22:58:11","modified_gmt":"2023-12-06T20:58:11","slug":"nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/","title":{"rendered":"Nun ist es amtlich: M\u00e4rchenonkel Habeck glaubt der eigenen Propaganda"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/6570ace1b480cc26c654c3e1.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                P\u00fcnktlich zu Nikolaus haben die beiden russischen Prankster Wowan und Lexus einen ihrer ber\u00fcchtigten Telefonstreiche gespielt. Robert Habeck glaubte gern, mit einem Vertreter der Afrikanischen Union zu plaudern. Hinterher beschwichtigte man in Berlin sogleich: Geheimnisse habe der Minister nicht preisgegeben.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Mirko Lehmann<\/em><\/p>\n<p>Da hat der Vizekanzler, Wirtschafts- und Klimaschutzminister, Verfasser von Kinderb\u00fcchern nun die Bescherung! Ausgerechnet er, der f\u00fcr <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/154764-350000-euro-gefaellig-bundeswirtschaftsminister-sucht\/\">hunderttausende Euro<\/a> in Szene gesetzte Durchblicker und <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/meinung\/177159-danke-robert-westliche-sanktionen-halfen\/\">antirussische Scharfmacher<\/a>, ausgerechnet der Oberolivgr\u00fcne ist den russischen Spa\u00dfmachern, die ihm t\u00fcchtig schmeichelten, auf den Leim gegangen. Offenbar nur allzu gern w\u00e4hnte sich Habeck in der Position, einmal am Telefon dem &#8220;Vertreter der Afrikanischen Union&#8221; die Welt aus Berliner Sicht zu erkl\u00e4ren.<\/p>\n<p>Sicher, v\u00f6llig Neues oder Spektakul\u00e4res ist in dem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/kurzclips\/video\/189107-eitelkeit-im-amt-robert-habeck\/\">Mitschnitt<\/a> nicht zu h\u00f6ren. Doch an ein paar Stellen des Gespr\u00e4chs musste sich der Minister h\u00f6rbar sortieren. Allerdings beeilte sich Habecks Ministerium, einerseits zuzugeben, dass es das peinliche Telefonat tats\u00e4chlich gegeben hat. Andererseits, so wird betont, seien weder &#8220;sicherheitsrelevante&#8221; noch &#8220;vertrauliche Informationen&#8221; Gegenstand des Gespr\u00e4chs gewesen. Und wegen technischer Probleme sei das Telefonat mehrfach unterbrochen worden. Allein aus diesem Grund m\u00fcsse es sich um einen Zusammenschnitt handeln, legt das Habeck-Ministerium nahe. In der von der <em>dpa<\/em> verbreiteten <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.berliner-zeitung.de\/news\/robert-habeck-faellt-auf-russische-trolle-herein-li.2165651\">Stellungnahme<\/a> \u00fcber das ministerielle Missgeschick wird dann auch unterstrichen, dass sich weder &#8220;das dargestellte Gesamtgespr\u00e4ch noch die dort gestellten Fragen sowie die angef\u00fcgten Antworten&#8221; best\u00e4tigen lie\u00dfen. Also alles nur halb so schlimm?<\/p>\n<p>Ob Wowan und Lexus nun besonderen Aufwand bei der angeblichen Montage betreiben mussten oder nicht: Unfreiwillig hat Robert Habeck preisgegeben, dass er tats\u00e4chlich an die eigene Propaganda glaubt. Denn wohl kaum haben ihm die \u2013 in den Westmedien sogenannten \u2013 &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.zdf.de\/nachrichten\/politik\/ausland\/wowan-lexus-kreml-propaganda-100.html#xtor=CS5-62\">Kreml-Trolle<\/a>&#8221; den Gefallen getan, ihm etwas anderes in den Mund zu legen, als was er tats\u00e4chlich gegen\u00fcber dem &#8220;Vertreter der Afrikanischen Union&#8221; gesagt hatte. Zu sehr liegt das Wiedergegebene auf der Berliner Regierungslinie. Die russischen Prankster brauchten daher gar nichts zu manipulieren.<\/p>\n<p>Habeck wiederholt im Gespr\u00e4ch mit dem &#8220;Diplomaten&#8221; dieselben Platit\u00fcden, die er sonst im Bundestag und gegen\u00fcber der Presse \u00e4u\u00dfert. Er kann nicht anders. Denn die Ansichten des deutschen Ministers sind tats\u00e4chlich genauso einf\u00e4ltig und schlicht: Putin wolle Afrika spalten. Putin verstehe einzig und allein &#8220;Druck&#8221;. Und von seinem eigentlichen Ressort hat der Minister immer noch keinen Schimmer \u2013 der Gasmarkt sei eben &#8220;gro\u00df&#8221; und &#8220;flexibel&#8221; und die Preise &#8220;hoch, zu hoch&#8221;.<\/p>\n<p>Insofern hat der Vizekanzler, und zwar unfreiwillig, doch ein Geheimnis offenbart, auch wenn man es bereits ahnte: Er kann nicht zwischen Wirklichkeit und Propaganda unterscheiden. Als ob dies nicht &#8220;sicherheitsrelevant&#8221; w\u00e4re!<\/p>\n<p>Wenn nur oft genug immer dieselben Floskeln wiederholt, dieselben wertewestlichen Phrasen gedroschen w\u00fcrden, so Habecks Hoffnung, dann \u00e4ndere sich irgendwann auch die Realit\u00e4t. Magisches Denken \u2013 wie im M\u00e4rchen.<\/p>\n<p>Sobald aber die wirkliche Wirklichkeit in die postmodern-konstruierte Welt des Robert Habeck einbricht, sieht er sich pl\u00f6tzlich von ihr &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/kurzclips\/video\/188926-habeck-verprasstes-geld-hat-immer\/\">umzingelt<\/a>&#8220;, wie man k\u00fcrzlich erfahren musste. Wen wundert es da, dass man weder in Moskau noch Peking, geschweige denn im sogenannten &#8220;Globalen S\u00fcden&#8221;, wo die Mehrheit der Menschheit lebt, die Berliner Regierung als Gespr\u00e4chspartner ernst nimmt. Von der verheerenden Berliner Politik ganz zu schweigen.<\/p>\n<p>All dies ein f\u00fcr alle Mal enth\u00fcllt zu haben, daf\u00fcr geb\u00fchrt dem &#8220;Vertreter der Afrikanischen Union&#8221; gro\u00dfer Dank.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/meinung\/188719-fotografen-und-visagisten-statt-demokratie\/\">Fotografen und Visagisten statt Demokratie<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/189123-nun-amtlich-maerchenonkel-habeck-glaubt\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>P\u00fcnktlich zu Nikolaus haben die beiden russischen Prankster Wowan und Lexus einen ihrer ber\u00fcchtigten Telefonstreiche gespielt. Robert Habeck glaubte gern, mit einem Vertreter der Afrikanischen Union zu plaudern. Hinterher beschwichtigte man in Berlin sogleich: Geheimnisse habe der Minister nicht preisgegeben. Von Mirko Lehmann Da hat der Vizekanzler, Wirtschafts- und Klimaschutzminister, Verfasser von Kinderb\u00fcchern nun die [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":51087,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1701896374"],"wp_automatic_camp":["217"],"47ff4c0bd016cead95f756d7bbc428d8":["Nun ist es amtlich: M\u00e4rchenonkel Habeck glaubt der eigenen Propaganda"],"original_link":["https:\/\/de.rt.com\/meinung\/189123-nun-amtlich-maerchenonkel-habeck-glaubt\/"],"_thumbnail_id":["51087"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-12-06 23:00:38\";}"],"jnews_social_counter_last_update":["1778578640"]},"categories":[19,23],"tags":[49658,82,947,20484,911,414,51354,2121,498],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nun ist es amtlich: M\u00e4rchenonkel Habeck glaubt der eigenen Propaganda - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nun ist es amtlich: M\u00e4rchenonkel Habeck glaubt der eigenen Propaganda\" \/>\n<meta property=\"og:description\" content=\"P\u00fcnktlich zu Nikolaus haben die beiden russischen Prankster Wowan und Lexus einen ihrer ber\u00fcchtigten Telefonstreiche gespielt. Robert Habeck glaubte gern, mit einem Vertreter der Afrikanischen Union zu plaudern. Hinterher beschwichtigte man in Berlin sogleich: Geheimnisse habe der Minister nicht preisgegeben. Von Mirko Lehmann Da hat der Vizekanzler, Wirtschafts- und Klimaschutzminister, Verfasser von Kinderb\u00fcchern nun die [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-06T20:58:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Nun-ist-es-amtlich-Maerchenonkel-Habeck-glaubt-der-eigenen-Propaganda.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Nun ist es amtlich: M\u00e4rchenonkel Habeck glaubt der eigenen Propaganda\",\"datePublished\":\"2023-12-06T20:58:11+00:00\",\"dateModified\":\"2023-12-06T20:58:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/\"},\"wordCount\":582,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Nun-ist-es-amtlich-Maerchenonkel-Habeck-glaubt-der-eigenen-Propaganda.jpg\",\"keywords\":[\"Amtlich\",\"der\",\"eigenen\",\"glaubt\",\"Habeck\",\"ist\",\"M\u00e4rchenonkel\",\"nun\",\"Propaganda\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/\",\"name\":\"Nun ist es amtlich: M\u00e4rchenonkel Habeck glaubt der eigenen Propaganda - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Nun-ist-es-amtlich-Maerchenonkel-Habeck-glaubt-der-eigenen-Propaganda.jpg\",\"datePublished\":\"2023-12-06T20:58:11+00:00\",\"dateModified\":\"2023-12-06T20:58:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Nun-ist-es-amtlich-Maerchenonkel-Habeck-glaubt-der-eigenen-Propaganda.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Nun-ist-es-amtlich-Maerchenonkel-Habeck-glaubt-der-eigenen-Propaganda.jpg\",\"width\":460,\"height\":259,\"caption\":\"Nun ist es amtlich: M\u00e4rchenonkel Habeck glaubt der eigenen Propaganda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nun ist es amtlich: M\u00e4rchenonkel Habeck glaubt der eigenen Propaganda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nun ist es amtlich: M\u00e4rchenonkel Habeck glaubt der eigenen Propaganda - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/","og_locale":"de_DE","og_type":"article","og_title":"Nun ist es amtlich: M\u00e4rchenonkel Habeck glaubt der eigenen Propaganda","og_description":"P\u00fcnktlich zu Nikolaus haben die beiden russischen Prankster Wowan und Lexus einen ihrer ber\u00fcchtigten Telefonstreiche gespielt. Robert Habeck glaubte gern, mit einem Vertreter der Afrikanischen Union zu plaudern. Hinterher beschwichtigte man in Berlin sogleich: Geheimnisse habe der Minister nicht preisgegeben. Von Mirko Lehmann Da hat der Vizekanzler, Wirtschafts- und Klimaschutzminister, Verfasser von Kinderb\u00fcchern nun die [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-12-06T20:58:11+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Nun-ist-es-amtlich-Maerchenonkel-Habeck-glaubt-der-eigenen-Propaganda.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Nun ist es amtlich: M\u00e4rchenonkel Habeck glaubt der eigenen Propaganda","datePublished":"2023-12-06T20:58:11+00:00","dateModified":"2023-12-06T20:58:11+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/"},"wordCount":582,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Nun-ist-es-amtlich-Maerchenonkel-Habeck-glaubt-der-eigenen-Propaganda.jpg","keywords":["Amtlich","der","eigenen","glaubt","Habeck","ist","M\u00e4rchenonkel","nun","Propaganda"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/","url":"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/","name":"Nun ist es amtlich: M\u00e4rchenonkel Habeck glaubt der eigenen Propaganda - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Nun-ist-es-amtlich-Maerchenonkel-Habeck-glaubt-der-eigenen-Propaganda.jpg","datePublished":"2023-12-06T20:58:11+00:00","dateModified":"2023-12-06T20:58:11+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Nun-ist-es-amtlich-Maerchenonkel-Habeck-glaubt-der-eigenen-Propaganda.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Nun-ist-es-amtlich-Maerchenonkel-Habeck-glaubt-der-eigenen-Propaganda.jpg","width":460,"height":259,"caption":"Nun ist es amtlich: M\u00e4rchenonkel Habeck glaubt der eigenen Propaganda"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/nun-ist-es-amtlich-maerchenonkel-habeck-glaubt-der-eigenen-propaganda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Nun ist es amtlich: M\u00e4rchenonkel Habeck glaubt der eigenen Propaganda"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/51086"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=51086"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/51086\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/51087"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=51086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=51086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=51086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}