{"id":50767,"date":"2023-12-01T18:35:18","date_gmt":"2023-12-01T16:35:18","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/"},"modified":"2023-12-01T18:35:18","modified_gmt":"2023-12-01T16:35:18","slug":"baerbocks-aussenpolitik-aggressiver-als-die-der-usa","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/","title":{"rendered":"Baerbocks Au\u00dfenpolitik \u2013 Aggressiver als die der USA"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/6569ea0548fbef6fa11b7882.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Sowohl die NATO als auch die OSZE haben sich in dieser Woche getroffen. Die deutsche Au\u00dfenministerin hat dort Deutschland vertreten und dabei deutlich gemacht, dass sie weiter an Aggression und Dialogverweigerung festh\u00e4lt. Baerbock verhilft Deutschland zu einem Ruf wie nach 1918.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Gert Ewen Ungar<\/em><\/p>\n<p>Die deutsche Au\u00dfenministerin hatte in dieser Woche gleich zwei relevante Treffen zu absolvieren. Zu Beginn der Woche trafen sich die Au\u00dfenminister der NATO-Staaten in Br\u00fcssel. Am Donnerstag und Freitag trifft sich der Ministerrat der OSZE in Skopje, der Hauptstadt Nordmazedoniens. Aussagen der deutschen Au\u00dfenministerin auf beiden Treffen machen deutlich, wie wenig regel- und wertebasiert die deutsche Au\u00dfenpolitik ist. Sie ist bestimmt von reiner Willk\u00fcr, dem Willen zur Macht, gepaart mit dem Hang zur Hysterie. Von Diplomatie keine Spur.\u00a0<\/p>\n<p>Das einzig verbindende Element der Politik Baerbocks ist ein blinder Gehorsam gegen\u00fcber den USA und Israels, wobei der deutsche Eifer Baerbocks hinsichtlich der Bekenntnisse zur Unterst\u00fctzung der Ukraine und Israels den gro\u00dfen Bruder in \u00dcbersee inzwischen blass aussehen l\u00e4sst. Deutsche Au\u00dfenpolitik unter Annalena Baerbock hat die der USA an Radikalit\u00e4t und Menschenverachtung l\u00e4ngst \u00fcberholt.<\/p>\n<p>So ist den NATO-Staaten durchaus bewusst, dass der Krieg in der Ukraine verloren ist. Es geht nun um einen gesichtswahrenden R\u00fcckzug. Daher weist NATO-Generalsekret\u00e4r Jens Stoltenberg auf die angeblich enormen Erfolge der Ukraine hin. 50 Prozent des von Russland urspr\u00fcnglichen Territoriums habe die Ukraine bereits zur\u00fcckerobert, flunkert Stoltenberg. Es sei ihm geschenkt, wenn es der Beilegung des Konflikts dient und man damit der Ukraine ihre Niederlage als Erfolg verkaufen kann.\u00a0<\/p>\n<p>Die USA fahren ihre Unterst\u00fctzung zur\u00fcck. In der EU wird die Uneinigkeit gr\u00f6\u00dfer. Die Ukraine wird an den Verhandlungstisch gedr\u00e4ngt. Die deutsche Au\u00dfenministerin dagegen will von Verhandlungen nach wie vor nichts wissen und h\u00e4ngt weiter der Idee an, Russland m\u00fcsse auf dem Schlachtfeld vernichtet und mit Sanktionen in den Ruin getrieben werden. Baerbock bleibt ihrer Rolle als deutsche Furie und unheilvolle Racheg\u00f6ttin treu, die nicht nur Russland, sondern auch die Ukraine und Deutschland kompromisslos ins Verderben f\u00fchrt.<\/p>\n<p>Auf dem NATO-Treffen pl\u00e4dierte nur ein Land daf\u00fcr, die Ukraine f\u00fcr eine weitere Offensive im kommenden Fr\u00fchling fit zu machen, und\u00a0dieses Land\u00a0hei\u00dft Deutschland. Der blutr\u00fcnstigen deutschen Au\u00dfenministerin gehen die bisherigen Verluste der Ukraine noch nicht weit genug. In den Leichenhallen und auf den Friedh\u00f6fen der Ukraine ist noch Platz, mag sie sich gedacht haben. Sie h\u00e4lt daher weiter an dem Ziel fest, der Ukraine durch deutsche Waffenlieferungen zu einem Sieg \u00fcber Russland zu verhelfen. Deutschland ist im Ukraine-Konflikt inzwischen Kriegstreiber Nummer eins. Endlich wieder ganz vorn mit dabei.<\/p>\n<p>Mahnende Stimmen und Einsch\u00e4tzungen, die zu einem anderen Ergebnis kommen als dem, dass die Ukraine einen Sieg \u00fcber Russland nicht nur erringen kann, sondern auch erringen muss, werden von Baerbock einfach ignoriert. Selbst die russlandfreundlicher Umtriebe v\u00f6llig unverd\u00e4chtige NATO hat verstanden, dass dieser Wunsch eines Sieges \u00fcber Russland nicht realistisch ist. Aber mit der Realit\u00e4t tut sich Baerbock nicht nur schwer. Die Au\u00dfenministerin hat sich verbunkert und vor der Realit\u00e4t verschanzt.\u00a0<\/p>\n<p>Nur so ist ihr erneuter, peinlicher Auftritt beim OSZE Ministerrat zu deuten. Dort stand sie erneut auf der politisch naiven Position, Russland m\u00fcsse sich einfach nur zur\u00fcckziehen, dann sei der Krieg vorbei. Dass der russische Au\u00dfenminister diesem Zeugnis geistiger Schlichtheit nicht beiwohnen wollte, nahm sie ihm nat\u00fcrlich \u00fcbel.\u00a0<\/p>\n<blockquote>\n<p><em>&#8220;Da Russland heute hier im Saal ist \u2013 der Au\u00dfenminister offensichtlich, wie auch bei anderen Sitzungen, nur wenn er selbst spricht, aber nicht um anderen zuzuh\u00f6ren \u2013 sage ich an dieser Stelle noch einmal deutlich: Stoppen Sie diesen Krieg, der auch ein Krieg auf genau diese Organisation, auf Sicherheit und Kooperation in Europa ist.<\/em><br \/><em>Stoppen Sie das uns\u00e4gliche Leid, das Sie \u00fcber Millionen von Menschen bringen und mit dem Sie zugleich tagt\u00e4glich die Werte unserer Organisation, dieser Organisation hier verletzen. Dazu braucht es keine Verhandlungen, dazu braucht es schon gar keine Zugest\u00e4ndnisse der Ukraine.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Es braucht keine Verhandlungen, keine Kompromisse, Russlands Interessen z\u00e4hlen nicht \u2013 das ist die deutsche Position. Damit tr\u00e4gt die deutsche Au\u00dfenministerin Verantwortung f\u00fcr das Leid der Ukrainer, denn sie setzt auf eine milit\u00e4rische L\u00f6sung und lehnt Diplomatie ganz offen ab. Keine Verhandlungen, keine Kompromisse. Diplomatisch ist Baerbock nie \u00fcber Verdun hinausgewachsen. Sie verhilft dem Deutschland der Gegenwart zu einem \u00e4hnlichen Ruf in der Welt wie nach 1918.\u00a0<\/p>\n<p>Die Toten nach den vom Westen sabotierten Friedensverhandlungen im M\u00e4rz 2022 zwischen Russland und der Ukraine gehen jedenfalls mit auf ihr Konto. Der Krieg k\u00f6nnte schon l\u00e4ngst zu Ende sein. Baerbock hat andere Pl\u00e4ne. Die Ukraine darf nicht aus den Augen geraten, die Unterst\u00fctzung und der Krieg m\u00fcssen weitergehen.<\/p>\n<p>Baerbock will kein Ende des Konflikts, sie will einen Sieg \u00fcber Russland und ist bereit, die Ukraine daf\u00fcr einen sehr hohen Preis bezahlen zu lassen. Die Menschen und das &#8220;uns\u00e4gliche Leid&#8221; interessieren Baerbock nicht. Das tats\u00e4chliche, menschliche Leid zerf\u00e4llt in Baerbocks Mund zu einem blo\u00df rhetorischen Mittel. In Israel interessiert sie das Leid der Pal\u00e4stinenser in Gaza \u00fcbrigens auch nicht. Sie war selbst dann noch gegen einen Waffenstillstand, als dieser in Kraft getreten war. Baerbock ist empathielos und ohne Moral. Sie repr\u00e4sentiert die Abwesenheit aller Werte.\u00a0<\/p>\n<p>Russland wirft sie vor, die OSZE zerst\u00f6ren zu wollen und betreibt dreiste Schuldumkehr.<\/p>\n<blockquote>\n<p><em>&#8220;Das perfide Spiel der russischen Regierung ist und war es eben auch, Organisationen, die auf ein friedliches Miteinander, auf Kooperation setzen, mit dem brutalen Angriffskrieg gegen die Ukraine ebenfalls zu zerst\u00f6ren&#8221;,<\/em><\/p>\n<\/blockquote>\n<p>verdreht Baerbock dreist die Tatsachen. Denn faktisch wird Russland aus dem Gremium immer weiter hinausgedr\u00e4ngt, an dessen Entstehung es als Rechtsnachfolger der Sowjetunion ma\u00dfgeblich beteiligt war.\u00a0<\/p>\n<p>Die Teilnahme russischer Diplomaten wird seit Jahren erschwert, russischen Pressevertretern wird das Visum verweigert, Teilnehmerstaaten machen ihre Teilnahme von einem Ausschluss Russlands abh\u00e4ngig. Wenn jemand am Niedergang der OSZE arbeitet, dann sind es die westlichen Vertreter. Sie verweigern schlicht den Dialog, sie verweigern das zu tun, was der Gr\u00fcndungsgedanke des Vorl\u00e4ufers der OSZE war. Die Konferenz f\u00fcr Sicherheit und Zusammenarbeit in Europa, KSZE, aus der die OSZE hervorgegangen ist, baute w\u00e4hrend der Zeit des Kalten Krieges Br\u00fccken der Kommunikation zwischen Ost und West. Sie suchte nach Gemeinsamem im Trennenden und entwickelte ein System kollektiver Sicherheit. Sicherheit gibt es immer nur f\u00fcr alle und nicht gegeneinander. Das f\u00fchrte zu Abr\u00fcstung.\u00a0<\/p>\n<p>Von diesem Gedanken hat sich Baerbock nicht nur verabschiedet, sie hat ihn schlicht nie verstanden. &#8220;Irgendeiner muss doch gewinnen!&#8221;, ist ihre au\u00dfenpolitische Leitlinie, bei der sie keine Kompromisse eingeht.<\/p>\n<p>Nat\u00fcrlich muss man in diesem Zusammenhang dem russischen Au\u00dfenminister recht geben, wenn er seine Aussage \u00fcber den Niedergang der OSZE wiederholt. Bereits auf dem letzten Treffen des OSZE-Ministerrats im vergangenen Jahr im polnischen Lodz sagte er, die Organisation stehe am Abgrund. Er f\u00fcgte in diesem Jahr hinzu, sie sei nur noch ein Anh\u00e4ngsel der NATO und der EU. Das ist richtig beobachtet.<\/p>\n<p>Russland hat in der OSEZ ein Veto-Recht, von dem es Gebrauch macht. Russland blockiert Entscheidungen, die nicht in seinem Interesse sind. Doch statt zur Diplomatie zur\u00fcckzukehren, um nach L\u00f6sungen zu suchen, die von Russland mitgetragen werden k\u00f6nnen, beschr\u00e4nkt sich Baerbock auf Anschuldigungen und Verurteilungen. Unter anderem blockiert Russland derzeit Personalentscheidungen. Das erm\u00f6glicht es Baerbock schlie\u00dflich doch noch, mit einem ihrer Verhaspler zur Erheiterung beizutragen.\u00a0<\/p>\n<blockquote>\n<p><em>&#8220;Ich halte es f\u00fcr dringend erforderlich, dass wir morgen die Verl\u00e4ngerung von diesen vier Personen gemeinsam beschlie\u00dfen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Wenn Russland zustimmt, sind vier OSZE-Diplomaten\u00a0dann um einige Zentimeter l\u00e4nger. Immerhin kann sie Verhaspler, mag man sich da tr\u00f6sten. Diplomatie jedenfalls kann Baerbock nicht, wie sie in dieser Woche erneut bewiesen hat.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/188540-baerbock-nachlassende-oeffentliche-aufmerksamkeit-fuer\/\">Baerbock: Nachlassende \u00f6ffentliche Aufmerksamkeit f\u00fcr die Ukraine ist &#8220;fatal&#8221;<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/188676-baerbocks-aussenpolitik-toedlicher-als-usa\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sowohl die NATO als auch die OSZE haben sich in dieser Woche getroffen. Die deutsche Au\u00dfenministerin hat dort Deutschland vertreten und dabei deutlich gemacht, dass sie weiter an Aggression und Dialogverweigerung festh\u00e4lt. Baerbock verhilft Deutschland zu einem Ruf wie nach 1918. Von Gert Ewen Ungar Die deutsche Au\u00dfenministerin hatte in dieser Woche gleich zwei relevante [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":50768,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1701448858"],"wp_automatic_camp":["217"],"fd5317ec3acd10b4b6303efbf15acc63":["Baerbocks Au\u00dfenpolitik \u2013 Aggressiver als die der USA"],"original_link":["https:\/\/de.rt.com\/meinung\/188676-baerbocks-aussenpolitik-toedlicher-als-usa\/"],"_thumbnail_id":["50768"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-12-01 18:42:03\";}"],"jnews_social_counter_last_update":["1783983573"]},"categories":[19,23],"tags":[29100,273,11441,5932,82,45,193],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Baerbocks Au\u00dfenpolitik \u2013 Aggressiver als die der USA - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baerbocks Au\u00dfenpolitik \u2013 Aggressiver als die der USA\" \/>\n<meta property=\"og:description\" content=\"Sowohl die NATO als auch die OSZE haben sich in dieser Woche getroffen. Die deutsche Au\u00dfenministerin hat dort Deutschland vertreten und dabei deutlich gemacht, dass sie weiter an Aggression und Dialogverweigerung festh\u00e4lt. Baerbock verhilft Deutschland zu einem Ruf wie nach 1918. Von Gert Ewen Ungar Die deutsche Au\u00dfenministerin hatte in dieser Woche gleich zwei relevante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-01T16:35:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Baerbocks-Aussenpolitik-\u2013-Aggressiver-als-die-der-USA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Baerbocks Au\u00dfenpolitik \u2013 Aggressiver als die der USA\",\"datePublished\":\"2023-12-01T16:35:18+00:00\",\"dateModified\":\"2023-12-01T16:35:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/\"},\"wordCount\":1329,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Baerbocks-Aussenpolitik-\u2013-Aggressiver-als-die-der-USA.jpg\",\"keywords\":[\"aggressiver\",\"als\",\"au\u00dfenpolitik\",\"Baerbocks\",\"der\",\"die\",\"USA\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/\",\"name\":\"Baerbocks Au\u00dfenpolitik \u2013 Aggressiver als die der USA - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Baerbocks-Aussenpolitik-\u2013-Aggressiver-als-die-der-USA.jpg\",\"datePublished\":\"2023-12-01T16:35:18+00:00\",\"dateModified\":\"2023-12-01T16:35:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Baerbocks-Aussenpolitik-\u2013-Aggressiver-als-die-der-USA.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Baerbocks-Aussenpolitik-\u2013-Aggressiver-als-die-der-USA.jpg\",\"width\":460,\"height\":259,\"caption\":\"Baerbocks Au\u00dfenpolitik \u2013 Aggressiver als die der USA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baerbocks Au\u00dfenpolitik \u2013 Aggressiver als die der USA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Baerbocks Au\u00dfenpolitik \u2013 Aggressiver als die der USA - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/","og_locale":"de_DE","og_type":"article","og_title":"Baerbocks Au\u00dfenpolitik \u2013 Aggressiver als die der USA","og_description":"Sowohl die NATO als auch die OSZE haben sich in dieser Woche getroffen. Die deutsche Au\u00dfenministerin hat dort Deutschland vertreten und dabei deutlich gemacht, dass sie weiter an Aggression und Dialogverweigerung festh\u00e4lt. Baerbock verhilft Deutschland zu einem Ruf wie nach 1918. Von Gert Ewen Ungar Die deutsche Au\u00dfenministerin hatte in dieser Woche gleich zwei relevante [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-12-01T16:35:18+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Baerbocks-Aussenpolitik-\u2013-Aggressiver-als-die-der-USA.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Baerbocks Au\u00dfenpolitik \u2013 Aggressiver als die der USA","datePublished":"2023-12-01T16:35:18+00:00","dateModified":"2023-12-01T16:35:18+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/"},"wordCount":1329,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Baerbocks-Aussenpolitik-\u2013-Aggressiver-als-die-der-USA.jpg","keywords":["aggressiver","als","au\u00dfenpolitik","Baerbocks","der","die","USA"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/","url":"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/","name":"Baerbocks Au\u00dfenpolitik \u2013 Aggressiver als die der USA - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Baerbocks-Aussenpolitik-\u2013-Aggressiver-als-die-der-USA.jpg","datePublished":"2023-12-01T16:35:18+00:00","dateModified":"2023-12-01T16:35:18+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Baerbocks-Aussenpolitik-\u2013-Aggressiver-als-die-der-USA.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/12\/Baerbocks-Aussenpolitik-\u2013-Aggressiver-als-die-der-USA.jpg","width":460,"height":259,"caption":"Baerbocks Au\u00dfenpolitik \u2013 Aggressiver als die der USA"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/baerbocks-aussenpolitik-aggressiver-als-die-der-usa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Baerbocks Au\u00dfenpolitik \u2013 Aggressiver als die der USA"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/50767"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=50767"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/50767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/50768"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=50767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=50767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=50767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}