{"id":50271,"date":"2023-11-23T16:46:34","date_gmt":"2023-11-23T14:46:34","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/"},"modified":"2023-11-23T16:46:34","modified_gmt":"2023-11-23T14:46:34","slug":"deutschland-hoechster-anstieg-der-suizide-seit-40-jahren","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/","title":{"rendered":"Deutschland: H\u00f6chster Anstieg der Suizide seit 40 Jahren"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/655f498b48fbef72134cd63f.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Zwei themenbezogene Institutionen haben eine \u00dcbersicht \u00fcber die aktuellen Suizidzahlen f\u00fcr das Jahr 2022 herausgegeben. Die Summe von Selbstt\u00f6tungen ist demnach um knapp zehn Prozent auf 10.119 gestiegen. Die h\u00e4ufigste Suizidmethode ist das Erh\u00e4ngen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Das Nationale Suizidpr\u00e4ventionsprogramm (NaSPro) und die Deutsche<br \/>Akademie f\u00fcr Suizidpr\u00e4vention (DASP) haben am 22. November im Rahmen einer\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.suizidpraevention.de\/datenschutz\/detail?tx_news_pi1%5Baction%5D=detail&amp;tx_news_pi1%5Bcontroller%5D=News&amp;tx_news_pi1%5Bnews%5D=23&amp;cHash=45c8caac70389c7384b6ae5c53e5f104\">Presseinformation<\/a>\u00a0die j\u00fcngsten Auswertungen einer \u00dcbersicht\u00a0aktueller Suizidzahlen in Deutschland f\u00fcr das Jahr 2022 herausgegeben. Die Gesamtzahl\u00a0l\u00e4ge laut Statistik mit 10.119 Selbstt\u00f6tungen erstmals seit 2015 wieder \u00fcber 10.000. Des Weiteren belegt die Auswertung, dass dabei\u00a060 Prozent M\u00e4nner und 30 Prozent Frauen auf diesem Wege ihrem Leben ein Ende setzten.<\/p>\n<p>Die Mitteilung weist darauf hin, dass sogenannte &#8220;assistierte Suizide&#8221;, der unterst\u00fctzenden Form von Sterbebegleitungen, zum Beispiel bei unheilbar kranken Menschen,\u00a0nicht gesondert ausgewiesen wurden. Diesbez\u00fcglich hei\u00dft es, dass das<br \/>Bundesverfassungsgericht im Jahr 2020 &#8220;das Verbot der gesch\u00e4ftsm\u00e4\u00dfigen F\u00f6rderung der Selbstt\u00f6tung f\u00fcr verfassungswidrig erkl\u00e4rt&#8221; hatte. Es sei zudem schlussendlich nicht zu kl\u00e4ren, ob der Anstieg der Suizide &#8220;durch Medikamente in den Jahren 2021 und 2022 gegen\u00fcber 2020 um 427 F\u00e4lle oder 42 Prozent auf 1.440 F\u00e4lle im Zusammenhang mit dem assistierten Suizid steht&#8221;, so die Mitteilung darlegend.<\/p>\n<p>Bei den betitelten &#8221;\u00a0Suizidmethoden&#8221; dominiere\u00a0das Erh\u00e4ngen (4.531) deutlich. Weiter hei\u00dft es:<\/p>\n<blockquote>\n<p><em>&#8220;Es folgten mit 1.440 F\u00e4llen Intoxikation (Vergiftung) durch Medikamente, sonstige Methoden, (1.413), Sturz (941), Schusswaffen (759, fast ausschlie\u00dflich M\u00e4nner) und das &#8220;sich vor ein bewegendes Objekt legen&#8221; (468). Danach folgen Gase\u00a0<\/em><em>(321), Ertrinken (214) und Suizid durch Rauch\/ Feuer (31).&#8221;<\/em><\/p>\n<\/blockquote>\n<p>In absoluten Zahlen \u00fcbersteigt im Jahr 2022 laut der Mitteilung &#8220;die Anzahl der Suizide von M\u00e4nnern in allen Altersgruppen die Anzahl der Suizide von Frauen deutlich&#8221;. Diesbez\u00fcglich hei\u00dft es:<\/p>\n<blockquote>\n<p><em>&#8220;74,2 Prozent aller Suizide im Jahr 2022 entfallen auf M\u00e4nner (7.504) und 25,8 Prozent auf Frauen (2.615). Die deutliche Mehrheit der Suizide entf\u00e4llt auf die<\/em><br \/><em>Altersgruppe der \u00fcber 50-J\u00e4hrigen (73,4, 7.430 F\u00e4lle).&#8221;<\/em><\/p>\n<\/blockquote>\n<p>In der Altersgruppe der\u00a025-44-J\u00e4hrigen stieg die Rate um 5,2 Prozent, bei den 45-64-J\u00e4hrigen um 8,3 Prozent und bei den \u00fcber 64-J\u00e4hrigen um 13,1 Prozent. Das Gesamtbild zeige daher, dass Selbstt\u00f6tungen\u00a0zunehmend &#8220;ein Ph\u00e4nomen des h\u00f6heren Lebensalters&#8221; darstellen. Im Vergleich zum Jahr 2000 ist dabei der Anteil der ab 60-J\u00e4hrigen &#8220;an den M\u00e4nnersuiziden stark angestiegen (von 35,5 Prozent auf 53,2 Prozent)&#8221;. Bei den Frauen lag der vergleichbare Anteil schon seit 2000 h\u00f6her.<\/p>\n<p>Ein explizit\u00a0dargelegtes Ph\u00e4nomen in der Mitteilung lautet:<\/p>\n<blockquote>\n<p><em>&#8220;Keine &#8216;Corona-Suizide&#8217; bei jungen Menschen unter 30&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Bezugnehmend auf die ern\u00fcchternden Zahlen zeige sich das Bild, dass es im Vergleich\u00a0mit dem Vorjahr (2021) &#8220;bei den j\u00fcngeren Menschen (15 bis 19 und 25 bis 29 Jahre) einen leichten Anstieg gegeben hat&#8221;. Die NaSPro- und\u00a0DASP-Autoren erkennen jedoch, dass in\u00a0allen Altersgruppen (der 10- bis 24-J\u00e4hrigen) &#8220;ein deutlicher R\u00fcckgang der Anzahl der Suizide im Vergleich zum Jahr 2000&#8221; vorliegen w\u00fcrde.\u00a0Der Vergleich der Suizidraten mit dem Vorjahr (2021) erg\u00e4be demnach ein \u00e4hnliches Bild. In der Gesamtbetrachtung lautet daher das Res\u00fcmee:<\/p>\n<blockquote>\n<p><em>&#8220;Die vorliegenden Daten geben keinen Hinweis auf einen bedeutsamen Einfluss der Covid-19 Pandemie auf die Suizidh\u00e4ufigkeit junger Menschen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Auff\u00e4llig\u00a0sei der Anstieg der Suizide durch Medikamente seit 2020 um 42 Prozent von 1.013 auf 1.440 F\u00e4lle. Der Anstieg w\u00fcrde sich \u00fcberwiegend auf die &#8220;vors\u00e4tzliche Selbstvergiftung durch und Exposition gegen\u00fcber sonstige(n) und nicht n\u00e4her\u00a0bezeichnete(n) Arzneimittel(n), Drogen und biologisch aktive(n) Substanzen&#8221; erkl\u00e4ren.\u00a0<\/p>\n<p>Gro\u00dfe Unterschiede w\u00fcrden sich im Vergleich der Ereignisse in den jeweiligen Bundesl\u00e4ndern zeigen.\u00a0Im Jahr 2022 hatten Sachsen (17,2 Prozent) und Sachsen-Anhalt (16,3 Prozent) die h\u00f6chsten Suizidzahlen. Am st\u00e4rksten gestiegen sind sie demnach in Brandenburg und Hamburg (um jeweils 2,4 Prozent). Bremen und NRW haben mit jeweils 9,0 Prozent die niedrigsten Suizidzahlen. Sachsen verzeichnet die meisten Suizide bei Frauen (9,0 Prozent), w\u00e4hrend Sachsen-Anhalt<br \/>die meisten Suizide bei den M\u00e4nnern (26,5 Prozent) aufweist.\u00a0<\/p>\n<p>Alle Angaben in der Pressemitteilung beruhen auf der vom Statistischen Bundesamt am 15. November 2023 herausgegebenen\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.gbe-bund.de\/gbe\/abrechnung.prc_abr_test_logon?p_uid=gasta&amp;p_aid=0&amp;p_sprache=D&amp;p_knoten=NE3392\">Todesursachenstatistik<\/a>.<\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/183099-inflation-laesst-altersarmut-explodieren-politik-sieht-zu\/\">Inflation l\u00e4sst Altersarmut explodieren \u2013 Politik sieht tatenlos zu<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/187890-deutschland-hoechster-anstieg-suizidzahlen-seit\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zwei themenbezogene Institutionen haben eine \u00dcbersicht \u00fcber die aktuellen Suizidzahlen f\u00fcr das Jahr 2022 herausgegeben. Die Summe von Selbstt\u00f6tungen ist demnach um knapp zehn Prozent auf 10.119 gestiegen. Die h\u00e4ufigste Suizidmethode ist das Erh\u00e4ngen. Das Nationale Suizidpr\u00e4ventionsprogramm (NaSPro) und die DeutscheAkademie f\u00fcr Suizidpr\u00e4vention (DASP) haben am 22. November im Rahmen einer\u00a0Presseinformation\u00a0die j\u00fcngsten Auswertungen einer \u00dcbersicht\u00a0aktueller [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":50272,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1700752451"],"wp_automatic_camp":["217"],"0f9015a79625b7c4a5957093d6c36653":["Deutschland: H\u00f6chster Anstieg der Suizide seit 40 Jahren"],"original_link":["https:\/\/de.rt.com\/inland\/187890-deutschland-hoechster-anstieg-suizidzahlen-seit\/"],"_thumbnail_id":["50272"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-11-23 17:15:51\";}"],"jnews_social_counter_last_update":["1788230685"]},"categories":[19,23],"tags":[19969,82,179,19623,1728,1829,50916],"class_list":["post-50271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-anstieg","tag-der","tag-deutschland","tag-hoechster","tag-jahren","tag-seit","tag-suizide"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Deutschland: H\u00f6chster Anstieg der Suizide seit 40 Jahren - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deutschland: H\u00f6chster Anstieg der Suizide seit 40 Jahren\" \/>\n<meta property=\"og:description\" content=\"Zwei themenbezogene Institutionen haben eine \u00dcbersicht \u00fcber die aktuellen Suizidzahlen f\u00fcr das Jahr 2022 herausgegeben. Die Summe von Selbstt\u00f6tungen ist demnach um knapp zehn Prozent auf 10.119 gestiegen. Die h\u00e4ufigste Suizidmethode ist das Erh\u00e4ngen. Das Nationale Suizidpr\u00e4ventionsprogramm (NaSPro) und die DeutscheAkademie f\u00fcr Suizidpr\u00e4vention (DASP) haben am 22. November im Rahmen einer\u00a0Presseinformation\u00a0die j\u00fcngsten Auswertungen einer \u00dcbersicht\u00a0aktueller [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-23T14:46:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Deutschland-Hoechster-Anstieg-der-Suizide-seit-40-Jahren.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Deutschland: H\u00f6chster Anstieg der Suizide seit 40 Jahren\",\"datePublished\":\"2023-11-23T14:46:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\\\/\"},\"wordCount\":656,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/11\\\/Deutschland-Hoechster-Anstieg-der-Suizide-seit-40-Jahren.jpg\",\"keywords\":[\"Anstieg\",\"der\",\"Deutschland\",\"h\u00f6chster\",\"Jahren\",\"seit\",\"Suizide\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\\\/\",\"name\":\"Deutschland: H\u00f6chster Anstieg der Suizide seit 40 Jahren - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/11\\\/Deutschland-Hoechster-Anstieg-der-Suizide-seit-40-Jahren.jpg\",\"datePublished\":\"2023-11-23T14:46:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/11\\\/Deutschland-Hoechster-Anstieg-der-Suizide-seit-40-Jahren.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/11\\\/Deutschland-Hoechster-Anstieg-der-Suizide-seit-40-Jahren.jpg\",\"width\":460,\"height\":259,\"caption\":\"Deutschland: H\u00f6chster Anstieg der Suizide seit 40 Jahren\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deutschland: H\u00f6chster Anstieg der Suizide seit 40 Jahren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Deutschland: H\u00f6chster Anstieg der Suizide seit 40 Jahren - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/","og_locale":"de_DE","og_type":"article","og_title":"Deutschland: H\u00f6chster Anstieg der Suizide seit 40 Jahren","og_description":"Zwei themenbezogene Institutionen haben eine \u00dcbersicht \u00fcber die aktuellen Suizidzahlen f\u00fcr das Jahr 2022 herausgegeben. Die Summe von Selbstt\u00f6tungen ist demnach um knapp zehn Prozent auf 10.119 gestiegen. Die h\u00e4ufigste Suizidmethode ist das Erh\u00e4ngen. Das Nationale Suizidpr\u00e4ventionsprogramm (NaSPro) und die DeutscheAkademie f\u00fcr Suizidpr\u00e4vention (DASP) haben am 22. November im Rahmen einer\u00a0Presseinformation\u00a0die j\u00fcngsten Auswertungen einer \u00dcbersicht\u00a0aktueller [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-11-23T14:46:34+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Deutschland-Hoechster-Anstieg-der-Suizide-seit-40-Jahren.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Deutschland: H\u00f6chster Anstieg der Suizide seit 40 Jahren","datePublished":"2023-11-23T14:46:34+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/"},"wordCount":656,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Deutschland-Hoechster-Anstieg-der-Suizide-seit-40-Jahren.jpg","keywords":["Anstieg","der","Deutschland","h\u00f6chster","Jahren","seit","Suizide"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/","url":"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/","name":"Deutschland: H\u00f6chster Anstieg der Suizide seit 40 Jahren - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Deutschland-Hoechster-Anstieg-der-Suizide-seit-40-Jahren.jpg","datePublished":"2023-11-23T14:46:34+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Deutschland-Hoechster-Anstieg-der-Suizide-seit-40-Jahren.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Deutschland-Hoechster-Anstieg-der-Suizide-seit-40-Jahren.jpg","width":460,"height":259,"caption":"Deutschland: H\u00f6chster Anstieg der Suizide seit 40 Jahren"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/deutschland-hoechster-anstieg-der-suizide-seit-40-jahren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Deutschland: H\u00f6chster Anstieg der Suizide seit 40 Jahren"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/50271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=50271"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/50271\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/50272"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=50271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=50271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=50271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}