{"id":49998,"date":"2023-11-19T08:30:23","date_gmt":"2023-11-19T06:30:23","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/"},"modified":"2023-11-19T08:30:23","modified_gmt":"2023-11-19T06:30:23","slug":"islam-versus-zivilisierter-westen-krieg-der-welten","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/","title":{"rendered":"Islam versus &quot;zivilisierter&quot; Westen: Krieg der Welten"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/65539d1fb480cc5ed16885ea.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die Vorstellung, die Hamas zu zerst\u00f6ren, ist von d\u00fcmmlicher Schlichtheit. Doch hinter dieser Arroganz lauert eine globale Gefahr f\u00fcr Teile der menschlichen Zivilisation. Die geopolitischen Ver\u00e4nderungen aber werden nicht zu stoppen sein.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Tom J. Wellbrock<\/em><\/p>\n<p>Der israelische <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/der-nahe-osten\/186951-netanjahu-wenn-israel-krieg-verliert\/\">Premierminister Benjamin Netanjahu<\/a> bevorzugt klare Worte. Gerichtet waren sie an die Amerikaner, aber letztlich an die ganze Welt, abgesehen von den Muslimen:<\/p>\n<p><em>&#8220;Wir m\u00fcssen siegen, um Israel zu sch\u00fctzen. Wir m\u00fcssen siegen, um den Nahen Osten zu sch\u00fctzen. Wir m\u00fcssen um der zivilisierten Welt willen gewinnen. Das ist der Kampf, den wir f\u00fchren, und er wird gerade jetzt ausgetragen. Es gibt keinen Ersatz f\u00fcr diesen Sieg. Wenn wir jetzt nicht gewinnen, ist Europa der N\u00e4chste und Sie sind der N\u00e4chste.&#8221;<\/em><\/p>\n<p>Das war Mitte November. Es zeigt die Geisteshaltung Netanjahus, aber es macht auch deutlich, dass es ein weltweites Problem gibt\u00a0\u2013 zwischen dem &#8220;werteorientierten Westen&#8221; und dem Islam. Netanjahu und seine Denkschule t\u00e4ten gut daran, die Situation n\u00fcchtern zu betrachten. In ihrem eigenen Interesse.<\/p>\n<p><strong><\/strong><\/p>\n<p><strong>Der Islam auf dem Vormarsch<\/strong><\/p>\n<p>Am 17. Januar <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.zdf.de\/nachrichten\/panorama\/infografik-tag-der-weltreligionen-100.html\">2021 schrieb das <em>ZDF<\/em><\/a><em>:<\/em><\/p>\n<blockquote>\n<p><em>&#8220;Nach wie vor haben die Weltreligionen einen hohen Stellenwert. Die Zahl der gl\u00e4ubigen Menschen w\u00e4chst, am st\u00e4rksten im Islam. In Deutschland aber nehmen die Kirchenaustritte zu.<\/em><\/p>\n<p><em>W\u00e4hrend man in Europa und besonders in Deutschland in den letzten Jahren eine Tendenz zur Glaubens-Abkehr feststellen kann, sieht es weltweit anders aus: Die <\/em><em>Anzahl der Gl\u00e4ubigen nimmt zu.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Bis heute hat sich an dieser Entwicklung nichts ge\u00e4ndert, im Gegenteil. W\u00e4hrend die Kirchen in Deutschland und anderswo Austritte und eine Abkehr vom Glauben beklagen, findet der Islam kontinuierlich Zulauf. Ebenfalls in dem Artikel des <em>ZDF<\/em> lesen wir:<\/p>\n<blockquote>\n<p>&#8220;<em>In vielen afrikanischen L\u00e4ndern zum Beispiel hat Religion eine gro\u00dfe Bedeutung, die Bev\u00f6lkerung hat ein junges Durchschnittsalter, das Bev\u00f6lkerungswachstum ist in diesen L\u00e4ndern am h\u00f6chsten. Weltweit <\/em><em>w\u00e4chst die Zahl<\/em><strong><em><\/em><\/strong><em>der Muslime am <\/em><em>schnellsten<\/em><em>. Auch das Christentum w\u00e4chst, aber langsamer.<\/em><\/p>\n<p><em>Im Jahr 2060, so prognostiziert das Pew Research Center, werde es <\/em><em>weltweit fast so viele Muslime wie Christen <\/em><em>geben. So stellten laut dem Forschungsinstitut Christen im Jahr 2015 31,2 Prozent der Weltbev\u00f6lkerung, Muslime 24,1 Prozent. F\u00fcr 2060 rechnet es mit 31,1 Prozent Muslime und 31,8 Prozent Christen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Nun ist es lediglich eine Prognose, aber zeichnet sich ab, was derzeit zu sehen ist, d\u00fcrfte der Anteil der Muslime bis 2060 weiter wachsen. W\u00e4hrend das Christentum stagniert oder zur\u00fcckgehen wird, gibt es keine grundlegende neue Tendenz.<\/p>\n<p><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.statista.com\/themen\/878\/muslime-und-islam\/#topicOverview\">Statista schrieb<\/a> am 5. Mai 2023:<\/p>\n<blockquote>\n<p>&#8220;<em>Der Islam geh\u00f6rt unzweifelhaft zu Deutschland: Rund\u00a0<\/em><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.statista.com\/statistik\/daten\/studie\/72321\/umfrage\/entwicklung-der-anzahl-der-muslime-in-deutschland-seit-1945\/\"><em>5,5 Millionen Menschen<\/em><\/a><em>\u00a0<\/em><em>aller muslimischen Glaubensrichtungen leben in Deutschland, womit der Islam hierzulande die drittgr\u00f6\u00dfte Glaubensgemeinschaft darstellt. Dieser Weltreligion geh\u00f6ren dabei insgesamt etwa\u00a0<\/em><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.statista.com\/statistik\/daten\/studie\/1116360\/umfrage\/anzahl-der-muslime-in-europa-und-weltweit\/\"><em>1,9 Milliarden Menschen<\/em><\/a><em>\u00a0<\/em><em>an, was einem Anteil von etwa\u00a0<\/em><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.statista.com\/statistik\/daten\/studie\/380914\/umfrage\/anteil-der-muslime-an-der-bevoelkerung-in-europa-und-der-welt\/\"><em>einem Viertel der Weltbev\u00f6lkerung<\/em><\/a><em>\u00a0<\/em><em>entspricht \u2013 mit steigender Tendenz. Bis heute gibt es allerdings nur wenige strukturierte Studien und Erhebungen zum Islam und den Muslimen, weswegen bei einigen Angaben auf mit Unsicherheiten behaftete Sch\u00e4tzungen oder Prognosen zur\u00fcckgegriffen werden muss.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Fast zwei Milliarden Muslime weltweit, wobei einger\u00e4umt wird, dass diesen Angaben Unsicherheiten innewohnen \u2013 es k\u00f6nnten also auch weniger oder mehr sein. In jedem Fall geht vom Islam eine nicht zu untersch\u00e4tzende Macht aus.<\/p>\n<p><strong><\/strong><\/p>\n<p><strong>Zerst\u00f6ren? Ausl\u00f6schen?<\/strong><\/p>\n<p>Wenn es nach Netanjahu geht, bombt Israel alles in Grund und Boden, was er als Gefahr f\u00fcr seinen Staat ansieht. Aktuell sieht man, dass er es ernst meint. In Deutschland hat Netanjahu keine Gegenwehr zu erwarten. Das T\u00f6ten von Zivilisten, darunter zahlreiche Frauen und Kinder, wird unter der Rubrik &#8220;Selbstverteidigung&#8221; abgehakt, die Israel zustehe. Punkt.<\/p>\n<p>Das obige Zitat belegt, dass der israelische Premierminister bereit ist, noch weiter zugehen. Die Zerst\u00f6rung der Hamas scheint nur Teil eines gr\u00f6\u00dferen Plans zu sein. Netanjahu sieht \u00fcberall Feinde, die ihn, den Westen, die ganze Welt bedrohen. Deutschlands Au\u00dfenministerin Annalena Baerbock (die Gr\u00fcnen) \u2013 ohnehin bekannt f\u00fcr ihre schlichten und kurzsichtigen Analysen \u2013 besteht darauf, dass es ohne die Zerst\u00f6rung der Hamas im Nahen Osten keinen Frieden geben k\u00f6nne.<\/p>\n<p>Beide machen einen gef\u00e4hrlichen Denkfehler.<\/p>\n<p><strong><\/strong><\/p>\n<p><strong>Von der Unm\u00f6glichkeit der Zerst\u00f6rung der Hamas<\/strong><\/p>\n<p>Selbst wenn man in Deutschland behauptet, die ermordeten Kinder in Pal\u00e4stina gingen auf das Konto der Hamas, da sie die Zivilbev\u00f6lkerung als Schutzschild missbrauche, ist die Forderung nach der Ausl\u00f6schung der Hamas absurd und realit\u00e4tsfern. Wohl fast jeder get\u00f6tete Pal\u00e4stinenser hat in seiner Familie ein potenzielles Mitglied der Hamas, das auf Rache sinnt. Durch die massenhaften Morde an Zivilisten begeben sich Israel und die unterst\u00fctzenden L\u00e4nder in eine gef\u00e4hrliche Lage. Man denkt unwillk\u00fcrlich an die Hydra, das Ungeheuer der griechischen Mythologie, dem mit jedem abgeschlagenen Kopf zwei neue nachwachsen.<\/p>\n<p>Wenn Israel weiter so agiert, wie es agiert, wird ein Fl\u00e4chenbrand nicht zu verhindern sein. Das Zitat des israelischen Verteidigungsministers macht deutlich, dass Israel zu allem bereit ist:<\/p>\n<blockquote>\n<p><em>&#8220;Was wir im Gazastreifen machen, geht auch in Beirut.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Doch das wird nicht funktionieren. Die israelischen politischen Verantwortungstr\u00e4ger irren sich, wenn sie glauben, durch ihre milit\u00e4rische St\u00e4rke den Nahen Osten oder auch nur Gaza dauerhaft kontrollieren zu k\u00f6nnen. In Gaza mag das bisher unter Inkaufnahme rigider und brutaler Politik m\u00f6glich gewesen sein. Doch nach dem 7. Oktober hat sich die Lage grundlegend ver\u00e4ndert. In Bezug auf ihre milit\u00e4rische Macht k\u00f6nnen die Israelis die USA fragen, wie erfolgreich diese materielle \u00dcberlegenheit ist, wenn man es mit Widerst\u00e4ndigen zu tun hat, die vom Glauben und Rachegel\u00fcsten dominiert werden.<\/p>\n<p>Es besteht die realistische Gefahr einer ganz anderen Ausl\u00f6schung, n\u00e4mlich der Israels. Und im Zuge dessen besteht eine weitere Gefahr darin, dass die Israel unterst\u00fctzenden L\u00e4nder die Eskalation fortsetzen\u00a0\u2013 ab einem gewissen Punkt sogar mit der berechtigten Sorge, Israel k\u00f6nnte von der Landkarte gestrichen werden, wenn arabische Staaten dies entscheiden. Israel und die westlichen L\u00e4nder haben es zu verantworten, sollte es so weit kommen.<\/p>\n<p>Es zeugt von uns alle bedrohender Arroganz und Selbstherrlichkeit, davon auszugehen, dass der Westen dar\u00fcber entscheidet, wer existieren darf und wer ausgel\u00f6scht werden muss. Dieses Prinzip hat Jahrzehnte funktioniert, insbesondere die USA haben der Welt ihre Interessen diktiert. Doch sp\u00e4testens seit Ausbruch des aktuellen Ukraine-Krieges hat der Aufbau einer neuen Ordnung begonnen, haben L\u00e4nder, die fr\u00fcher stillgehalten haben, ihre eigene St\u00e4rke und ihre eigenen Interessen entdeckt. Auch im Nahen Osten hatte der Westen \u00fcber Jahrzehnte seine Finger im Spiel, hat L\u00e4nder \u00fcberfallen, Regime Changes durchgef\u00fchrt oder versucht, hat Terrororganisationen aufgebaut und finanziert.<\/p>\n<p>Als &#8220;Die Anstalt&#8221; noch Satire gemacht und den M\u00e4chtigen auf die Finger geschaut hat, hat sie die Zusammenh\u00e4nge in <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=zSubuPm_TpE\">einem entlarvenden Beitrag<\/a> auf den Punkt gebracht. Heute wird so getan, als sei das, was im Nahen Osten passiert, v\u00f6llig losgel\u00f6st von den westlichen M\u00e4chten geschehen. Dem ist nicht so!<\/p>\n<p>Letztlich ist es auch der islamistische Terror, der k\u00fcnstlich von den USA und der NATO erzeugt wurde, aus eigenen Interessen, und mit einem Gr\u00f6\u00dftma\u00df an Skrupellosigkeit. Erinnert sei an Madeline Albright, die auf die Frage nach 500.000 ermordeten Kindern im Irak einst sagte:<\/p>\n<blockquote>\n<p>&#8220;<em>Ja, es war den Preis wert.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Wie viele Angeh\u00f6rige der get\u00f6teten Kinder von damals m\u00f6gen sich in der Zeit danach radikalisiert haben? Wie viele haben sich dem Terror zugewandt, um Vergeltung zu \u00fcben? Wie viele werden es nach den tausenden Toten im Gazastreifen sein?<\/p>\n<p>Die Machtverh\u00e4ltnisse verschieben sich, \u00fcberall auf der Welt. Es gibt Bestrebungen der Kooperation zwischen den L\u00e4ndern, es gibt den Ansatz, auf Augenh\u00f6he zu agieren und voneinander zu profitieren. Man wird sehen, inwieweit sich diese Herangehensweise durchsetzen und verwirklichen l\u00e4sst. Und es gibt die andere Seite, die, die dem Krieg und der Eskalation zugewandt ist\u00a0\u2013 die, die nach wie vor eine imperiale Machtzuschreibung sucht; die, die auf Konfrontation statt Kooperation setzt.<\/p>\n<p>Und gerade diese Seite der Konfrontation wird verlieren, sie wird im besten Falle still und leise bedeutungslos werden, wenn sich die weltweiten Strukturen ver\u00e4ndern. Im schlimmsten Fall wird sie eine gewaltsame Niederlage erleiden, bevor sie ebenfalls in der Bedeutungslosigkeit verschwindet. Nicht nur L\u00e4nder wie Russland und China und Zusammenschl\u00fcsse wie die BRICS werden in Zukunft die geopolitische Lage bestimmen. Auch die schon heute fast zwei Milliarden Muslime werden ihre Rolle einfordern.<\/p>\n<p>Wenn bei dieser Ausgangslage die deutsche Au\u00dfenministerin davon spricht, die Hamas zerst\u00f6ren zu wollen, um Frieden im Nahen Osten herzustellen, kann man nur verwundert den Kopf sch\u00fctteln. Baerbock und die Machthaber, die sie repr\u00e4sentiert, leben in einer blutigen Scheinwelt, in der sie die F\u00e4den ziehen. Die Realit\u00e4t dagegen hat jene F\u00e4den l\u00e4ngst durchschnitten, die Betroffenen haben es nur noch nicht bemerkt.<\/p>\n<\/p>\n<p><em>Tom J. Wellbrock ist Journalist, Sprecher, Texter, Podcaster, Moderator und Mitherausgeber des Blogs\u00a0<\/em><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.neulandrebellen.de\/\">neulandrebellen<\/a><em>.<\/em><\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/meinung\/185738-distanzieren-und-positionieren-innerer-frieden\/\">Distanzieren und positionieren: Innerer Frieden durch \u00e4u\u00dfere Feindbilder <\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/187030-islam-versus-zivilisierter-westen-krieg\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Vorstellung, die Hamas zu zerst\u00f6ren, ist von d\u00fcmmlicher Schlichtheit. Doch hinter dieser Arroganz lauert eine globale Gefahr f\u00fcr Teile der menschlichen Zivilisation. Die geopolitischen Ver\u00e4nderungen aber werden nicht zu stoppen sein. Von Tom J. Wellbrock Der israelische Premierminister Benjamin Netanjahu bevorzugt klare Worte. Gerichtet waren sie an die Amerikaner, aber letztlich an die ganze [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":49999,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1700375859"],"wp_automatic_camp":["217"],"d178593ed4f23b49a0334aa4ce24f3a1":["Islam versus &quot;zivilisierter&quot; Westen: Krieg der Welten"],"original_link":["https:\/\/de.rt.com\/meinung\/187030-islam-versus-zivilisierter-westen-krieg\/"],"_thumbnail_id":["49999"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-11-19 08:39:47\";}"],"jnews_social_counter_last_update":["1784024794"]},"categories":[19,23],"tags":[82,10204,130,50770,17288,378],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Islam versus &quot;zivilisierter&quot; Westen: Krieg der Welten - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Islam versus &quot;zivilisierter&quot; Westen: Krieg der Welten\" \/>\n<meta property=\"og:description\" content=\"Die Vorstellung, die Hamas zu zerst\u00f6ren, ist von d\u00fcmmlicher Schlichtheit. Doch hinter dieser Arroganz lauert eine globale Gefahr f\u00fcr Teile der menschlichen Zivilisation. Die geopolitischen Ver\u00e4nderungen aber werden nicht zu stoppen sein. Von Tom J. Wellbrock Der israelische Premierminister Benjamin Netanjahu bevorzugt klare Worte. Gerichtet waren sie an die Amerikaner, aber letztlich an die ganze [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-19T06:30:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Islam-versus-quotzivilisierterquot-Westen-Krieg-der-Welten.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Islam versus &quot;zivilisierter&quot; Westen: Krieg der Welten\",\"datePublished\":\"2023-11-19T06:30:23+00:00\",\"dateModified\":\"2023-11-19T06:30:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/\"},\"wordCount\":1489,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Islam-versus-quotzivilisierterquot-Westen-Krieg-der-Welten.jpg\",\"keywords\":[\"der\",\"Islam\",\"krieg\",\"quotzivilisierterquot\",\"Welten\",\"Westen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/\",\"name\":\"Islam versus &quot;zivilisierter&quot; Westen: Krieg der Welten - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Islam-versus-quotzivilisierterquot-Westen-Krieg-der-Welten.jpg\",\"datePublished\":\"2023-11-19T06:30:23+00:00\",\"dateModified\":\"2023-11-19T06:30:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Islam-versus-quotzivilisierterquot-Westen-Krieg-der-Welten.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Islam-versus-quotzivilisierterquot-Westen-Krieg-der-Welten.jpg\",\"width\":460,\"height\":259,\"caption\":\"Islam versus &quot;zivilisierter&quot; Westen: Krieg der Welten\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Islam versus &quot;zivilisierter&quot; Westen: Krieg der Welten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Islam versus &quot;zivilisierter&quot; Westen: Krieg der Welten - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/","og_locale":"de_DE","og_type":"article","og_title":"Islam versus &quot;zivilisierter&quot; Westen: Krieg der Welten","og_description":"Die Vorstellung, die Hamas zu zerst\u00f6ren, ist von d\u00fcmmlicher Schlichtheit. Doch hinter dieser Arroganz lauert eine globale Gefahr f\u00fcr Teile der menschlichen Zivilisation. Die geopolitischen Ver\u00e4nderungen aber werden nicht zu stoppen sein. Von Tom J. Wellbrock Der israelische Premierminister Benjamin Netanjahu bevorzugt klare Worte. Gerichtet waren sie an die Amerikaner, aber letztlich an die ganze [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-11-19T06:30:23+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Islam-versus-quotzivilisierterquot-Westen-Krieg-der-Welten.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Islam versus &quot;zivilisierter&quot; Westen: Krieg der Welten","datePublished":"2023-11-19T06:30:23+00:00","dateModified":"2023-11-19T06:30:23+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/"},"wordCount":1489,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Islam-versus-quotzivilisierterquot-Westen-Krieg-der-Welten.jpg","keywords":["der","Islam","krieg","quotzivilisierterquot","Welten","Westen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/","url":"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/","name":"Islam versus &quot;zivilisierter&quot; Westen: Krieg der Welten - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Islam-versus-quotzivilisierterquot-Westen-Krieg-der-Welten.jpg","datePublished":"2023-11-19T06:30:23+00:00","dateModified":"2023-11-19T06:30:23+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Islam-versus-quotzivilisierterquot-Westen-Krieg-der-Welten.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/11\/Islam-versus-quotzivilisierterquot-Westen-Krieg-der-Welten.jpg","width":460,"height":259,"caption":"Islam versus &quot;zivilisierter&quot; Westen: Krieg der Welten"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/islam-versus-zivilisierter-westen-krieg-der-welten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Islam versus &quot;zivilisierter&quot; Westen: Krieg der Welten"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/49998"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=49998"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/49998\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/49999"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=49998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=49998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=49998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}