{"id":49770,"date":"2023-11-15T11:16:25","date_gmt":"2023-11-15T09:16:25","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/"},"modified":"2023-11-15T11:16:25","modified_gmt":"2023-11-15T09:16:25","slug":"verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/","title":{"rendered":"Verfassungsgericht kippt Nachtragshaushalt der Ampelkoalition"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/10\/breaking3.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Das Bundesverfassungsgericht hat geurteilt, dass der Bund zur Bek\u00e4mpfung der Corona-Krise gedachte Gelder nicht f\u00fcr den Klimaschutz nutzen darf. Die \u00c4nderung des Nachtragshaushalts 2021 sei verfassungswidrig, verk\u00fcndete das h\u00f6chste Gericht Deutschlands am Mittwoch in Karlsruhe\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Weitere Informationen in K\u00fcrze.<\/em><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/187097-verfassungsgericht-kippt-nachtragshaushalt-ampelkoalition\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Bundesverfassungsgericht hat geurteilt, dass der Bund zur Bek\u00e4mpfung der Corona-Krise gedachte Gelder nicht f\u00fcr den Klimaschutz nutzen darf. Die \u00c4nderung des Nachtragshaushalts 2021 sei verfassungswidrig, verk\u00fcndete das h\u00f6chste Gericht Deutschlands am Mittwoch in Karlsruhe Weitere Informationen in K\u00fcrze. Source link<\/p>\n","protected":false},"author":3,"featured_media":23828,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1700040366"],"wp_automatic_camp":["217"],"065e87d2ca1274b36f43b5231eafdb85":["Verfassungsgericht kippt Nachtragshaushalt der Ampelkoalition"],"original_link":["https:\/\/de.rt.com\/inland\/187097-verfassungsgericht-kippt-nachtragshaushalt-ampelkoalition\/"],"_thumbnail_id":["23828"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-11-15 11:27:59\";}"],"jnews_social_counter_last_update":["1778304005"]},"categories":[19,23],"tags":[22395,82,18073,50647,24561],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Verfassungsgericht kippt Nachtragshaushalt der Ampelkoalition - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verfassungsgericht kippt Nachtragshaushalt der Ampelkoalition\" \/>\n<meta property=\"og:description\" content=\"Das Bundesverfassungsgericht hat geurteilt, dass der Bund zur Bek\u00e4mpfung der Corona-Krise gedachte Gelder nicht f\u00fcr den Klimaschutz nutzen darf. Die \u00c4nderung des Nachtragshaushalts 2021 sei verfassungswidrig, verk\u00fcndete das h\u00f6chste Gericht Deutschlands am Mittwoch in Karlsruhe Weitere Informationen in K\u00fcrze. Source link\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-15T09:16:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Verfassungsgericht kippt Nachtragshaushalt der Ampelkoalition\",\"datePublished\":\"2023-11-15T09:16:25+00:00\",\"dateModified\":\"2023-11-15T09:16:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/\"},\"wordCount\":51,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg\",\"keywords\":[\"Ampelkoalition\",\"der\",\"kippt\",\"Nachtragshaushalt\",\"Verfassungsgericht\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/\",\"name\":\"Verfassungsgericht kippt Nachtragshaushalt der Ampelkoalition - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg\",\"datePublished\":\"2023-11-15T09:16:25+00:00\",\"dateModified\":\"2023-11-15T09:16:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg\",\"width\":460,\"height\":259,\"caption\":\"Oberstes britisches Gericht untersagt Unabh\u00e4ngigkeitsreferendum in Schottland\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verfassungsgericht kippt Nachtragshaushalt der Ampelkoalition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Verfassungsgericht kippt Nachtragshaushalt der Ampelkoalition - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/","og_locale":"de_DE","og_type":"article","og_title":"Verfassungsgericht kippt Nachtragshaushalt der Ampelkoalition","og_description":"Das Bundesverfassungsgericht hat geurteilt, dass der Bund zur Bek\u00e4mpfung der Corona-Krise gedachte Gelder nicht f\u00fcr den Klimaschutz nutzen darf. Die \u00c4nderung des Nachtragshaushalts 2021 sei verfassungswidrig, verk\u00fcndete das h\u00f6chste Gericht Deutschlands am Mittwoch in Karlsruhe Weitere Informationen in K\u00fcrze. Source link","og_url":"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-11-15T09:16:25+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Verfassungsgericht kippt Nachtragshaushalt der Ampelkoalition","datePublished":"2023-11-15T09:16:25+00:00","dateModified":"2023-11-15T09:16:25+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/"},"wordCount":51,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg","keywords":["Ampelkoalition","der","kippt","Nachtragshaushalt","Verfassungsgericht"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/","url":"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/","name":"Verfassungsgericht kippt Nachtragshaushalt der Ampelkoalition - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg","datePublished":"2023-11-15T09:16:25+00:00","dateModified":"2023-11-15T09:16:25+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg","width":460,"height":259,"caption":"Oberstes britisches Gericht untersagt Unabh\u00e4ngigkeitsreferendum in Schottland"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/verfassungsgericht-kippt-nachtragshaushalt-der-ampelkoalition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Verfassungsgericht kippt Nachtragshaushalt der Ampelkoalition"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/49770"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=49770"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/49770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/23828"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=49770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=49770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=49770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}