{"id":49668,"date":"2023-11-13T11:35:54","date_gmt":"2023-11-13T09:35:54","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/"},"modified":"2023-11-13T11:35:54","modified_gmt":"2023-11-13T09:35:54","slug":"spd-vorsitz-klingbeil-und-esken-treten-wieder-an","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/","title":{"rendered":"SPD-Vorsitz: Klingbeil und Esken treten wieder an"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/10\/breaking3.jpg\" \/><\/p>\n<div class=\"ArticleView-bottomShares\">\n<div class=\"ShareBlock-isReact\" data-rtcomponent=\"ShareBlock\" onload=\"return {\n        socials: JSON.parse('\\u005B\\u0022facebook\\u0022,\\u0022fbmessage\\u0022,\\u0022xtwitter\\u0022,\\u0022whatsapp\\u0022,\\u0022telegram\\u0022,\\u0022mailto\\u0022,\\u0022pocket\\u0022,\\u0022copylink\\u0022,\\u0022pdflink\\u0022\\u005D'),\n        direction: JSON.parse('\\u0022row\\u0022'),\n        type: JSON.parse('\\u0022hasFull\\u0022'),\n        params: JSON.parse('\\u007B\\u0022counters\\u0022\\u003Atrue,\\u0022href\\u0022\\u003A\\u0022https\\u003A\\\\\\\/\\\\\\\/de.rt.com\\\\\\\/inland\\\\\\\/186840\\u002Dspd\\u002Dvorsitz\\u002Dklingbeil\\u002Dund\\u002Desken\\\\\\\/\\u0022,\\u0022shortUrl\\u0022\\u003A\\u0022https\\u003A\\\\\\\/\\\\\\\/kurz.rt.com\\\\\\\/4060\\u0022\\u007D'),\n    };\"><\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/186840-spd-vorsitz-klingbeil-und-esken\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Source link<\/p>\n","protected":false},"author":3,"featured_media":23828,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1699869106"],"wp_automatic_camp":["217"],"9bda2986299ad1947710cb3701ff817b":["SPD-Vorsitz: Klingbeil und Esken treten wieder an"],"original_link":["https:\/\/de.rt.com\/inland\/186840-spd-vorsitz-klingbeil-und-esken\/"],"_thumbnail_id":["23828"],"jnews_social_counter_last_update":["1778286704"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-11-13 11:52:58\";}"]},"categories":[19,23],"tags":[24077,18061,50599,19677,140,904],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SPD-Vorsitz: Klingbeil und Esken treten wieder an - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SPD-Vorsitz: Klingbeil und Esken treten wieder an\" \/>\n<meta property=\"og:description\" content=\"Source link\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-13T09:35:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"SPD-Vorsitz: Klingbeil und Esken treten wieder an\",\"datePublished\":\"2023-11-13T09:35:54+00:00\",\"dateModified\":\"2023-11-13T09:35:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/\"},\"wordCount\":10,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg\",\"keywords\":[\"Esken\",\"Klingbeil\",\"SPDVorsitz\",\"treten\",\"und\",\"wieder\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/\",\"name\":\"SPD-Vorsitz: Klingbeil und Esken treten wieder an - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg\",\"datePublished\":\"2023-11-13T09:35:54+00:00\",\"dateModified\":\"2023-11-13T09:35:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg\",\"width\":460,\"height\":259,\"caption\":\"Oberstes britisches Gericht untersagt Unabh\u00e4ngigkeitsreferendum in Schottland\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SPD-Vorsitz: Klingbeil und Esken treten wieder an\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SPD-Vorsitz: Klingbeil und Esken treten wieder an - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/","og_locale":"de_DE","og_type":"article","og_title":"SPD-Vorsitz: Klingbeil und Esken treten wieder an","og_description":"Source link","og_url":"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-11-13T09:35:54+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"SPD-Vorsitz: Klingbeil und Esken treten wieder an","datePublished":"2023-11-13T09:35:54+00:00","dateModified":"2023-11-13T09:35:54+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/"},"wordCount":10,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg","keywords":["Esken","Klingbeil","SPDVorsitz","treten","und","wieder"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/","url":"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/","name":"SPD-Vorsitz: Klingbeil und Esken treten wieder an - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg","datePublished":"2023-11-13T09:35:54+00:00","dateModified":"2023-11-13T09:35:54+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/11\/Oberstes-britisches-Gericht-untersagt-Unabhaengigkeitsreferendum-in-Schottland.jpg","width":460,"height":259,"caption":"Oberstes britisches Gericht untersagt Unabh\u00e4ngigkeitsreferendum in Schottland"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/spd-vorsitz-klingbeil-und-esken-treten-wieder-an\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"SPD-Vorsitz: Klingbeil und Esken treten wieder an"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/49668"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=49668"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/49668\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/23828"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=49668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=49668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=49668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}