{"id":48861,"date":"2023-10-28T16:18:17","date_gmt":"2023-10-28T14:18:17","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\/"},"modified":"2023-10-28T16:18:17","modified_gmt":"2023-10-28T14:18:17","slug":"eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\/","title":{"rendered":"EU-Gipfel: Weitere Waffenlieferungen an Ukraine \u2012 Finanzielle Unterst\u00fctzung scheitert"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/653cfe4f48fbef2c6528be8e.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Auf dem EU-Gipfel versicherte man der Ukraine erneut die volle Solidarit\u00e4t. Deutschland liefert in immer gr\u00f6\u00dferem Umfang Waffen. Finanzielle Zusagen an die Ukraine seitens der EU sind am Veto Ungarns und der Slowakei gescheitert.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die EU bleibt weiter bei ihrer Sprachregelung und sichert der Ukraine milit\u00e4rische und finanzielle Unterst\u00fctzung &#8220;so lange wie n\u00f6tig&#8221; zu. Allerdings konnten sich die Mitgliedsstaaten nicht auf eine\u00a0weitere finanzielle Absicherung der Ukraine\u00a0in H\u00f6he von 50 Milliarden Euro bis 2027 einigen. Sowohl Ungarns Ministerpr\u00e4sident Viktor Orb\u00e1n als auch Robert Fico, Ministerpr\u00e4sident der Slowakei, verweigerten ihre Zustimmung.\u00a0<\/p>\n<p>In einem Interview sagte Orb\u00e1n, er sehe keinen Grund, warum er ungarisches Steuergeld in die Ukraine schicken sollte, um damit eine Strategie zu unterst\u00fctzen, die nicht funktioniere. Das Ziel sei, der Ukraine zu einem Sieg \u00fcber Russland zu verhelfen, um dadurch auch die Regierung in Moskau zu st\u00fcrzen. Dieses Ziel sei nicht realistisch. Es sei daher notwendig, \u00fcber einen Plan B zu sprechen.\u00a0<\/p>\n<p>Die Bundesregierung bleibt diesem Ziel jedoch treu und setzt daher auf eine Verl\u00e4ngerung des Krieges durch weitere Waffenlieferungen. Bereits Anfang Oktober hat Deutschland zugesagt, seine milit\u00e4rische Unterst\u00fctzung der Ukraine massiv aufzustocken. Deutschland liefert ein weiteres Flugabwehrsystem sowie Panzer und Munition.<\/p>\n<p>Dabei hat sich die Lieferung von Kampfpanzern des Typs Leopard 2 als &#8220;Game Changer&#8221;, wie sie den deutschen Medienkonsumenten zu Beginn des Jahres verkauft wurde, nicht bewahrheitet. Die deutschen Kampfpanzer sollten der Ukraine im Kampfverband einen Durchsto\u00df durch die russische Front in Richtung Asowsches Meer erm\u00f6glichen. Dies ist grundlegend gescheitert und f\u00fchrte auf Seiten der Ukraine zu enormen Verlusten an Technik und Leben. Dennoch bleibt die Bundesregierung bei dieser Strategie und liefert Waffen nach.\u00a0<\/p>\n<p>Weitere finanzielle Unterst\u00fctzung der Ukraine will die EU \u00fcber die Umwidmung eingefrorener russischer Gelder erm\u00f6glichen. Im Rahmen der Sanktionen hat die EU russisches Verm\u00f6gen im Umfang von 300 Milliarden Euro eingefroren. Die EU sucht nach rechtssicheren Wegen, um die Gelder an die Ukraine zu \u00fcberweisen.<\/p>\n<p>Aktuell ist geplant, zumindest die Zinseinnahmen aus dem eingefrorenen Guthaben an die Ukraine zu \u00fcbertragen. Nach Angaben der <em>Financial Times<\/em> handelt es sich um einen Betrag von rund 3 Milliarden Euro, die nach geltendem Recht Russland zustehen.\u00a0Russland verweist auf den generell v\u00f6lkerrechtswidrigen Charakter der Sanktionen. Sie wurden nicht durch einen UN-Sicherheitsratsbeschluss legitimiert und sind damit illegal.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/meinung\/185184-neben-orban-jetzt-zweiter-unruhestifter\/\">Neben Orb\u00e1n jetzt ein zweiter &#8220;Unruhestifter&#8221; bei EU-Gipfeltreffen<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/185256-eu-gipfel-weitere-waffenlieferungen-an\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf dem EU-Gipfel versicherte man der Ukraine erneut die volle Solidarit\u00e4t. Deutschland liefert in immer gr\u00f6\u00dferem Umfang Waffen. Finanzielle Zusagen an die Ukraine seitens der EU sind am Veto Ungarns und der Slowakei gescheitert. Die EU bleibt weiter bei ihrer Sprachregelung und sichert der Ukraine milit\u00e4rische und finanzielle Unterst\u00fctzung &#8220;so lange wie n\u00f6tig&#8221; zu. Allerdings [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":48862,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1698503095"],"wp_automatic_camp":["217"],"84aaa70cf182037fe24aa367918a4fc2":["EU-Gipfel: Weitere Waffenlieferungen an Ukraine \u2012 Finanzielle Unterst\u00fctzung scheitert"],"original_link":["https:\/\/de.rt.com\/europa\/185256-eu-gipfel-weitere-waffenlieferungen-an\/"],"_thumbnail_id":["48862"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-10-28 16:26:02\";}"],"jnews_social_counter_last_update":["1788386771"]},"categories":[19,23],"tags":[40642,24494,1160,127,962,370,823],"class_list":["post-48861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-eugipfel","tag-finanzielle","tag-scheitert","tag-ukraine","tag-unterstuetzung","tag-waffenlieferungen","tag-weitere"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>EU-Gipfel: Weitere Waffenlieferungen an Ukraine \u2012 Finanzielle Unterst\u00fctzung scheitert - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-\u2012-finanzielle-unterstuetzung-scheitert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EU-Gipfel: Weitere Waffenlieferungen an Ukraine \u2012 Finanzielle Unterst\u00fctzung scheitert\" \/>\n<meta property=\"og:description\" content=\"Auf dem EU-Gipfel versicherte man der Ukraine erneut die volle Solidarit\u00e4t. Deutschland liefert in immer gr\u00f6\u00dferem Umfang Waffen. Finanzielle Zusagen an die Ukraine seitens der EU sind am Veto Ungarns und der Slowakei gescheitert. Die EU bleibt weiter bei ihrer Sprachregelung und sichert der Ukraine milit\u00e4rische und finanzielle Unterst\u00fctzung &#8220;so lange wie n\u00f6tig&#8221; zu. Allerdings [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-\u2012-finanzielle-unterstuetzung-scheitert\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-28T14:18:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/EU-Gipfel-Weitere-Waffenlieferungen-an-Ukraine-\u2012-Finanzielle-Unterstuetzung-scheitert.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"EU-Gipfel: Weitere Waffenlieferungen an Ukraine \u2012 Finanzielle Unterst\u00fctzung scheitert\",\"datePublished\":\"2023-10-28T14:18:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\\\/\"},\"wordCount\":410,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/10\\\/EU-Gipfel-Weitere-Waffenlieferungen-an-Ukraine-\u2012-Finanzielle-Unterstuetzung-scheitert.jpg\",\"keywords\":[\"EUGipfel\",\"finanzielle\",\"scheitert\",\"ukraine\",\"Unterst\u00fctzung\",\"Waffenlieferungen\",\"weitere\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\\\/\",\"name\":\"EU-Gipfel: Weitere Waffenlieferungen an Ukraine \u2012 Finanzielle Unterst\u00fctzung scheitert - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/10\\\/EU-Gipfel-Weitere-Waffenlieferungen-an-Ukraine-\u2012-Finanzielle-Unterstuetzung-scheitert.jpg\",\"datePublished\":\"2023-10-28T14:18:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/10\\\/EU-Gipfel-Weitere-Waffenlieferungen-an-Ukraine-\u2012-Finanzielle-Unterstuetzung-scheitert.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/10\\\/EU-Gipfel-Weitere-Waffenlieferungen-an-Ukraine-\u2012-Finanzielle-Unterstuetzung-scheitert.jpg\",\"width\":460,\"height\":259,\"caption\":\"EU-Gipfel: Weitere Waffenlieferungen an Ukraine \u2012 Finanzielle Unterst\u00fctzung scheitert\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EU-Gipfel: Weitere Waffenlieferungen an Ukraine \u2012 Finanzielle Unterst\u00fctzung scheitert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"EU-Gipfel: Weitere Waffenlieferungen an Ukraine \u2012 Finanzielle Unterst\u00fctzung scheitert - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-\u2012-finanzielle-unterstuetzung-scheitert\/","og_locale":"de_DE","og_type":"article","og_title":"EU-Gipfel: Weitere Waffenlieferungen an Ukraine \u2012 Finanzielle Unterst\u00fctzung scheitert","og_description":"Auf dem EU-Gipfel versicherte man der Ukraine erneut die volle Solidarit\u00e4t. Deutschland liefert in immer gr\u00f6\u00dferem Umfang Waffen. Finanzielle Zusagen an die Ukraine seitens der EU sind am Veto Ungarns und der Slowakei gescheitert. Die EU bleibt weiter bei ihrer Sprachregelung und sichert der Ukraine milit\u00e4rische und finanzielle Unterst\u00fctzung &#8220;so lange wie n\u00f6tig&#8221; zu. Allerdings [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-\u2012-finanzielle-unterstuetzung-scheitert\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-10-28T14:18:17+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/EU-Gipfel-Weitere-Waffenlieferungen-an-Ukraine-\u2012-Finanzielle-Unterstuetzung-scheitert.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"EU-Gipfel: Weitere Waffenlieferungen an Ukraine \u2012 Finanzielle Unterst\u00fctzung scheitert","datePublished":"2023-10-28T14:18:17+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\/"},"wordCount":410,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/EU-Gipfel-Weitere-Waffenlieferungen-an-Ukraine-\u2012-Finanzielle-Unterstuetzung-scheitert.jpg","keywords":["EUGipfel","finanzielle","scheitert","ukraine","Unterst\u00fctzung","Waffenlieferungen","weitere"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\/","url":"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\/","name":"EU-Gipfel: Weitere Waffenlieferungen an Ukraine \u2012 Finanzielle Unterst\u00fctzung scheitert - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/EU-Gipfel-Weitere-Waffenlieferungen-an-Ukraine-\u2012-Finanzielle-Unterstuetzung-scheitert.jpg","datePublished":"2023-10-28T14:18:17+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/EU-Gipfel-Weitere-Waffenlieferungen-an-Ukraine-\u2012-Finanzielle-Unterstuetzung-scheitert.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/EU-Gipfel-Weitere-Waffenlieferungen-an-Ukraine-\u2012-Finanzielle-Unterstuetzung-scheitert.jpg","width":460,"height":259,"caption":"EU-Gipfel: Weitere Waffenlieferungen an Ukraine \u2012 Finanzielle Unterst\u00fctzung scheitert"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/eu-gipfel-weitere-waffenlieferungen-an-ukraine-%e2%80%92-finanzielle-unterstuetzung-scheitert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"EU-Gipfel: Weitere Waffenlieferungen an Ukraine \u2012 Finanzielle Unterst\u00fctzung scheitert"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/48861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=48861"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/48861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/48862"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=48861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=48861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=48861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}