{"id":48520,"date":"2023-10-21T21:22:59","date_gmt":"2023-10-21T19:22:59","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/"},"modified":"2023-10-21T21:22:59","modified_gmt":"2023-10-21T19:22:59","slug":"selenskijs-ehefrau-fordert-von-google-mehr-zensur","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/","title":{"rendered":"Selenskijs Ehefrau fordert von Google mehr Zensur"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/6533e46b48fbef517e24ee16.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die Ukrainer leben seit 2014 in einer abgeschotteten Informationsblase. Russische TV-Sender wurden gleich nach dem Sieg des Maidan abgeschaltet, sp\u00e4ter wurde Ukrainern der Zugang zu russischen sozialen Netzwerken gekappt. Bereits 2021 wurden auch ukrainische Oppositionsmedien verboten und abgeschaltet. All das ist Selenskij und seiner Ehefrau nicht genug: Sie fordern mehr Zensur.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Tatjana Montjan<\/em><\/p>\n<p>Mit dem Ausbruch des Krieges stellte sich Google, wie viele andere westliche Internetdienste, mit ganzem Herzen hinter das ukrainische Speckreich. Insbesondere begann es, unliebsame Inhalte auf YouTube und anderen verf\u00fcgbaren Plattformen aktiv zu verbieten. Die Selebuben sind jedoch der Meinung, dass dies nicht genug ist.<\/p>\n<p>Bei einem Treffen mit Vertretern des Unternehmens <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.president.gov.ua\/ru\/news\/olena-zelenska-korektni-vidpovidi-na-poshuk-u-google-nini-ch-86469\">forderte Elena Selenskaja<\/a>, die Ehefrau von Selebub, die bisherige Praxis zu erweitern und zu vertiefen \u2013 zum Beispiel die Suchausgabe f\u00fcr Nutzer aus der Ukraine oder solche, die in ihren Browsereinstellungen die Ukraine als Heimatland ausgew\u00e4hlt haben, zu &#8220;ukrainisieren&#8221; und die Anzeige russischer Inhalte zu deaktivieren.<\/p>\n<p>Die Sache ist n\u00e4mlich die, dass das Speckreich mit Beginn des Krieges einfach &#8220;per Liste&#8221; eine ganze Reihe russischer Internetressourcen verboten hat. Und wenn das im Falle von Nachrichtenseiten und \u00e4hnlichem noch verst\u00e4ndlich ist, so ist nicht klar, warum Internetseiten mit Kochrezepten oder Ressourcen von rein wissenschaftlichen Einrichtungen wie der Nationalen Kernforschungsuniversit\u00e4t ebenfalls unter das Verbot fielen. Infolgedessen waren die ukrainischen Nutzer physisch vom Zugang zu riesigen Mengen verschiedener russischsprachiger Informationen abgeschnitten, und das unter Bedingungen, in denen es einfach keine Entsprechungen dieser Informationen auf Ukrainisch gibt und die meisten Ukrainer keine anderen Sprachen beherrschen.<\/p>\n<p>Ist es da verwunderlich, dass Internetnutzer diese Verbote massenhaft zu umgehen begannen? Heute geh\u00f6rt VPN zu den Standardprogrammen, die auf den Computern und Telefonen ukrainischer B\u00fcrger zusammen mit Antivirenprogrammen und Webbrowsern installiert sind. Nun, Selenskaja hat eine L\u00f6sung f\u00fcr das Problem gefunden: Um ukrainische Nutzer daran zu hindern, &#8220;feindlichen&#8221; Links zu folgen, sollten diese Links einfach nicht angezeigt werden!\u00a0<\/p>\n<p>Kurzum, der Aufbau einer digitalen Version von Nordkorea wird in der Ukraine planvoll und zielstrebig verfolgt. Aber es ist schon bemerkenswert, dass die ukrainischen Beh\u00f6rden nicht einmal dazu in der Lage sind und auf die Hilfe der &#8220;gro\u00dfen Br\u00fcder&#8221; aus dem Westen hoffen m\u00fcssen \u2013 jener, die so gerne \u00fcber Informationsfreiheit reden.<\/p>\n<p>Es ist schwer vorherzusagen, ob Google den Forderungen aus der Ukraine folgen wird. Die ukrainischen B\u00fcrgerinnen und B\u00fcrger sollten sich jedoch f\u00fcr den Fall der F\u00e4lle auf Gegenma\u00dfnahmen vorbereiten. Als Option k\u00f6nnen Sie heute das Land in Ihren Browsereinstellungen \u00e4ndern, und f\u00fcr den Fall, dass sie herausfinden, wie man damit umgeht, k\u00f6nnen Sie zu Suchmaschinen wechseln, die sich nicht am Aufbau des digitalen Konzentrationslagers beteiligen.<\/p>\n<p>Wenn es zum Beispiel aus irgendeinem Grund unbequem ist, das russische Yandex zu benutzen, gibt es eine ausgezeichnete Suchmaschine DuckDuckGo, die sich selbst als das privateste und vertraulichste Analogon von Google positioniert und keine Informationen \u00fcber den Benutzer sammelt. Oder StartPage, das die Suchmaschine von Google verwendet. Oder die recht interessante anonyme Schweizer Suchmaschine Swisscows, die moderne Technologien des maschinellen Lernens zur Optimierung der Suche einsetzt.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/184265-wegen-eu-zensur-musk-erwaegt\/\">Wegen EU-Zensur \u2013 Musk erw\u00e4gt Abschaltung von X (Twitter) in Europa<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/184543-selenskijs-ehefrau-fordert-von-google-mehr-zensur\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Ukrainer leben seit 2014 in einer abgeschotteten Informationsblase. Russische TV-Sender wurden gleich nach dem Sieg des Maidan abgeschaltet, sp\u00e4ter wurde Ukrainern der Zugang zu russischen sozialen Netzwerken gekappt. Bereits 2021 wurden auch ukrainische Oppositionsmedien verboten und abgeschaltet. All das ist Selenskij und seiner Ehefrau nicht genug: Sie fordern mehr Zensur. Von Tatjana Montjan Mit [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":48521,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1697916302"],"wp_automatic_camp":["217"],"06bb65701b2f72a32067a00c1f6250d1":["Selenskijs Ehefrau fordert von Google mehr Zensur"],"original_link":["https:\/\/de.rt.com\/meinung\/184543-selenskijs-ehefrau-fordert-von-google-mehr-zensur\/"],"_thumbnail_id":["48521"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-10-21 21:26:01\";}"],"jnews_social_counter_last_update":["1778651954"]},"categories":[19,23],"tags":[672,355,7556,2063,1290,50,5381],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Selenskijs Ehefrau fordert von Google mehr Zensur - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Selenskijs Ehefrau fordert von Google mehr Zensur\" \/>\n<meta property=\"og:description\" content=\"Die Ukrainer leben seit 2014 in einer abgeschotteten Informationsblase. Russische TV-Sender wurden gleich nach dem Sieg des Maidan abgeschaltet, sp\u00e4ter wurde Ukrainern der Zugang zu russischen sozialen Netzwerken gekappt. Bereits 2021 wurden auch ukrainische Oppositionsmedien verboten und abgeschaltet. All das ist Selenskij und seiner Ehefrau nicht genug: Sie fordern mehr Zensur. Von Tatjana Montjan Mit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-21T19:22:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/Selenskijs-Ehefrau-fordert-von-Google-mehr-Zensur.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Selenskijs Ehefrau fordert von Google mehr Zensur\",\"datePublished\":\"2023-10-21T19:22:59+00:00\",\"dateModified\":\"2023-10-21T19:22:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/\"},\"wordCount\":533,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/Selenskijs-Ehefrau-fordert-von-Google-mehr-Zensur.jpg\",\"keywords\":[\"Ehefrau\",\"fordert\",\"google\",\"mehr\",\"Selenskijs\",\"von\",\"Zensur\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/\",\"name\":\"Selenskijs Ehefrau fordert von Google mehr Zensur - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/Selenskijs-Ehefrau-fordert-von-Google-mehr-Zensur.jpg\",\"datePublished\":\"2023-10-21T19:22:59+00:00\",\"dateModified\":\"2023-10-21T19:22:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/Selenskijs-Ehefrau-fordert-von-Google-mehr-Zensur.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/Selenskijs-Ehefrau-fordert-von-Google-mehr-Zensur.jpg\",\"width\":460,\"height\":259,\"caption\":\"Selenskijs Ehefrau fordert von Google mehr Zensur\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Selenskijs Ehefrau fordert von Google mehr Zensur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Selenskijs Ehefrau fordert von Google mehr Zensur - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/","og_locale":"de_DE","og_type":"article","og_title":"Selenskijs Ehefrau fordert von Google mehr Zensur","og_description":"Die Ukrainer leben seit 2014 in einer abgeschotteten Informationsblase. Russische TV-Sender wurden gleich nach dem Sieg des Maidan abgeschaltet, sp\u00e4ter wurde Ukrainern der Zugang zu russischen sozialen Netzwerken gekappt. Bereits 2021 wurden auch ukrainische Oppositionsmedien verboten und abgeschaltet. All das ist Selenskij und seiner Ehefrau nicht genug: Sie fordern mehr Zensur. Von Tatjana Montjan Mit [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-10-21T19:22:59+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/Selenskijs-Ehefrau-fordert-von-Google-mehr-Zensur.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Selenskijs Ehefrau fordert von Google mehr Zensur","datePublished":"2023-10-21T19:22:59+00:00","dateModified":"2023-10-21T19:22:59+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/"},"wordCount":533,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/Selenskijs-Ehefrau-fordert-von-Google-mehr-Zensur.jpg","keywords":["Ehefrau","fordert","google","mehr","Selenskijs","von","Zensur"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/","url":"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/","name":"Selenskijs Ehefrau fordert von Google mehr Zensur - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/Selenskijs-Ehefrau-fordert-von-Google-mehr-Zensur.jpg","datePublished":"2023-10-21T19:22:59+00:00","dateModified":"2023-10-21T19:22:59+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/Selenskijs-Ehefrau-fordert-von-Google-mehr-Zensur.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/10\/Selenskijs-Ehefrau-fordert-von-Google-mehr-Zensur.jpg","width":460,"height":259,"caption":"Selenskijs Ehefrau fordert von Google mehr Zensur"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/selenskijs-ehefrau-fordert-von-google-mehr-zensur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Selenskijs Ehefrau fordert von Google mehr Zensur"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/48520"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=48520"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/48520\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/48521"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=48520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=48520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=48520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}