{"id":47237,"date":"2023-09-29T19:04:06","date_gmt":"2023-09-29T17:04:06","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/"},"modified":"2023-09-29T19:04:06","modified_gmt":"2023-09-29T17:04:06","slug":"heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/","title":{"rendered":"Heucheln, teilen, herrschen \u2013 oder: Die populistischen M\u00e4rchen des Friedrich Merz"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/6515753c48fbef15647d35d4.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der CDU-Chef und politische Migrationskrisen-Mitverursacher Merz hat wieder mal gelogen, wohl um die unteren Bev\u00f6lkerungsschichten gegeneinander aufzubringen. Seine Behauptung, Asylbewerber schnappten Deutschen die Zahnarzttermine weg, h\u00e4lt einer \u00dcberpr\u00fcfung nicht stand.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Susan Bonath<\/em><\/p>\n<p>Noch k\u00fcrzlich betonte CDU-Chef Friedrich Merz, eine Zusammenarbeit mit der AfD sei <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.welt.de\/politik\/deutschland\/article247649376\/CDU-Chef-Merz-nennt-Zusammenarbeit-mit-AfD-unvorstellbar.html\">ausgeschlossen<\/a>.<\/p>\n<p>Durch einen solchen Schritt, so fabulierte er fast religi\u00f6s aufgeladen, w\u00fcrde die CDU &#8220;ihre Seele verkaufen.&#8221; Dahinter steckt wohl politisches Kalk\u00fcl, um die brave konservative W\u00e4hlerschaft nicht zu verschrecken. Denn tats\u00e4chlich unterscheidet die Merz-CDU von der AfD fast nichts.<\/p>\n<p>Der CDU-Chef teilt nicht nur die neoliberalen Ansichten zur Wirtschaftspolitik \u2013 die schon in 16 Regierungsjahren unter Angela Merkel den Kurs der CDU bestimmten, und an denen die Ampel-Regierung nicht ernsthaft r\u00fcttelt \u2013 mit der AfD. Auch in Sachen Migrationskrise verh\u00e4lt er sich genauso, wie es der AfD gern vorgeworfen wird: Sich populistisch als Gerechtigkeitsfan geb\u00e4rdend, griff er \u2013 nicht zum ersten Mal \u2013 in die Trickkiste der Verdrehungen und L\u00fcgen, um die zornige Bev\u00f6lkerung auf seine Seite zu ziehen.<\/p>\n<h4><strong>Asylbewerber bekommen weniger als B\u00fcrgergeld-Bezieher<\/strong><\/h4>\n<p>Laut der Springer-Zeitung <em><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.welt.de\/politik\/deutschland\/article247703198\/Merz-Aussage-ueber-abgelehnte-Asylbewerber-beim-Zahnarzt-ein-Faktencheck.html\">Welt<\/a><\/em>\u00a0forderte er in einem Gespr\u00e4ch mit dem Blatt zun\u00e4chst, der Leistungsbezug f\u00fcr Asylbewerber in Deutschland geh\u00f6re &#8220;auf den Pr\u00fcfstand&#8221;. &#8220;Die B\u00fcrger&#8221;, so Merz, w\u00fcrden angeblich alle &#8220;wahnsinnig, wenn die sehen, dass 300.000 Asylbewerber, die abgelehnt sind, nicht ausreisen, die vollen Leistungen bekommen.&#8221;<\/p>\n<p>Damit implizierte Merz, die Menschen w\u00fcrden f\u00fcrstlich finanziert.\u00a0Dabei sieht die Wahrheit ganz anders aus. Das Budget f\u00fcr Fl\u00fcchtlinge \u2013 sofern sie nicht aus der Ukraine stammen \u2013 liegt weit unter dem der B\u00fcrgergeld-S\u00e4tze.<\/p>\n<p>Viele sitzen \u00fcber Jahre in Mehrbettzimmern in Asylbewerberheimen fest. Als alleinstehender Erwachsener bekommt man dort 369 Euro pro Monat, davon in der Regel nur 164 Euro in bar <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.asyl.net\/view\/leistungssaetze-des-asylbewerberleistungsgesetzes-ab-112023\">ausgezahlt<\/a>.<\/p>\n<p>Zum Vergleich: Ein alleinstehender B\u00fcrgergeld-Bezieher ohne Erwerbseinkommen bekommt aktuell 502 Euro, dazu die Kosten f\u00fcr eine &#8220;angemessene&#8221; Miete erstattet. Doch Fl\u00fcchtling ist nicht gleich Fl\u00fcchtling, das Prinzip &#8220;teilen und herrschen&#8221; ist auch ganz unten Programm. W\u00e4hrend die einen meist jahrelang nicht arbeiten d\u00fcrfen und sich in Massenunterk\u00fcnften von Minis\u00e4tzen \u00fcber Wasser halten m\u00fcssen, d\u00fcrfen ukrainische Kriegsfl\u00fcchtlinge sofort das B\u00fcrgergeld beantragen.<\/p>\n<h4><strong>Gesundheitssystem kaputtgespart durch neoliberale Politik \u00e0 la Merz<\/strong><\/h4>\n<p>Schleierhaft ist, was Friedrich Merz an solchen Hungers\u00e4tzen f\u00fcr nicht privilegierte Asylbewerber noch k\u00fcrzen will, ohne noch mehr Kriminalit\u00e4t zu provozieren. Von irgendwas ern\u00e4hren m\u00fcssen sich die Leute schlie\u00dflich. Doch damit nicht genug: Letztlich griff Merz zu einer bewussten L\u00fcge, mit dem offensichtlichen Ziel, die Bev\u00f6lkerung noch heftiger gegeneinander aufzuwiegeln.<\/p>\n<p>So sagte Merz laut <em>Welt<\/em>:<\/p>\n<blockquote>\n<p><em> &#8220;Die sitzen beim Arzt und lassen sich die Z\u00e4hne neu machen, und die deutschen B\u00fcrger nebendran kriegen keine Termine.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Wahr daran ist nur, dass die medizinische Versorgung in Deutschland f\u00fcr die normalen Lohnarbeiter immer miserabler wird. Kassenpatienten m\u00fcssen oft viele Monate auf einen Facharzttermin warten, etwa bei Augen\u00e4rzten, Neurologen oder Kieferchirurgen.<\/p>\n<p>Die katastrophalen Missst\u00e4nde haben nichts mit irgendwelchen Fl\u00fcchtlingen, aber sehr viel mit der von Merz favorisierten neoliberalen Privatisierungs- und Deregulierungsagenda im Gesundheitswesen der letzten 25 Jahre zu tun. Ein dem Markt unterworfenes Gesundheitssystem muss eben Gewinne erzielen. Da kommt als erster an die Reihe, wer gen\u00fcgend Kaufkraft hat und ein paar Scheine auf den Tisch legt.<\/p>\n<h4><strong>Behandlung f\u00fcr Fl\u00fcchtlinge nur im akuten Notfall<\/strong><\/h4>\n<p>Und wie das immer so bei Propaganda ist, geht es um Emotionen, nicht um Fakten. So auch bei Merz, denn wahr ist vielmehr: Die von ihm erw\u00e4hnten gut 300.000 abgelehnten, aber gro\u00dfteils aus verschiedenen Gr\u00fcnden vor\u00fcbergehend geduldeten Asylbewerber erhalten ausschlie\u00dflich im Notfall medizinische Versorgung, wie ein <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bundesgesundheitsministerium.de\/themen\/internationale-gesundheitspolitik\/migration-und-integration\/fluechtlinge-und-gesundheit\/online-ratgeber-fuer-asylsuchende\/allgemeine-informationen-zur-gkv.html\">Blick<\/a> auf die Seite des Bundesministeriums der Gesundheit (BMG) belegt.<\/p>\n<p>Demnach sind Asylbewerber w\u00e4hrend der gesamten Dauer ihres Asylverfahrens, das oft viele Jahre dauert, nicht krankenversichert. Eine \u00e4rztliche Behandlung bezahlen ihnen die Sozial\u00e4mter ausschlie\u00dflich im akuten Notfall, also wenn sie schwer erkrankt sind, unter Schmerzen leiden oder schwanger sind. Je nach Bundesland m\u00fcssen sie entweder jedes Mal beim Sozialamt daf\u00fcr einen Schein beantragen oder sie bekommen eine elektronische Gesundheitskarte. Erst wenn Fl\u00fcchtlinge und Migranten einen Aufenthaltstitel erhalten haben, d\u00fcrfen sie Mitglied in einer gesetzlichen Krankenkasse werden.<\/p>\n<p>Das gilt auch f\u00fcr einen Besuch beim Zahnarzt. Kronen, Br\u00fccken oder Prothesen geh\u00f6ren nicht zum regul\u00e4ren Leistungsumfang. Nur im Notfall, etwa wenn Betroffene durch Zahnlosigkeit nicht mehr essen k\u00f6nnen, werden Kosten f\u00fcr eine billige Prothese \u00fcbernommen. Ansonsten gilt: Den Zahnarzt aufsuchen d\u00fcrfen Asylbewerber nur bei akuten Schmerzen und Erkrankungen im Mund.<\/p>\n<p>Die Bundeszahn\u00e4rztekammer schreibt dazu in einem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bzaek.de\/recht\/behandlung-von-asylbewerbern-und-asylbewerberinnen.html\">Merkblatt<\/a>,\u00a0<strong><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bzaek.de\/recht\/behandlung-von-asylbewerbern-und-asylbewerberinnen.html\"><\/a><\/strong>dass \u00c4rzte entscheiden m\u00fcssten, welche Behandlungen und Untersuchungen tats\u00e4chlich zwingend notwendig und vom Asylbewerberleistungsgesetz abgedeckt seien. Dabei k\u00f6nne &#8220;der Behandler in einen ethischen Konflikt geraden, wenn m\u00f6gliche zahnerhaltende Ma\u00dfnahmen nicht finanziert werden.&#8221; Denn normalerweise berechtige &#8220;erst der akute Schmerzfall eine Behandlung&#8221;.<\/p>\n<h4><strong>Imperialismus schafft Fl\u00fcchtlingsstr\u00f6me<\/strong><\/h4>\n<p>Diese Feststellungen \u00e4ndern nat\u00fcrlich nichts an der Tatsache, dass Deutschland nicht unbegrenzt Fl\u00fcchtlinge aufnehmen kann, ohne massive soziale Verwerfungen in Kauf zu nehmen. Die Politik schafft es ja nicht einmal, f\u00fcr ausreichend bezahlbaren Wohnraum zu sorgen. Darunter leidet ganz besonders der \u00e4rmere Teil der einheimischen Bev\u00f6lkerung.<\/p>\n<p>Fakt ist aber auch: Solange die NATO-Staaten jenseits und diesseits des Atlantiks mit ihrer imperialistischen und neokolonialistischen Au\u00dfenpolitik die L\u00e4nder des globalen S\u00fcdens weiterhin wirtschaftlich auspl\u00fcndern und allerorts neue Brandherde f\u00fcr Kriege legen, werden die Fl\u00fcchtlingsstr\u00f6me in die EU nicht abrei\u00dfen. Schlie\u00dflich verlassen Menschen nicht ihre Heimat gen Norden, weil das Wetter in Deutschland so toll ist.<\/p>\n<p>Auch die rabiateste Abschottungspolitik wird daran nichts \u00e4ndern, solange USA und EU ihren imperialistischen Krieg mit und ohne Waffengewalt vorantreiben. Langfristig w\u00e4re das Problem nur durch eine Abkehr vom systemischen Wahnsinn zu l\u00f6sen, hin zu einer Kooperation mit den abh\u00e4ngten L\u00e4ndern, in denen Elend, Hunger und hohe Kindersterblichkeit auch im 21. Jahrhundert real sind.<\/p>\n<h4><strong>Die Heuchelei der Migrationskrisen-Verursacher<\/strong><\/h4>\n<p>Doch f\u00fcr eben diese imperialistische Politik stehen nicht nur einzelne Politiker, wie Friedrich Merz, sondern fast alle gr\u00f6\u00dferen Parteien, von der CDU \u00fcber die FDP und die AfD bis hin zu den Gr\u00fcnen und zur SPD. Auch die Partei Die Linke hat ihren einst oppositionellen Kurs dazu weitgehend aufgegeben und agiert nurmehr als zahnloser Tiger mit schwachen Bekenntnissen.<\/p>\n<p>W\u00fcrden die EU-Staaten ernsthaft die Fl\u00fcchtlingsstr\u00f6me bek\u00e4mpfen wollen, m\u00fcssten sie wohl geschlossen aus der NATO austreten, mit Afrika, China, Indien und Russland verhandeln und eigenst\u00e4ndige B\u00fcndnisse zum gegenseitigen Vorteil etablieren, mit dem vorrangigen Ziel gegenseitiger Wirtschaftsf\u00f6rderung.<\/p>\n<p>Das aber w\u00fcrde so gar nicht zum kapitalistischen Hauen und Stechen um Maximalprofit und Marktanteile passen. Einsicht und Umkehr sind nicht in Sicht. Der ehemalige BlackRock-Lobbyist Merz und viele andere Politiker werden sicherlich noch \u00f6fter populistisch l\u00fcgen. Denn solange sich die &#8220;kleinen Leute&#8221; an die sprichw\u00f6rtliche Gurgel gehen, k\u00f6nnen Million\u00e4re wie er sich beruhigt auf ihren Posten zur\u00fccklehnen.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/meinung\/177525-im-westlichen-trend-ampel-regierung\/\">Im westlichen Trend: Ampel-Regierung plant umfangreicheren Sozialabbau als gedacht<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/182105-heucheln-teilen-herrschen-oder-populistischen\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der CDU-Chef und politische Migrationskrisen-Mitverursacher Merz hat wieder mal gelogen, wohl um die unteren Bev\u00f6lkerungsschichten gegeneinander aufzubringen. Seine Behauptung, Asylbewerber schnappten Deutschen die Zahnarzttermine weg, h\u00e4lt einer \u00dcberpr\u00fcfung nicht stand. Von Susan Bonath Noch k\u00fcrzlich betonte CDU-Chef Friedrich Merz, eine Zusammenarbeit mit der AfD sei ausgeschlossen. Durch einen solchen Schritt, so fabulierte er fast religi\u00f6s [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":47238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1696007276"],"wp_automatic_camp":["217"],"3b643ca5700df85dff1bf843b6278efd":["Heucheln, teilen, herrschen \u2013 oder: Die populistischen M\u00e4rchen des Friedrich Merz"],"original_link":["https:\/\/de.rt.com\/meinung\/182105-heucheln-teilen-herrschen-oder-populistischen\/"],"_thumbnail_id":["47238"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-09-29 19:09:01\";}"],"jnews_social_counter_last_update":["1783940195"]},"categories":[19,23],"tags":[583,45,18727,45181,49364,41704,18728,268,49365,21468],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Heucheln, teilen, herrschen \u2013 oder: Die populistischen M\u00e4rchen des Friedrich Merz - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Heucheln, teilen, herrschen \u2013 oder: Die populistischen M\u00e4rchen des Friedrich Merz\" \/>\n<meta property=\"og:description\" content=\"Der CDU-Chef und politische Migrationskrisen-Mitverursacher Merz hat wieder mal gelogen, wohl um die unteren Bev\u00f6lkerungsschichten gegeneinander aufzubringen. Seine Behauptung, Asylbewerber schnappten Deutschen die Zahnarzttermine weg, h\u00e4lt einer \u00dcberpr\u00fcfung nicht stand. Von Susan Bonath Noch k\u00fcrzlich betonte CDU-Chef Friedrich Merz, eine Zusammenarbeit mit der AfD sei ausgeschlossen. Durch einen solchen Schritt, so fabulierte er fast religi\u00f6s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-29T17:04:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Heucheln-teilen-herrschen-\u2013-oder-Die-populistischen-Maerchen-des-Friedrich.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Heucheln, teilen, herrschen \u2013 oder: Die populistischen M\u00e4rchen des Friedrich Merz\",\"datePublished\":\"2023-09-29T17:04:06+00:00\",\"dateModified\":\"2023-09-29T17:04:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/\"},\"wordCount\":1195,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Heucheln-teilen-herrschen-\u2013-oder-Die-populistischen-Maerchen-des-Friedrich.jpg\",\"keywords\":[\"des\",\"die\",\"Friedrich\",\"herrschen\",\"Heucheln\",\"M\u00e4rchen\",\"Merz\",\"oder\",\"populistischen\",\"teilen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/\",\"name\":\"Heucheln, teilen, herrschen \u2013 oder: Die populistischen M\u00e4rchen des Friedrich Merz - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Heucheln-teilen-herrschen-\u2013-oder-Die-populistischen-Maerchen-des-Friedrich.jpg\",\"datePublished\":\"2023-09-29T17:04:06+00:00\",\"dateModified\":\"2023-09-29T17:04:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Heucheln-teilen-herrschen-\u2013-oder-Die-populistischen-Maerchen-des-Friedrich.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Heucheln-teilen-herrschen-\u2013-oder-Die-populistischen-Maerchen-des-Friedrich.jpg\",\"width\":460,\"height\":259,\"caption\":\"Heucheln, teilen, herrschen \u2013 oder: Die populistischen M\u00e4rchen des Friedrich Merz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Heucheln, teilen, herrschen \u2013 oder: Die populistischen M\u00e4rchen des Friedrich Merz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Heucheln, teilen, herrschen \u2013 oder: Die populistischen M\u00e4rchen des Friedrich Merz - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/","og_locale":"de_DE","og_type":"article","og_title":"Heucheln, teilen, herrschen \u2013 oder: Die populistischen M\u00e4rchen des Friedrich Merz","og_description":"Der CDU-Chef und politische Migrationskrisen-Mitverursacher Merz hat wieder mal gelogen, wohl um die unteren Bev\u00f6lkerungsschichten gegeneinander aufzubringen. Seine Behauptung, Asylbewerber schnappten Deutschen die Zahnarzttermine weg, h\u00e4lt einer \u00dcberpr\u00fcfung nicht stand. Von Susan Bonath Noch k\u00fcrzlich betonte CDU-Chef Friedrich Merz, eine Zusammenarbeit mit der AfD sei ausgeschlossen. Durch einen solchen Schritt, so fabulierte er fast religi\u00f6s [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-09-29T17:04:06+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Heucheln-teilen-herrschen-\u2013-oder-Die-populistischen-Maerchen-des-Friedrich.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Heucheln, teilen, herrschen \u2013 oder: Die populistischen M\u00e4rchen des Friedrich Merz","datePublished":"2023-09-29T17:04:06+00:00","dateModified":"2023-09-29T17:04:06+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/"},"wordCount":1195,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Heucheln-teilen-herrschen-\u2013-oder-Die-populistischen-Maerchen-des-Friedrich.jpg","keywords":["des","die","Friedrich","herrschen","Heucheln","M\u00e4rchen","Merz","oder","populistischen","teilen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/","url":"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/","name":"Heucheln, teilen, herrschen \u2013 oder: Die populistischen M\u00e4rchen des Friedrich Merz - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Heucheln-teilen-herrschen-\u2013-oder-Die-populistischen-Maerchen-des-Friedrich.jpg","datePublished":"2023-09-29T17:04:06+00:00","dateModified":"2023-09-29T17:04:06+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Heucheln-teilen-herrschen-\u2013-oder-Die-populistischen-Maerchen-des-Friedrich.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Heucheln-teilen-herrschen-\u2013-oder-Die-populistischen-Maerchen-des-Friedrich.jpg","width":460,"height":259,"caption":"Heucheln, teilen, herrschen \u2013 oder: Die populistischen M\u00e4rchen des Friedrich Merz"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/heucheln-teilen-herrschen-oder-die-populistischen-maerchen-des-friedrich-merz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Heucheln, teilen, herrschen \u2013 oder: Die populistischen M\u00e4rchen des Friedrich Merz"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/47237"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=47237"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/47237\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/47238"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=47237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=47237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=47237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}