{"id":47229,"date":"2023-09-29T16:37:57","date_gmt":"2023-09-29T14:37:57","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/"},"modified":"2023-09-29T16:37:57","modified_gmt":"2023-09-29T14:37:57","slug":"baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/","title":{"rendered":"Baden-W\u00fcrttemberg: AfD bei Umfrage in Westdeutschland erstmals bei 20 Prozent"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/6516ce9d48fbef158d45529e.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die Politik der &#8220;Ampel&#8221; zeigt Wirkung: Erstmals erreichte die AfD in einer Umfrage in einem westdeutschen Bundesland 20 Prozent \u2013 w\u00e4hrend Gr\u00fcne und SPD deutlich Federn lassen mussten. Die Linke tauchte nur noch unter &#8220;Sonstige&#8221; Parteien auf und wurde gar nicht mehr einzeln erfasst.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>In einer aktuellen Umfrage erreicht die AfD erstmals die 20-Prozent-Marke, wie der Merkur am Freitag\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.merkur.de\/politik\/afd-alternative-fuer-deutschland-rechtspopulismus-bundessprecher-90015079.html\">berichtete<\/a>.\u00a0W\u00e4hrend damit jeder f\u00fcnfte Befragte die 2013 gegr\u00fcndete Partei w\u00e4hlen w\u00fcrde, b\u00fc\u00dften die B\u00fcndnis 90\/Die Gr\u00fcnen von Ministerpr\u00e4sident Winfried Kretschmann erneut\u00a0Sympathien\u00a0ein \u2013 und landeten bei 22 Prozent (minus zwei Prozent).<\/p>\n<p>Von den 1162 Befragten antwortete jeder F\u00fcnfte auf die Frage &#8220;Welche Partei w\u00fcrden Sie w\u00e4hlen, wenn am kommenden Sonntag in Baden-W\u00fcrttemberg Landtagswahl w\u00e4re?&#8221; mit &#8220;AfD&#8221;. Damit h\u00e4tte die Partei ihr Ergebnis von der letzten Landtagswahl im M\u00e4rz 2021 mehr als verdoppelt. Unter Spitzenkandidat Bernd G\u00f6gel, der 2022 sein Amt als Fraktionsvorsitzender nach einem Strafbefehl abgab, holte die AfD damals 9,7 Prozent.<\/p>\n<p>Verbessern konnte sich auch die\u00a0CDU auf\u00a029 Prozent (plus drei Prozent zur letzten Umfrage im Juli 2023) sowie die FDP von sieben auf acht Prozent. Federn lassen musste die SPD mit zw\u00f6lf Prozent (minus einem Prozent) w\u00e4hrend DIE LINKE gar nicht mehr einzeln aufgef\u00fchrt wird. Sie ist bei den &#8220;Sonstigen&#8221; Parteien dabei, die zusammen von elf auf neun Prozent in der Umfrage zur\u00fcckfallen.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freeassange.rtde.live\/europa\/181431-deutschlands-911-akt-wirtschaftsterrors-wird\/\">Deutschlands 9\/11: Dieser Akt des Wirtschaftsterrors wird die Zukunft von ganz Europa ver\u00e4ndern<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/182242-baden-wuerttemberg-afd-bei-umfrage\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Politik der &#8220;Ampel&#8221; zeigt Wirkung: Erstmals erreichte die AfD in einer Umfrage in einem westdeutschen Bundesland 20 Prozent \u2013 w\u00e4hrend Gr\u00fcne und SPD deutlich Federn lassen mussten. Die Linke tauchte nur noch unter &#8220;Sonstige&#8221; Parteien auf und wurde gar nicht mehr einzeln erfasst. In einer aktuellen Umfrage erreicht die AfD erstmals die 20-Prozent-Marke, wie [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":47230,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1695998531"],"wp_automatic_camp":["217"],"38f013cee9bed9d90c36051161586446":["Baden-W\u00fcrttemberg: AfD bei Umfrage in Westdeutschland erstmals bei 20 Prozent"],"original_link":["https:\/\/de.rt.com\/inland\/182242-baden-wuerttemberg-afd-bei-umfrage\/"],"_thumbnail_id":["47230"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-09-29 16:43:16\";}"],"jnews_social_counter_last_update":["1784125904"]},"categories":[19,23],"tags":[3815,25665,363,7182,1429,1428,19798],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Baden-W\u00fcrttemberg: AfD bei Umfrage in Westdeutschland erstmals bei 20 Prozent - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baden-W\u00fcrttemberg: AfD bei Umfrage in Westdeutschland erstmals bei 20 Prozent\" \/>\n<meta property=\"og:description\" content=\"Die Politik der &#8220;Ampel&#8221; zeigt Wirkung: Erstmals erreichte die AfD in einer Umfrage in einem westdeutschen Bundesland 20 Prozent \u2013 w\u00e4hrend Gr\u00fcne und SPD deutlich Federn lassen mussten. Die Linke tauchte nur noch unter &#8220;Sonstige&#8221; Parteien auf und wurde gar nicht mehr einzeln erfasst. In einer aktuellen Umfrage erreicht die AfD erstmals die 20-Prozent-Marke, wie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-29T14:37:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Baden-Wuerttemberg-AfD-bei-Umfrage-in-Westdeutschland-erstmals-bei-20-Prozent.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Baden-W\u00fcrttemberg: AfD bei Umfrage in Westdeutschland erstmals bei 20 Prozent\",\"datePublished\":\"2023-09-29T14:37:57+00:00\",\"dateModified\":\"2023-09-29T14:37:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/\"},\"wordCount\":258,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Baden-Wuerttemberg-AfD-bei-Umfrage-in-Westdeutschland-erstmals-bei-20-Prozent.jpg\",\"keywords\":[\"AfD\",\"BadenW\u00fcrttemberg\",\"bei\",\"Erstmals\",\"Prozent\",\"Umfrage\",\"Westdeutschland\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/\",\"name\":\"Baden-W\u00fcrttemberg: AfD bei Umfrage in Westdeutschland erstmals bei 20 Prozent - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Baden-Wuerttemberg-AfD-bei-Umfrage-in-Westdeutschland-erstmals-bei-20-Prozent.jpg\",\"datePublished\":\"2023-09-29T14:37:57+00:00\",\"dateModified\":\"2023-09-29T14:37:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Baden-Wuerttemberg-AfD-bei-Umfrage-in-Westdeutschland-erstmals-bei-20-Prozent.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Baden-Wuerttemberg-AfD-bei-Umfrage-in-Westdeutschland-erstmals-bei-20-Prozent.jpg\",\"width\":460,\"height\":259,\"caption\":\"Baden-W\u00fcrttemberg: AfD bei Umfrage in Westdeutschland erstmals bei 20 Prozent\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baden-W\u00fcrttemberg: AfD bei Umfrage in Westdeutschland erstmals bei 20 Prozent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Baden-W\u00fcrttemberg: AfD bei Umfrage in Westdeutschland erstmals bei 20 Prozent - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/","og_locale":"de_DE","og_type":"article","og_title":"Baden-W\u00fcrttemberg: AfD bei Umfrage in Westdeutschland erstmals bei 20 Prozent","og_description":"Die Politik der &#8220;Ampel&#8221; zeigt Wirkung: Erstmals erreichte die AfD in einer Umfrage in einem westdeutschen Bundesland 20 Prozent \u2013 w\u00e4hrend Gr\u00fcne und SPD deutlich Federn lassen mussten. Die Linke tauchte nur noch unter &#8220;Sonstige&#8221; Parteien auf und wurde gar nicht mehr einzeln erfasst. In einer aktuellen Umfrage erreicht die AfD erstmals die 20-Prozent-Marke, wie [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-09-29T14:37:57+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Baden-Wuerttemberg-AfD-bei-Umfrage-in-Westdeutschland-erstmals-bei-20-Prozent.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Baden-W\u00fcrttemberg: AfD bei Umfrage in Westdeutschland erstmals bei 20 Prozent","datePublished":"2023-09-29T14:37:57+00:00","dateModified":"2023-09-29T14:37:57+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/"},"wordCount":258,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Baden-Wuerttemberg-AfD-bei-Umfrage-in-Westdeutschland-erstmals-bei-20-Prozent.jpg","keywords":["AfD","BadenW\u00fcrttemberg","bei","Erstmals","Prozent","Umfrage","Westdeutschland"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/","url":"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/","name":"Baden-W\u00fcrttemberg: AfD bei Umfrage in Westdeutschland erstmals bei 20 Prozent - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Baden-Wuerttemberg-AfD-bei-Umfrage-in-Westdeutschland-erstmals-bei-20-Prozent.jpg","datePublished":"2023-09-29T14:37:57+00:00","dateModified":"2023-09-29T14:37:57+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Baden-Wuerttemberg-AfD-bei-Umfrage-in-Westdeutschland-erstmals-bei-20-Prozent.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Baden-Wuerttemberg-AfD-bei-Umfrage-in-Westdeutschland-erstmals-bei-20-Prozent.jpg","width":460,"height":259,"caption":"Baden-W\u00fcrttemberg: AfD bei Umfrage in Westdeutschland erstmals bei 20 Prozent"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/baden-wuerttemberg-afd-bei-umfrage-in-westdeutschland-erstmals-bei-20-prozent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Baden-W\u00fcrttemberg: AfD bei Umfrage in Westdeutschland erstmals bei 20 Prozent"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/47229"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=47229"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/47229\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/47230"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=47229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=47229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=47229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}