{"id":47160,"date":"2023-09-28T14:18:56","date_gmt":"2023-09-28T12:18:56","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/"},"modified":"2023-09-28T14:18:56","modified_gmt":"2023-09-28T12:18:56","slug":"taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/","title":{"rendered":"Taiwan pr\u00e4sentiert erstes U-Boot aus heimischer Produktion"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/651563b348fbef156d799c4a.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Taipei hat den Bau des ersten U-Boots aus heimischer Produktion abgeschlossen. Wie die Pr\u00e4sidentin Tsai Ing-wen am Donnerstag erkl\u00e4rte, muss das Kriegsschiff nun getestet werden. Angesichts der Spannungen im Pazifik will die Inselrepublik ihr Milit\u00e4r verst\u00e4rken.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Am Donnerstag hat Taiwan die Fertigstellung des ersten U-Boots aus heimischer Produktion bekanntgegeben. Bei einer feierlichen Veranstaltung im Hafen der Stadt Kaohsiung k\u00fcndigte die Staatspr\u00e4sidentin Tsai Ing-wen den Start des Testbetriebs an. Laut <em>Associated Press<\/em>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/apnews.com\/article\/taiwan-domestic-submarine-tests-cd69c0be2dfc0acac949ee797130558e\">betonte<\/a> sie, dass ein taiwanesisches U-Boot bisher als etwas Unm\u00f6gliches angesehen worden sei. Trotzdem sei nun ein solches Schiff von einheimischen Fachleuten hergestellt worden. Der Bau des U-Boots sei Tsai zufolge im Rahmen des Ausbaus asymmetrischer Kriegskapazit\u00e4ten erfolgt. Die\u00a0<em>AP<\/em>\u00a0zitiert die Pr\u00e4sidentin wie folgt:<\/p>\n<blockquote>\n<p><em>&#8220;Der Bau eines U-Boots ist die konkrete Umsetzung unserer Entschlossenheit, unser Land zu sch\u00fctzen. U-Boote sind ein wichtiger Ausr\u00fcstungsgegenstand f\u00fcr die taiwanesische Marine, um asymmetrische Kampfkapazit\u00e4ten in Bezug auf Strategie und Taktik zu entwickeln.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Cheng Wen-lon, der Chef des Unternehmens CSBC, welches das Unterwasserfahrzeug produziert hat, bezeichnete den Bauprozess als &#8220;qualvoll&#8221;. Planung und Herstellung h\u00e4tten ihm zufolge sieben Jahre gedauert. Auch wenn das CSBC in den vergangenen Jahren ohne viel Aufhebens gearbeitet habe, sei die Schaffung des U-Bootes keineswegs reibungslos verlaufen.<\/p>\n<p>Unterdessen berichtet <em>AP<\/em>, dass das Kriegsschiff sowohl im Hafen als auch auf hoher See mehreren Testes unterzogen werde. Erst danach werde es in Dienst gestellt. Das Unterseeboot geh\u00f6rt der Hai-Kun-Klasse an, benannt nach dem Fisch Kun aus der chinesischen Mythologie, der von enormen Proportionen gepr\u00e4gt ist.<\/p>\n<p>Taiwan begann mit dem Bau eigener U-Boote, nachdem Peking durch Androhung wirtschaftlicher und diplomatischer Sanktionen Taipeis Bem\u00fchungen gehemmt hatte, Schiffe aus dem Ausland zu beschaffen.\u00a0Am Donnerstag erkl\u00e4rte Chinas Verteidigungsministerium, dass Taiwan mit dem U-Boot-Bau den Weg zu seiner eigenen Vernichtung beschritten habe.\u00a0Dar\u00fcber hinaus betonte der Pressesprecher des Ministeriums in Peking, dass keine Waffen, die Taiwan kaufe oder produziere, die Wiedervereinigung der Insel mit dem chinesischen Festland verhindern w\u00fcrden.<\/p>\n<p><strong>Mehr zum Thema\u00a0\u2013\u00a0<\/strong><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/asien\/180850-wirtschaftliche-integration-erster-schritt-fuer\/\">Wirtschaftliche Integration: Erster Schritt f\u00fcr chinesische Wiedervereinigung?<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/asien\/182089-taiwan-schliesst-bau\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Taipei hat den Bau des ersten U-Boots aus heimischer Produktion abgeschlossen. Wie die Pr\u00e4sidentin Tsai Ing-wen am Donnerstag erkl\u00e4rte, muss das Kriegsschiff nun getestet werden. Angesichts der Spannungen im Pazifik will die Inselrepublik ihr Milit\u00e4r verst\u00e4rken. Am Donnerstag hat Taiwan die Fertigstellung des ersten U-Boots aus heimischer Produktion bekanntgegeben. Bei einer feierlichen Veranstaltung im Hafen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":47161,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1695904958"],"wp_automatic_camp":["217"],"2de26868cfc5f021bc05f13cd42968b3":["Taiwan pr\u00e4sentiert erstes U-Boot aus heimischer Produktion"],"original_link":["https:\/\/de.rt.com\/asien\/182089-taiwan-schliesst-bau\/"],"_thumbnail_id":["47161"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-09-28 14:43:39\";}"],"jnews_social_counter_last_update":["1778691214"]},"categories":[19,23],"tags":[679,21061,45689,9199,3315,1043,27452],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Taiwan pr\u00e4sentiert erstes U-Boot aus heimischer Produktion - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taiwan pr\u00e4sentiert erstes U-Boot aus heimischer Produktion\" \/>\n<meta property=\"og:description\" content=\"Taipei hat den Bau des ersten U-Boots aus heimischer Produktion abgeschlossen. Wie die Pr\u00e4sidentin Tsai Ing-wen am Donnerstag erkl\u00e4rte, muss das Kriegsschiff nun getestet werden. Angesichts der Spannungen im Pazifik will die Inselrepublik ihr Milit\u00e4r verst\u00e4rken. Am Donnerstag hat Taiwan die Fertigstellung des ersten U-Boots aus heimischer Produktion bekanntgegeben. Bei einer feierlichen Veranstaltung im Hafen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-28T12:18:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Taiwan-praesentiert-erstes-U-Boot-aus-heimischer-Produktion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Taiwan pr\u00e4sentiert erstes U-Boot aus heimischer Produktion\",\"datePublished\":\"2023-09-28T12:18:56+00:00\",\"dateModified\":\"2023-09-28T12:18:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/\"},\"wordCount\":355,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Taiwan-praesentiert-erstes-U-Boot-aus-heimischer-Produktion.jpg\",\"keywords\":[\"aus\",\"Erstes\",\"heimischer\",\"pr\u00e4sentiert\",\"Produktion\",\"Taiwan\",\"UBoot\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/\",\"name\":\"Taiwan pr\u00e4sentiert erstes U-Boot aus heimischer Produktion - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Taiwan-praesentiert-erstes-U-Boot-aus-heimischer-Produktion.jpg\",\"datePublished\":\"2023-09-28T12:18:56+00:00\",\"dateModified\":\"2023-09-28T12:18:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Taiwan-praesentiert-erstes-U-Boot-aus-heimischer-Produktion.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Taiwan-praesentiert-erstes-U-Boot-aus-heimischer-Produktion.jpg\",\"width\":460,\"height\":259,\"caption\":\"Taiwan pr\u00e4sentiert erstes U-Boot aus heimischer Produktion\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taiwan pr\u00e4sentiert erstes U-Boot aus heimischer Produktion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Taiwan pr\u00e4sentiert erstes U-Boot aus heimischer Produktion - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/","og_locale":"de_DE","og_type":"article","og_title":"Taiwan pr\u00e4sentiert erstes U-Boot aus heimischer Produktion","og_description":"Taipei hat den Bau des ersten U-Boots aus heimischer Produktion abgeschlossen. Wie die Pr\u00e4sidentin Tsai Ing-wen am Donnerstag erkl\u00e4rte, muss das Kriegsschiff nun getestet werden. Angesichts der Spannungen im Pazifik will die Inselrepublik ihr Milit\u00e4r verst\u00e4rken. Am Donnerstag hat Taiwan die Fertigstellung des ersten U-Boots aus heimischer Produktion bekanntgegeben. Bei einer feierlichen Veranstaltung im Hafen [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-09-28T12:18:56+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Taiwan-praesentiert-erstes-U-Boot-aus-heimischer-Produktion.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Taiwan pr\u00e4sentiert erstes U-Boot aus heimischer Produktion","datePublished":"2023-09-28T12:18:56+00:00","dateModified":"2023-09-28T12:18:56+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/"},"wordCount":355,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Taiwan-praesentiert-erstes-U-Boot-aus-heimischer-Produktion.jpg","keywords":["aus","Erstes","heimischer","pr\u00e4sentiert","Produktion","Taiwan","UBoot"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/","url":"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/","name":"Taiwan pr\u00e4sentiert erstes U-Boot aus heimischer Produktion - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Taiwan-praesentiert-erstes-U-Boot-aus-heimischer-Produktion.jpg","datePublished":"2023-09-28T12:18:56+00:00","dateModified":"2023-09-28T12:18:56+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Taiwan-praesentiert-erstes-U-Boot-aus-heimischer-Produktion.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Taiwan-praesentiert-erstes-U-Boot-aus-heimischer-Produktion.jpg","width":460,"height":259,"caption":"Taiwan pr\u00e4sentiert erstes U-Boot aus heimischer Produktion"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/taiwan-praesentiert-erstes-u-boot-aus-heimischer-produktion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Taiwan pr\u00e4sentiert erstes U-Boot aus heimischer Produktion"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/47160"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=47160"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/47160\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/47161"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=47160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=47160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=47160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}