{"id":46415,"date":"2023-09-15T15:05:37","date_gmt":"2023-09-15T13:05:37","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/"},"modified":"2023-09-15T15:05:37","modified_gmt":"2023-09-15T13:05:37","slug":"finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/","title":{"rendered":"Finnland k\u00fcndigt Verbot f\u00fcr Autos mit russischen Kennzeichen an"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/65044e7b48fbef4d4529611b.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Finnland ist das vierte Land, das eine Landesgrenze mit Russland hat und beschlossen hat, Autos mit russischen Nummernschildern zu verbieten. Zuvor hatten bereits Estland, Lettland und Litauen eine solche Ma\u00dfnahme ergriffen. Jetzt hat nur Polen kein solches Verbot.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Wie das finnische Au\u00dfenministerium mitteilte, haben die finnischen Beh\u00f6rden\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/um.fi\/ajankohtaista\/-\/asset_publisher\/gc654PySnjTX\/content\/rajoituksia-venajalle-rekisteroityjen-autojen-tuontiin\/35732\">angek\u00fcndigt<\/a>, ab Mitternacht des 16. September ein Einreiseverbot f\u00fcr Autos mit russischen Kennzeichen zu verh\u00e4ngen.<\/p>\n<p>Nach Angaben des Ministeriums k\u00f6nnen nur EU-B\u00fcrger mit st\u00e4ndigem Wohnsitz in Russland oder deren Familienangeh\u00f6rige sowie Diplomaten mit einem in Russland zugelassenen Auto einreisen. Dar\u00fcber hinaus gilt die Beschr\u00e4nkung nicht f\u00fcr F\u00e4lle, in denen die Einreise aus humanit\u00e4ren Gr\u00fcnden erforderlich ist.<\/p>\n<p>Elina Valtonen, Leiterin des finnischen Au\u00dfenministeriums, wies darauf hin, dass die Beschlagnahmung von Autos nicht infrage kommt, sondern nur im Falle einer strafrechtlichen Untersuchung m\u00f6glich ist, berichtet\u00a0<em>Yle<\/em>. F\u00fcr die Entfernung von Autos mit russischen Kennzeichen aus dem Land sind sechs Monate vorgesehen \u2013 die Frist l\u00e4uft am 16. M\u00e4rz 2024 ab.<\/p>\n<p>Die russische Botschaft in Finnland hatte zuvor den B\u00fcrgern empfohlen, nicht mit Autos mit russischen Kennzeichen in das Nachbarland zu reisen.<\/p>\n<p>Neben Finnland haben auch Estland, Lettland und Litauen, die Landesgrenzen zu Russland haben, sowie Deutschland bereits Einreiseverbote erlassen. In Estland sind nur Busse und Motorr\u00e4der zugelassen. Lettland hat eine Ausnahme f\u00fcr Fahrzeuge von Unternehmen gemacht, die G\u00fcter im Transit durch das EU-Gebiet zwischen dem Kaliningrader Gebiet und Russland transportieren. Litauen hat ebenfalls eine Ausnahme f\u00fcr Privatfahrzeuge gemacht, die von Russland nach Kaliningrad und umgekehrt fahren. Alle L\u00e4nder warnten vor der drohenden Beschlagnahmung von Fahrzeugen.<\/p>\n<p>Die Frage des Einreiseverbots wurde aufgeworfen, nachdem die Europ\u00e4ische Kommission am 8. September klargestellt hatte, dass die Einreise in EU-L\u00e4nder mit in Russland zugelassenen Personenkraftwagen als verbotene Einfuhr gilt, selbst wenn die Fahrzeuge f\u00fcr private Zwecke genutzt werden. Die Europ\u00e4ische Kommission betonte, dass jeder Mitgliedsstaat das Recht hat, selbst zu entscheiden, ob er ein Verbot einf\u00fchren will, die Klarstellungen haben empfehlenden Charakter. Gleichzeitig hat Deutschland diese Beschr\u00e4nkungen bereits in der Vergangenheit befolgt.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/170341-estland-verweigert-immobilienbesitzern-aus-russland\/\">Estland verweigert Immobilienbesitzern aus Russland Einreise<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/180877-finnland-kuendigt-verbot-fuer-autos\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finnland ist das vierte Land, das eine Landesgrenze mit Russland hat und beschlossen hat, Autos mit russischen Nummernschildern zu verbieten. Zuvor hatten bereits Estland, Lettland und Litauen eine solche Ma\u00dfnahme ergriffen. Jetzt hat nur Polen kein solches Verbot. Wie das finnische Au\u00dfenministerium mitteilte, haben die finnischen Beh\u00f6rden\u00a0angek\u00fcndigt, ab Mitternacht des 16. September ein Einreiseverbot f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":46416,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1694783432"],"wp_automatic_camp":["217"],"ca273e4a5aa83089592b4e433c4f0541":["Finnland k\u00fcndigt Verbot f\u00fcr Autos mit russischen Kennzeichen an"],"original_link":["https:\/\/de.rt.com\/international\/180877-finnland-kuendigt-verbot-fuer-autos\/"],"_thumbnail_id":["46416"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-09-15 15:12:38\";}"],"jnews_social_counter_last_update":["1788351731"]},"categories":[19,23],"tags":[4031,1906,221,44943,4224,419,973,3817],"class_list":["post-46415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-autos","tag-finnland","tag-fuer","tag-kennzeichen","tag-kuendigt","tag-mit","tag-russischen","tag-verbot"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Finnland k\u00fcndigt Verbot f\u00fcr Autos mit russischen Kennzeichen an - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finnland k\u00fcndigt Verbot f\u00fcr Autos mit russischen Kennzeichen an\" \/>\n<meta property=\"og:description\" content=\"Finnland ist das vierte Land, das eine Landesgrenze mit Russland hat und beschlossen hat, Autos mit russischen Nummernschildern zu verbieten. Zuvor hatten bereits Estland, Lettland und Litauen eine solche Ma\u00dfnahme ergriffen. Jetzt hat nur Polen kein solches Verbot. Wie das finnische Au\u00dfenministerium mitteilte, haben die finnischen Beh\u00f6rden\u00a0angek\u00fcndigt, ab Mitternacht des 16. September ein Einreiseverbot f\u00fcr [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-15T13:05:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Finnland-kuendigt-Verbot-fuer-Autos-mit-russischen-Kennzeichen-an.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Finnland k\u00fcndigt Verbot f\u00fcr Autos mit russischen Kennzeichen an\",\"datePublished\":\"2023-09-15T13:05:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\\\/\"},\"wordCount\":374,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/09\\\/Finnland-kuendigt-Verbot-fuer-Autos-mit-russischen-Kennzeichen-an.jpg\",\"keywords\":[\"Autos\",\"Finnland\",\"f\u00fcr\",\"Kennzeichen\",\"k\u00fcndigt\",\"mit\",\"russischen\",\"Verbot\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\\\/\",\"name\":\"Finnland k\u00fcndigt Verbot f\u00fcr Autos mit russischen Kennzeichen an - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/09\\\/Finnland-kuendigt-Verbot-fuer-Autos-mit-russischen-Kennzeichen-an.jpg\",\"datePublished\":\"2023-09-15T13:05:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/09\\\/Finnland-kuendigt-Verbot-fuer-Autos-mit-russischen-Kennzeichen-an.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2023\\\/09\\\/Finnland-kuendigt-Verbot-fuer-Autos-mit-russischen-Kennzeichen-an.jpg\",\"width\":460,\"height\":259,\"caption\":\"Finnland k\u00fcndigt Verbot f\u00fcr Autos mit russischen Kennzeichen an\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finnland k\u00fcndigt Verbot f\u00fcr Autos mit russischen Kennzeichen an\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Finnland k\u00fcndigt Verbot f\u00fcr Autos mit russischen Kennzeichen an - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/","og_locale":"de_DE","og_type":"article","og_title":"Finnland k\u00fcndigt Verbot f\u00fcr Autos mit russischen Kennzeichen an","og_description":"Finnland ist das vierte Land, das eine Landesgrenze mit Russland hat und beschlossen hat, Autos mit russischen Nummernschildern zu verbieten. Zuvor hatten bereits Estland, Lettland und Litauen eine solche Ma\u00dfnahme ergriffen. Jetzt hat nur Polen kein solches Verbot. Wie das finnische Au\u00dfenministerium mitteilte, haben die finnischen Beh\u00f6rden\u00a0angek\u00fcndigt, ab Mitternacht des 16. September ein Einreiseverbot f\u00fcr [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-09-15T13:05:37+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Finnland-kuendigt-Verbot-fuer-Autos-mit-russischen-Kennzeichen-an.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Finnland k\u00fcndigt Verbot f\u00fcr Autos mit russischen Kennzeichen an","datePublished":"2023-09-15T13:05:37+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/"},"wordCount":374,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Finnland-kuendigt-Verbot-fuer-Autos-mit-russischen-Kennzeichen-an.jpg","keywords":["Autos","Finnland","f\u00fcr","Kennzeichen","k\u00fcndigt","mit","russischen","Verbot"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/","url":"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/","name":"Finnland k\u00fcndigt Verbot f\u00fcr Autos mit russischen Kennzeichen an - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Finnland-kuendigt-Verbot-fuer-Autos-mit-russischen-Kennzeichen-an.jpg","datePublished":"2023-09-15T13:05:37+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Finnland-kuendigt-Verbot-fuer-Autos-mit-russischen-Kennzeichen-an.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Finnland-kuendigt-Verbot-fuer-Autos-mit-russischen-Kennzeichen-an.jpg","width":460,"height":259,"caption":"Finnland k\u00fcndigt Verbot f\u00fcr Autos mit russischen Kennzeichen an"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/finnland-kuendigt-verbot-fuer-autos-mit-russischen-kennzeichen-an\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Finnland k\u00fcndigt Verbot f\u00fcr Autos mit russischen Kennzeichen an"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/46415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=46415"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/46415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/46416"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=46415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=46415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=46415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}