{"id":45985,"date":"2023-09-08T16:24:45","date_gmt":"2023-09-08T14:24:45","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/"},"modified":"2023-09-08T16:24:45","modified_gmt":"2023-09-08T14:24:45","slug":"elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/","title":{"rendered":"Elon Musk korrigiert Darstellung zur angeblichen Sabotage eines ukrainischen Angriffs"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/64fb1ac4b480cc27cd0735fd.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Im Prinzip l\u00e4uft es zwar auf dasselbe hinaus: Elon Musk hat die Darstellung des Autors seiner Biografie bestritten, er habe sein Unternehmen SpaceX angewiesen, dem ukrainischen Milit\u00e4r den Zugang zur Starlink-Satellitenkommunikation zu kappen. Es wurde aber nichts abgeschaltet, schrieb Musk, er habe es &#8220;nur&#8221; abgelehnt, die Verbindung einzuschalten.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Elon Musk hat der Schilderung eines renommierten Journalisten widersprochen, das Unternehmen SpaceX habe 2022 auf Weisung von Musk\u00a0den Zugang des ukrainischen Milit\u00e4rs zur Starlink-Satellitenkommunikation nahe der Krim gekappt, um einen Angriff auf die russische Marine zu verhindern.\u00a0<\/p>\n<p>In seiner Antwort auf der Plattform X, dem Twitter-Nachfolger, am Donnerstag (Ortszeit US-Zeitzone) stellt der Multimilliard\u00e4r und Eigent\u00fcmer von Starlink die Abl\u00e4ufe anders dar.\u00a0Demnach war das Starlink-System in diesem Gebiet ohnehin niemals verf\u00fcgbar. Musks Richtigstellung lautet w\u00f6rtlich:\u00a0<\/p>\n<blockquote>\n<p><em>&#8220;Die fraglichen Starlink-Regionen wurden nicht aktiviert. SpaceX hat nichts abgeschaltet.&#8221;<\/em><\/p>\n<\/blockquote>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">The Starlink regions in question were not activated. SpaceX did not deactivate anything.<\/p>\n<p>\u2014 Elon Musk (@elonmusk) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/elonmusk\/status\/1699913329261813809?ref_src=twsrc%5Etfw\">September 7, 2023<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Musk r\u00e4umte jedoch ein, dass es durchaus eine Anfrage der Ukraine gegeben hatte, die Kommunikation bis nach Sewastopol zu aktivieren, was er jedoch abgelehnt h\u00e4tte:<\/p>\n<blockquote>\n<p><em>&#8220;Es gab eine dringende Anfrage der Regierungsbeh\u00f6rden, Starlink bis nach Sewastopol zu aktivieren. Die offensichtliche Absicht war, den gr\u00f6\u00dften Teil der russischen Flotte vor Anker zu versenken. H\u00e4tte ich diesem Ersuchen zugestimmt, w\u00e4re SpaceX ausdr\u00fccklich an einer gr\u00f6\u00dferen Kriegshandlung und Konflikteskalation beteiligt gewesen.&#8221;<\/em><\/p>\n<\/blockquote>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\" data-conversation=\"none\">\n<p lang=\"en\" dir=\"ltr\">There was an emergency request from government authorities to activate Starlink all the way to Sevastopol.The obvious intent being to sink most of the Russian fleet at anchor.If I had agreed to their request, then SpaceX would be explicitly complicit in a major act of war and\u2026<\/p>\n<p>\u2014 Elon Musk (@elonmusk) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/elonmusk\/status\/1699917639043404146?ref_src=twsrc%5Etfw\">September 7, 2023<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Wie bereits fr\u00fcher hier <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/180094-musk-verwehrt-ukrainischen-streitkraeften-zugang\/\">berichtet<\/a>, hatte\u00a0Walter Isaacson in einer jetzt ver\u00f6ffentlichten Biografie von Elon Musk behauptet, der US-Milliard\u00e4r habe\u00a0den Zugang des ukrainischen Milit\u00e4rs auf die Starlink-Satellitenkommunikation nahe der Krim gekappt und damit einen Angriff der Ukraine faktisch sabotiert.\u00a0In einem Gespr\u00e4ch mit Isaacson habe Musk betont, dass &#8220;Starlink nicht dazu gedacht war, in Kriege verwickelt zu werden&#8221;.<\/p>\n<p>Musk startete die ersten Starlink-Satelliten im Jahr 2019 mit SpaceX-Raketen. Inzwischen sind mehr als 5.000 dieser Starlink-Satelliten auf erdnahen Umlaufbahnen in bis zu etwa 550 Kilometern H\u00f6he \u00fcber der Erdoberfl\u00e4che in Betrieb. Dies ist etwa die H\u00e4lfte aller aktiven Satelliten weltweit, w\u00e4hrend sich andere Satelliten teils darunter, teils in gr\u00f6\u00dferer H\u00f6he um die Erde bewegen. Die Starlink-Satelliten sind f\u00fcr eine Betriebsdauer von etwa dreieinhalb Jahren ausgelegt. Auf der Erde wird die bidirektionale Verbindung mit einem Terminal hergestellt, das zugleich mit einem Router ausgestattet ist.<\/p>\n<p>Dank Starlink ist das Internet nicht nur bei Naturkatastrophen und in abgelegenen Gebieten, sondern nun theoretisch auch in Kriegsgebieten verf\u00fcgbar. Die verf\u00fcgbare Geschwindigkeit der Daten\u00fcbertragung erreicht 100 Mbit\/s, was beispielsweise selbst f\u00fcr Online-Spiele und Videotelefonate ausreicht.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/180094-musk-verwehrt-ukrainischen-streitkraeften-zugang\/\">Musk verwehrte ukrainischen Streitkr\u00e4ften Zugang zu Starlink \u2013 und vereitelte Angriff auf Krim<\/a><\/p>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/180163-elon-musk-korrigiert-darstellung-zu-starlink-abschaltung\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Prinzip l\u00e4uft es zwar auf dasselbe hinaus: Elon Musk hat die Darstellung des Autors seiner Biografie bestritten, er habe sein Unternehmen SpaceX angewiesen, dem ukrainischen Milit\u00e4r den Zugang zur Starlink-Satellitenkommunikation zu kappen. Es wurde aber nichts abgeschaltet, schrieb Musk, er habe es &#8220;nur&#8221; abgelehnt, die Verbindung einzuschalten. Elon Musk hat der Schilderung eines renommierten [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":45986,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1694185801"],"wp_automatic_camp":["217"],"1d86fc3bd84da21eee5a7e516adedd45":["Elon Musk korrigiert Darstellung zur angeblichen Sabotage eines ukrainischen Angriffs"],"original_link":["https:\/\/de.rt.com\/international\/180163-elon-musk-korrigiert-darstellung-zu-starlink-abschaltung\/"],"_thumbnail_id":["45986"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-09-08 17:11:05\";}"],"jnews_social_counter_last_update":["1784123086"]},"categories":[19,23],"tags":[16552,21409,25827,2111,2056,24606,1582,30977,2332,581],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elon Musk korrigiert Darstellung zur angeblichen Sabotage eines ukrainischen Angriffs - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elon Musk korrigiert Darstellung zur angeblichen Sabotage eines ukrainischen Angriffs\" \/>\n<meta property=\"og:description\" content=\"Im Prinzip l\u00e4uft es zwar auf dasselbe hinaus: Elon Musk hat die Darstellung des Autors seiner Biografie bestritten, er habe sein Unternehmen SpaceX angewiesen, dem ukrainischen Milit\u00e4r den Zugang zur Starlink-Satellitenkommunikation zu kappen. Es wurde aber nichts abgeschaltet, schrieb Musk, er habe es &#8220;nur&#8221; abgelehnt, die Verbindung einzuschalten. Elon Musk hat der Schilderung eines renommierten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-08T14:24:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Elon-Musk-korrigiert-Darstellung-zur-angeblichen-Sabotage-eines-ukrainischen-Angriffs.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Elon Musk korrigiert Darstellung zur angeblichen Sabotage eines ukrainischen Angriffs\",\"datePublished\":\"2023-09-08T14:24:45+00:00\",\"dateModified\":\"2023-09-08T14:24:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/\"},\"wordCount\":509,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Elon-Musk-korrigiert-Darstellung-zur-angeblichen-Sabotage-eines-ukrainischen-Angriffs.jpg\",\"keywords\":[\"angeblichen\",\"Angriffs\",\"Darstellung\",\"eines\",\"ELON\",\"korrigiert\",\"Musk\",\"Sabotage\",\"ukrainischen\",\"zur\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/\",\"name\":\"Elon Musk korrigiert Darstellung zur angeblichen Sabotage eines ukrainischen Angriffs - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Elon-Musk-korrigiert-Darstellung-zur-angeblichen-Sabotage-eines-ukrainischen-Angriffs.jpg\",\"datePublished\":\"2023-09-08T14:24:45+00:00\",\"dateModified\":\"2023-09-08T14:24:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Elon-Musk-korrigiert-Darstellung-zur-angeblichen-Sabotage-eines-ukrainischen-Angriffs.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Elon-Musk-korrigiert-Darstellung-zur-angeblichen-Sabotage-eines-ukrainischen-Angriffs.jpg\",\"width\":460,\"height\":259,\"caption\":\"Elon Musk korrigiert Darstellung zur angeblichen Sabotage eines ukrainischen Angriffs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elon Musk korrigiert Darstellung zur angeblichen Sabotage eines ukrainischen Angriffs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Elon Musk korrigiert Darstellung zur angeblichen Sabotage eines ukrainischen Angriffs - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/","og_locale":"de_DE","og_type":"article","og_title":"Elon Musk korrigiert Darstellung zur angeblichen Sabotage eines ukrainischen Angriffs","og_description":"Im Prinzip l\u00e4uft es zwar auf dasselbe hinaus: Elon Musk hat die Darstellung des Autors seiner Biografie bestritten, er habe sein Unternehmen SpaceX angewiesen, dem ukrainischen Milit\u00e4r den Zugang zur Starlink-Satellitenkommunikation zu kappen. Es wurde aber nichts abgeschaltet, schrieb Musk, er habe es &#8220;nur&#8221; abgelehnt, die Verbindung einzuschalten. Elon Musk hat der Schilderung eines renommierten [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-09-08T14:24:45+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Elon-Musk-korrigiert-Darstellung-zur-angeblichen-Sabotage-eines-ukrainischen-Angriffs.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Elon Musk korrigiert Darstellung zur angeblichen Sabotage eines ukrainischen Angriffs","datePublished":"2023-09-08T14:24:45+00:00","dateModified":"2023-09-08T14:24:45+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/"},"wordCount":509,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Elon-Musk-korrigiert-Darstellung-zur-angeblichen-Sabotage-eines-ukrainischen-Angriffs.jpg","keywords":["angeblichen","Angriffs","Darstellung","eines","ELON","korrigiert","Musk","Sabotage","ukrainischen","zur"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/","url":"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/","name":"Elon Musk korrigiert Darstellung zur angeblichen Sabotage eines ukrainischen Angriffs - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Elon-Musk-korrigiert-Darstellung-zur-angeblichen-Sabotage-eines-ukrainischen-Angriffs.jpg","datePublished":"2023-09-08T14:24:45+00:00","dateModified":"2023-09-08T14:24:45+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Elon-Musk-korrigiert-Darstellung-zur-angeblichen-Sabotage-eines-ukrainischen-Angriffs.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Elon-Musk-korrigiert-Darstellung-zur-angeblichen-Sabotage-eines-ukrainischen-Angriffs.jpg","width":460,"height":259,"caption":"Elon Musk korrigiert Darstellung zur angeblichen Sabotage eines ukrainischen Angriffs"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/elon-musk-korrigiert-darstellung-zur-angeblichen-sabotage-eines-ukrainischen-angriffs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Elon Musk korrigiert Darstellung zur angeblichen Sabotage eines ukrainischen Angriffs"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/45985"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=45985"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/45985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/45986"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=45985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=45985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=45985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}