{"id":45695,"date":"2023-09-04T19:35:14","date_gmt":"2023-09-04T17:35:14","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/"},"modified":"2023-09-04T19:35:14","modified_gmt":"2023-09-04T17:35:14","slug":"medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/","title":{"rendered":"Medienbericht: McDonald&#039;s will fr\u00fcher oder sp\u00e4ter nach Russland zur\u00fcckkehren"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/64f5ba3848fbef43b970c0a2.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Inhaber des McDonald&#8217;s-Konzerns, die sich nach Beginn des Ukraine-Konflikts mit gro\u00dfem Get\u00f6se aus dem russischen Markt zur\u00fcckgezogen haben, sind, wie sich zeigt, nicht f\u00fcr immer gegangen. Sie haben den R\u00fcckkauf des Unternehmens ins Auge gefasst, \u2013 sobald es die Lage erlaubt.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Der russische Gesch\u00e4ftsmann Alexander Gowor, der die Fast-Food-Kette McDonald&#8217;s von dem US-amerikanischen Unternehmen aufgekauft hat, erz\u00e4hlte der Nachrichtenagentur <em>TASS<\/em>, dass die Eigent\u00fcmer der Kette die M\u00f6glichkeit einer R\u00fcckkehr auf den russischen Markt &#8220;durch die Hintert\u00fcr&#8221; ins Auge gefasst h\u00e4tten. Laut Gowor wurde er, ein ehemaliger McDonald&#8217;s-Franchisenehmer, gerade deshalb als neuer Eigent\u00fcmer des Betriebs in Russland ausgew\u00e4hlt. Der Gesch\u00e4ftsmann erkl\u00e4rte gegen\u00fcber <em>TASS<\/em>:<\/p>\n<blockquote>\n<p><em>&#8220;Diejenigen, die die Entscheidung im Namen des Unternehmens getroffen haben, hatten ihre eigene Logik. Um ehrlich zu sein, h\u00e4tte ich mich an ihrer Stelle auch f\u00fcr mich entschieden. Ich hatte mich bereits als Partner bew\u00e4hrt, ich kannte das System in- und auswendig. Welchen Grund sollte McDonald&#8217;s haben, ein Risiko mit einem Au\u00dfenseiter einzugehen? Sie machten keinen Hehl daraus, dass sie mit einer R\u00fcckkehr nach Russland rechneten, wenn sich die Umst\u00e4nde \u00e4nderten, und sie wollten sicher sein, dass das Gesch\u00e4ft nicht zusammenbrechen w\u00fcrde.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Gowor sagte auch, dass er Vertretern des amerikanischen Unternehmens versprochen habe, dass er eine Kontrollbeteiligung an der russischen Kette behalten werde. Gleichzeitig sehe die Vereinbarung auch eine Option f\u00fcr die sp\u00e4tere R\u00fcckgabe des McDonald&#8217;s-Gesch\u00e4fts vor \u2013 und alles, was der russische Unternehmer in der Zwischenzeit in das Gesch\u00e4ft investieren w\u00fcrde, m\u00fcssten ihm die US-Amerikaner bei einer \u00dcbernahme zur\u00fcckerstatten.<\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/russland\/172461-russlands-mcdonalds-ersatz-uebertrifft-original\/\">Russlands McDonald&#8217;s-Ersatz \u00fcbertrifft Original<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/russland\/179720-medienbericht-mcdonalds-will-frueher-oder\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inhaber des McDonald&#8217;s-Konzerns, die sich nach Beginn des Ukraine-Konflikts mit gro\u00dfem Get\u00f6se aus dem russischen Markt zur\u00fcckgezogen haben, sind, wie sich zeigt, nicht f\u00fcr immer gegangen. Sie haben den R\u00fcckkauf des Unternehmens ins Auge gefasst, \u2013 sobald es die Lage erlaubt. Der russische Gesch\u00e4ftsmann Alexander Gowor, der die Fast-Food-Kette McDonald&#8217;s von dem US-amerikanischen Unternehmen aufgekauft [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":45696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1693849001"],"wp_automatic_camp":["217"],"d7b5b3ae3660a8bfa91d8b1b4f033ea3":["Medienbericht: McDonald&#039;s will fr\u00fcher oder sp\u00e4ter nach Russland zur\u00fcckkehren"],"original_link":["https:\/\/de.rt.com\/russland\/179720-medienbericht-mcdonalds-will-frueher-oder\/"],"_thumbnail_id":["45696"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-09-04 19:37:42\";}"],"jnews_social_counter_last_update":["1784149987"]},"categories":[19,23],"tags":[36553,20958,869,979,268,126,15978,10019],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Medienbericht: McDonald&#039;s will fr\u00fcher oder sp\u00e4ter nach Russland zur\u00fcckkehren - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medienbericht: McDonald&#039;s will fr\u00fcher oder sp\u00e4ter nach Russland zur\u00fcckkehren\" \/>\n<meta property=\"og:description\" content=\"Inhaber des McDonald&#8217;s-Konzerns, die sich nach Beginn des Ukraine-Konflikts mit gro\u00dfem Get\u00f6se aus dem russischen Markt zur\u00fcckgezogen haben, sind, wie sich zeigt, nicht f\u00fcr immer gegangen. Sie haben den R\u00fcckkauf des Unternehmens ins Auge gefasst, \u2013 sobald es die Lage erlaubt. Der russische Gesch\u00e4ftsmann Alexander Gowor, der die Fast-Food-Kette McDonald&#8217;s von dem US-amerikanischen Unternehmen aufgekauft [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-04T17:35:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Medienbericht-McDonald039s-will-frueher-oder-spaeter-nach-Russland-zurueckkehren.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Medienbericht: McDonald&#039;s will fr\u00fcher oder sp\u00e4ter nach Russland zur\u00fcckkehren\",\"datePublished\":\"2023-09-04T17:35:14+00:00\",\"dateModified\":\"2023-09-04T17:35:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/\"},\"wordCount\":303,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Medienbericht-McDonald039s-will-frueher-oder-spaeter-nach-Russland-zurueckkehren.jpg\",\"keywords\":[\"fr\u00fcher\",\"McDonald039s\",\"Medienbericht\",\"nach\",\"oder\",\"russland\",\"sp\u00e4ter\",\"zur\u00fcckkehren\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/\",\"name\":\"Medienbericht: McDonald&#039;s will fr\u00fcher oder sp\u00e4ter nach Russland zur\u00fcckkehren - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Medienbericht-McDonald039s-will-frueher-oder-spaeter-nach-Russland-zurueckkehren.jpg\",\"datePublished\":\"2023-09-04T17:35:14+00:00\",\"dateModified\":\"2023-09-04T17:35:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Medienbericht-McDonald039s-will-frueher-oder-spaeter-nach-Russland-zurueckkehren.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Medienbericht-McDonald039s-will-frueher-oder-spaeter-nach-Russland-zurueckkehren.jpg\",\"width\":460,\"height\":259,\"caption\":\"Medienbericht: McDonald&#039;s will fr\u00fcher oder sp\u00e4ter nach Russland zur\u00fcckkehren\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medienbericht: McDonald&#039;s will fr\u00fcher oder sp\u00e4ter nach Russland zur\u00fcckkehren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Medienbericht: McDonald&#039;s will fr\u00fcher oder sp\u00e4ter nach Russland zur\u00fcckkehren - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/","og_locale":"de_DE","og_type":"article","og_title":"Medienbericht: McDonald&#039;s will fr\u00fcher oder sp\u00e4ter nach Russland zur\u00fcckkehren","og_description":"Inhaber des McDonald&#8217;s-Konzerns, die sich nach Beginn des Ukraine-Konflikts mit gro\u00dfem Get\u00f6se aus dem russischen Markt zur\u00fcckgezogen haben, sind, wie sich zeigt, nicht f\u00fcr immer gegangen. Sie haben den R\u00fcckkauf des Unternehmens ins Auge gefasst, \u2013 sobald es die Lage erlaubt. Der russische Gesch\u00e4ftsmann Alexander Gowor, der die Fast-Food-Kette McDonald&#8217;s von dem US-amerikanischen Unternehmen aufgekauft [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-09-04T17:35:14+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Medienbericht-McDonald039s-will-frueher-oder-spaeter-nach-Russland-zurueckkehren.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Medienbericht: McDonald&#039;s will fr\u00fcher oder sp\u00e4ter nach Russland zur\u00fcckkehren","datePublished":"2023-09-04T17:35:14+00:00","dateModified":"2023-09-04T17:35:14+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/"},"wordCount":303,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Medienbericht-McDonald039s-will-frueher-oder-spaeter-nach-Russland-zurueckkehren.jpg","keywords":["fr\u00fcher","McDonald039s","Medienbericht","nach","oder","russland","sp\u00e4ter","zur\u00fcckkehren"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/","url":"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/","name":"Medienbericht: McDonald&#039;s will fr\u00fcher oder sp\u00e4ter nach Russland zur\u00fcckkehren - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Medienbericht-McDonald039s-will-frueher-oder-spaeter-nach-Russland-zurueckkehren.jpg","datePublished":"2023-09-04T17:35:14+00:00","dateModified":"2023-09-04T17:35:14+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Medienbericht-McDonald039s-will-frueher-oder-spaeter-nach-Russland-zurueckkehren.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/09\/Medienbericht-McDonald039s-will-frueher-oder-spaeter-nach-Russland-zurueckkehren.jpg","width":460,"height":259,"caption":"Medienbericht: McDonald&#039;s will fr\u00fcher oder sp\u00e4ter nach Russland zur\u00fcckkehren"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/medienbericht-mcdonalds-will-frueher-oder-spaeter-nach-russland-zurueckkehren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Medienbericht: McDonald&#039;s will fr\u00fcher oder sp\u00e4ter nach Russland zur\u00fcckkehren"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/45695"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=45695"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/45695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/45696"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=45695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=45695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=45695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}