{"id":45416,"date":"2023-08-30T17:42:02","date_gmt":"2023-08-30T15:42:02","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/"},"modified":"2023-08-30T17:42:02","modified_gmt":"2023-08-30T15:42:02","slug":"schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/","title":{"rendered":"Schoigu auf Inspektion bei R\u00fcstungsbetrieben im Gebiet Tula"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/64ef5a7b48fbef32120db3e8.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Russlands Verteidigungsminister Sergei Schoigu besucht R\u00fcstungsbetriebe im Gebiet Tula. Dort inspiziert er die Herstellung von Radarsystemen und fordert zu weiterer Beschleunigung der Produktion auf.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Russlands Verteidigungsminister Sergei Schoigu ist im Gebiet Tula zu einer Inspektion eingetroffen, um die Erf\u00fcllung des staatlichen R\u00fcstungsvertrags zu pr\u00fcfen. Laut einer offiziellen Erkl\u00e4rung <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/mod_russia\/29937\">besuchte<\/a> der Minister Betriebe des R\u00fcstungsunternehmens Almas-Antei, wo moderne Modelle von Radarsystemen herstellt werden.<\/p>\n<p>Jan Nowikow, Generaldirektor von Almas-Antei, berichtete Schoigu \u00fcber die erh\u00f6hte Produktion moderner Artilleriebek\u00e4mpfungsradare und das beschleunigte Liefertempo an Einheiten der russischen Streitkr\u00e4fte in der Zone der milit\u00e4rischen Sonderoperation. Dank der Rekonstruktion und der technischen Neuausr\u00fcstung, die im Laufe der vergangenen zwei Jahre durchgef\u00fchrt wurden, stieg die potenzielle Produktionskapazit\u00e4t f\u00fcr das gesamte Sortiment des Unternehmens um ein Vielfaches. Die Qualit\u00e4t hergestellter Waren sowie die Produktionsfristen konnten durch effektive technische L\u00f6sungen und Einf\u00fchrung l\u00e4ngerer Arbeitsschichten erh\u00f6ht werden.<\/p>\n<p>Nach Abschluss der Inspektion hielt Schoigu eine Sitzung mit der Leitung von Almas-Antei und den Vertretern der zust\u00e4ndigen Milit\u00e4rbeh\u00f6rden ab. Der Verteidigungsminister ordnete eine weitere Beschleunigung der Produktion und Reparaturarbeiten. Im Rahmen der milit\u00e4rischen Sonderoperation spiele dies eine wichtige Rolle f\u00fcr die Artilleriebek\u00e4mpfung. Russische Einheiten m\u00fcssen mit allem versorgt werden, was daf\u00fcr erforderlich sei. In diesem Zusammenhang forderte Schoigu das Unternehmen auf, den 24-Stunden-Betrieb an jedem Tag der Woche zu organisieren.<\/p>\n<p><strong>Mehr zum Thema\u00a0\u2013\u00a0<\/strong><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/178452-washington-post-pentagon-leidet-unter\/\">Washington Post: Pentagon leidet unter Munitionsmangel<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/russland\/179343-schoigu-mit-inspektion-an-ruestungsbetrieben\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Russlands Verteidigungsminister Sergei Schoigu besucht R\u00fcstungsbetriebe im Gebiet Tula. Dort inspiziert er die Herstellung von Radarsystemen und fordert zu weiterer Beschleunigung der Produktion auf. Russlands Verteidigungsminister Sergei Schoigu ist im Gebiet Tula zu einer Inspektion eingetroffen, um die Erf\u00fcllung des staatlichen R\u00fcstungsvertrags zu pr\u00fcfen. Laut einer offiziellen Erkl\u00e4rung besuchte der Minister Betriebe des R\u00fcstungsunternehmens Almas-Antei, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":45417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1693412454"],"wp_automatic_camp":["217"],"f2948647566c251ec97defa00908aaf6":["Schoigu auf Inspektion bei R\u00fcstungsbetrieben im Gebiet Tula"],"original_link":["https:\/\/de.rt.com\/russland\/179343-schoigu-mit-inspektion-an-ruestungsbetrieben\/"],"_thumbnail_id":["45417"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-08-30 18:22:02\";}"],"jnews_social_counter_last_update":["1778597089"]},"categories":[19,23],"tags":[133,363,23009,47700,48305,5673,40386],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Schoigu auf Inspektion bei R\u00fcstungsbetrieben im Gebiet Tula - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schoigu auf Inspektion bei R\u00fcstungsbetrieben im Gebiet Tula\" \/>\n<meta property=\"og:description\" content=\"Russlands Verteidigungsminister Sergei Schoigu besucht R\u00fcstungsbetriebe im Gebiet Tula. Dort inspiziert er die Herstellung von Radarsystemen und fordert zu weiterer Beschleunigung der Produktion auf. Russlands Verteidigungsminister Sergei Schoigu ist im Gebiet Tula zu einer Inspektion eingetroffen, um die Erf\u00fcllung des staatlichen R\u00fcstungsvertrags zu pr\u00fcfen. Laut einer offiziellen Erkl\u00e4rung besuchte der Minister Betriebe des R\u00fcstungsunternehmens Almas-Antei, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-30T15:42:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/Schoigu-auf-Inspektion-bei-Ruestungsbetrieben-im-Gebiet-Tula.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Schoigu auf Inspektion bei R\u00fcstungsbetrieben im Gebiet Tula\",\"datePublished\":\"2023-08-30T15:42:02+00:00\",\"dateModified\":\"2023-08-30T15:42:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/\"},\"wordCount\":256,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/Schoigu-auf-Inspektion-bei-Ruestungsbetrieben-im-Gebiet-Tula.jpg\",\"keywords\":[\"AUF\",\"bei\",\"Gebiet\",\"Inspektion\",\"R\u00fcstungsbetrieben\",\"Schoigu\",\"Tula\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/\",\"name\":\"Schoigu auf Inspektion bei R\u00fcstungsbetrieben im Gebiet Tula - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/Schoigu-auf-Inspektion-bei-Ruestungsbetrieben-im-Gebiet-Tula.jpg\",\"datePublished\":\"2023-08-30T15:42:02+00:00\",\"dateModified\":\"2023-08-30T15:42:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/Schoigu-auf-Inspektion-bei-Ruestungsbetrieben-im-Gebiet-Tula.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/Schoigu-auf-Inspektion-bei-Ruestungsbetrieben-im-Gebiet-Tula.jpg\",\"width\":460,\"height\":259,\"caption\":\"Schoigu auf Inspektion bei R\u00fcstungsbetrieben im Gebiet Tula\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schoigu auf Inspektion bei R\u00fcstungsbetrieben im Gebiet Tula\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Schoigu auf Inspektion bei R\u00fcstungsbetrieben im Gebiet Tula - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/","og_locale":"de_DE","og_type":"article","og_title":"Schoigu auf Inspektion bei R\u00fcstungsbetrieben im Gebiet Tula","og_description":"Russlands Verteidigungsminister Sergei Schoigu besucht R\u00fcstungsbetriebe im Gebiet Tula. Dort inspiziert er die Herstellung von Radarsystemen und fordert zu weiterer Beschleunigung der Produktion auf. Russlands Verteidigungsminister Sergei Schoigu ist im Gebiet Tula zu einer Inspektion eingetroffen, um die Erf\u00fcllung des staatlichen R\u00fcstungsvertrags zu pr\u00fcfen. Laut einer offiziellen Erkl\u00e4rung besuchte der Minister Betriebe des R\u00fcstungsunternehmens Almas-Antei, [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-08-30T15:42:02+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/Schoigu-auf-Inspektion-bei-Ruestungsbetrieben-im-Gebiet-Tula.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Schoigu auf Inspektion bei R\u00fcstungsbetrieben im Gebiet Tula","datePublished":"2023-08-30T15:42:02+00:00","dateModified":"2023-08-30T15:42:02+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/"},"wordCount":256,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/Schoigu-auf-Inspektion-bei-Ruestungsbetrieben-im-Gebiet-Tula.jpg","keywords":["AUF","bei","Gebiet","Inspektion","R\u00fcstungsbetrieben","Schoigu","Tula"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/","url":"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/","name":"Schoigu auf Inspektion bei R\u00fcstungsbetrieben im Gebiet Tula - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/Schoigu-auf-Inspektion-bei-Ruestungsbetrieben-im-Gebiet-Tula.jpg","datePublished":"2023-08-30T15:42:02+00:00","dateModified":"2023-08-30T15:42:02+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/Schoigu-auf-Inspektion-bei-Ruestungsbetrieben-im-Gebiet-Tula.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/Schoigu-auf-Inspektion-bei-Ruestungsbetrieben-im-Gebiet-Tula.jpg","width":460,"height":259,"caption":"Schoigu auf Inspektion bei R\u00fcstungsbetrieben im Gebiet Tula"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/schoigu-auf-inspektion-bei-ruestungsbetrieben-im-gebiet-tula\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Schoigu auf Inspektion bei R\u00fcstungsbetrieben im Gebiet Tula"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/45416"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=45416"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/45416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/45417"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=45416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=45416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=45416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}