{"id":42088,"date":"2023-08-16T19:19:55","date_gmt":"2023-08-16T17:19:55","guid":{"rendered":"https:\/\/just-now.news\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/"},"modified":"2023-08-16T19:19:55","modified_gmt":"2023-08-16T17:19:55","slug":"antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/","title":{"rendered":"&quot;Antifa-Methoden&quot; in Chemnitz? Vermummte \u00fcberfallen mutma\u00dflichen Neonazi mit Machete"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/64dcfe2d48fbef278e15d215.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                In einem Chemnitzer Park ist ein mutma\u00dflicher Rechtsextremer von einer Gruppe Vermummter angegriffen und verletzt worden. Ihm sollen drei Finger abgehackt worden sein. Die Polizei schlie\u00dft ein politisches Motiv nicht aus. Steckt die Antifa dahinter?\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Im Chemnitzer Stadtpark ist am Dienstagnachmittag ein Mann brutal angegriffen worden. Das 29-j\u00e4hrige Opfer wurde aktuellen Erkenntnissen zufolge um kurz nach 15 Uhr von mehreren vermummten Personen angegriffen.<\/p>\n<p>Der Mann wurde dabei erheblich verletzt, die schwarz vermummten T\u00e4ter konnten unerkannt fliehen. Wie die\u00a0<em>Bild<\/em>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bild.de\/regional\/chemnitz\/chemnitz-news\/brutaler-angriff-in-chemnitz-mann-28-mit-machete-drei-finger-abgehackt-85063284.bild.html\">berichtete<\/a>, sollen ihm mit einer Machete drei Finger abgehackt worden sein. Die genaue Art der Verletzungen gab die\u00a0Polizei\u00a0auf Anfrage von <em>t-online<\/em> nicht bekannt. Der Sprecher der Chemnitzer Staatsanwaltschaft best\u00e4tigte aber, dass man nach einem Gegenstand, der als Waffe benutzt wurde, suche, und dass das Opfer schwer verletzt wurde.\u00a0<\/p>\n<p>Bei dem Angegriffenen soll es sich um einen bekannten Neonazi handeln, der ein entsprechendes T-Shirt anhatte. Das k\u00f6nnte die sogenannten &#8220;Antifa&#8221; auf den Plan gerufen haben, die wie im Fall um die verurteilte Lisa Engel in letzter Zeit immer st\u00e4rker zu brutalen Methoden tendiert, um ihre politischen Gegner einzusch\u00fcchtern. Typisch ist dabei stets die komplett in Schwarz vermummte Kleidung.\u00a0<\/p>\n<p>Weder zur Verletzung noch zum mutma\u00dflichen politischen Hintergrund des Opfers wollte das LKA auf Nachfrage Angaben machen. Man hoffe noch auf Zeugenhinweise, da sich die Tat am helllichten Tage ereignet habe.<\/p>\n<p>Die Publizistin Birgit Kelle kommentierte das Geschehen\u00a0auf X (ehemals Twitter) mit den Worten:<\/p>\n<blockquote>\n<p><em>&#8220;Es scheint nicht mehr Konsens in diesem Land, dass Meinungsverschiedenheiten nicht mit roher Gewalt und Waffen ausgetragen werden. Die klammheimliche Freude mancher, wenn es die vermeintlich &#8220;Richtigen&#8221; trifft, wird noch wie ein Boomerang zur\u00fcckschlagen.&#8221;<\/em><\/p>\n<\/blockquote>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">Es scheint nicht mehr Konsens in diesem Land, dass Meinungsverschiedenheiten nicht mit roher Gewalt und Waffen ausgetragen werden.Die kammheimliche Freude mancher, wenn es die vermeintlich &#8220;Richtigen&#8221; trifft, wird noch wie ein Boomerang zur\u00fcckschlagen. <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/dWHCnUKoHn\">https:\/\/t.co\/dWHCnUKoHn<\/a><\/p>\n<p>\u2014 Birgit Kelle (@Birgit_Kelle) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/Birgit_Kelle\/status\/1691752480810406232?ref_src=twsrc%5Etfw\">August 16, 2023<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p><strong>Mehr zum Thema<\/strong>\u00a0&#8211;\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/177621-rechtsanwalt-markus-haintz-stellt-strafanzeige-gegen-hr-und-polizei\/\">Antifa-Feindesliste: Rechtsanwalt Markus Haintz stellt Strafanzeige gegen hr und Polizei<\/a><\/p>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/178049-antifa-methoden-in-chemnitz-vermummte\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In einem Chemnitzer Park ist ein mutma\u00dflicher Rechtsextremer von einer Gruppe Vermummter angegriffen und verletzt worden. Ihm sollen drei Finger abgehackt worden sein. Die Polizei schlie\u00dft ein politisches Motiv nicht aus. Steckt die Antifa dahinter? Im Chemnitzer Stadtpark ist am Dienstagnachmittag ein Mann brutal angegriffen worden. Das 29-j\u00e4hrige Opfer wurde aktuellen Erkenntnissen zufolge um kurz [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":42089,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1692207089"],"wp_automatic_camp":["217"],"fd6eb7472064ec0f1fd65985b965feaa":["&quot;Antifa-Methoden&quot; in Chemnitz? Vermummte \u00fcberfallen mutma\u00dflichen Neonazi mit Machete"],"original_link":["https:\/\/de.rt.com\/inland\/178049-antifa-methoden-in-chemnitz-vermummte\/"],"_thumbnail_id":["42089"],"jnews_social_counter_last_update":["1778549153"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2023-08-16 19:32:51\";}"]},"categories":[19,23],"tags":[7935,27793,419,20689,34146,47824,31650,39054],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Antifa-Methoden&quot; in Chemnitz? Vermummte \u00fcberfallen mutma\u00dflichen Neonazi mit Machete - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Antifa-Methoden&quot; in Chemnitz? Vermummte \u00fcberfallen mutma\u00dflichen Neonazi mit Machete\" \/>\n<meta property=\"og:description\" content=\"In einem Chemnitzer Park ist ein mutma\u00dflicher Rechtsextremer von einer Gruppe Vermummter angegriffen und verletzt worden. Ihm sollen drei Finger abgehackt worden sein. Die Polizei schlie\u00dft ein politisches Motiv nicht aus. Steckt die Antifa dahinter? Im Chemnitzer Stadtpark ist am Dienstagnachmittag ein Mann brutal angegriffen worden. Das 29-j\u00e4hrige Opfer wurde aktuellen Erkenntnissen zufolge um kurz [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-16T17:19:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/quotAntifa-Methodenquot-in-Chemnitz-Vermummte-ueberfallen-mutmasslichen-Neonazi-mit-Machete.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"&quot;Antifa-Methoden&quot; in Chemnitz? Vermummte \u00fcberfallen mutma\u00dflichen Neonazi mit Machete\",\"datePublished\":\"2023-08-16T17:19:55+00:00\",\"dateModified\":\"2023-08-16T17:19:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/\"},\"wordCount\":349,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/quotAntifa-Methodenquot-in-Chemnitz-Vermummte-ueberfallen-mutmasslichen-Neonazi-mit-Machete.jpg\",\"keywords\":[\"Chemnitz\",\"Machete\",\"mit\",\"mutma\u00dflichen\",\"Neonazi\",\"quotAntifaMethodenquot\",\"\u00fcberfallen\",\"Vermummte\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/\",\"name\":\"&quot;Antifa-Methoden&quot; in Chemnitz? Vermummte \u00fcberfallen mutma\u00dflichen Neonazi mit Machete - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/quotAntifa-Methodenquot-in-Chemnitz-Vermummte-ueberfallen-mutmasslichen-Neonazi-mit-Machete.jpg\",\"datePublished\":\"2023-08-16T17:19:55+00:00\",\"dateModified\":\"2023-08-16T17:19:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/quotAntifa-Methodenquot-in-Chemnitz-Vermummte-ueberfallen-mutmasslichen-Neonazi-mit-Machete.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/quotAntifa-Methodenquot-in-Chemnitz-Vermummte-ueberfallen-mutmasslichen-Neonazi-mit-Machete.jpg\",\"width\":460,\"height\":259,\"caption\":\"&quot;Antifa-Methoden&quot; in Chemnitz? Vermummte \u00fcberfallen mutma\u00dflichen Neonazi mit Machete\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&quot;Antifa-Methoden&quot; in Chemnitz? Vermummte \u00fcberfallen mutma\u00dflichen Neonazi mit Machete\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"&quot;Antifa-Methoden&quot; in Chemnitz? Vermummte \u00fcberfallen mutma\u00dflichen Neonazi mit Machete - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/","og_locale":"de_DE","og_type":"article","og_title":"&quot;Antifa-Methoden&quot; in Chemnitz? Vermummte \u00fcberfallen mutma\u00dflichen Neonazi mit Machete","og_description":"In einem Chemnitzer Park ist ein mutma\u00dflicher Rechtsextremer von einer Gruppe Vermummter angegriffen und verletzt worden. Ihm sollen drei Finger abgehackt worden sein. Die Polizei schlie\u00dft ein politisches Motiv nicht aus. Steckt die Antifa dahinter? Im Chemnitzer Stadtpark ist am Dienstagnachmittag ein Mann brutal angegriffen worden. Das 29-j\u00e4hrige Opfer wurde aktuellen Erkenntnissen zufolge um kurz [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2023-08-16T17:19:55+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/quotAntifa-Methodenquot-in-Chemnitz-Vermummte-ueberfallen-mutmasslichen-Neonazi-mit-Machete.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"&quot;Antifa-Methoden&quot; in Chemnitz? Vermummte \u00fcberfallen mutma\u00dflichen Neonazi mit Machete","datePublished":"2023-08-16T17:19:55+00:00","dateModified":"2023-08-16T17:19:55+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/"},"wordCount":349,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/quotAntifa-Methodenquot-in-Chemnitz-Vermummte-ueberfallen-mutmasslichen-Neonazi-mit-Machete.jpg","keywords":["Chemnitz","Machete","mit","mutma\u00dflichen","Neonazi","quotAntifaMethodenquot","\u00fcberfallen","Vermummte"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/","url":"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/","name":"&quot;Antifa-Methoden&quot; in Chemnitz? Vermummte \u00fcberfallen mutma\u00dflichen Neonazi mit Machete - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/quotAntifa-Methodenquot-in-Chemnitz-Vermummte-ueberfallen-mutmasslichen-Neonazi-mit-Machete.jpg","datePublished":"2023-08-16T17:19:55+00:00","dateModified":"2023-08-16T17:19:55+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/quotAntifa-Methodenquot-in-Chemnitz-Vermummte-ueberfallen-mutmasslichen-Neonazi-mit-Machete.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2023\/08\/quotAntifa-Methodenquot-in-Chemnitz-Vermummte-ueberfallen-mutmasslichen-Neonazi-mit-Machete.jpg","width":460,"height":259,"caption":"&quot;Antifa-Methoden&quot; in Chemnitz? Vermummte \u00fcberfallen mutma\u00dflichen Neonazi mit Machete"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/antifa-methoden-in-chemnitz-vermummte-ueberfallen-mutmasslichen-neonazi-mit-machete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"&quot;Antifa-Methoden&quot; in Chemnitz? Vermummte \u00fcberfallen mutma\u00dflichen Neonazi mit Machete"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/42088"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=42088"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/42088\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/42089"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=42088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=42088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=42088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}